{"id":213862,"date":"2025-02-19T16:34:44","date_gmt":"2025-02-19T13:34:44","guid":{"rendered":"https:\/\/walltopia.com\/products\/non%20class\u00e9\/graffiti-up-up-up\/"},"modified":"2026-01-15T22:54:37","modified_gmt":"2026-01-15T19:54:37","slug":"graffiti-up-up-up","status":"publish","type":"product","link":"https:\/\/walltopia.com\/fr\/product\/graffiti-fun-walls\/graffiti-up-up-up\/","title":{"rendered":"Graffiti Up, Up, Up"},"content":{"rendered":"<p>*La voie d&rsquo;escalade est pr\u00e9d\u00e9termin\u00e9e et pr\u00e9sente un niveau de difficult\u00e9 de trois.<\/p>\n<p><strong>Sp\u00e9cifications techniques :<\/strong><\/p>\n<h4>Type de structure<\/h4>\n<p>Graffiti Up, Up, Up est livr\u00e9 avec notre structure standard en acier qui doit \u00eatre ancr\u00e9e dans le sol et sur le dessus du cadre. La structure pour les emplacements ext\u00e9rieurs est galvanis\u00e9e \u00e0 chaud, ce qui garantit sa durabilit\u00e9 et sa r\u00e9sistance aux conditions m\u00e9t\u00e9orologiques partout dans le monde. <\/p>\n<h4>Ancrage<\/h4>\n<p>Vous devez ancrer deux plaques d&rsquo;acier de base, chacune avec quatre ancrages en bas, et fixer \u00e9galement deux points de fixation en haut. Les points de fixation sup\u00e9rieurs peuvent varier en fonction de l&rsquo;espace d&rsquo;installation pour soutenir correctement votre Graffiti Up, Up, Up. La structure doit \u00eatre ancr\u00e9e dans une dalle de b\u00e9ton solide d&rsquo;une \u00e9paisseur minimale de 15 cm. Pour vous assurer que votre sol peut supporter le Graffiti Up, Up, Up, <strong>veuillez trouver ci-joint les calculs statiques des charges<\/strong> <em>Walltopia Standard Loads File<\/em> <strong>dans la section t\u00e9l\u00e9chargeable et consultez toujours votre ing\u00e9nieur ou un professionnel qualifi\u00e9.<\/strong>   <\/p>\n<h4>Placement<\/h4>\n<p>Graffiti Up, Up, Up doit \u00eatre plac\u00e9 \u00e0 l&rsquo;\u00e9cart d&rsquo;objets durs tels que des colonnes de b\u00e2timents, des rampes, des meubles ou autres. Les dimensions de la zone de s\u00e9curit\u00e9 sont d\u00e9finies dans les photos du produit. Il s&rsquo;agit de la zone qu&rsquo;il est obligatoire de maintenir \u00e0 l&rsquo;\u00e9cart de tout obstacle.  <\/p>\n<h4>Panneaux lat\u00e9raux<\/h4>\n<p>Veuillez noter que les panneaux lat\u00e9raux <strong>ne<\/strong> sont <strong>PAS inclus<\/strong> dans le prix du produit. Si vous souhaitez acheter des panneaux lat\u00e9raux pour vos Fun Walls, veuillez consulter notre <em><span style=\"text-decoration: underline;\">Page produit Panneaux lat\u00e9raux<\/span><\/em> et consultez l&rsquo;un de nos ing\u00e9nieurs. <\/p>\n<h4>Rev\u00eatement de sol<\/h4>\n<p>Nous vous recommandons vivement d&rsquo;installer un rev\u00eatement de sol de s\u00e9curit\u00e9 dans la zone de s\u00e9curit\u00e9 autour de chaque mur d&rsquo;escalade. Vous pouvez acheter un tapis mural en corde de 15 cm d&rsquo;\u00e9paisseur avec une finition en moquette grise ou un rev\u00eatement de sol de s\u00e9curit\u00e9 One More Life de Walltopia ou installer un autre type de rev\u00eatement de sol absorbant les chocs. <\/p>\n<h4>Produits compl\u00e9mentaires<\/h4>\n<p>Ce produit ne peut pas \u00eatre utilis\u00e9 sans un syst\u00e8me de blocage automatique !<\/p>\n<p>Notre structure Fun Walls est compatible avec l&rsquo;assurage automatique Tru Blue de Headrush et l&rsquo;assurage automatique Perfect Descend.<\/p>\n<p>N&rsquo;oubliez pas de consulter nos accessoires de s\u00e9curit\u00e9 ici. Les barri\u00e8res de s\u00e9curit\u00e9 facilitent l&rsquo;utilisation et r\u00e9duisent le risque d&rsquo;escalade non s\u00e9curis\u00e9e. Les sangles d&rsquo;autoassurage y sont attach\u00e9es lorsque personne ne grimpe. Les sangles d&rsquo;assurage automatique sont attach\u00e9es lorsque personne ne grimpe.   <\/p>\n<p>Choisissez d&rsquo;installer notre Smart Gate et r\u00e9duisez le risque d&rsquo;incidents au minimum. Nous vous recommandons \u00e9galement notre syst\u00e8me d&rsquo;auto-assurage qui contribue non seulement \u00e0 la s\u00e9curit\u00e9 des grimpeurs, mais qui facilite \u00e9galement les op\u00e9rations en r\u00e9duisant le nombre de membres du personnel requis &#8211; les participants \u00e2g\u00e9s de 5 ans peuvent utiliser l&rsquo;appareil seuls, sans supervision ! <\/p>\n<h4>Options d&rsquo;exp\u00e9dition<\/h4>\n<p>Ce produit est exp\u00e9di\u00e9 en pi\u00e8ces d\u00e9tach\u00e9es et doit \u00eatre assembl\u00e9 \u00e0 la livraison. Tous les composants, y compris la structure en acier, sont con\u00e7us pour \u00eatre facilement assembl\u00e9s. Des instructions d\u00e9taill\u00e9es sont fournies pour s&rsquo;assurer que le produit final peut \u00eatre utilis\u00e9 en toute s\u00e9curit\u00e9 et qu&rsquo;il pr\u00e9sente un aspect et une finition excellents.  <\/p>\n<h4>Machines n\u00e9cessaires \u00e0 l&rsquo;assemblage<\/h4>\n<p>Liste des outils : Tournevis \u00e0 percussion, perceuse, meuleuse d&rsquo;angle, pistolet \u00e0 percussion &#8211; douilles 17\/ 19, scie sauteuse, cl\u00e9s manuelles &#8211; 13 \/ 17 \/ 19 \/ 24, piliers, rubans de mesure.<\/p>\n<p>Machines : \u00c9l\u00e9vateur \u00e0 ciseaux capable de soulever 260 kg jusqu&rsquo;\u00e0 8 m\u00e8tres, chariot \u00e9l\u00e9vateur \u00e0 fourche 2T &#8211; pour le d\u00e9chargement, transpalette.<\/p>\n","protected":false},"excerpt":{"rendered":"*La voie d&rsquo;escalade est pr\u00e9d\u00e9termin\u00e9e et pr\u00e9sente un niveau de difficult\u00e9 de trois. Sp\u00e9cifications techniques : Type de structure Graffiti&#8230;","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"product_brand":[],"product_cat":[7573],"product_tag":[],"class_list":["post-213862","product","type-product","status-publish","product_cat-graffiti-fun-walls","first","onbackorder","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Graffiti Up, Up, Up | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/fr\/product\/graffiti-fun-walls\/graffiti-up-up-up\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Graffiti Up, Up, Up\" \/>\n<meta property=\"og:description\" content=\"*La voie d&rsquo;escalade est pr\u00e9d\u00e9termin\u00e9e et pr\u00e9sente un niveau de difficult\u00e9 de trois. Sp\u00e9cifications techniques : Type de structure Graffiti...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/fr\/product\/graffiti-fun-walls\/graffiti-up-up-up\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T19:54:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027183952\/FW_graffiti_up_up_up_1.5x8m_cam2_for_woocommerce_catalog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"841\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/product\\\/graffiti-fun-walls\\\/graffiti-up-up-up\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/product\\\/graffiti-fun-walls\\\/graffiti-up-up-up\\\/\",\"name\":\"Graffiti Up, Up, Up | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#website\"},\"datePublished\":\"2025-02-19T13:34:44+00:00\",\"dateModified\":\"2026-01-15T19:54:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/product\\\/graffiti-fun-walls\\\/graffiti-up-up-up\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/fr\\\/product\\\/graffiti-fun-walls\\\/graffiti-up-up-up\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/product\\\/graffiti-fun-walls\\\/graffiti-up-up-up\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/accueil-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/?page_id=66307\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Graffiti Up, Up, Up\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Graffiti Up, Up, Up | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/fr\/product\/graffiti-fun-walls\/graffiti-up-up-up\/","og_locale":"fr_FR","og_type":"article","og_title":"Graffiti Up, Up, Up","og_description":"*La voie d&rsquo;escalade est pr\u00e9d\u00e9termin\u00e9e et pr\u00e9sente un niveau de difficult\u00e9 de trois. Sp\u00e9cifications techniques : Type de structure Graffiti...","og_url":"https:\/\/walltopia.com\/fr\/product\/graffiti-fun-walls\/graffiti-up-up-up\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2026-01-15T19:54:37+00:00","og_image":[{"width":841,"height":1920,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027183952\/FW_graffiti_up_up_up_1.5x8m_cam2_for_woocommerce_catalog.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/fr\/product\/graffiti-fun-walls\/graffiti-up-up-up\/","url":"https:\/\/walltopia.com\/fr\/product\/graffiti-fun-walls\/graffiti-up-up-up\/","name":"Graffiti Up, Up, Up | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/fr\/#website"},"datePublished":"2025-02-19T13:34:44+00:00","dateModified":"2026-01-15T19:54:37+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/fr\/product\/graffiti-fun-walls\/graffiti-up-up-up\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/fr\/product\/graffiti-fun-walls\/graffiti-up-up-up\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/fr\/product\/graffiti-fun-walls\/graffiti-up-up-up\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/fr\/accueil-fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/walltopia.com\/fr\/?page_id=66307"},{"@type":"ListItem","position":3,"name":"Graffiti Up, Up, Up"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/fr\/#website","url":"https:\/\/walltopia.com\/fr\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/fr\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/product\/213862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/product\/213862\/revisions"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/media?parent=213862"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/product_brand?post=213862"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/product_cat?post=213862"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/product_tag?post=213862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}