{"id":118456,"date":"2021-03-08T17:02:52","date_gmt":"2021-03-08T14:02:52","guid":{"rendered":"http:\/\/walltopia.com\/testimonials\/mike-aston\/"},"modified":"2021-03-08T17:02:52","modified_gmt":"2021-03-08T14:02:52","slug":"mike-aston","status":"publish","type":"wt_testimonial","link":"https:\/\/walltopia.com\/fr\/testimonials\/mike-aston\/","title":{"rendered":"Mike Aston"},"featured_media":0,"template":"","testimonial_category":[828],"class_list":["post-118456","wt_testimonial","type-wt_testimonial","status-publish","hentry","testimonial_category-climbing"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mike Aston | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/fr\/testimonials\/mike-aston\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mike Aston\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/fr\/testimonials\/mike-aston\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/testimonials\\\/mike-aston\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/testimonials\\\/mike-aston\\\/\",\"name\":\"Mike Aston | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-03-08T14:02:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/testimonials\\\/mike-aston\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/fr\\\/testimonials\\\/mike-aston\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/testimonials\\\/mike-aston\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/accueil-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Testimonials\",\"item\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/testimonials\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mike Aston\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mike Aston | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/fr\/testimonials\/mike-aston\/","og_locale":"fr_FR","og_type":"article","og_title":"Mike Aston","og_url":"https:\/\/walltopia.com\/fr\/testimonials\/mike-aston\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/fr\/testimonials\/mike-aston\/","url":"https:\/\/walltopia.com\/fr\/testimonials\/mike-aston\/","name":"Mike Aston | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/fr\/#website"},"datePublished":"2021-03-08T14:02:52+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/fr\/testimonials\/mike-aston\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/fr\/testimonials\/mike-aston\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/fr\/testimonials\/mike-aston\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/fr\/accueil-fr\/"},{"@type":"ListItem","position":2,"name":"Testimonials","item":"https:\/\/walltopia.com\/fr\/testimonials\/"},{"@type":"ListItem","position":3,"name":"Mike Aston"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/fr\/#website","url":"https:\/\/walltopia.com\/fr\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/fr\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/wt_testimonial\/118456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/wt_testimonial"}],"about":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/types\/wt_testimonial"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/media?parent=118456"}],"wp:term":[{"taxonomy":"testimonial_category","embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/testimonial_category?post=118456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}