{"id":385870,"date":"2024-10-24T10:46:20","date_gmt":"2024-10-24T07:46:20","guid":{"rendered":"https:\/\/walltopia.com\/testimonials\/lensemble-de-lequipe-a-fait-preuve-dun-grand-professionnalisme-et-sest-reellement-impliquee-dans-le-projet\/"},"modified":"2024-10-24T10:46:20","modified_gmt":"2024-10-24T07:46:20","slug":"lensemble-de-lequipe-a-fait-preuve-dun-grand-professionnalisme-et-sest-reellement-impliquee-dans-le-projet","status":"publish","type":"wt_testimonial","link":"https:\/\/walltopia.com\/fr\/testimonials\/lensemble-de-lequipe-a-fait-preuve-dun-grand-professionnalisme-et-sest-reellement-impliquee-dans-le-projet\/","title":{"rendered":"L&rsquo;ensemble de l&rsquo;\u00e9quipe a fait preuve d&rsquo;un grand professionnalisme et s&rsquo;est r\u00e9ellement impliqu\u00e9e dans le projet."},"featured_media":0,"template":"","testimonial_category":[828],"class_list":["post-385870","wt_testimonial","type-wt_testimonial","status-publish","hentry","testimonial_category-climbing"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L&#039;ensemble de l&#039;\u00e9quipe a fait preuve d&#039;un grand professionnalisme et s&#039;est r\u00e9ellement impliqu\u00e9e dans le projet. | Walltopia<\/title>\n<meta name=\"description\" content=\"Nous sommes impressionn\u00e9s par leur fiabilit\u00e9. Tout s&#039;est d\u00e9roul\u00e9 presque exactement comme pr\u00e9vu. Ils ont \u00e9galement eu un dialogue tr\u00e8s ouvert et honn\u00eate et ont r\u00e9solu les probl\u00e8mes de mani\u00e8re efficace.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/fr\/testimonials\/lensemble-de-lequipe-a-fait-preuve-dun-grand-professionnalisme-et-sest-reellement-impliquee-dans-le-projet\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;ensemble de l&#039;\u00e9quipe a fait preuve d&#039;un grand professionnalisme et s&#039;est r\u00e9ellement impliqu\u00e9e dans le projet.\" \/>\n<meta property=\"og:description\" content=\"Nous sommes impressionn\u00e9s par leur fiabilit\u00e9. Tout s&#039;est d\u00e9roul\u00e9 presque exactement comme pr\u00e9vu. Ils ont \u00e9galement eu un dialogue tr\u00e8s ouvert et honn\u00eate et ont r\u00e9solu les probl\u00e8mes de mani\u00e8re efficace.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/fr\/testimonials\/lensemble-de-lequipe-a-fait-preuve-dun-grand-professionnalisme-et-sest-reellement-impliquee-dans-le-projet\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/testimonials\\\/lensemble-de-lequipe-a-fait-preuve-dun-grand-professionnalisme-et-sest-reellement-impliquee-dans-le-projet\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/testimonials\\\/lensemble-de-lequipe-a-fait-preuve-dun-grand-professionnalisme-et-sest-reellement-impliquee-dans-le-projet\\\/\",\"name\":\"L'ensemble de l'\u00e9quipe a fait preuve d'un grand professionnalisme et s'est r\u00e9ellement impliqu\u00e9e dans le projet. | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#website\"},\"datePublished\":\"2024-10-24T07:46:20+00:00\",\"description\":\"Nous sommes impressionn\u00e9s par leur fiabilit\u00e9. Tout s'est d\u00e9roul\u00e9 presque exactement comme pr\u00e9vu. Ils ont \u00e9galement eu un dialogue tr\u00e8s ouvert et honn\u00eate et ont r\u00e9solu les probl\u00e8mes de mani\u00e8re efficace.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/testimonials\\\/lensemble-de-lequipe-a-fait-preuve-dun-grand-professionnalisme-et-sest-reellement-impliquee-dans-le-projet\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/fr\\\/testimonials\\\/lensemble-de-lequipe-a-fait-preuve-dun-grand-professionnalisme-et-sest-reellement-impliquee-dans-le-projet\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/testimonials\\\/lensemble-de-lequipe-a-fait-preuve-dun-grand-professionnalisme-et-sest-reellement-impliquee-dans-le-projet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/accueil-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Testimonials\",\"item\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/testimonials\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L&#8217;ensemble de l&#8217;\u00e9quipe a fait preuve d&#8217;un grand professionnalisme et s&#8217;est r\u00e9ellement impliqu\u00e9e dans le projet.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L'ensemble de l'\u00e9quipe a fait preuve d'un grand professionnalisme et s'est r\u00e9ellement impliqu\u00e9e dans le projet. | Walltopia","description":"Nous sommes impressionn\u00e9s par leur fiabilit\u00e9. Tout s'est d\u00e9roul\u00e9 presque exactement comme pr\u00e9vu. Ils ont \u00e9galement eu un dialogue tr\u00e8s ouvert et honn\u00eate et ont r\u00e9solu les probl\u00e8mes de mani\u00e8re efficace.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/fr\/testimonials\/lensemble-de-lequipe-a-fait-preuve-dun-grand-professionnalisme-et-sest-reellement-impliquee-dans-le-projet\/","og_locale":"fr_FR","og_type":"article","og_title":"L'ensemble de l'\u00e9quipe a fait preuve d'un grand professionnalisme et s'est r\u00e9ellement impliqu\u00e9e dans le projet.","og_description":"Nous sommes impressionn\u00e9s par leur fiabilit\u00e9. Tout s'est d\u00e9roul\u00e9 presque exactement comme pr\u00e9vu. Ils ont \u00e9galement eu un dialogue tr\u00e8s ouvert et honn\u00eate et ont r\u00e9solu les probl\u00e8mes de mani\u00e8re efficace.","og_url":"https:\/\/walltopia.com\/fr\/testimonials\/lensemble-de-lequipe-a-fait-preuve-dun-grand-professionnalisme-et-sest-reellement-impliquee-dans-le-projet\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/fr\/testimonials\/lensemble-de-lequipe-a-fait-preuve-dun-grand-professionnalisme-et-sest-reellement-impliquee-dans-le-projet\/","url":"https:\/\/walltopia.com\/fr\/testimonials\/lensemble-de-lequipe-a-fait-preuve-dun-grand-professionnalisme-et-sest-reellement-impliquee-dans-le-projet\/","name":"L'ensemble de l'\u00e9quipe a fait preuve d'un grand professionnalisme et s'est r\u00e9ellement impliqu\u00e9e dans le projet. | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/fr\/#website"},"datePublished":"2024-10-24T07:46:20+00:00","description":"Nous sommes impressionn\u00e9s par leur fiabilit\u00e9. Tout s'est d\u00e9roul\u00e9 presque exactement comme pr\u00e9vu. Ils ont \u00e9galement eu un dialogue tr\u00e8s ouvert et honn\u00eate et ont r\u00e9solu les probl\u00e8mes de mani\u00e8re efficace.","breadcrumb":{"@id":"https:\/\/walltopia.com\/fr\/testimonials\/lensemble-de-lequipe-a-fait-preuve-dun-grand-professionnalisme-et-sest-reellement-impliquee-dans-le-projet\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/fr\/testimonials\/lensemble-de-lequipe-a-fait-preuve-dun-grand-professionnalisme-et-sest-reellement-impliquee-dans-le-projet\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/fr\/testimonials\/lensemble-de-lequipe-a-fait-preuve-dun-grand-professionnalisme-et-sest-reellement-impliquee-dans-le-projet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/fr\/accueil-fr\/"},{"@type":"ListItem","position":2,"name":"Testimonials","item":"https:\/\/walltopia.com\/fr\/testimonials\/"},{"@type":"ListItem","position":3,"name":"L&#8217;ensemble de l&#8217;\u00e9quipe a fait preuve d&#8217;un grand professionnalisme et s&#8217;est r\u00e9ellement impliqu\u00e9e dans le projet."}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/fr\/#website","url":"https:\/\/walltopia.com\/fr\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/fr\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/wt_testimonial\/385870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/wt_testimonial"}],"about":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/types\/wt_testimonial"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/media?parent=385870"}],"wp:term":[{"taxonomy":"testimonial_category","embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/testimonial_category?post=385870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}