{"id":385900,"date":"2024-08-01T10:26:15","date_gmt":"2024-08-01T07:26:15","guid":{"rendered":"https:\/\/walltopia.com\/testimonials\/le-devouement-de-lequipe-walltopia-pendant-la-phase-dinstallation-a-ete-vraiment-admirable\/"},"modified":"2024-08-01T10:26:15","modified_gmt":"2024-08-01T07:26:15","slug":"le-devouement-de-lequipe-walltopia-pendant-la-phase-dinstallation-a-ete-vraiment-admirable","status":"publish","type":"wt_testimonial","link":"https:\/\/walltopia.com\/fr\/testimonials\/le-devouement-de-lequipe-walltopia-pendant-la-phase-dinstallation-a-ete-vraiment-admirable\/","title":{"rendered":"Le d\u00e9vouement de l&rsquo;\u00e9quipe Walltopia pendant la phase d&rsquo;installation a \u00e9t\u00e9 vraiment admirable."},"featured_media":0,"template":"","testimonial_category":[],"class_list":["post-385900","wt_testimonial","type-wt_testimonial","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le d\u00e9vouement de l&#039;\u00e9quipe Walltopia pendant la phase d&#039;installation a \u00e9t\u00e9 vraiment admirable. | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/fr\/testimonials\/le-devouement-de-lequipe-walltopia-pendant-la-phase-dinstallation-a-ete-vraiment-admirable\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le d\u00e9vouement de l&#039;\u00e9quipe Walltopia pendant la phase d&#039;installation a \u00e9t\u00e9 vraiment admirable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/fr\/testimonials\/le-devouement-de-lequipe-walltopia-pendant-la-phase-dinstallation-a-ete-vraiment-admirable\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/testimonials\\\/le-devouement-de-lequipe-walltopia-pendant-la-phase-dinstallation-a-ete-vraiment-admirable\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/testimonials\\\/le-devouement-de-lequipe-walltopia-pendant-la-phase-dinstallation-a-ete-vraiment-admirable\\\/\",\"name\":\"Le d\u00e9vouement de l'\u00e9quipe Walltopia pendant la phase d'installation a \u00e9t\u00e9 vraiment admirable. | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#website\"},\"datePublished\":\"2024-08-01T07:26:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/testimonials\\\/le-devouement-de-lequipe-walltopia-pendant-la-phase-dinstallation-a-ete-vraiment-admirable\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/fr\\\/testimonials\\\/le-devouement-de-lequipe-walltopia-pendant-la-phase-dinstallation-a-ete-vraiment-admirable\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/testimonials\\\/le-devouement-de-lequipe-walltopia-pendant-la-phase-dinstallation-a-ete-vraiment-admirable\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/accueil-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Testimonials\",\"item\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/testimonials\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le d\u00e9vouement de l&#8217;\u00e9quipe Walltopia pendant la phase d&#8217;installation a \u00e9t\u00e9 vraiment admirable.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le d\u00e9vouement de l'\u00e9quipe Walltopia pendant la phase d'installation a \u00e9t\u00e9 vraiment admirable. | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/fr\/testimonials\/le-devouement-de-lequipe-walltopia-pendant-la-phase-dinstallation-a-ete-vraiment-admirable\/","og_locale":"fr_FR","og_type":"article","og_title":"Le d\u00e9vouement de l'\u00e9quipe Walltopia pendant la phase d'installation a \u00e9t\u00e9 vraiment admirable.","og_url":"https:\/\/walltopia.com\/fr\/testimonials\/le-devouement-de-lequipe-walltopia-pendant-la-phase-dinstallation-a-ete-vraiment-admirable\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/fr\/testimonials\/le-devouement-de-lequipe-walltopia-pendant-la-phase-dinstallation-a-ete-vraiment-admirable\/","url":"https:\/\/walltopia.com\/fr\/testimonials\/le-devouement-de-lequipe-walltopia-pendant-la-phase-dinstallation-a-ete-vraiment-admirable\/","name":"Le d\u00e9vouement de l'\u00e9quipe Walltopia pendant la phase d'installation a \u00e9t\u00e9 vraiment admirable. | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/fr\/#website"},"datePublished":"2024-08-01T07:26:15+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/fr\/testimonials\/le-devouement-de-lequipe-walltopia-pendant-la-phase-dinstallation-a-ete-vraiment-admirable\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/fr\/testimonials\/le-devouement-de-lequipe-walltopia-pendant-la-phase-dinstallation-a-ete-vraiment-admirable\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/fr\/testimonials\/le-devouement-de-lequipe-walltopia-pendant-la-phase-dinstallation-a-ete-vraiment-admirable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/fr\/accueil-fr\/"},{"@type":"ListItem","position":2,"name":"Testimonials","item":"https:\/\/walltopia.com\/fr\/testimonials\/"},{"@type":"ListItem","position":3,"name":"Le d\u00e9vouement de l&#8217;\u00e9quipe Walltopia pendant la phase d&#8217;installation a \u00e9t\u00e9 vraiment admirable."}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/fr\/#website","url":"https:\/\/walltopia.com\/fr\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/fr\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/wt_testimonial\/385900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/wt_testimonial"}],"about":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/types\/wt_testimonial"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/media?parent=385900"}],"wp:term":[{"taxonomy":"testimonial_category","embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/testimonial_category?post=385900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}