{"id":147682,"date":"2023-01-19T14:47:55","date_gmt":"2023-01-19T11:47:55","guid":{"rendered":"http:\/\/walltopia.com\/products\/adventure-trail\/"},"modified":"2026-01-28T11:29:09","modified_gmt":"2026-01-28T08:29:09","slug":"adventure-trail","status":"publish","type":"wt_wall_type","link":"https:\/\/walltopia.com\/fr\/products\/adventure-trail\/","title":{"rendered":"Adventure Trail"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"Le sentier d&rsquo;aventure Walltopia est un terrain de jeu sur\u00e9lev\u00e9 avec des hauteurs palpitantes, des obstacles stimulants et un amusement s\u00fbr et sans harnais pour tous.","protected":false},"featured_media":177010,"template":"","wall_category":[808],"class_list":["post-147682","wt_wall_type","type-wt_wall_type","status-publish","has-post-thumbnail","hentry","wall_category-active-entertainment-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adventure Trail | Walltopia<\/title>\n<meta name=\"description\" content=\"L&#039;Adventure Trail est une aire de jeux sur\u00e9lev\u00e9e pour les enfants, qui permet aux participants de ressentir le frisson des hauteurs sans avoir besoin d&#039;un harnais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/fr\/products\/adventure-trail\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adventure Trail\" \/>\n<meta property=\"og:description\" content=\"L&#039;Adventure Trail est une aire de jeux sur\u00e9lev\u00e9e pour les enfants, qui permet aux participants de ressentir le frisson des hauteurs sans avoir besoin d&#039;un harnais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/fr\/products\/adventure-trail\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-28T08:29:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251210124531\/walltopia-adventure-trail-ocean-park-01.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/products\\\/adventure-trail\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/products\\\/adventure-trail\\\/\",\"name\":\"Adventure Trail | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/products\\\/adventure-trail\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/products\\\/adventure-trail\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20251210124531\\\/walltopia-adventure-trail-ocean-park-01.webp\",\"datePublished\":\"2023-01-19T11:47:55+00:00\",\"dateModified\":\"2026-01-28T08:29:09+00:00\",\"description\":\"L'Adventure Trail est une aire de jeux sur\u00e9lev\u00e9e pour les enfants, qui permet aux participants de ressentir le frisson des hauteurs sans avoir besoin d'un harnais.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/products\\\/adventure-trail\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/fr\\\/products\\\/adventure-trail\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/products\\\/adventure-trail\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20251210124531\\\/walltopia-adventure-trail-ocean-park-01.webp\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20251210124531\\\/walltopia-adventure-trail-ocean-park-01.webp\",\"width\":1500,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/products\\\/adventure-trail\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/accueil-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Walltopia products\",\"item\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/climbing-walls-types\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adventure Trail\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adventure Trail | Walltopia","description":"L'Adventure Trail est une aire de jeux sur\u00e9lev\u00e9e pour les enfants, qui permet aux participants de ressentir le frisson des hauteurs sans avoir besoin d'un harnais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/fr\/products\/adventure-trail\/","og_locale":"fr_FR","og_type":"article","og_title":"Adventure Trail","og_description":"L'Adventure Trail est une aire de jeux sur\u00e9lev\u00e9e pour les enfants, qui permet aux participants de ressentir le frisson des hauteurs sans avoir besoin d'un harnais.","og_url":"https:\/\/walltopia.com\/fr\/products\/adventure-trail\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2026-01-28T08:29:09+00:00","og_image":[{"width":1500,"height":800,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251210124531\/walltopia-adventure-trail-ocean-park-01.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/walltopia.com\/fr\/products\/adventure-trail\/","url":"https:\/\/walltopia.com\/fr\/products\/adventure-trail\/","name":"Adventure Trail | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/fr\/products\/adventure-trail\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/fr\/products\/adventure-trail\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251210124531\/walltopia-adventure-trail-ocean-park-01.webp","datePublished":"2023-01-19T11:47:55+00:00","dateModified":"2026-01-28T08:29:09+00:00","description":"L'Adventure Trail est une aire de jeux sur\u00e9lev\u00e9e pour les enfants, qui permet aux participants de ressentir le frisson des hauteurs sans avoir besoin d'un harnais.","breadcrumb":{"@id":"https:\/\/walltopia.com\/fr\/products\/adventure-trail\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/fr\/products\/adventure-trail\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/walltopia.com\/fr\/products\/adventure-trail\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251210124531\/walltopia-adventure-trail-ocean-park-01.webp","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251210124531\/walltopia-adventure-trail-ocean-park-01.webp","width":1500,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/fr\/products\/adventure-trail\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/fr\/accueil-fr\/"},{"@type":"ListItem","position":2,"name":"Walltopia products","item":"https:\/\/walltopia.com\/fr\/climbing-walls-types\/"},{"@type":"ListItem","position":3,"name":"Adventure Trail"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/fr\/#website","url":"https:\/\/walltopia.com\/fr\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/fr\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/wt_wall_type\/147682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/wt_wall_type"}],"about":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/types\/wt_wall_type"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/media\/177010"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/media?parent=147682"}],"wp:term":[{"taxonomy":"wall_category","embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/wall_category?post=147682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}