{"id":115549,"date":"2021-03-31T19:32:27","date_gmt":"2021-03-31T16:32:27","guid":{"rendered":"http:\/\/walltopia.com\/servizi\/manutenzione-e-ispezione\/"},"modified":"2026-01-15T17:31:12","modified_gmt":"2026-01-15T14:31:12","slug":"manutenzione-e-ispezione","status":"publish","type":"page","link":"https:\/\/walltopia.com\/it\/servizi\/manutenzione-e-ispezione\/","title":{"rendered":"Manutenzione e ispezione"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_empty_space height=&#8221;100px&#8221;]<div class=\"info-block-container info-block shdw shdw margin-bottom-100\"><div class=\"content\"><h2>Every safety standard recommends yearly maintenance and inspection visits<\/h2><div class=\"full-width-container\"><p>Walltopia offers a comprehensive safety inspection service designed to ensure your facility operates both safely and successfully. Our maintenance inspections are available for any facility, regardless of whether it was constructed by us.<\/p>\n<p>The maintenance inspections we conduct adhere to European standards and are carried out by our globally based, qualified technicians.<\/p>\n<p>Upon completion, we provide a detailed report of the inspection process. This report highlights any issues of concern and offers recommendations on the urgency with which each issue should be addressed.<\/p>\n<\/div><\/div><!-- .content --><div id=\"chocolat-parent\" class=\"image\"><a class=\"chocolat-image\" href=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027143225\/SAM_3644-15-copy-scaled.webp\"><img decoding=\"async\" src=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027143225\/SAM_3644-15-copy-800x600.webp\" width=\"100%\" height=\"auto\" alt=\"\" \/><\/a><\/div><\/div><!-- .info-block-container --><div class=\"info-block-container wp-bakery-block info-block shdw margin-bottom-100\"><div class=\"content\"><h2>Services for Climbing Walls<\/h2><div class=\"full-width-container\"><\/p>\n<ul>\n<li>Examination of the overall level of safety of the wall, its construction, foundations and surfaces - special attention is given to all protection systems<\/li>\n<li>Route setting (e.g. removing, cleaning and reinstallation of the holds)<\/li>\n<li>Testing of the Wall according to EN 12572-1:2007<\/li>\n<li>Inspection the anchor bolts of the attachment points<\/li>\n<li>Visual inspection of the welding of the attachment points<\/li>\n<li>Assesment of deformations (if any) of the construction (trusses, bracings, panel holders, etc.)<\/li>\n<li>Examination of bolts of the main structure<\/li>\n<li>Check-up for loose or rotated protection points<\/li>\n<li>Assesment of the state of the climbing surface<\/li>\n<\/ul>\n<p>\n<\/div><\/div><!-- .content --><div id=\"chocolat-parent\" class=\"image\"><a class=\"chocolat-image\" href=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223817\/u-bolt-1.jpg\" title=\"Services for Climbing Walls\"><img decoding=\"async\" src=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223817\/u-bolt-1-800x600.jpg\" width=\"100%\" height=\"auto\" alt=\"\" \/><\/a><\/div><!-- .image --><\/div><!-- .info-block-container --><div class=\"info-block-container wp-bakery-block info-block shdw margin-bottom-100\"><div class=\"content\"><h2>Services for Active Entertainment Products<\/h2><div class=\"full-width-container\"><\/p>\n<ul>\n<li>Examination of the overall level of safety of the product, its construction, foundations and surfaces - special attention is given to all protection systems;<\/li>\n<li>Testing of the products according to different EU standards, depending on the product\/facility;<\/li>\n<li>Visual inspection of the welding of the attachment points<\/li>\n<li>Assessment of deformations (if any) of the construction (trusses, bracings, panel holders, etc.)<\/li>\n<li>Examination of bolts of the main structure<\/li>\n<li>Check-up for loose or rotated protection points<\/li>\n<\/ul>\n<p>\n<\/div><\/div><!-- .content --><div id=\"chocolat-parent\" class=\"image\"><a class=\"chocolat-image\" href=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240227155609\/image00077-1-scaled.jpeg\" title=\"Services for Active Entertainment Products\"><img decoding=\"async\" src=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240227155609\/image00077-1-800x600.jpeg\" width=\"100%\" height=\"auto\" alt=\"\" \/><\/a><\/div><!-- .image --><\/div><!-- .info-block-container --><div class=\"info-block-container wp-bakery-block info-block shdw margin-bottom-100\"><div class=\"content\"><h2>Contact us<\/h2><div class=\"full-width-container\"><p>Please note that to have your wall comply with the European Standard EN 12572-1:2007, the wall should pass a full inspection at least once a year.<\/p>\n<p>For more details on Walltopia\u2019s maintenance services, please contact us at customerservice@walltopia.com<\/p>\n<\/div><a href=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090955\/WT_Inspection_FAQ_final.pdf\" class=\"hover-effect-fast wt-link\" target=\"_blank\">Download Inspection FAQ<\/a><\/div><!-- .content --><div id=\"chocolat-parent\" class=\"image\"><a class=\"chocolat-image\" href=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027222959\/255023051_4626552277391169_8663455097930040373_n.jpg\" title=\"Contact us\"><img decoding=\"async\" src=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027222959\/255023051_4626552277391169_8663455097930040373_n-800x600.jpg\" width=\"100%\" height=\"auto\" alt=\"\" \/><\/a><\/div><!-- .image --><\/div><!-- .info-block-container -->[vc_raw_html css=&#8221;&#8221;]PGgyIHN0eWxlPSJtYXJnaW4tYm90dG9tOiAyMHB4OyI+RG9tYW5kZSBmcmVxdWVudGkgc3VsbCdpc3BlemlvbmU8L2gyPgpbZmFxIGlkPSIxNzY4MzEiXQpbZmFxIGlkPSIxNzY4MzIiXQpbZmFxIGlkPSIxNzY4MzMiXQpbZmFxIGlkPSIxNzY4MzQiXQpbZmFxIGlkPSIxNzY4MzUiXQpbZmFxIGlkPSIxNzY4MzYiXQpbZmFxIGlkPSIxNzY4MzgiXQpbZmFxIGlkPSIxNzY4MzkiXQpbZmFxIGlkPSIxNzY4NDAiXQpbZmFxIGlkPSIxNzY4NDEiXQpbZmFxIGlkPSIxNzY4NDIiXQ==[\/vc_raw_html][vc_empty_space height=&#8221;100px&#8221;][vc_raw_html css=&#8221;&#8221;]PGgyPlJhcHBvcnRvIGRpIHJlY2xhbW88L2gyPgo8cD5QZXIgc2VnbmFsYXJlIHVuIGluY2lkZW50ZSBvIHVuIHByb2JsZW1hIHJlbGF0aXZvIGFsIHByb2RvdHRvLCB1dGlsaXp6YSBpbCBub3N0cm8gPHN0cm9uZz5tb2R1bG88L3N0cm9uZz4gdWZmaWNpYWxlIDxzdHJvbmc+cGVyIGxhIHNlZ25hbGF6aW9uZSBkaSB1biByZWNsYW1vPC9zdHJvbmc+LCByaXBvcnRhdG8gZGkgc2VndWl0bzwvcD4KCjxwPkwnaW52aW8gZGV2ZSBlc3NlcmUgY29tcGxldGF0byBzb2xvIGRhbGwnaXN0cnV0dG9yZSwgZGFsIGNhcG9zcXVhZHJhIG8gZGFsIHJlc3BvbnNhYmlsZSBkZWxsYSBzdHJ1dHR1cmEuIFRpIHByZWdoaWFtbyBkaSBmb3JuaXJlIHVuYSBkZXNjcml6aW9uZSBjaGlhcmEgZGVsIHJlY2xhbW8sIGluY2x1ZGVuZG8gdHV0dGkgaSBkZXR0YWdsaSBlIGxlIGNpcmNvc3RhbnplIHJpbGV2YW50aSwgZSBkaSBwcmVwYXJhcmUgcHJvdmUgYSBzb3N0ZWdubyBjb21lIGZvdG8sIHZpZGVvIG8gZG9jdW1lbnRpLCBmb3JuZW5kbyB1biBVUkwgYSB1bmEgY2FydGVsbGEgZGVsIGNsb3VkLWRyaXZlIGNvbnRlbmVudGUgcXVlc3RpIGZpbGUuIFByaW1hIGRpIGNvbXBpbGFyZSBlIGludmlhcmUgaWwgbW9kdWxvLCBhc3NpY3VyYXRpIGRpIGxlZ2dlcmUgbGEgbm9zdHJhIDxzdHJvbmc+UG9saXRpY2EgZGkgcmVjbGFtbzwvc3Ryb25nPiBhbGwnaW5kaXJpenpvIDxhIGhyZWY9Imh0dHBzOi8vd2FsbHRvcGlhLmNvbS9pdC9wb2xpdGljYS1kaS1yZWNsYW1vLyIgdGFyZ2V0PSJfYmxhbmsiIHJlbD0ibm9vcGVuZXIiPndhbGx0b3BpYS5jb20vY2xhaW0tcG9saWN5PC9hPi4gIDwvcD4KCjxwPjxhIGhyZWY9Imh0dHBzOi8vd2FsbHRvcGlhLmNvbS9pdC9yYXBwb3J0by1kaS1yZWNsYW1vLyIgdGFyZ2V0PSJfYmxhbmsiIHJlbD0ibm9vcGVuZXIiIGNsYXNzPSJ3dC1saW5rIj5Nb2R1bG8gZGkgZGVudW5jaWEgZGkgc2luaXN0cm88L2E+PC9wPg==[\/vc_raw_html][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_empty_space height=&#8221;100px&#8221;][vc_raw_html css=&#8221;&#8221;]PGgyIHN0eWxlPSJtYXJnaW4tYm90dG9tOiAyMHB4OyI+RG9tYW5kZSBmcmVxdWVudGkgc3VsbCdpc3BlemlvbmU8L2gyPgpbZmFxIGlkPSIxNzY4MzEiXQpbZmFxIGlkPSIxNzY4MzIiXQpbZmFxIGlkPSIxNzY4MzMiXQpbZmFxIGlkPSIxNzY4MzQiXQpbZmFxIGlkPSIxNzY4MzUiXQpbZmFxIGlkPSIxNzY4MzYiXQpbZmFxIGlkPSIxNzY4MzgiXQpbZmFxIGlkPSIxNzY4MzkiXQpbZmFxIGlkPSIxNzY4NDAiXQpbZmFxIGlkPSIxNzY4NDEiXQpbZmFxIGlkPSIxNzY4NDIiXQ==[\/vc_raw_html][vc_empty_space height=&#8221;100px&#8221;][vc_raw_html css=&#8221;&#8221;]PGgyPlJhcHBvcnRvIGRpIHJlY2xhbW88L2gyPgo8cD5QZXIgc2VnbmFsYXJlIHVuIGluY2lkZW50ZSBvIHVuIHByb2JsZW1hIHJlbGF0aXZvIGFsIHByb2RvdHRvLCB1dGlsaXp6YSBpbCBub3N0cm8gPHN0cm9uZz5tb2R1bG88L3N0cm9uZz4gdWZmaWNpYWxlIDxzdHJvbmc+cGVyIGxhIHNlZ25hbGF6aW9uZSBkaSB1biByZWNsYW1vPC9zdHJvbmc+LCByaXBvcnRhdG8gZGkgc2VndWl0bzwvcD4KCjxwPkwnaW52aW8gZGV2ZSBlc3NlcmUgY29tcGxldGF0byBzb2xvIGRhbGwnaXN0cnV0dG9yZSwgZGFsIGNhcG9zcXVhZHJhIG8gZGFsIHJlc3BvbnNhYmlsZSBkZWxsYSBzdHJ1dHR1cmEuIFRpIHByZWdoaWFtbyBkaSBmb3JuaXJlIHVuYSBkZXNjcml6aW9uZSBjaGlhcmEgZGVsIHJlY2xhbW8sIGluY2x1ZGVuZG8gdHV0dGkgaSBkZXR0YWdsaSBlIGxlIGNpcmNvc3RhbnplIHJpbGV2YW50aSwgZSBkaSBwcmVwYXJhcmUgcHJvdmUgYSBzb3N0ZWdubyBjb21lIGZvdG8sIHZpZGVvIG8gZG9jdW1lbnRpLCBmb3JuZW5kbyB1biBVUkwgYSB1bmEgY2FydGVsbGEgZGVsIGNsb3VkLWRyaXZlIGNvbnRlbmVudGUgcXVlc3RpIGZpbGUuIFByaW1hIGRpIGNvbXBpbGFyZSBlIGludmlhcmUgaWwgbW9kdWxvLCBhc3NpY3VyYXRpIGRpIGxlZ2dlcmUgbGEgbm9zdHJhIDxzdHJvbmc+UG9saXRpY2EgZGkgcmVjbGFtbzwvc3Ryb25nPiBhbGwnaW5kaXJpenpvIDxhIGhyZWY9Imh0dHBzOi8vd2FsbHRvcGlhLmNvbS9pdC9wb2xpdGljYS1kaS1yZWNsYW1vLyIgdGFyZ2V0PSJfYmxhbmsiIHJlbD0ibm9vcGVuZXIiPndhbGx0b3BpYS5jb20vY2xhaW0tcG9saWN5PC9hPi4gIDwvcD4KCjxwPjxhIGhyZWY9Imh0dHBzOi8vd2FsbHRvcGlhLmNvbS9pdC9yYXBwb3J0by1kaS1yZWNsYW1vLyIgdGFyZ2V0PSJfYmxhbmsiIHJlbD0ibm9vcGVuZXIiIGNsYXNzPSJ3dC1saW5rIj5Nb2R1bG8gZGkgZGVudW5jaWEgZGkgc2luaXN0cm88L2E+PC9wPg==[\/vc_raw_html][\/vc_column][\/vc_row]","protected":false},"author":6,"featured_media":21477,"parent":115538,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-big-header.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-115549","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Manutenzione e ispezione | Walltopia<\/title>\n<meta name=\"description\" content=\"Offriamo un servizio completo di ispezioni di sicurezza per garantire che la tua struttura operi in modo sicuro e con successo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/it\/servizi\/manutenzione-e-ispezione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manutenzione e ispezione\" \/>\n<meta property=\"og:description\" content=\"Offriamo un servizio completo di ispezioni di sicurezza per garantire che la tua struttura operi in modo sicuro e con successo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/it\/servizi\/manutenzione-e-ispezione\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:31:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026091245\/maintenance_inspection.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"582\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/servizi\\\/manutenzione-e-ispezione\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/servizi\\\/manutenzione-e-ispezione\\\/\",\"name\":\"Manutenzione e ispezione | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/servizi\\\/manutenzione-e-ispezione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/servizi\\\/manutenzione-e-ispezione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026091245\\\/maintenance_inspection.jpg\",\"datePublished\":\"2021-03-31T16:32:27+00:00\",\"dateModified\":\"2026-01-15T14:31:12+00:00\",\"description\":\"Offriamo un servizio completo di ispezioni di sicurezza per garantire che la tua struttura operi in modo sicuro e con successo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/servizi\\\/manutenzione-e-ispezione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/servizi\\\/manutenzione-e-ispezione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/servizi\\\/manutenzione-e-ispezione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026091245\\\/maintenance_inspection.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026091245\\\/maintenance_inspection.jpg\",\"width\":1200,\"height\":582},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/servizi\\\/manutenzione-e-ispezione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/casa-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servizi\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/servizi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Manutenzione e ispezione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Manutenzione e ispezione | Walltopia","description":"Offriamo un servizio completo di ispezioni di sicurezza per garantire che la tua struttura operi in modo sicuro e con successo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/it\/servizi\/manutenzione-e-ispezione\/","og_locale":"it_IT","og_type":"article","og_title":"Manutenzione e ispezione","og_description":"Offriamo un servizio completo di ispezioni di sicurezza per garantire che la tua struttura operi in modo sicuro e con successo.","og_url":"https:\/\/walltopia.com\/it\/servizi\/manutenzione-e-ispezione\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2026-01-15T14:31:12+00:00","og_image":[{"width":1200,"height":582,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026091245\/maintenance_inspection.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/it\/servizi\/manutenzione-e-ispezione\/","url":"https:\/\/walltopia.com\/it\/servizi\/manutenzione-e-ispezione\/","name":"Manutenzione e ispezione | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/it\/servizi\/manutenzione-e-ispezione\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/it\/servizi\/manutenzione-e-ispezione\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026091245\/maintenance_inspection.jpg","datePublished":"2021-03-31T16:32:27+00:00","dateModified":"2026-01-15T14:31:12+00:00","description":"Offriamo un servizio completo di ispezioni di sicurezza per garantire che la tua struttura operi in modo sicuro e con successo.","breadcrumb":{"@id":"https:\/\/walltopia.com\/it\/servizi\/manutenzione-e-ispezione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/it\/servizi\/manutenzione-e-ispezione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/servizi\/manutenzione-e-ispezione\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026091245\/maintenance_inspection.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026091245\/maintenance_inspection.jpg","width":1200,"height":582},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/it\/servizi\/manutenzione-e-ispezione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/it\/casa-it\/"},{"@type":"ListItem","position":2,"name":"Servizi","item":"https:\/\/walltopia.com\/it\/servizi\/"},{"@type":"ListItem","position":3,"name":"Manutenzione e ispezione"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/it\/#website","url":"https:\/\/walltopia.com\/it\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/it\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/pages\/115549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/comments?post=115549"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/pages\/115549\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/pages\/115538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media\/21477"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media?parent=115549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}