{"id":116093,"date":"2023-06-25T18:46:47","date_gmt":"2023-06-25T15:46:47","guid":{"rendered":"http:\/\/walltopia.com\/non-categorizzato\/ricordo-del-wics-2023\/"},"modified":"2026-01-15T21:57:59","modified_gmt":"2026-01-15T18:57:59","slug":"ricordo-del-wics-2023","status":"publish","type":"post","link":"https:\/\/walltopia.com\/it\/ricordo-del-wics-2023\/","title":{"rendered":"Ricordo del WICS 2023"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]<strong>Il WICS 2023 ha riunito per la terza volta un gruppo ristretto di manager di alto livello, proprietari di palestre, rappresentanti di federazioni e altri professionisti del settore dell&#8217;arrampicata provenienti da tutto il mondo. Il summit \u00e8 stato caratterizzato da una vasta gamma di attivit\u00e0, tra cui approfondite tavole rotonde e presentazioni, e un&#8217;esilarante gara di arrampicata con un forte focus sulla creazione di vie. Inoltre, c&#8217;era una vivace sala espositiva che esponeva le ultime prese e i volumi di arrampicata delle migliori marche. Inoltre, erano presenti le ultime novit\u00e0 tecnologiche in fatto di dispositivi autobelay e sistemi di pavimentazione. Per finire, c&#8217;\u00e8 stata la &#8220;famigerata&#8221; festa sul tetto di Walltopia.    Approfondiamo i punti salienti del WICS 2023.<\/strong><\/p>\n<h4>La comunit\u00e0 dell&#8217;arrampicata \u00e8 in crescita<\/h4>\n<p>WICS 2023 \u00e8 stata la prima edizione del raduno internazionale dei professionisti del settore dell&#8217;arrampicata dal 2019 ed \u00e8 stata un&#8217;esplosione. Negli ultimi 4 anni, il mondo sembra essere cambiato molto, segnato da numerosi eventi negativi, da molteplici chiusure di aziende e dalla paura per il futuro. Tuttavia, l&#8217;industria dell&#8217;arrampicata si dimostra in ascesa in termini di crescita, sviluppo e professionalizzazione, pur essendo ancora nel suo periodo romantico. L&#8217;arrampicata sembra essere un&#8217;attivit\u00e0 commerciale sostenibile in quanto sia i proprietari che i loro clienti sono animati dalla passione. L&#8217;entusiasmo per l&#8217;arrampicata non sembra andare da nessuna parte. In effetti, \u00e8 sembrato che la scena internazionale fosse desiderosa di incontrarsi e condividere le proprie intuizioni, scoperte, preoccupazioni, sfide e soluzioni.   Il WICS \u00e8 riuscito a portare tanta energia positiva e tanti sorrisi attraverso un prezioso lavoro di networking e approfondimenti![\/vc_column_text][vc_empty_space][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=CkIUr4ZpRrA&#8221; css=&#8221;.vc_custom_1707321837401{margin-bottom: 50px !important;}&#8221;][vc_custom_heading text=&#8221;Partecipazione e diversit\u00e0&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text css=&#8221;&#8221;]Il WICS di quest&#8217;anno \u00e8 stato il pi\u00f9 internazionale di sempre, con rappresentanti provenienti da oltre 30 paesi, tra cui Stati Uniti, Regno Unito, Cina, Corea del Sud e molti altri. A differenza delle edizioni precedenti, che erano pi\u00f9 incentrate sull&#8217;Europa e sugli Stati Uniti, quest&#8217;anno ha visto una partecipazione globale pi\u00f9 ampia. <\/p>\n<p>Questo \u00e8 probabilmente dovuto al fatto che i mercati occidentali hanno un&#8217;industria dell&#8217;arrampicata consolidata da tempo e quindi un maggior numero di professionisti disposti a viaggiare. La presenza internazionale del WICS 2023 ha favorito un ricco scambio di idee, rendendolo un raduno davvero vario e inclusivo di esperti di arrampicata provenienti da diversi contesti e culture.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]\n<p><em>Partecipazione al WICS 2023 per regione<\/em><\/p>\n[\/vc_column_text][vc_single_image image=&#8221;112832&#8243; img_size=&#8221;full&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1707321731391{margin-top: 50px !important;}&#8221;][vc_column][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1707130451408{margin-top: 50px !important;}&#8221;][vc_column][vc_custom_heading text=&#8221;Programma della conferenza&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_column_text css=&#8221;&#8221;]Il programma della conferenza WICS 2023 ha coperto un&#8217;ampia gamma di argomenti importanti per l&#8217;industria dell&#8217;arrampicata. Le sessioni hanno affrontato le tendenze del mercato globale, l&#8217;importanza di avvicinare i giovani all&#8217;arrampicata, le migliori pratiche nella creazione delle vie e il futuro delle competizioni di arrampicata. Grazie a una schiera di esperti di fama, i partecipanti hanno potuto trarre preziose indicazioni e spunti di riflessione da queste presentazioni e discussioni stimolanti.[\/vc_column_text][vc_text_separator title=&#8221;GIORNO 1&#8243; title_align=&#8221;separator_align_left&#8221; css=&#8221;.vc_custom_1707316173992{margin-top: 50px !important;margin-bottom: 30px !important;}&#8221;][vc_column_text css=&#8221;&#8221;]Il summit \u00e8 iniziato con la sessione &#8220;Ricerca e analisi dell&#8217;industria dell&#8217;arrampicata&#8221;, presentata da Borislav Stefanov, che ha offerto uno sguardo basato sui dati sullo stato attuale e sulle prospettive future del settore. In seguito, la sessione &#8220;Stato globale del mercato&#8221; ha fornito una panoramica completa sullo stato del settore nelle varie regioni. Professionisti esperti come Peter Zeidelhack, Mark Sebille e Yasmin Gahtani, tra gli altri, hanno condiviso le loro opinioni sui rispettivi paesi, offrendo ai partecipanti una comprensione approfondita del panorama mondiale dell&#8217;arrampicata.[\/vc_column_text][vc_gallery interval=&#8221;3&#8243; images=&#8221;112839,112846,112853&#8243; img_size=&#8221;full&#8221; css=&#8221;.vc_custom_1707316194193{margin-top: 30px !important;}&#8221;][vc_column_text css=&#8221;&#8221;]Il programma \u00e8 proseguito con &#8220;Creare generazioni di arrampicatori&#8221;, in cui Robyn Erbesfield-Raboutou, Alice Kao e Remi Moehring hanno discusso il ruolo delle palestre nel coinvolgere i giovani e nel trattenerli come clienti a lungo termine. Inoltre, &#8220;Progettazione architettonica delle palestre di arrampicata&#8221; ha visto la partecipazione di esperti che hanno discusso le tendenze nell&#8217;utilizzo degli spazi e il loro riflesso sugli interessi della comunit\u00e0. <\/p>\n<p>Inoltre, &#8220;Le gare di arrampicata&#8221; ha riunito i leader del settore, tra cui Finuco Martinez e Stefano Ghisolfi, per esaminare l&#8217;evoluzione e il futuro delle gare, fornendo preziose prospettive su questo aspetto dinamico dello sport.[\/vc_column_text][vc_gallery interval=&#8221;3&#8243; images=&#8221;112867,112874,112860,113496,113510&#8243; img_size=&#8221;full&#8221; css=&#8221;.vc_custom_1707321279215{margin-top: 30px !important;}&#8221;][vc_text_separator title=&#8221;GIORNO 2&#8243; title_align=&#8221;separator_align_left&#8221; css=&#8221;.vc_custom_1707316689952{margin-top: 50px !important;margin-bottom: 30px !important;}&#8221;][vc_column_text css=&#8221;&#8221;]Il secondo giorno si \u00e8 aperto con la sessione &#8220;Tendenze del calcolo delle rotte&#8221;, che ha visto la partecipazione di Peter Zeidelhack, Jan De Smit, Nataleigh Bell, Niklas Wiechmann e Guillermo Burba. Durante la sessione \u00e8 stato analizzato il modo in cui le pratiche di calcolo delle rotte si sono evolute nel corso degli anni e il loro impatto sul settore. La professionalit\u00e0 dei relatori e l&#8217;approccio incentrato sul cliente hanno infiammato il pubblico, dando vita a conversazioni che si sono estese al di l\u00e0 del panel e alla folla. Lo scambio dinamico di idee ha evidenziato l&#8217;importanza del routeetting nel plasmare l&#8217;esperienza dell&#8217;arrampicata.[\/vc_column_text][vc_gallery interval=&#8221;3&#8243; images=&#8221;112909,112881,112902,112895,112888&#8243; img_size=&#8221;full&#8221;][vc_column_text css=&#8221;&#8221;]In &#8220;La strada dall&#8217;arrampicata all&#8217;imprenditoria&#8221;, Matilda S\u00f6derlund ha condiviso il suo percorso, descrivendo le sfide per bilanciare una carriera da arrampicatore professionista con la gestione di una palestra di successo. In seguito, Jon Colbert ha presentato &#8220;Metriche importanti per capire le prestazioni di una palestra&#8221;, offrendo approfondimenti basati sui dati relativi agli indicatori di prestazione chiave per la crescita dei ricavi. <\/p>\n<p>Infine, il summit si \u00e8 concluso con una sessione che ha visto la partecipazione dei principali proprietari di catene di palestre, guidata dal CEO di Walltopia Ivaylo Penchev, che ha incoraggiato una discussione aperta e una riflessione sulle sfide del settore. Nel complesso, il programma ha fornito ai partecipanti una comprensione approfondita del panorama del settore e delle opportunit\u00e0 future.[\/vc_column_text][vc_gallery interval=&#8221;3&#8243; images=&#8221;112923,112916,113503,113517&#8243; img_size=&#8221;full&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1707316237846{margin-top: 50px !important;}&#8221;][vc_column][vc_custom_heading text=&#8221;Valore erogato&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_column_text css=&#8221;&#8221;]<strong>Il WICS 2023 si \u00e8 rivelato prezioso per i suoi partecipanti, offrendo una piattaforma per il networking, l&#8217;apprendimento e la collaborazione. I partecipanti hanno elogiato il summit per aver creato nuove partnership, rafforzato i legami esistenti e discusso le sfide e le soluzioni del settore. In particolare, molti hanno ritenuto che l&#8217;esposizione a preziose intuizioni dal mondo dell&#8217;arrampicata professionale sia stato un vantaggio fondamentale dell&#8217;evento.  <\/strong>[\/vc_column_text]<blockquote class=\"custom relative full-width-container margin-bottom-25\" style=\"color: #000000; font-size: 24px; line-height: 1.5; background-color: #f3f5f6;\"><div class=\"content block width-100 float-left\">``A small intimate group of experienced people who know what they are talking about``<\/div><span class=\"dashicons dashicons-format-quote\" style=\"color: #a3e7f0;\"><\/span><\/blockquote>[vc_row_inner css=&#8221;.vc_custom_1707319473972{margin-top: 50px !important;}&#8221;][vc_column_inner width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;113272&#8243; img_size=&#8221;full&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;3\/4&#8243;][vc_column_text]\n<p><a href=\"https:\/\/climbingsummit.com\/speakers\/halil-ngah\/\">Halil Ngah<\/a>, fondatore e CEO di <a href=\"https:\/\/climb-asia.com\/\">Climb Asia <\/a>, ha apprezzato la qualit\u00e0 dei partecipanti, che erano ben preparati nel settore dell&#8217;arrampicata: <em>&#8220;Un piccolo gruppo intimo di persone esperte che sanno di cosa stanno parlando&#8221;<\/em>. Ha riconosciuto la rapida evoluzione del settore e ha auspicato l&#8217;adozione di strumenti di successo da altri settori per spingerlo in avanti.<\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1707319479383{margin-top: 50px !important;}&#8221;][vc_column_inner width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;113286&#8243; img_size=&#8221;full&#8221; add_caption=&#8221;yes&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;3\/4&#8243;][vc_column_text]\n<p>Yasmin Gahtani, responsabile della <a href=\"https:\/\/climbing.sa\/\">Federazione di Arrampicata ed Escursionismo dell&#8217;Arabia Saudita<\/a>, ha apprezzato le opportunit\u00e0 di networking e gli approfondimenti ottenuti dalle tavole rotonde. &#8221; <em>L&#8217;opportunit\u00e0 di parlare con persone che hanno palestre di arrampicata gi\u00e0 esistenti e di apprendere quali ricerche hanno dovuto fare per aprire nuove palestre&#8221;<\/em> l&#8217;ha aiutata a rendersi conto delle opportunit\u00e0 e delle azioni da intraprendere nel suo paese per sviluppare la scena dell&#8217;arrampicata indoor.<\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1707319486559{margin-top: 50px !important;}&#8221;][vc_column_inner width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;113279&#8243; img_size=&#8221;full&#8221; add_caption=&#8221;yes&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;3\/4&#8243;][vc_column_text]\n<p>Jose Sausedo, proprietario di <a href=\"https:\/\/www.adamanta.mx\/\">Adamanta Climbing<\/a> in Messico, ha dichiarato che un&#8217;idea che utilizzer\u00e0 nelle sue palestre \u00e8 quella di concentrarsi maggiormente sulle giovani generazioni e di riconoscere il loro potenziale impatto sulla crescita del settore. <em>&#8220;Per me, in particolare, il punto di vista del panel Creating Generations of Climbers \u00e8 quello di concentrarmi maggiormente sui bambini, perch\u00e9 sono il futuro dell&#8217;arrampicata e anche una parte importante delle entrate e dei profitti del settore&#8221;.<\/em><\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1707321535688{margin-top: 30px !important;}&#8221;][vc_column][vc_column_text]<a href=\"https:\/\/climbingsummit.com\/speakers\/paula-horwitz\/\">Paula Horwitz<\/a>, ex direttrice della <a href=\"https:\/\/www.cwapro.org\/\">Climbing Wall Association<\/a> negli Stati Uniti, ha trovato utile la comprensione dei vari mercati e dei loro tassi di crescita. <em>&#8220;L&#8217;attenzione per il livello esecutivo, il livello di competenza al WICS \u00e8 pi\u00f9 alto&#8221;<\/em>, ha commentato a proposito del pubblico che ha incontrato al WICS.<\/p>\n<p><a href=\"https:\/\/climbingsummit.com\/speakers\/zhu-haoqin\/\">Zhu Haoqin &#8211; Zac<\/a> di Banana Climbing ha osservato una particolare apertura e volont\u00e0 di condivisione tra i partecipanti, creando un ambiente di networking collaborativo. Ha trovato il WICS il pi\u00f9 valido tra i recenti eventi di settore a cui ha partecipato e ha condiviso volentieri le sue intuizioni sullo sviluppo del settore in Cina durante il panel Global State of the Market.<\/p>\n<p><a href=\"https:\/\/climbingsummit.com\/speakers\/simon-brunner\/\">Simon Bruenner<\/a> di <a href=\"https:\/\/blockhelden.de\/\">Blockhelden <\/a>, in Germania, ha apprezzato la presenza di persone esperte e sinceramente appassionate e competenti nel settore dell&#8217;arrampicata. Ha apprezzato particolarmente la presentazione di Yasmin Gahtani della Federazione di arrampicata dell&#8217;Arabia Saudita. Simon ha apprezzato la natura aperta e inclusiva dell&#8217;evento, incoraggiata dal CEO di Walltopia Ivaylo Penchev, che ha stimolato la partecipazione attiva e l&#8217;espressione di prospettive diverse.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1707318588801{margin-top: 50px !important;}&#8221;][vc_column][vc_custom_heading text=&#8221;Mostra di prese per l&apos;arrampicata&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_column_text css=&#8221;&#8221;]L&#8217;esposizione al WICS 2023 ha messo in mostra gli ultimi design di prese e volumi di otto grandi marchi: <a href=\"https:\/\/www.hrt-holds.com\/\">HRT<\/a>, <a href=\"https:\/\/www.cheeta-holds.com\/\">Cheeta<\/a>, <a href=\"https:\/\/www.flathold.com\/\">Flathold<\/a>, <a href=\"https:\/\/ibexholds.com\/\">Ibex<\/a>, <a href=\"https:\/\/suprclimbing.com\/\">Sup&#8217;R<\/a>, <a href=\"https:\/\/www.agripp.com\/en\/\">Agripp<\/a>, <a href=\"https:\/\/settercloset.com\/\">Kilter<\/a>, <a href=\"https:\/\/thrillseekerholds.com\/\">Thrill Seeker<\/a> e <a href=\"https:\/\/ubh.jp\/\">Under Blue Hold<\/a>. Queste forme all&#8217;avanguardia hanno offerto interessanti opportunit\u00e0 di tracciare percorsi creativi. I proprietari di palestre di arrampicata e i tracciatori di vie hanno trovato un valore immenso nella mostra, scoprendo prodotti che hanno il potenziale di elevare le loro strutture di arrampicata e di migliorare l&#8217;esperienza complessiva di arrampicata per i loro clienti.<\/p>\n<p>L&#8217;enfasi della mostra sulla qualit\u00e0 e sull&#8217;ingegno rifletteva l&#8217;impegno del settore verso il miglioramento continuo e l&#8217;innovazione nell&#8217;arrampicata indoor. Il successo del summit \u00e8 stato ulteriormente rafforzato dal supporto degli sponsor fornitori: <a href=\"https:\/\/composite-x.com\/\">Composite-X,<\/a> <a href=\"https:\/\/headrushtech.com\/\">Headrush<\/a>, HRT, <a href=\"https:\/\/www.climbmat.com\/\">Climbmat <\/a>e <a href=\"https:\/\/gymrealm.com\/\">GymRealm<\/a>. Queste aziende leader del settore non solo hanno contribuito alla vivacit\u00e0 della mostra, ma hanno anche svolto un ruolo strumentale nell&#8217;elevare la qualit\u00e0 complessiva dell&#8217;evento.[\/vc_column_text][vc_gallery interval=&#8221;3&#8243; images=&#8221;113307,113328,113349,113293,113363,113370,113335,113342,113314,113356,113321,113300&#8243; img_size=&#8221;full&#8221; css=&#8221;.vc_custom_1707319504935{margin-top: 30px !important;}&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1707318588801{margin-top: 50px !important;}&#8221;][vc_column][vc_custom_heading text=&#8221;Imposta e invia Comp&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_column_text css=&#8221;&#8221;]La serata di apertura del WICS 2023 \u00e8 stata caratterizzata da un diverso tipo di gara di bouldering: Set&amp;Send. Con il suo formato inedito, la gara ha messo in evidenza la preparazione dei percorsi come parte fondamentale delle gare, insieme alle prestazioni degli atleti. Arrampicatori e tracciatori di vie hanno lavorato insieme per risolvere i problemi su tre massi firmati Walltopia che presentano i pannelli pi\u00f9 recenti dell&#8217;azienda: il masso di legno, il masso di bamb\u00f9 e il masso di pietra.<\/p>\n<p>C&#8217;erano 5 squadre, composte da un tracciatore di vie e da un arrampicatore uomo e donna, in rappresentanza di 5 diversi marchi di prese: Flathold, Kilter, Sup&#8217;R, Cheeta e HRT. Ogni squadra poteva prevedere i propri problemi, ma non quelli degli altri. Tuttavia, hanno potuto osservarli mentre si appostavano e si anticipavano, quindi la scalata non \u00e8 stata a vista. Nonostante un paio di piccoli difetti organizzativi, la gara \u00e8 stata un&#8217;esperienza divertente sia per i partecipanti che per il pubblico, che non ha smesso di applaudire! La gara \u00e8 stata anche trasmessa in diretta su YouTube con il commento perfetto dei commentatori di fama mondiale Charlie Boscoe e Danaan Markey. Gli atleti hanno dato vita a una prestazione oltremodo eccellente, con esiti inaspettati dei tentativi di scalata e un risultato che non \u00e8 stato chiaro fino all&#8217;ultimo invio! Il risultato finale \u00e8 il seguente:<\/p>\n<h5><strong>Arrampicatori di sesso femminile:<\/strong><\/h5>\n<ol>\n<li>Lucia Dorfell<\/li>\n<li>Brooke Raboutou<\/li>\n<li>Cloe Coscoy<\/li>\n<\/ol>\n<h5><strong>Arrampicatori maschi:<\/strong><\/h5>\n<ul>\n<li>Boyan Kirov<\/li>\n<li>Slav Kirov<\/li>\n<li>Shawn Raboutou<\/li>\n<\/ul>\n<p>La premiazione per il tracciato delle vie \u00e8 stata separata e decisa da una votazione tra tutti i partecipanti alla competizione &#8211; tracciatori e arrampicatori. Ognuno di loro ha votato in forma anonima il proprio problema preferito nelle tre categorie seguenti:<\/p>\n<p><strong>Problema pi\u00f9 creativo (quello pi\u00f9 difficile da leggere)<\/strong> &#8211; vinto da Dirk Uhlig &#8211; HRT holds<br \/>\n<strong>Problema pi\u00f9 attraente<\/strong> (quello che \u00e8 stato pi\u00f9 attraente da guardare) &#8211; vinto da Gautier Supper &#8211; prese Sup&#8217;R<br \/>\n<strong>Il boulder pi\u00f9 estetico<\/strong> (la migliore opera d&#8217;arte sulle pareti) &#8211; anche il pi\u00f9 difficile da decidere, perch\u00e9 apparentemente tutti i problemi sembravano fantastici sulle pareti. Tre setter si sono divisi il premio: Tsukuru Hori (Cheeta holds), Dirk Uhlig (HRT) e Pierre Broyer (Flathold).[\/vc_column_text][vc_gallery interval=&#8221;3&#8243; images=&#8221;113258,113398,101751,113391,113237,113377,113384,103226,113251,113186&#8243; img_size=&#8221;full&#8221; css=&#8221;.vc_custom_1707320008920{margin-top: 30px !important;}&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1707318588801{margin-top: 50px !important;}&#8221;][vc_column][vc_custom_heading text=&#8221;Festa di chiusura&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_column_text css=&#8221;&#8221;]Al termine del World Indoor Climbing Summit 2023, i partecipanti hanno assistito a una memorabile festa in piscina sul tetto della sede centrale di Walltopia. Con una vista mozzafiato sul tramonto, l&#8217;evento \u00e8 stato l&#8217;occasione per rilassarsi, sorseggiare drink da un open bar e intrattenere conversazioni informali. Alcuni non hanno resistito a una nuotata rinfrescante in piscina, mentre altri hanno continuato a fare networking in un ambiente rilassato. Con l&#8217;avanzare della serata, la festa si \u00e8 spostata all&#8217;interno e si \u00e8 protratta fino alle ore piccole, lasciando a tutti ricordi indelebili e legami pi\u00f9 forti dopo un indimenticabile finale di vertice.[\/vc_column_text][vc_gallery interval=&#8221;3&#8243; images=&#8221;113461,113405,113454,113447,113419,113426,113433,113440&#8243; img_size=&#8221;full&#8221; css=&#8221;.vc_custom_1707320429271{margin-top: 30px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1729671305532{margin-top: 30px !important;}&#8221;]In conclusione, il World Indoor Climbing Summit 2023 \u00e8 stato un grande successo, che ha lasciato un impatto significativo sui professionisti dell&#8217;arrampicata. La sua portata internazionale ha incoraggiato lo scambio di idee, favorendo la collaborazione e il networking. Nel corso del tempo, mentre gli argomenti principali sono rimasti gli stessi, il livello della conversazione \u00e8 maturato, diventando pi\u00f9 professionale e incentrato sul cliente.  <\/p>\n<p>L&#8217;industria si \u00e8 evoluta, bilanciando un servizio di alta qualit\u00e0 con la passione per l&#8217;arrampicata. In definitiva, l&#8217;evento ha dimostrato che l&#8217;unit\u00e0 all&#8217;interno della comunit\u00e0 dell&#8217;arrampicata trascende le differenze culturali, guidata dall&#8217;amore comune per questo sport.[\/vc_column_text][vc_gallery interval=&#8221;3&#8243; images=&#8221;113475,112860,112888,113405,113468,113482,112909&#8243; img_size=&#8221;full&#8221;][vc_separator][vc_column_text css=&#8221;.vc_custom_1729671368850{margin-top: 30px !important;}&#8221;]\n<h6>  WICS desidera ringraziare di cuore tutti i partecipanti, i relatori e i partecipanti che hanno contribuito a rendere il World Indoor Climbing Summit (WICS) 2023 un grande successo di networking per il settore dell&#8217;arrampicata indoor. Le vostre intuizioni e i vostri contributi durante le discussioni e le presentazioni hanno contribuito a plasmare il futuro del nostro settore. Siamo inoltre grati ai nostri sponsor e partner per il loro prezioso supporto alla realizzazione del WICS 2023.  <\/h6>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]Il WICS 2023 ha riunito per la terza volta un gruppo ristretto di manager di alto livello, proprietari di&#8230;","protected":false},"author":6,"featured_media":112888,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[909,908],"tags":[],"class_list":["post-116093","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arrampicata","category-sala-stampa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ricordo del WICS 2023 | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/it\/ricordo-del-wics-2023\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ricordo del WICS 2023\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]Il WICS 2023 ha riunito per la terza volta un gruppo ristretto di manager di alto livello, proprietari di...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/it\/ricordo-del-wics-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-25T15:46:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T18:57:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240205134849\/RoutesettingTrends-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ani Manova\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/ricordo-del-wics-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/ricordo-del-wics-2023\\\/\"},\"author\":{\"name\":\"Ani Manova\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/12e3d2cc8853cc95d0f08065e0bc93f1\"},\"headline\":\"Ricordo del WICS 2023\",\"datePublished\":\"2023-06-25T15:46:47+00:00\",\"dateModified\":\"2026-01-15T18:57:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/ricordo-del-wics-2023\\\/\"},\"wordCount\":2724,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/ricordo-del-wics-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20240205134849\\\/RoutesettingTrends-2-scaled.jpg\",\"articleSection\":[\"Arrampicata\",\"Sala stampa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/ricordo-del-wics-2023\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/ricordo-del-wics-2023\\\/\",\"name\":\"Ricordo del WICS 2023 | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/ricordo-del-wics-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/ricordo-del-wics-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20240205134849\\\/RoutesettingTrends-2-scaled.jpg\",\"datePublished\":\"2023-06-25T15:46:47+00:00\",\"dateModified\":\"2026-01-15T18:57:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/ricordo-del-wics-2023\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/ricordo-del-wics-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/ricordo-del-wics-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20240205134849\\\/RoutesettingTrends-2-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20240205134849\\\/RoutesettingTrends-2-scaled.jpg\",\"width\":1200,\"height\":800,\"caption\":\"WICS 2023 - Routesetting Trends led by Peter Zeidelhack, Jan De Smit, Nataleigh Bell, Niklas Wiechmann, and Guillermo Burba\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/ricordo-del-wics-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/casa-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ricordo del WICS 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/12e3d2cc8853cc95d0f08065e0bc93f1\",\"name\":\"Ani Manova\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ricordo del WICS 2023 | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/it\/ricordo-del-wics-2023\/","og_locale":"it_IT","og_type":"article","og_title":"Ricordo del WICS 2023","og_description":"[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]Il WICS 2023 ha riunito per la terza volta un gruppo ristretto di manager di alto livello, proprietari di...","og_url":"https:\/\/walltopia.com\/it\/ricordo-del-wics-2023\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2023-06-25T15:46:47+00:00","article_modified_time":"2026-01-15T18:57:59+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240205134849\/RoutesettingTrends-2-scaled.jpg","type":"image\/jpeg"}],"author":"Ani Manova","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/it\/ricordo-del-wics-2023\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/ricordo-del-wics-2023\/"},"author":{"name":"Ani Manova","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/12e3d2cc8853cc95d0f08065e0bc93f1"},"headline":"Ricordo del WICS 2023","datePublished":"2023-06-25T15:46:47+00:00","dateModified":"2026-01-15T18:57:59+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/it\/ricordo-del-wics-2023\/"},"wordCount":2724,"publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/it\/ricordo-del-wics-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240205134849\/RoutesettingTrends-2-scaled.jpg","articleSection":["Arrampicata","Sala stampa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/it\/ricordo-del-wics-2023\/","url":"https:\/\/walltopia.com\/it\/ricordo-del-wics-2023\/","name":"Ricordo del WICS 2023 | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/it\/ricordo-del-wics-2023\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/it\/ricordo-del-wics-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240205134849\/RoutesettingTrends-2-scaled.jpg","datePublished":"2023-06-25T15:46:47+00:00","dateModified":"2026-01-15T18:57:59+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/it\/ricordo-del-wics-2023\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/it\/ricordo-del-wics-2023\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/ricordo-del-wics-2023\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240205134849\/RoutesettingTrends-2-scaled.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240205134849\/RoutesettingTrends-2-scaled.jpg","width":1200,"height":800,"caption":"WICS 2023 - Routesetting Trends led by Peter Zeidelhack, Jan De Smit, Nataleigh Bell, Niklas Wiechmann, and Guillermo Burba"},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/it\/ricordo-del-wics-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/it\/casa-it\/"},{"@type":"ListItem","position":2,"name":"Ricordo del WICS 2023"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/it\/#website","url":"https:\/\/walltopia.com\/it\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/it\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/12e3d2cc8853cc95d0f08065e0bc93f1","name":"Ani Manova"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/116093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/comments?post=116093"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/116093\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media\/112888"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media?parent=116093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/categories?post=116093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/tags?post=116093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}