{"id":180628,"date":"2021-06-18T10:32:06","date_gmt":"2021-06-18T07:32:06","guid":{"rendered":"https:\/\/walltopia.com\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\/"},"modified":"2026-01-15T16:51:56","modified_gmt":"2026-01-15T13:51:56","slug":"walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016","status":"publish","type":"post","link":"https:\/\/walltopia.com\/it\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\/","title":{"rendered":"Walltopia Adventure e Walltopia Caves esporranno al DEAL 2016"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_custom_heading text=&#8221;Il Dubai Entertainment Amusement and Leisure Show, il pi\u00f9 grande evento per le attrazioni e il divertimento nella regione MEA, riunir\u00e0 ancora una volta esperti da tutto il mondo alla ricerca di nuove ed entusiasmanti idee, progetti e approfondimenti del settore.&#8221; font_container=&#8221;tag:h2|font_size:18|text_align:left|color:%23000000|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><a href=\"https:\/\/adventure.walltopia.com\/\">Walltopia Adventure<\/a> sar\u00e0 per la terza volta un espositore e siamo molto ansiosi di mostrare i nostri ultimi prodotti e innovazioni. Unisciti a noi per scoprire perch\u00e9 il <a href=\"https:\/\/adventure.walltopia.com\/products\/rollglider\/\">Rollglider<\/a> \u00e8 la tendenza pi\u00f9 in voga nell&#8217;industria del divertimento e come le attrazioni di intrattenimento attivo possono trasformare il tuo centro di intrattenimento in un&#8217;arena di avventura completamente nuova e attirare pi\u00f9 clienti. <\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Scopri tutto quello che c&#8217;\u00e8 da sapere sui nostri prodotti <a href=\"https:\/\/adventure.walltopia.com\/products\/rollglider\/\">Rollglider<\/a>, <a href=\"https:\/\/adventure.walltopia.com\/products\/fun-walls\/\">Fun Walls<\/a> e <a href=\"https:\/\/adventure.walltopia.com\/products\/ropes-course\/\">Ropes Course<\/a> allo stand L17. <a href=\"https:\/\/adventure.walltopia.com\/products\/walltopia-caves\/\">Walltopia Caves<\/a> ha ampliato in modo significativo il suo portfolio nell&#8217;ultimo anno e presenter\u00e0 i suoi prodotti in uno stand separato, il K19. Se sei alla ricerca di aree gioco per bambini, sistemi di speleologia, soluzioni di tematizzazione, rocce artificiali o progetti realistici, il team di Walltopia Caves ti dar\u00e0 delle idee fantastiche e ti mostrer\u00e0 come il tuo <a href=\"https:\/\/adventure.walltopia.com\/industries\/family-entertainment-centers\/\">FEC<\/a>, il tuo parco a tema, il tuo museo, il tuo acquario o un&#8217;altra struttura di divertimento possono diventare ancora pi\u00f9 interattivi e avventurosi. <\/p>\n[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_gallery interval=&#8221;3&#8243; images=&#8221;21789,21795&#8243; img_size=&#8221;full&#8221; css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1624001482418{padding-top: 2% !important;}&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Dove:<\/strong> Dubai World Trade Center, Hall Zabeel 5<br \/>\n<strong>Quando:<\/strong> 19 &#8211; 21 aprile<\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Contattaci a <a href=\"mailto:sales@walltopia.com\">sales@walltopia.com<\/a> per fissare in anticipo un incontro con il nostro team.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_custom_heading text=&#8221;Il Dubai Entertainment Amusement and Leisure Show, il pi\u00f9 grande evento per le attrazioni e il divertimento nella regione&#8230;","protected":false},"author":10,"featured_media":21783,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[908],"tags":[1777,1781,1779,1775,1021,1020],"class_list":["post-180628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sala-stampa","tag-avventura-a-walltopia","tag-deal","tag-grotte-di-walltopia","tag-pareti-divertenti","tag-percorso-a-corde","tag-rollglider-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Walltopia Adventure e Walltopia Caves esporranno al DEAL 2016 | Walltopia<\/title>\n<meta name=\"description\" content=\"Unisciti a noi nel pi\u00f9 grande evento dedicato alle attrazioni e al divertimento nella regione MEA. Siamo ansiosi di mostrare i nostri ultimi prodotti e innovazioni.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/it\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Walltopia Adventure e Walltopia Caves esporranno al DEAL 2016\" \/>\n<meta property=\"og:description\" content=\"Unisciti a noi nel pi\u00f9 grande evento dedicato alle attrazioni e al divertimento nella regione MEA. Siamo ansiosi di mostrare i nostri ultimi prodotti e innovazioni.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/it\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-18T07:32:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T13:51:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090542\/Walltopia-DEAL-2016.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"the_id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\\\/\"},\"author\":{\"name\":\"the_id\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\"},\"headline\":\"Walltopia Adventure e Walltopia Caves esporranno al DEAL 2016\",\"datePublished\":\"2021-06-18T07:32:06+00:00\",\"dateModified\":\"2026-01-15T13:51:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\\\/\"},\"wordCount\":336,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090542\\\/Walltopia-DEAL-2016.jpg\",\"keywords\":[\"Avventura a Walltopia\",\"DEAL\",\"grotte di walltopia\",\"Pareti divertenti\",\"percorso a corde\",\"Rollglider\"],\"articleSection\":[\"Sala stampa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\\\/\",\"name\":\"Walltopia Adventure e Walltopia Caves esporranno al DEAL 2016 | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090542\\\/Walltopia-DEAL-2016.jpg\",\"datePublished\":\"2021-06-18T07:32:06+00:00\",\"dateModified\":\"2026-01-15T13:51:56+00:00\",\"description\":\"Unisciti a noi nel pi\u00f9 grande evento dedicato alle attrazioni e al divertimento nella regione MEA. Siamo ansiosi di mostrare i nostri ultimi prodotti e innovazioni.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090542\\\/Walltopia-DEAL-2016.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090542\\\/Walltopia-DEAL-2016.jpg\",\"width\":900,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/casa-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Walltopia Adventure e Walltopia Caves esporranno al DEAL 2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\",\"name\":\"the_id\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Walltopia Adventure e Walltopia Caves esporranno al DEAL 2016 | Walltopia","description":"Unisciti a noi nel pi\u00f9 grande evento dedicato alle attrazioni e al divertimento nella regione MEA. Siamo ansiosi di mostrare i nostri ultimi prodotti e innovazioni.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/it\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\/","og_locale":"it_IT","og_type":"article","og_title":"Walltopia Adventure e Walltopia Caves esporranno al DEAL 2016","og_description":"Unisciti a noi nel pi\u00f9 grande evento dedicato alle attrazioni e al divertimento nella regione MEA. Siamo ansiosi di mostrare i nostri ultimi prodotti e innovazioni.","og_url":"https:\/\/walltopia.com\/it\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2021-06-18T07:32:06+00:00","article_modified_time":"2026-01-15T13:51:56+00:00","og_image":[{"width":900,"height":478,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090542\/Walltopia-DEAL-2016.jpg","type":"image\/jpeg"}],"author":"the_id","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/it\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\/"},"author":{"name":"the_id","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff"},"headline":"Walltopia Adventure e Walltopia Caves esporranno al DEAL 2016","datePublished":"2021-06-18T07:32:06+00:00","dateModified":"2026-01-15T13:51:56+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/it\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\/"},"wordCount":336,"publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/it\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090542\/Walltopia-DEAL-2016.jpg","keywords":["Avventura a Walltopia","DEAL","grotte di walltopia","Pareti divertenti","percorso a corde","Rollglider"],"articleSection":["Sala stampa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/it\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\/","url":"https:\/\/walltopia.com\/it\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\/","name":"Walltopia Adventure e Walltopia Caves esporranno al DEAL 2016 | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/it\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/it\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090542\/Walltopia-DEAL-2016.jpg","datePublished":"2021-06-18T07:32:06+00:00","dateModified":"2026-01-15T13:51:56+00:00","description":"Unisciti a noi nel pi\u00f9 grande evento dedicato alle attrazioni e al divertimento nella regione MEA. Siamo ansiosi di mostrare i nostri ultimi prodotti e innovazioni.","breadcrumb":{"@id":"https:\/\/walltopia.com\/it\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/it\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090542\/Walltopia-DEAL-2016.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090542\/Walltopia-DEAL-2016.jpg","width":900,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/it\/walltopia-adventure-e-walltopia-caves-esporranno-al-deal-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/it\/casa-it\/"},{"@type":"ListItem","position":2,"name":"Walltopia Adventure e Walltopia Caves esporranno al DEAL 2016"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/it\/#website","url":"https:\/\/walltopia.com\/it\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/it\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff","name":"the_id"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/180628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/comments?post=180628"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/180628\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media\/21783"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media?parent=180628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/categories?post=180628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/tags?post=180628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}