{"id":180679,"date":"2021-06-18T10:01:59","date_gmt":"2021-06-18T07:01:59","guid":{"rendered":"https:\/\/walltopia.com\/partecipa-allavventura-di-walltopia-al-mipim\/"},"modified":"2026-01-15T16:52:04","modified_gmt":"2026-01-15T13:52:04","slug":"partecipa-allavventura-di-walltopia-al-mipim","status":"publish","type":"post","link":"https:\/\/walltopia.com\/it\/partecipa-allavventura-di-walltopia-al-mipim\/","title":{"rendered":"Partecipa all&#8217;avventura di Walltopia al MIPIM"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Uno dei maggiori eventi per i professionisti del settore immobiliare, il <a href=\"http:\/\/www.mipim.com\">MIPIM Expo<\/a>, si terr\u00e0 a Cannes, in Francia, dal 15 al 18 marzo e <a href=\"https:\/\/adventure.walltopia.com\/\">Walltopia Adventure<\/a> sar\u00e0 tra le aziende espositrici. Unisciti a noi per scoprire perch\u00e9 la nostra ultima innovazione nel campo dell&#8217;avventura &#8211; il <a href=\"https:\/\/adventure.walltopia.com\/products\/rollglider\/\">Rollglider<\/a> &#8211; \u00e8 la nuova tendenza nel settore delle attrazioni. Salva la data: il <strong>16 marzo alle ore 15:00<\/strong>, presso il nostro stand, terremo una presentazione speciale dal titolo &#8220;Bring Active Entertainment to Your Location&#8221;.  <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Contatta <a href=\"mailto:sales@walltopia.com\">sales@walltopia.com<\/a> per fissare un incontro in anticipo.<\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Dove:<\/strong> Palais des Festivals, Cannes, Francia<br \/>\n<strong>Numero dello stand:<\/strong> P-1.G25<br \/>\n<strong>Quando:<\/strong> 15 &#8211; 18 marzo<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_column_text css_animation=&#8221;fadeInUp&#8221;] Uno dei maggiori eventi per i professionisti del settore immobiliare, il MIPIM Expo, si terr\u00e0 a Cannes, in&#8230;","protected":false},"author":10,"featured_media":21777,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[908],"tags":[1789],"class_list":["post-180679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sala-stampa","tag-mipim"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Partecipa all&#039;avventura di Walltopia al MIPIM | Walltopia<\/title>\n<meta name=\"description\" content=\"Unisciti a noi per scoprire perch\u00e9 la nostra ultima innovazione nel campo dell&#039;avventura - il Rollglider - \u00e8 la nuova tendenza nel settore delle attrazioni.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/it\/partecipa-allavventura-di-walltopia-al-mipim\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Partecipa all&#039;avventura di Walltopia al MIPIM\" \/>\n<meta property=\"og:description\" content=\"Unisciti a noi per scoprire perch\u00e9 la nostra ultima innovazione nel campo dell&#039;avventura - il Rollglider - \u00e8 la nuova tendenza nel settore delle attrazioni.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/it\/partecipa-allavventura-di-walltopia-al-mipim\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-18T07:01:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T13:52:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090544\/mipim.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"the_id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/partecipa-allavventura-di-walltopia-al-mipim\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/partecipa-allavventura-di-walltopia-al-mipim\\\/\"},\"author\":{\"name\":\"the_id\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\"},\"headline\":\"Partecipa all&#8217;avventura di Walltopia al MIPIM\",\"datePublished\":\"2021-06-18T07:01:59+00:00\",\"dateModified\":\"2026-01-15T13:52:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/partecipa-allavventura-di-walltopia-al-mipim\\\/\"},\"wordCount\":126,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/partecipa-allavventura-di-walltopia-al-mipim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090544\\\/mipim.jpg\",\"keywords\":[\"MIPIM\"],\"articleSection\":[\"Sala stampa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/partecipa-allavventura-di-walltopia-al-mipim\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/partecipa-allavventura-di-walltopia-al-mipim\\\/\",\"name\":\"Partecipa all'avventura di Walltopia al MIPIM | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/partecipa-allavventura-di-walltopia-al-mipim\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/partecipa-allavventura-di-walltopia-al-mipim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090544\\\/mipim.jpg\",\"datePublished\":\"2021-06-18T07:01:59+00:00\",\"dateModified\":\"2026-01-15T13:52:04+00:00\",\"description\":\"Unisciti a noi per scoprire perch\u00e9 la nostra ultima innovazione nel campo dell'avventura - il Rollglider - \u00e8 la nuova tendenza nel settore delle attrazioni.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/partecipa-allavventura-di-walltopia-al-mipim\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/partecipa-allavventura-di-walltopia-al-mipim\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/partecipa-allavventura-di-walltopia-al-mipim\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090544\\\/mipim.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090544\\\/mipim.jpg\",\"width\":900,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/partecipa-allavventura-di-walltopia-al-mipim\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/casa-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Partecipa all&#8217;avventura di Walltopia al MIPIM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\",\"name\":\"the_id\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Partecipa all'avventura di Walltopia al MIPIM | Walltopia","description":"Unisciti a noi per scoprire perch\u00e9 la nostra ultima innovazione nel campo dell'avventura - il Rollglider - \u00e8 la nuova tendenza nel settore delle attrazioni.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/it\/partecipa-allavventura-di-walltopia-al-mipim\/","og_locale":"it_IT","og_type":"article","og_title":"Partecipa all'avventura di Walltopia al MIPIM","og_description":"Unisciti a noi per scoprire perch\u00e9 la nostra ultima innovazione nel campo dell'avventura - il Rollglider - \u00e8 la nuova tendenza nel settore delle attrazioni.","og_url":"https:\/\/walltopia.com\/it\/partecipa-allavventura-di-walltopia-al-mipim\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2021-06-18T07:01:59+00:00","article_modified_time":"2026-01-15T13:52:04+00:00","og_image":[{"width":900,"height":478,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090544\/mipim.jpg","type":"image\/jpeg"}],"author":"the_id","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/it\/partecipa-allavventura-di-walltopia-al-mipim\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/partecipa-allavventura-di-walltopia-al-mipim\/"},"author":{"name":"the_id","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff"},"headline":"Partecipa all&#8217;avventura di Walltopia al MIPIM","datePublished":"2021-06-18T07:01:59+00:00","dateModified":"2026-01-15T13:52:04+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/it\/partecipa-allavventura-di-walltopia-al-mipim\/"},"wordCount":126,"publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/it\/partecipa-allavventura-di-walltopia-al-mipim\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090544\/mipim.jpg","keywords":["MIPIM"],"articleSection":["Sala stampa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/it\/partecipa-allavventura-di-walltopia-al-mipim\/","url":"https:\/\/walltopia.com\/it\/partecipa-allavventura-di-walltopia-al-mipim\/","name":"Partecipa all'avventura di Walltopia al MIPIM | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/it\/partecipa-allavventura-di-walltopia-al-mipim\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/it\/partecipa-allavventura-di-walltopia-al-mipim\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090544\/mipim.jpg","datePublished":"2021-06-18T07:01:59+00:00","dateModified":"2026-01-15T13:52:04+00:00","description":"Unisciti a noi per scoprire perch\u00e9 la nostra ultima innovazione nel campo dell'avventura - il Rollglider - \u00e8 la nuova tendenza nel settore delle attrazioni.","breadcrumb":{"@id":"https:\/\/walltopia.com\/it\/partecipa-allavventura-di-walltopia-al-mipim\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/it\/partecipa-allavventura-di-walltopia-al-mipim\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/partecipa-allavventura-di-walltopia-al-mipim\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090544\/mipim.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090544\/mipim.jpg","width":900,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/it\/partecipa-allavventura-di-walltopia-al-mipim\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/it\/casa-it\/"},{"@type":"ListItem","position":2,"name":"Partecipa all&#8217;avventura di Walltopia al MIPIM"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/it\/#website","url":"https:\/\/walltopia.com\/it\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/it\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff","name":"the_id"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/180679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/comments?post=180679"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/180679\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media\/21777"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media?parent=180679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/categories?post=180679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/tags?post=180679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}