{"id":183294,"date":"2021-06-21T10:30:00","date_gmt":"2021-06-21T07:30:00","guid":{"rendered":"https:\/\/walltopia.com\/junction-climbing-dal-sogno-alla-realta\/"},"modified":"2026-01-15T17:00:00","modified_gmt":"2026-01-15T14:00:00","slug":"junction-climbing-dal-sogno-alla-realta","status":"publish","type":"post","link":"https:\/\/walltopia.com\/it\/junction-climbing-dal-sogno-alla-realta\/","title":{"rendered":"Junction Climbing: dal sogno alla realt\u00e0"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_custom_heading text=&#8221;Un&apos;idea. Un&apos;idea che si trasforma in un sogno. E un sogno che si trasforma in un progetto. Un progetto con molte domande, variabili e notti insonni.   &#8221; font_container=&#8221;tag:h2|font_size:18|text_align:left|color:%23000000|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Questo \u00e8 il punto di partenza di molte delle palestre di arrampicata che conosciamo. A volte non c&#8217;\u00e8 una buona palestra di arrampicata nella zona, a volte ce n&#8217;\u00e8 una ma non \u00e8 sufficiente per servire la comunit\u00e0, a volte pensi di poterla migliorare. Oppure credi che il tuo lavoro da 9-5 ti sia servito bene fino ad ora. \u00c8 arrivato il momento di iniziare a coltivare la tua idea, trasformarla in un sogno e poi in un progetto.   <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Ispirandoci alla storia che si cela dietro ogni palestra di arrampicata e alle lezioni che ci sono state impartite lungo il percorso, inizieremo una serie di brevi interviste con i proprietari delle palestre per esplorare la forza che li ha spinti a creare e gestire una palestra di arrampicata.<\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Oggi ti presentiamo John Kudelka di <a href=\"https:\/\/www.junctionclimbing.com\/\">Junction Climbing<\/a>. Una palestra a cui ci sentiamo particolarmente vicini perch\u00e9 abbiamo assistito alle numerose lotte e battaglie che il team Junction ha dovuto combattere per realizzarsi. Hanno dimostrato che se credi fermamente in qualcosa e lavori duramente per ottenerla, tutto il resto si risolve da solo.  <\/p>\n[\/vc_column_text][vc_custom_heading text=&#8221;WT: Ti ricordi come ti \u00e8 venuta l&apos;idea di possedere una palestra di arrampicata? Cosa ti ha spinto a farlo? &#8221; font_container=&#8221;tag:h2|font_size:18|text_align:left|color:%23ed2020|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_column_text css_animation=&#8221;fadeInUp&#8221; css=&#8221;&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>John:<\/strong> <em>Ho lavorato per diversi imprenditori e ho visto il successo che si poteva ottenere possedendo un&#8217;azienda invece di lavorare per un&#8217;altra. Quello che volevo era un&#8217;attivit\u00e0 che fosse un fulcro di comunit\u00e0 e di attivit\u00e0, che contribuisse positivamente al mondo invece di sottrarlo. Un&#8217;attivit\u00e0 che evitasse le trappole della gestione dell&#8217;inventario, del traffico stagionale o dell&#8217;attesa dei pagamenti. Avevo lavorato nell&#8217;industria dell&#8217;outdoor e avevo visto l&#8217;arrampicata passare dalla marginalit\u00e0 al mainstream. La nostra citt\u00e0 non aveva una palestra di arrampicata mentre altre pi\u00f9 piccole ce l&#8217;avevano. Sapevo che se fossi riuscito a realizzarla, avrebbe funzionato. Seduto in un ristorante preferito con mia moglie, le proposi l&#8217;idea e lei fu subito d&#8217;accordo che si trattava di un&#8217;ottima strada.      <\/em><\/p>\n[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_gallery interval=&#8221;3&#8243; images=&#8221;22167,22119,22125&#8243; img_size=&#8221;full&#8221; css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1624259504594{padding-top: 2% !important;}&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_custom_heading text=&#8221;WT: Qual \u00e8 stata la sfida pi\u00f9 difficile lungo il percorso che ha portato dal sogno alla realt\u00e0?&#8221; font_container=&#8221;tag:h2|font_size:18|text_align:left|color:%23ed2020|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>John:<\/strong> <em>La cosa pi\u00f9 difficile \u00e8 stata cercare di lavorare su tutti i tasselli senza sapere quali si sarebbero svolti e in quale ordine? Facciamo un&#8217;offerta per un edificio senza sapere se possiamo ottenere la riqualificazione urbanistica? Quanto chiediamo alla banca quando non conosciamo ancora il nostro progetto finale? Come assumiamo il personale senza sapere esattamente quando inizier\u00e0 a lavorare? Abbiamo corso dei grossi rischi e la maggior parte di essi ha dato i suoi frutti.    <\/em><\/p>\n[\/vc_column_text][vc_custom_heading text=&#8221;WT: Com&apos;\u00e8 stata la notte prima dell&apos;apertura ufficiale? E poi, come \u00e8 stato il grande giorno successivo? &#8221; font_container=&#8221;tag:h2|font_size:18|text_align:left|color:%23ed2020|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>John:<\/strong> <em>La notte precedente \u00e8 stata frenetica! Stavamo ancora installando i pavimenti e sistemando i supporti! Il giorno successivo \u00e8 stato un&#8217;esplosione. Salutando, assicurando e accompagnando continuamente le persone. Quando tutto fu finito, tutto ci\u00f2 che potevamo vedere era un futuro luminoso, il lavoro e lo stress della costruzione erano finiti.    <\/em><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;22131&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1624259986574{padding-top: 2% !important;}&#8221;][vc_single_image image=&#8221;22143&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1624259977712{padding-top: 4% !important;}&#8221;][vc_single_image image=&#8221;22149&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1624260275381{padding-top: 4% !important;}&#8221;][vc_single_image image=&#8221;22137&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1624260216340{padding-top: 4% !important;}&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_custom_heading text=&#8221;WT: Guardando al passato, cambieresti qualcosa?&#8221; font_container=&#8221;tag:h2|font_size:18|text_align:left|color:%23ed2020|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>John:<\/strong><em>  A volte si parlava di piccoli dettagli e poi si sorvolava mentre ci si concentrava su cose che sembravano pi\u00f9 importanti. Poi, quando arriva il momento, ci chiediamo perch\u00e9 non abbiamo fatto quella cosa di cui avevamo parlato una volta. Inoltre, cerca un contabile in anticipo.  <\/em><\/p>\n[\/vc_column_text][vc_custom_heading text=&#8221;WT: Hai qualche consiglio da dare a chi sta pensando di seguire il tuo percorso?&#8221; font_container=&#8221;tag:h2|font_size:18|text_align:left|color:%23ed2020|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>John:<\/strong> <em>Continua a lavorare. Troppo spesso ci\u00f2 che impedisce la realizzazione di una palestra \u00e8 che le persone si arrendono, non che gli ostacoli non possano essere superati. Inoltre, la palestra che sogni potrebbe essere diversa da quella che puoi realizzare: vincoli edilizi, finanziamenti, zone, tutto ci\u00f2 potrebbe costringere a un risultato diverso. Possedere una palestra qualsiasi \u00e8 meglio che non possedere nessuna palestra e pu\u00f2 essere un trampolino di lancio per cose pi\u00f9 grandi. Infine, procurati per tempo un contabile. Sapere dove hai speso ogni dollaro pu\u00f2 essere fondamentale in futuro.   <\/em><\/p>\n[\/vc_column_text][vc_custom_heading text=&#8221;WT: In tre parole, cosa significa per te possedere e gestire una palestra di arrampicata?&#8221; font_container=&#8221;tag:h2|font_size:18|text_align:left|color:%23ed2020|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>John:<\/strong> <em>Il miglior lavoro di sempre.<\/em><\/p>\n[\/vc_column_text][vc_column_text css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1624260345227{padding-top: 2% !important;}&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">John Kudelka, Junction Climbing a Londra, Canada<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1624260564686{padding-top: 2% !important;}&#8221;][vc_column css_animation=&#8221;fadeInUp&#8221; width=&#8221;1\/3&#8243;]<div class=\"link-button-container block width-100  text-align-left\"><a class=\"wt-link \" href=\"https:\/\/www.facebook.com\/JunctionClimbingCentre\" target=\"_blank\">Junction Climbing Facebook<\/a><\/div>[\/vc_column][vc_column css_animation=&#8221;fadeInUp&#8221; width=&#8221;1\/3&#8243;]<div class=\"link-button-container block width-100  text-align-left\"><a class=\"wt-link \" href=\"https:\/\/www.instagram.com\/climbjunction\/\" target=\"_blank\">Junction Climbing Instagram<\/a><\/div>[\/vc_column][vc_column css_animation=&#8221;fadeInUp&#8221; width=&#8221;1\/3&#8243;]<div class=\"link-button-container block width-100  text-align-left\"><a class=\"wt-link \" href=\"https:\/\/www.junctionclimbing.com\/\" target=\"_blank\">Junction Climbing Website<\/a><\/div>[\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_custom_heading text=&#8221;Un&apos;idea. Un&apos;idea che si trasforma in un sogno. E un sogno che si trasforma in un progetto. Un progetto&#8230;","protected":false},"author":10,"featured_media":22161,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[909,908],"tags":[2251,2253],"class_list":["post-183294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arrampicata","category-sala-stampa","tag-intervista","tag-palestra-di-arrampicata"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Junction Climbing: dal sogno alla realt\u00e0 | Walltopia<\/title>\n<meta name=\"description\" content=\"Incontra John Kudelka di Junction Climbing che condivide la sua storia da tutte le lotte all&#039;apertura di successo della sua palestra di arrampicata.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/it\/junction-climbing-dal-sogno-alla-realta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Junction Climbing: dal sogno alla realt\u00e0\" \/>\n<meta property=\"og:description\" content=\"Incontra John Kudelka di Junction Climbing che condivide la sua storia da tutte le lotte all&#039;apertura di successo della sua palestra di arrampicata.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/it\/junction-climbing-dal-sogno-alla-realta\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-21T07:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085719\/25567144146_888c28eb7a_o-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"801\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"the_id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/junction-climbing-dal-sogno-alla-realta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/junction-climbing-dal-sogno-alla-realta\\\/\"},\"author\":{\"name\":\"the_id\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\"},\"headline\":\"Junction Climbing: dal sogno alla realt\u00e0\",\"datePublished\":\"2021-06-21T07:30:00+00:00\",\"dateModified\":\"2026-01-15T14:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/junction-climbing-dal-sogno-alla-realta\\\/\"},\"wordCount\":1214,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/junction-climbing-dal-sogno-alla-realta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085719\\\/25567144146_888c28eb7a_o-1.jpg\",\"keywords\":[\"intervista\",\"palestra di arrampicata\"],\"articleSection\":[\"Arrampicata\",\"Sala stampa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/junction-climbing-dal-sogno-alla-realta\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/junction-climbing-dal-sogno-alla-realta\\\/\",\"name\":\"Junction Climbing: dal sogno alla realt\u00e0 | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/junction-climbing-dal-sogno-alla-realta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/junction-climbing-dal-sogno-alla-realta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085719\\\/25567144146_888c28eb7a_o-1.jpg\",\"datePublished\":\"2021-06-21T07:30:00+00:00\",\"dateModified\":\"2026-01-15T14:00:00+00:00\",\"description\":\"Incontra John Kudelka di Junction Climbing che condivide la sua storia da tutte le lotte all'apertura di successo della sua palestra di arrampicata.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/junction-climbing-dal-sogno-alla-realta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/junction-climbing-dal-sogno-alla-realta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/junction-climbing-dal-sogno-alla-realta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085719\\\/25567144146_888c28eb7a_o-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085719\\\/25567144146_888c28eb7a_o-1.jpg\",\"width\":1200,\"height\":801},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/junction-climbing-dal-sogno-alla-realta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/casa-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Junction Climbing: dal sogno alla realt\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\",\"name\":\"the_id\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Junction Climbing: dal sogno alla realt\u00e0 | Walltopia","description":"Incontra John Kudelka di Junction Climbing che condivide la sua storia da tutte le lotte all'apertura di successo della sua palestra di arrampicata.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/it\/junction-climbing-dal-sogno-alla-realta\/","og_locale":"it_IT","og_type":"article","og_title":"Junction Climbing: dal sogno alla realt\u00e0","og_description":"Incontra John Kudelka di Junction Climbing che condivide la sua storia da tutte le lotte all'apertura di successo della sua palestra di arrampicata.","og_url":"https:\/\/walltopia.com\/it\/junction-climbing-dal-sogno-alla-realta\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2021-06-21T07:30:00+00:00","article_modified_time":"2026-01-15T14:00:00+00:00","og_image":[{"width":1200,"height":801,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085719\/25567144146_888c28eb7a_o-1.jpg","type":"image\/jpeg"}],"author":"the_id","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/it\/junction-climbing-dal-sogno-alla-realta\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/junction-climbing-dal-sogno-alla-realta\/"},"author":{"name":"the_id","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff"},"headline":"Junction Climbing: dal sogno alla realt\u00e0","datePublished":"2021-06-21T07:30:00+00:00","dateModified":"2026-01-15T14:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/it\/junction-climbing-dal-sogno-alla-realta\/"},"wordCount":1214,"publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/it\/junction-climbing-dal-sogno-alla-realta\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085719\/25567144146_888c28eb7a_o-1.jpg","keywords":["intervista","palestra di arrampicata"],"articleSection":["Arrampicata","Sala stampa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/it\/junction-climbing-dal-sogno-alla-realta\/","url":"https:\/\/walltopia.com\/it\/junction-climbing-dal-sogno-alla-realta\/","name":"Junction Climbing: dal sogno alla realt\u00e0 | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/it\/junction-climbing-dal-sogno-alla-realta\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/it\/junction-climbing-dal-sogno-alla-realta\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085719\/25567144146_888c28eb7a_o-1.jpg","datePublished":"2021-06-21T07:30:00+00:00","dateModified":"2026-01-15T14:00:00+00:00","description":"Incontra John Kudelka di Junction Climbing che condivide la sua storia da tutte le lotte all'apertura di successo della sua palestra di arrampicata.","breadcrumb":{"@id":"https:\/\/walltopia.com\/it\/junction-climbing-dal-sogno-alla-realta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/it\/junction-climbing-dal-sogno-alla-realta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/junction-climbing-dal-sogno-alla-realta\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085719\/25567144146_888c28eb7a_o-1.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085719\/25567144146_888c28eb7a_o-1.jpg","width":1200,"height":801},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/it\/junction-climbing-dal-sogno-alla-realta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/it\/casa-it\/"},{"@type":"ListItem","position":2,"name":"Junction Climbing: dal sogno alla realt\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/it\/#website","url":"https:\/\/walltopia.com\/it\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/it\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff","name":"the_id"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/183294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/comments?post=183294"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/183294\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media\/22161"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media?parent=183294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/categories?post=183294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/tags?post=183294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}