{"id":183563,"date":"2021-06-18T17:01:58","date_gmt":"2021-06-18T14:01:58","guid":{"rendered":"https:\/\/walltopia.com\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\/"},"modified":"2026-01-15T17:00:41","modified_gmt":"2026-01-15T14:00:41","slug":"unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa","status":"publish","type":"post","link":"https:\/\/walltopia.com\/it\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\/","title":{"rendered":"Unisciti a Walltopia Adventure per le conferenze ACCT e EEE negli USA"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_custom_heading text=&#8221;La conferenza annuale dell&apos;Association of Challenge Course Technology (ACCT) si terr\u00e0 a Savannah, GA e noi, in qualit\u00e0 di membri dell&apos;ACCT, saremo sicuramente presenti.&#8221; font_container=&#8221;tag:h2|font_size:18|text_align:left|color:%23000000|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221; link=&#8221;url:https%3A%2F%2Facctconference.com%2F|title:ACCT|target:_blank|&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Vieni a trovarci al <strong>Westin Savannah Harbor Golf Resort &amp; Spa<\/strong> dal<strong> 2<\/strong> al <strong>4<\/strong><strong> febbraio<\/strong> presso gli stand <strong>607 e 707<\/strong>. Cerca il nostro <a href=\"https:\/\/adventure.walltopia.com\/products\/rollglider\/\">Rollglider<\/a>, che \u00e8 sicuramente la prossima grande novit\u00e0 nel settore dei divertimenti, e scopri di pi\u00f9 su <a href=\"https:\/\/adventure.walltopia.com\/products\/ropes-course\/\">Ropes Course<\/a>, <a href=\"https:\/\/adventure.walltopia.com\/products\/ninja-course\/\">Ninja Course<\/a>, <a href=\"https:\/\/adventure.walltopia.com\/products\/walltopia-caves\/\">Walltopia Caves<\/a> e <a href=\"https:\/\/adventure.walltopia.com\/products\/fun-walls\/\">Fun Walls<\/a>. <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Il nostro tour negli Stati Uniti prosegue a Santa Monica, in California, dove, insieme ai maggiori esperti americani e internazionali dell&#8217;industria del divertimento, parleremo del futuro dell&#8217;intrattenimento alla <a href=\"http:\/\/www.cvent.com\/events\/2017-entertainment-experience-evolution\/archived-aea074d7522c40adad273d5ed8a84f32.aspx\">Entertainment Experience Evolution Conference (EEE)<\/a>. Il nostro CEO, Ivaylo Penchev, terr\u00e0 una tavola rotonda l&#8217;<strong>8 febbraio alle 7:30 del mattino<\/strong> presso la sala espositori del <strong>Fairmont Miramar Hotel<\/strong>. Unisciti a noi per scoprire come i prodotti di intrattenimento attivo possono aiutare a trasformare i normali centri commerciali in centri di destinazione. I nostri delegati saranno presenti anche allo stand 8 durante la conferenza, sia il 7 che l&#8217;8 febbraio.   <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Contattaci a <a href=\"mailto:adventure@walltopia.com\">adventure@walltopia.com<\/a> per fissare un incontro in anticipo per uno dei due eventi.<\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>  Ci vediamo l\u00ec!<\/strong><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_custom_heading text=&#8221;La conferenza annuale dell&apos;Association of Challenge Course Technology (ACCT) si terr\u00e0 a Savannah, GA e noi, in qualit\u00e0 di&#8230;","protected":false},"author":10,"featured_media":22023,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[908],"tags":[1858,2281],"class_list":["post-183563","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sala-stampa","tag-acct","tag-eee"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Unisciti a Walltopia Adventure per le conferenze ACCT e EEE negli USA | Walltopia<\/title>\n<meta name=\"description\" content=\"Unisciti a noi alla Conferenza ACCT di Savannah, GA, per scoprire i corsi pi\u00f9 impegnativi. Leggi l&#039;articolo per maggiori dettagli sull&#039;evento.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/it\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unisciti a Walltopia Adventure per le conferenze ACCT e EEE negli USA\" \/>\n<meta property=\"og:description\" content=\"Unisciti a noi alla Conferenza ACCT di Savannah, GA, per scoprire i corsi pi\u00f9 impegnativi. Leggi l&#039;articolo per maggiori dettagli sull&#039;evento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/it\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-18T14:01:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:00:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085905\/ACCT-EEE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"the_id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\\\/\"},\"author\":{\"name\":\"the_id\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\"},\"headline\":\"Unisciti a Walltopia Adventure per le conferenze ACCT e EEE negli USA\",\"datePublished\":\"2021-06-18T14:01:58+00:00\",\"dateModified\":\"2026-01-15T14:00:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\\\/\"},\"wordCount\":253,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085905\\\/ACCT-EEE.jpg\",\"keywords\":[\"ACCT\",\"EEE\"],\"articleSection\":[\"Sala stampa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\\\/\",\"name\":\"Unisciti a Walltopia Adventure per le conferenze ACCT e EEE negli USA | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085905\\\/ACCT-EEE.jpg\",\"datePublished\":\"2021-06-18T14:01:58+00:00\",\"dateModified\":\"2026-01-15T14:00:41+00:00\",\"description\":\"Unisciti a noi alla Conferenza ACCT di Savannah, GA, per scoprire i corsi pi\u00f9 impegnativi. Leggi l'articolo per maggiori dettagli sull'evento.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085905\\\/ACCT-EEE.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085905\\\/ACCT-EEE.jpg\",\"width\":900,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/casa-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unisciti a Walltopia Adventure per le conferenze ACCT e EEE negli USA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\",\"name\":\"the_id\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Unisciti a Walltopia Adventure per le conferenze ACCT e EEE negli USA | Walltopia","description":"Unisciti a noi alla Conferenza ACCT di Savannah, GA, per scoprire i corsi pi\u00f9 impegnativi. Leggi l'articolo per maggiori dettagli sull'evento.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/it\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\/","og_locale":"it_IT","og_type":"article","og_title":"Unisciti a Walltopia Adventure per le conferenze ACCT e EEE negli USA","og_description":"Unisciti a noi alla Conferenza ACCT di Savannah, GA, per scoprire i corsi pi\u00f9 impegnativi. Leggi l'articolo per maggiori dettagli sull'evento.","og_url":"https:\/\/walltopia.com\/it\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2021-06-18T14:01:58+00:00","article_modified_time":"2026-01-15T14:00:41+00:00","og_image":[{"width":900,"height":478,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085905\/ACCT-EEE.jpg","type":"image\/jpeg"}],"author":"the_id","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/it\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\/"},"author":{"name":"the_id","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff"},"headline":"Unisciti a Walltopia Adventure per le conferenze ACCT e EEE negli USA","datePublished":"2021-06-18T14:01:58+00:00","dateModified":"2026-01-15T14:00:41+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/it\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\/"},"wordCount":253,"publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/it\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085905\/ACCT-EEE.jpg","keywords":["ACCT","EEE"],"articleSection":["Sala stampa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/it\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\/","url":"https:\/\/walltopia.com\/it\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\/","name":"Unisciti a Walltopia Adventure per le conferenze ACCT e EEE negli USA | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/it\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/it\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085905\/ACCT-EEE.jpg","datePublished":"2021-06-18T14:01:58+00:00","dateModified":"2026-01-15T14:00:41+00:00","description":"Unisciti a noi alla Conferenza ACCT di Savannah, GA, per scoprire i corsi pi\u00f9 impegnativi. Leggi l'articolo per maggiori dettagli sull'evento.","breadcrumb":{"@id":"https:\/\/walltopia.com\/it\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/it\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085905\/ACCT-EEE.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085905\/ACCT-EEE.jpg","width":900,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/it\/unisciti-a-walltopia-adventure-per-le-conferenze-acct-e-eee-negli-usa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/it\/casa-it\/"},{"@type":"ListItem","position":2,"name":"Unisciti a Walltopia Adventure per le conferenze ACCT e EEE negli USA"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/it\/#website","url":"https:\/\/walltopia.com\/it\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/it\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff","name":"the_id"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/183563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/comments?post=183563"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/183563\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media\/22023"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media?parent=183563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/categories?post=183563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/tags?post=183563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}