{"id":185866,"date":"2021-06-22T16:51:26","date_gmt":"2021-06-22T13:51:26","guid":{"rendered":"https:\/\/walltopia.com\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\/"},"modified":"2026-01-15T17:30:39","modified_gmt":"2026-01-15T14:30:39","slug":"rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione","status":"publish","type":"post","link":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\/","title":{"rendered":"Rivestimento Walltopia duplex: la nostra soluzione contro la corrosione"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_custom_heading text=&#8221;Forse non arriva sempre con un botto immediato, come fanno i terremoti, i tornado e gli uragani, ma questo silenzioso e lento distruttore costa all&apos;economia degli Stati Uniti pi\u00f9 di tutti gli altri disastri naturali messi insieme, per un totale di 437 miliardi di dollari all&apos;anno, pari al 3% del PIL degli Stati Uniti.&#8221; font_container=&#8221;tag:h2|font_size:18|text_align:left|color:%23000000|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221; css=&#8221;&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Hai gi\u00e0 indovinato? No? Ok, ecco un altro indizio: questa minaccia dilagante trasforma una tonnellata di acciaio in ruggine ogni 90 secondi, in tutto il mondo. S\u00ec, esattamente! \u00c8 la corrosione!    <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">La corrosione compromette la vita utile dei nostri beni, aumenta i costi di riparazione e manutenzione. Inoltre, fa crollare edifici e chiudere impianti industriali, provoca esplosioni, perdite tossiche e incendi. La protezione dalla corrosione \u00e8 legata a molte industrie e settori come i trasporti, le apparecchiature energetiche, l&#8217;approvvigionamento idrico e l&#8217;ingegneria delle infrastrutture. In effetti, non c&#8217;\u00e8 quasi nessuna azienda Fortune 500, oltre a quelle del settore finanziario, assicurativo o bancario, che abbia il privilegio di non avere a che fare direttamente con la corrosione. \u00c8 qui che i costi sostenuti da produttori e fornitori di beni e servizi vengono trasferiti ai clienti.    <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">La corrosione pu\u00f2 essere definita in senso lato come qualsiasi interazione chimica o elettrochimica tra un materiale e il suo ambiente, che causa il deterioramento del materiale e delle sue propriet\u00e0. Proprio come l&#8217;acqua scorre verso il livello pi\u00f9 basso, i processi naturali hanno la tendenza a spostarsi verso gli stati energetici pi\u00f9 bassi possibili. Per la maggior parte dei metalli, ad eccezione di quelli nobili, lo stato energetico pi\u00f9 basso \u00e8 la forma di ossidi, proprio come il minerale metallico da cui sono stati lavorati. Quindi, i metalli sono destinati a tornare lentamente a questo stato se non si prendono le dovute precauzioni. La velocit\u00e0 di attacco corrosivo di un determinato elemento metallico dipende dalle propriet\u00e0 chimiche intrinseche del metallo stesso e dalla corrosivit\u00e0 dell&#8217;ambiente in cui si trova. In generale, gli ambienti umidi, inquinati industrialmente e saturi di acqua salata sono particolarmente aggressivi per le strutture metalliche.     <\/p>\n[\/vc_column_text][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;22716&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;fadeInUp&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;22704&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;fadeInUp&#8221;][\/vc_column_inner][\/vc_row_inner][vc_column_text css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1729251757312{padding-top: 2% !important;}&#8221;]\n<h4>Come rallentare la corrosione<\/h4>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Tuttavia, esistono diversi metodi per rallentare la corrosione. Uno di questi \u00e8 l&#8217;applicazione di un rivestimento metallico sacrificale, che isola il metallo sottostante dagli agenti corrosivi. Questo pu\u00f2 essere ottenuto con la zincatura, ovvero immergendo elementi di acciaio accuratamente preparati nello zinco fuso. Il risultato \u00e8 uno strato protettivo di zinco, legato metallurgicamente al substrato di acciaio tramite una lega di ferro e zinco. Questo tipo di protezione dalla corrosione prolunga la vita utile delle strutture in acciaio di almeno 20-40 anni in ambienti industriali e fino a 100 anni in aree poco inquinate. I rivestimenti polimerici, o semplicemente vernici, hanno lo stesso scopo dei rivestimenti metallici, ma sono in grado di prolungarne la durata fino a 10 anni.     <\/p>\n<h4>I nostri sistemi duplex<\/h4>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Le opere in acciaio sono una parte essenziale dell&#8217;ingegneria strutturale di Walltopia. Per questo ci sentiamo obbligati a non generare costi evitabili legati alla corrosione. Il nostro modo per farlo \u00e8 offrire tutte le nostre strutture in acciaio per esterni con un &#8220;rivestimento duplex&#8221;, ovvero uno strato di vernice polimerica sopra lo strato di zinco. Grazie all&#8217;effetto sinergico, i sistemi duplex hanno una durata da 1,2 a 1,5 volte superiore ai periodi di protezione combinati della zincatura a caldo e della verniciatura.   <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Il nostro contributo a un mondo meno arrugginito forse non risolve i problemi di corrosione globale, ma protegge gli investimenti dei nostri clienti e garantisce la sicurezza dei loro clienti prolungando la durata delle costruzioni in acciaio per esterni delle attrazioni e delle strutture che realizziamo.<\/p>\n[\/vc_column_text][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 15px; line-height: 1.8em;\">*Ruggine la guerra pi\u00f9 lunga&#8221; di Jonathan Waldman<\/p>\n[\/vc_column_text][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 15px; line-height: 1.8em;\">FONTI<br \/>\n&#8220;Corrosion Protection&#8221; di ArcelorMittal Europe<br \/>\n&#8220;Corrosion: Understanding the Basics&#8221; di ASM International<br \/>\n&#8220;Rust: The longest war&#8221; di Jonathan Waldman<br \/>\n&#8220;The Cost of Corrosion in China&#8221; di Baorong Hou, Institute of Oceanology, Chinese Academy of Sciences, Qingdao, Shandong, China<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"La corrosione influisce sulla durata di vita delle apparecchiature: per combatterla Walltopia utilizza zinco e vernici polimeriche. Per sapere come leggere l&#8217;articolo completo. ","protected":false},"author":10,"featured_media":22710,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[914,908],"tags":[2576,2602],"class_list":["post-185866","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intrattenimento-attivo","category-sala-stampa","tag-innovazione","tag-rivestimento-duplex"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Rivestimento Walltopia duplex: la nostra soluzione contro la corrosione | Walltopia<\/title>\n<meta name=\"description\" content=\"La corrosione influisce sulla durata di vita delle apparecchiature: per combatterla Walltopia utilizza zinco e vernici polimeriche. Per sapere come leggere l&#039;articolo completo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rivestimento Walltopia duplex: la nostra soluzione contro la corrosione\" \/>\n<meta property=\"og:description\" content=\"La corrosione influisce sulla durata di vita delle apparecchiature: per combatterla Walltopia utilizza zinco e vernici polimeriche. Per sapere come leggere l&#039;articolo completo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-22T13:51:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:30:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026084201\/DuplexCoating.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"the_id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\\\/\"},\"author\":{\"name\":\"the_id\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\"},\"headline\":\"Rivestimento Walltopia duplex: la nostra soluzione contro la corrosione\",\"datePublished\":\"2021-06-22T13:51:26+00:00\",\"dateModified\":\"2026-01-15T14:30:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\\\/\"},\"wordCount\":763,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026084201\\\/DuplexCoating.jpeg\",\"keywords\":[\"innovazione\",\"Rivestimento Duplex\"],\"articleSection\":[\"Intrattenimento attivo\",\"Sala stampa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\\\/\",\"name\":\"Rivestimento Walltopia duplex: la nostra soluzione contro la corrosione | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026084201\\\/DuplexCoating.jpeg\",\"datePublished\":\"2021-06-22T13:51:26+00:00\",\"dateModified\":\"2026-01-15T14:30:39+00:00\",\"description\":\"La corrosione influisce sulla durata di vita delle apparecchiature: per combatterla Walltopia utilizza zinco e vernici polimeriche. Per sapere come leggere l'articolo completo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026084201\\\/DuplexCoating.jpeg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026084201\\\/DuplexCoating.jpeg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/casa-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rivestimento Walltopia duplex: la nostra soluzione contro la corrosione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\",\"name\":\"the_id\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rivestimento Walltopia duplex: la nostra soluzione contro la corrosione | Walltopia","description":"La corrosione influisce sulla durata di vita delle apparecchiature: per combatterla Walltopia utilizza zinco e vernici polimeriche. Per sapere come leggere l'articolo completo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\/","og_locale":"it_IT","og_type":"article","og_title":"Rivestimento Walltopia duplex: la nostra soluzione contro la corrosione","og_description":"La corrosione influisce sulla durata di vita delle apparecchiature: per combatterla Walltopia utilizza zinco e vernici polimeriche. Per sapere come leggere l'articolo completo.","og_url":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2021-06-22T13:51:26+00:00","article_modified_time":"2026-01-15T14:30:39+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026084201\/DuplexCoating.jpeg","type":"image\/jpeg"}],"author":"the_id","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\/"},"author":{"name":"the_id","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff"},"headline":"Rivestimento Walltopia duplex: la nostra soluzione contro la corrosione","datePublished":"2021-06-22T13:51:26+00:00","dateModified":"2026-01-15T14:30:39+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\/"},"wordCount":763,"publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026084201\/DuplexCoating.jpeg","keywords":["innovazione","Rivestimento Duplex"],"articleSection":["Intrattenimento attivo","Sala stampa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\/","url":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\/","name":"Rivestimento Walltopia duplex: la nostra soluzione contro la corrosione | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026084201\/DuplexCoating.jpeg","datePublished":"2021-06-22T13:51:26+00:00","dateModified":"2026-01-15T14:30:39+00:00","description":"La corrosione influisce sulla durata di vita delle apparecchiature: per combatterla Walltopia utilizza zinco e vernici polimeriche. Per sapere come leggere l'articolo completo.","breadcrumb":{"@id":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026084201\/DuplexCoating.jpeg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026084201\/DuplexCoating.jpeg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/it\/casa-it\/"},{"@type":"ListItem","position":2,"name":"Rivestimento Walltopia duplex: la nostra soluzione contro la corrosione"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/it\/#website","url":"https:\/\/walltopia.com\/it\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/it\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff","name":"the_id"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/185866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/comments?post=185866"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/185866\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media\/22710"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media?parent=185866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/categories?post=185866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/tags?post=185866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}