{"id":187364,"date":"2021-06-21T15:05:35","date_gmt":"2021-06-21T12:05:35","guid":{"rendered":"https:\/\/walltopia.com\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\/"},"modified":"2026-01-15T17:35:27","modified_gmt":"2026-01-15T14:35:27","slug":"i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019","status":"publish","type":"post","link":"https:\/\/walltopia.com\/it\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\/","title":{"rendered":"I punti salienti della seconda edizione del World Indoor Climbing Summit 2019"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_custom_heading text=&#8221;Il secondo World Indoor Climbing Summit si \u00e8 tenuto il 19-21 giugno 2019 a Sofia, in Bulgaria, e ha messo in contatto gli esperti di livello C del settore dell&apos;arrampicata.&#8221; font_container=&#8221;tag:h2|font_size:18|text_align:left|color:%23000000|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221; css=&#8221;&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Abbiamo riunito 290 tra i pi\u00f9 importanti protagonisti dell&#8217;arrampicata indoor per discutere del futuro del nostro settore. Il summit ha presentato ai partecipanti conferenze e tavole rotonde. Gli argomenti trattati spaziavano dal giorno in cui si decide di aprire una palestra alla pianificazione e alla costruzione, fino alle operazioni quotidiane. Un workshop si \u00e8 concentrato sulle migliori pratiche per la definizione dei percorsi. Ma soprattutto, ci\u00f2 che ha reso il WICS pi\u00f9 prezioso \u00e8 stato lo scambio di conoscenze ed esperienze tra esperti del settore provenienti da 29 paesi. Abbiamo portato nuove prospettive sullo stato del settore in tutto il mondo, dai mercati consolidati a quelli in via di sviluppo.     <\/p>\n<h4>Nuovi argomenti<\/h4>\n[\/vc_column_text][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_gallery interval=&#8221;3&#8243; images=&#8221;22371,22377,22383,22389,22395,22401&#8243; img_size=&#8221;full&#8221; css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1624276824920{padding-top: 2% !important;}&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text css_animation=&#8221;fadeInUp&#8221; css=&#8221;&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Uno dei punti salienti della seconda edizione del WICS \u00e8 stata l&#8217;introduzione di nuovi argomenti. Abbiamo parlato di finanziamenti attraverso il private equity e se i ristoranti hanno un posto nelle palestre di roccia. Abbiamo anche raggiunto altri settori pi\u00f9 maturi nel tentativo di imparare da loro. Professionisti di grande esperienza dell&#8217;industria del fitness hanno tenuto una tavola rotonda. Hanno presentato il modo in cui hanno gestito la vasta espansione del settore. Inoltre, hanno condiviso alcune pratiche che potrebbero essere applicate anche alle palestre di arrampicata.     <\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text css_animation=&#8221;fadeInUp&#8221; css=&#8221;&#8221;]\n<h4>La crescita dell&#8217;arrampicata<\/h4>\n<p style=\"font-size: 18px; line-height: 1.8em;\">L&#8217;intervento conclusivo \u00e8 stato una grande discussione sul futuro dell&#8217;arrampicata che ha scatenato un dibattito sul fatto che la crescita che l&#8217;arrampicata sta affrontando porter\u00e0 o meno a una perdita del suo carattere. Le opinioni erano polarizzate. Le persone erano per lo pi\u00f9 ottimiste sul fatto che non solo dovremmo trovare un modo per mantenere l&#8217;unicit\u00e0 dell&#8217;arrampicata, ma anche di sfruttarla per farla conoscere a un pubblico pi\u00f9 vasto. Non c&#8217;\u00e8 stata una previsione chiara su cosa aspettarsi in un futuro lontano. Tuttavia, la maggior parte dei partecipanti ha condiviso che vede nuovi orizzonti se siamo disposti ad adattarci e a rispondere alle esigenze delle comunit\u00e0 di arrampicatori in continua crescita. Il summit si \u00e8 concluso con un&#8217;epica festa sul tetto per celebrare il successo dell&#8217;evento, le cose imparate e i legami creati con drink e balli notturni.     <\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_gallery interval=&#8221;3&#8243; images=&#8221;22407,22413,22419,22425,22431&#8243; img_size=&#8221;full&#8221; css_animation=&#8221;fadeInUp&#8221;][\/vc_column_inner][\/vc_row_inner][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">\u00c8 stato un piacere ospitare ancora una volta esperti del settore dell&#8217;arrampicata provenienti da tutto il mondo per la seconda edizione del WICS. Siamo pronti a crescere e a migliorare ancora di pi\u00f9. Rimani sintonizzato per conoscere le date della prossima edizione.  <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Le foto dell&#8217;evento sono disponibili sulla <a href=\"https:\/\/www.facebook.com\/pg\/worldindoorclimbingsummit\/photos\/?tab=album&amp;album_id=310536736491660\">pagina FB di WICS<\/a>.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Il secondo World Indoor Climbing Summit si \u00e8 svolto a Sofia, in Bulgaria, e ha messo in contatto gli esperti di livello C del settore dell&#8217;arrampicata.","protected":false},"author":10,"featured_media":22365,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[908],"tags":[2837,2838],"class_list":["post-187364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sala-stampa","tag-wics","tag-wics2019"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>I punti salienti della seconda edizione del World Indoor Climbing Summit 2019 | Walltopia<\/title>\n<meta name=\"description\" content=\"Il secondo World Indoor Climbing Summit si \u00e8 svolto a Sofia, in Bulgaria, e ha messo in contatto gli esperti di livello C del settore dell&#039;arrampicata.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/it\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I punti salienti della seconda edizione del World Indoor Climbing Summit 2019\" \/>\n<meta property=\"og:description\" content=\"Il secondo World Indoor Climbing Summit si \u00e8 svolto a Sofia, in Bulgaria, e ha messo in contatto gli esperti di livello C del settore dell&#039;arrampicata.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/it\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-21T12:05:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:35:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085339\/wics-2019-panel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"491\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"the_id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\\\/\"},\"author\":{\"name\":\"the_id\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\"},\"headline\":\"I punti salienti della seconda edizione del World Indoor Climbing Summit 2019\",\"datePublished\":\"2021-06-21T12:05:35+00:00\",\"dateModified\":\"2026-01-15T14:35:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\\\/\"},\"wordCount\":572,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085339\\\/wics-2019-panel.jpg\",\"keywords\":[\"wics\",\"WICS2019\"],\"articleSection\":[\"Sala stampa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\\\/\",\"name\":\"I punti salienti della seconda edizione del World Indoor Climbing Summit 2019 | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085339\\\/wics-2019-panel.jpg\",\"datePublished\":\"2021-06-21T12:05:35+00:00\",\"dateModified\":\"2026-01-15T14:35:27+00:00\",\"description\":\"Il secondo World Indoor Climbing Summit si \u00e8 svolto a Sofia, in Bulgaria, e ha messo in contatto gli esperti di livello C del settore dell'arrampicata.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085339\\\/wics-2019-panel.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085339\\\/wics-2019-panel.jpg\",\"width\":900,\"height\":491},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/casa-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I punti salienti della seconda edizione del World Indoor Climbing Summit 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\",\"name\":\"the_id\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"I punti salienti della seconda edizione del World Indoor Climbing Summit 2019 | Walltopia","description":"Il secondo World Indoor Climbing Summit si \u00e8 svolto a Sofia, in Bulgaria, e ha messo in contatto gli esperti di livello C del settore dell'arrampicata.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/it\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\/","og_locale":"it_IT","og_type":"article","og_title":"I punti salienti della seconda edizione del World Indoor Climbing Summit 2019","og_description":"Il secondo World Indoor Climbing Summit si \u00e8 svolto a Sofia, in Bulgaria, e ha messo in contatto gli esperti di livello C del settore dell'arrampicata.","og_url":"https:\/\/walltopia.com\/it\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2021-06-21T12:05:35+00:00","article_modified_time":"2026-01-15T14:35:27+00:00","og_image":[{"width":900,"height":491,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085339\/wics-2019-panel.jpg","type":"image\/jpeg"}],"author":"the_id","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/it\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\/"},"author":{"name":"the_id","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff"},"headline":"I punti salienti della seconda edizione del World Indoor Climbing Summit 2019","datePublished":"2021-06-21T12:05:35+00:00","dateModified":"2026-01-15T14:35:27+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/it\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\/"},"wordCount":572,"publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/it\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085339\/wics-2019-panel.jpg","keywords":["wics","WICS2019"],"articleSection":["Sala stampa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/it\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\/","url":"https:\/\/walltopia.com\/it\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\/","name":"I punti salienti della seconda edizione del World Indoor Climbing Summit 2019 | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/it\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/it\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085339\/wics-2019-panel.jpg","datePublished":"2021-06-21T12:05:35+00:00","dateModified":"2026-01-15T14:35:27+00:00","description":"Il secondo World Indoor Climbing Summit si \u00e8 svolto a Sofia, in Bulgaria, e ha messo in contatto gli esperti di livello C del settore dell'arrampicata.","breadcrumb":{"@id":"https:\/\/walltopia.com\/it\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/it\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085339\/wics-2019-panel.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085339\/wics-2019-panel.jpg","width":900,"height":491},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/it\/i-punti-salienti-della-seconda-edizione-del-world-indoor-climbing-summit-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/it\/casa-it\/"},{"@type":"ListItem","position":2,"name":"I punti salienti della seconda edizione del World Indoor Climbing Summit 2019"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/it\/#website","url":"https:\/\/walltopia.com\/it\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/it\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff","name":"the_id"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/187364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/comments?post=187364"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/187364\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media\/22365"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media?parent=187364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/categories?post=187364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/tags?post=187364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}