{"id":192710,"date":"2017-09-27T08:29:58","date_gmt":"2017-09-27T05:29:58","guid":{"rendered":"https:\/\/walltopia.com\/walltopia-alla-family-attractions-expo-di-birmingham\/"},"modified":"2026-01-15T17:47:33","modified_gmt":"2026-01-15T14:47:33","slug":"walltopia-alla-family-attractions-expo-di-birmingham","status":"publish","type":"post","link":"https:\/\/walltopia.com\/it\/walltopia-alla-family-attractions-expo-di-birmingham\/","title":{"rendered":"Walltopia alla Family Attractions Expo di Birmingham"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column css_animation=&#8221;fadeInUp&#8221;][vc_column_text]\n<p style=\"font-size:18px; line-height: 1.8em;\">Visiteremo presto <b>Birmingham<\/b> e vogliamo incontrarti per parlare dei tuoi progetti futuri di espansione o ristrutturazione della tua struttura. Scopri come le nostre soluzioni di intrattenimento attivo creano esperienze uniche per i visitatori del FEC e, in definitiva, portano pi\u00f9 clienti. <\/p>\n<p style=\"font-size:18px; line-height: 1.8em;\">Passa allo <b> stand 1130 <\/b> del <b> NEC <\/b> l&#8217;<b> 8 e il 9 novembre<\/b>. Ti consigliamo di fissare un incontro in anticipo con uno dei membri del nostro team. Contattaci a <a href=\"mailto:adventure@walltopia.com\">adventure@walltopia.com.<\/a>  <\/p>\n<p style=\"font-size:18px; line-height: 1.8em;\">Non dimenticare di dare un&#8217;occhiata alle nostre giostre aeree <a href=\"https:\/\/staging-3.walltopia.com\/products\/rollglider\/\" target=\"_blank\" rel=\"noopener\">(Rollglider)<\/a>, ai <a href=\"https:\/\/staging-3.walltopia.com\/products\/ropes-course\/\" target=\"_blank\" rel=\"noopener\">percorsi a corda<\/a>, alle <a href=\"https:\/\/staging-3.walltopia.com\/products\/fun-walls\/\" target=\"_blank\" rel=\"noopener\">pareti interattive<\/a> per bambini e adulti (Fun Walls) e ai percorsi a ostacoli <a href=\"https:\/\/staging-3.walltopia.com\/products\/ninja-course\/\" target=\"_blank\" rel=\"noopener\">(Ninja Course)<\/a>.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Visiteremo presto Birmingham e vogliamo incontrarti per parlare dei tuoi progetti futuri di espansione o ristrutturazione della tua struttura.","protected":false},"author":5,"featured_media":95533,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[914],"tags":[3894,3893],"class_list":["post-192710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intrattenimento-attivo","tag-attrazioni-per-famiglie","tag-expo-delle-attrazioni-per-famiglie-a-birmingham"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Walltopia alla Family Attractions Expo di Birmingham | Walltopia<\/title>\n<meta name=\"description\" content=\"Scopri come le nostre soluzioni di intrattenimento attivo creano esperienze uniche per i visitatori del FEC e, in definitiva, portano pi\u00f9 clienti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/it\/walltopia-alla-family-attractions-expo-di-birmingham\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Walltopia alla Family Attractions Expo di Birmingham\" \/>\n<meta property=\"og:description\" content=\"Scopri come le nostre soluzioni di intrattenimento attivo creano esperienze uniche per i visitatori del FEC e, in definitiva, portano pi\u00f9 clienti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/it\/walltopia-alla-family-attractions-expo-di-birmingham\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-27T05:29:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:47:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145410\/Walltopia-Family-Attractions-Expo-Birmingham-2017.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-alla-family-attractions-expo-di-birmingham\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-alla-family-attractions-expo-di-birmingham\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Walltopia alla Family Attractions Expo di Birmingham\",\"datePublished\":\"2017-09-27T05:29:58+00:00\",\"dateModified\":\"2026-01-15T14:47:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-alla-family-attractions-expo-di-birmingham\\\/\"},\"wordCount\":125,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-alla-family-attractions-expo-di-birmingham\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145410\\\/Walltopia-Family-Attractions-Expo-Birmingham-2017.jpg\",\"keywords\":[\"Attrazioni per famiglie\",\"Expo delle attrazioni per famiglie a Birmingham\"],\"articleSection\":[\"Intrattenimento attivo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-alla-family-attractions-expo-di-birmingham\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-alla-family-attractions-expo-di-birmingham\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-alla-family-attractions-expo-di-birmingham\\\/\",\"name\":\"Walltopia alla Family Attractions Expo di Birmingham | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-alla-family-attractions-expo-di-birmingham\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-alla-family-attractions-expo-di-birmingham\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145410\\\/Walltopia-Family-Attractions-Expo-Birmingham-2017.jpg\",\"datePublished\":\"2017-09-27T05:29:58+00:00\",\"dateModified\":\"2026-01-15T14:47:33+00:00\",\"description\":\"Scopri come le nostre soluzioni di intrattenimento attivo creano esperienze uniche per i visitatori del FEC e, in definitiva, portano pi\u00f9 clienti.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-alla-family-attractions-expo-di-birmingham\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-alla-family-attractions-expo-di-birmingham\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-alla-family-attractions-expo-di-birmingham\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145410\\\/Walltopia-Family-Attractions-Expo-Birmingham-2017.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145410\\\/Walltopia-Family-Attractions-Expo-Birmingham-2017.jpg\",\"width\":900,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-alla-family-attractions-expo-di-birmingham\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/casa-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Walltopia alla Family Attractions Expo di Birmingham\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Walltopia alla Family Attractions Expo di Birmingham | Walltopia","description":"Scopri come le nostre soluzioni di intrattenimento attivo creano esperienze uniche per i visitatori del FEC e, in definitiva, portano pi\u00f9 clienti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/it\/walltopia-alla-family-attractions-expo-di-birmingham\/","og_locale":"it_IT","og_type":"article","og_title":"Walltopia alla Family Attractions Expo di Birmingham","og_description":"Scopri come le nostre soluzioni di intrattenimento attivo creano esperienze uniche per i visitatori del FEC e, in definitiva, portano pi\u00f9 clienti.","og_url":"https:\/\/walltopia.com\/it\/walltopia-alla-family-attractions-expo-di-birmingham\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2017-09-27T05:29:58+00:00","article_modified_time":"2026-01-15T14:47:33+00:00","og_image":[{"width":900,"height":478,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145410\/Walltopia-Family-Attractions-Expo-Birmingham-2017.jpg","type":"image\/jpeg"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/it\/walltopia-alla-family-attractions-expo-di-birmingham\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/walltopia-alla-family-attractions-expo-di-birmingham\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Walltopia alla Family Attractions Expo di Birmingham","datePublished":"2017-09-27T05:29:58+00:00","dateModified":"2026-01-15T14:47:33+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/it\/walltopia-alla-family-attractions-expo-di-birmingham\/"},"wordCount":125,"commentCount":0,"publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/it\/walltopia-alla-family-attractions-expo-di-birmingham\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145410\/Walltopia-Family-Attractions-Expo-Birmingham-2017.jpg","keywords":["Attrazioni per famiglie","Expo delle attrazioni per famiglie a Birmingham"],"articleSection":["Intrattenimento attivo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/walltopia.com\/it\/walltopia-alla-family-attractions-expo-di-birmingham\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/it\/walltopia-alla-family-attractions-expo-di-birmingham\/","url":"https:\/\/walltopia.com\/it\/walltopia-alla-family-attractions-expo-di-birmingham\/","name":"Walltopia alla Family Attractions Expo di Birmingham | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/it\/walltopia-alla-family-attractions-expo-di-birmingham\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/it\/walltopia-alla-family-attractions-expo-di-birmingham\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145410\/Walltopia-Family-Attractions-Expo-Birmingham-2017.jpg","datePublished":"2017-09-27T05:29:58+00:00","dateModified":"2026-01-15T14:47:33+00:00","description":"Scopri come le nostre soluzioni di intrattenimento attivo creano esperienze uniche per i visitatori del FEC e, in definitiva, portano pi\u00f9 clienti.","breadcrumb":{"@id":"https:\/\/walltopia.com\/it\/walltopia-alla-family-attractions-expo-di-birmingham\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/it\/walltopia-alla-family-attractions-expo-di-birmingham\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/walltopia-alla-family-attractions-expo-di-birmingham\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145410\/Walltopia-Family-Attractions-Expo-Birmingham-2017.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145410\/Walltopia-Family-Attractions-Expo-Birmingham-2017.jpg","width":900,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/it\/walltopia-alla-family-attractions-expo-di-birmingham\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/it\/casa-it\/"},{"@type":"ListItem","position":2,"name":"Walltopia alla Family Attractions Expo di Birmingham"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/it\/#website","url":"https:\/\/walltopia.com\/it\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/it\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/192710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/comments?post=192710"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/192710\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media\/95533"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media?parent=192710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/categories?post=192710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/tags?post=192710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}