{"id":194559,"date":"2018-09-18T05:50:41","date_gmt":"2018-09-18T02:50:41","guid":{"rendered":"https:\/\/walltopia.com\/walltopia-active-entertainment-alla-conferenza-annuale-aza\/"},"modified":"2026-01-15T17:52:36","modified_gmt":"2026-01-15T14:52:36","slug":"walltopia-active-entertainment-alla-conferenza-annuale-aza","status":"publish","type":"post","link":"https:\/\/walltopia.com\/it\/walltopia-active-entertainment-alla-conferenza-annuale-aza\/","title":{"rendered":"Walltopia Active Entertainment alla conferenza annuale AZA"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column css_animation=&#8221;fadeInUp&#8221;][vc_column_text]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Walltopia porta il divertimento attivo negli zoo! Il nostro team sar\u00e0 presente alla conferenza annuale dell&#8217;Association of Zoos and Aquariums per mostrarti perch\u00e9 i nostri <a href=\"https:\/\/staging-3.walltopia.com\/products\/ropes-course\/\" target=\"_blank\" rel=\"noopener\">percorsi a fune<\/a>, le <a href=\"https:\/\/staging-3.walltopia.com\/products\/rollglider\/\" target=\"_blank\" rel=\"noopener\">giostre aeree<\/a>, le <a href=\"https:\/\/staging-3.walltopia.com\/products\/fun-walls\/\" target=\"_blank\" rel=\"noopener\">strutture di arrampicata<\/a>, gli <a href=\"https:\/\/staging-3.walltopia.com\/products\/ninja-course\/\" target=\"_blank\" rel=\"noopener\">ostacoli<\/a> e gli <a href=\"https:\/\/staging-3.walltopia.com\/products\/adventure-hub\/\" target=\"_blank\" rel=\"noopener\">elementi tematici<\/a> sono un modo intelligente per diversificare qualsiasi zoo o acquario. Abbiamo in serbo nuovi ed entusiasmanti aggiornamenti sui prodotti e nuovi e innovativi progetti di percorsi a fune da condividere.  <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">L&#8217;evento si terr\u00e0 al <b>Washington State Convention Center<\/b> di <b>Seattle, WA<\/b>. Incontra il nostro team allo <b>stand 823<\/b> dal <b>23 al 27 settembre<\/b>, oppure <a href=\"mailto:adventure@walltopia.com\">contattaci<\/a> per fissare un incontro in anticipo. <\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Walltopia porta il divertimento attivo negli zoo! Il nostro team sar\u00e0 presente alla conferenza annuale dell&#8217;Association of Zoos and Aquariums. ","protected":false},"author":5,"featured_media":95690,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[914],"tags":[4029],"class_list":["post-194559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intrattenimento-attivo","tag-conferenza-annuale-aza"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Walltopia Active Entertainment alla conferenza annuale AZA | Walltopia<\/title>\n<meta name=\"description\" content=\"Scopri le ultime novit\u00e0 di Walltopia per l&#039;Intrattenimento Attivo e gli innovativi percorsi a corde per gli zoo. Ti aspettano entusiasmanti aggiornamenti!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/it\/walltopia-active-entertainment-alla-conferenza-annuale-aza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Walltopia Active Entertainment alla conferenza annuale AZA\" \/>\n<meta property=\"og:description\" content=\"Scopri le ultime novit\u00e0 di Walltopia per l&#039;Intrattenimento Attivo e gli innovativi percorsi a corde per gli zoo. Ti aspettano entusiasmanti aggiornamenti!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/it\/walltopia-active-entertainment-alla-conferenza-annuale-aza\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-18T02:50:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:52:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145154\/Walltopia-AZA-Annual-Conference-2018-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-active-entertainment-alla-conferenza-annuale-aza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-active-entertainment-alla-conferenza-annuale-aza\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Walltopia Active Entertainment alla conferenza annuale AZA\",\"datePublished\":\"2018-09-18T02:50:41+00:00\",\"dateModified\":\"2026-01-15T14:52:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-active-entertainment-alla-conferenza-annuale-aza\\\/\"},\"wordCount\":125,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-active-entertainment-alla-conferenza-annuale-aza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145154\\\/Walltopia-AZA-Annual-Conference-2018-1.jpg\",\"keywords\":[\"Conferenza annuale AZA\"],\"articleSection\":[\"Intrattenimento attivo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-active-entertainment-alla-conferenza-annuale-aza\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-active-entertainment-alla-conferenza-annuale-aza\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-active-entertainment-alla-conferenza-annuale-aza\\\/\",\"name\":\"Walltopia Active Entertainment alla conferenza annuale AZA | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-active-entertainment-alla-conferenza-annuale-aza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-active-entertainment-alla-conferenza-annuale-aza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145154\\\/Walltopia-AZA-Annual-Conference-2018-1.jpg\",\"datePublished\":\"2018-09-18T02:50:41+00:00\",\"dateModified\":\"2026-01-15T14:52:36+00:00\",\"description\":\"Scopri le ultime novit\u00e0 di Walltopia per l'Intrattenimento Attivo e gli innovativi percorsi a corde per gli zoo. Ti aspettano entusiasmanti aggiornamenti!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-active-entertainment-alla-conferenza-annuale-aza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-active-entertainment-alla-conferenza-annuale-aza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-active-entertainment-alla-conferenza-annuale-aza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145154\\\/Walltopia-AZA-Annual-Conference-2018-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145154\\\/Walltopia-AZA-Annual-Conference-2018-1.jpg\",\"width\":900,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-active-entertainment-alla-conferenza-annuale-aza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/casa-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Walltopia Active Entertainment alla conferenza annuale AZA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Walltopia Active Entertainment alla conferenza annuale AZA | Walltopia","description":"Scopri le ultime novit\u00e0 di Walltopia per l'Intrattenimento Attivo e gli innovativi percorsi a corde per gli zoo. Ti aspettano entusiasmanti aggiornamenti!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/it\/walltopia-active-entertainment-alla-conferenza-annuale-aza\/","og_locale":"it_IT","og_type":"article","og_title":"Walltopia Active Entertainment alla conferenza annuale AZA","og_description":"Scopri le ultime novit\u00e0 di Walltopia per l'Intrattenimento Attivo e gli innovativi percorsi a corde per gli zoo. Ti aspettano entusiasmanti aggiornamenti!","og_url":"https:\/\/walltopia.com\/it\/walltopia-active-entertainment-alla-conferenza-annuale-aza\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2018-09-18T02:50:41+00:00","article_modified_time":"2026-01-15T14:52:36+00:00","og_image":[{"width":900,"height":478,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145154\/Walltopia-AZA-Annual-Conference-2018-1.jpg","type":"image\/jpeg"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/it\/walltopia-active-entertainment-alla-conferenza-annuale-aza\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/walltopia-active-entertainment-alla-conferenza-annuale-aza\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Walltopia Active Entertainment alla conferenza annuale AZA","datePublished":"2018-09-18T02:50:41+00:00","dateModified":"2026-01-15T14:52:36+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/it\/walltopia-active-entertainment-alla-conferenza-annuale-aza\/"},"wordCount":125,"commentCount":0,"publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/it\/walltopia-active-entertainment-alla-conferenza-annuale-aza\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145154\/Walltopia-AZA-Annual-Conference-2018-1.jpg","keywords":["Conferenza annuale AZA"],"articleSection":["Intrattenimento attivo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/walltopia.com\/it\/walltopia-active-entertainment-alla-conferenza-annuale-aza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/it\/walltopia-active-entertainment-alla-conferenza-annuale-aza\/","url":"https:\/\/walltopia.com\/it\/walltopia-active-entertainment-alla-conferenza-annuale-aza\/","name":"Walltopia Active Entertainment alla conferenza annuale AZA | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/it\/walltopia-active-entertainment-alla-conferenza-annuale-aza\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/it\/walltopia-active-entertainment-alla-conferenza-annuale-aza\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145154\/Walltopia-AZA-Annual-Conference-2018-1.jpg","datePublished":"2018-09-18T02:50:41+00:00","dateModified":"2026-01-15T14:52:36+00:00","description":"Scopri le ultime novit\u00e0 di Walltopia per l'Intrattenimento Attivo e gli innovativi percorsi a corde per gli zoo. Ti aspettano entusiasmanti aggiornamenti!","breadcrumb":{"@id":"https:\/\/walltopia.com\/it\/walltopia-active-entertainment-alla-conferenza-annuale-aza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/it\/walltopia-active-entertainment-alla-conferenza-annuale-aza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/walltopia-active-entertainment-alla-conferenza-annuale-aza\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145154\/Walltopia-AZA-Annual-Conference-2018-1.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145154\/Walltopia-AZA-Annual-Conference-2018-1.jpg","width":900,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/it\/walltopia-active-entertainment-alla-conferenza-annuale-aza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/it\/casa-it\/"},{"@type":"ListItem","position":2,"name":"Walltopia Active Entertainment alla conferenza annuale AZA"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/it\/#website","url":"https:\/\/walltopia.com\/it\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/it\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/194559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/comments?post=194559"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/194559\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media\/95690"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media?parent=194559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/categories?post=194559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/tags?post=194559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}