{"id":194868,"date":"2018-05-14T12:28:04","date_gmt":"2018-05-14T09:28:04","guid":{"rendered":"https:\/\/walltopia.com\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\/"},"modified":"2026-01-15T17:53:13","modified_gmt":"2026-01-15T14:53:13","slug":"walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini","status":"publish","type":"post","link":"https:\/\/walltopia.com\/it\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\/","title":{"rendered":"Walltopia al pi\u00f9 grande raduno di proprietari di parchi trampolini"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column css_animation=&#8221;fadeInUp&#8221;][vc_column_text]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Walltopia \u00e8 un espositore ufficiale della <a href=\"http:\/\/www.indoortrampolineparks.org\/page\/Hotel\" target=\"_blank\" rel=\"noopener\">Conferenza e Fiera dell&#8217;Associazione Internazionale dei Parchi Trampolino<\/a> ad Amsterdam. Il nostro team sar\u00e0 presente allo <b>stand 26 il 21 e 22 maggio<\/b> presso il <b>Beurs van Berlage<\/b> per condividere i dettagli sulla diversificazione dei parchi di trampolini e offrire ai clienti nuovi tipi di movimento da esplorare. Parteciperemo inoltre a una tavola rotonda sul tema <b>&#8220;Aggiungere attrazioni e migliorare l&#8217;esperienza degli ospiti&#8221;<\/b> il <b>21 maggio alle 15:00<\/b>.  <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\"><a href=\"https:\/\/staging-3.walltopia.com\/contact-us\/\">Scrivici<\/a> per fissare un incontro in anticipo.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Walltopia \u00e8 un espositore ufficiale della Conferenza e Fiera dell&#8217;Associazione Internazionale dei Parchi Trampolino ad Amsterdam.","protected":false},"author":5,"featured_media":95654,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[914],"tags":[4330],"class_list":["post-194868","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intrattenimento-attivo","tag-parchi-di-trampolino"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Walltopia al pi\u00f9 grande raduno di proprietari di parchi trampolini | Walltopia<\/title>\n<meta name=\"description\" content=\"Incontra Walltopia al Beurs van Berlage, per esplorare nuovi modi di migliorare i parchi di trampolini con esperienze di movimento innovative per i tuoi clienti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/it\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Walltopia al pi\u00f9 grande raduno di proprietari di parchi trampolini\" \/>\n<meta property=\"og:description\" content=\"Incontra Walltopia al Beurs van Berlage, per esplorare nuovi modi di migliorare i parchi di trampolini con esperienze di movimento innovative per i tuoi clienti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/it\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-14T09:28:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:53:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145226\/Walltopia-Trampoline-Park-Owners-Gathering.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Walltopia al pi\u00f9 grande raduno di proprietari di parchi trampolini\",\"datePublished\":\"2018-05-14T09:28:04+00:00\",\"dateModified\":\"2026-01-15T14:53:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\\\/\"},\"wordCount\":104,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145226\\\/Walltopia-Trampoline-Park-Owners-Gathering.jpg\",\"keywords\":[\"Parchi di trampolino\"],\"articleSection\":[\"Intrattenimento attivo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\\\/\",\"name\":\"Walltopia al pi\u00f9 grande raduno di proprietari di parchi trampolini | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145226\\\/Walltopia-Trampoline-Park-Owners-Gathering.jpg\",\"datePublished\":\"2018-05-14T09:28:04+00:00\",\"dateModified\":\"2026-01-15T14:53:13+00:00\",\"description\":\"Incontra Walltopia al Beurs van Berlage, per esplorare nuovi modi di migliorare i parchi di trampolini con esperienze di movimento innovative per i tuoi clienti.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145226\\\/Walltopia-Trampoline-Park-Owners-Gathering.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145226\\\/Walltopia-Trampoline-Park-Owners-Gathering.jpg\",\"width\":900,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/casa-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Walltopia al pi\u00f9 grande raduno di proprietari di parchi trampolini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Walltopia al pi\u00f9 grande raduno di proprietari di parchi trampolini | Walltopia","description":"Incontra Walltopia al Beurs van Berlage, per esplorare nuovi modi di migliorare i parchi di trampolini con esperienze di movimento innovative per i tuoi clienti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/it\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\/","og_locale":"it_IT","og_type":"article","og_title":"Walltopia al pi\u00f9 grande raduno di proprietari di parchi trampolini","og_description":"Incontra Walltopia al Beurs van Berlage, per esplorare nuovi modi di migliorare i parchi di trampolini con esperienze di movimento innovative per i tuoi clienti.","og_url":"https:\/\/walltopia.com\/it\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2018-05-14T09:28:04+00:00","article_modified_time":"2026-01-15T14:53:13+00:00","og_image":[{"width":900,"height":478,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145226\/Walltopia-Trampoline-Park-Owners-Gathering.jpg","type":"image\/jpeg"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/it\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Walltopia al pi\u00f9 grande raduno di proprietari di parchi trampolini","datePublished":"2018-05-14T09:28:04+00:00","dateModified":"2026-01-15T14:53:13+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/it\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\/"},"wordCount":104,"commentCount":0,"publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/it\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145226\/Walltopia-Trampoline-Park-Owners-Gathering.jpg","keywords":["Parchi di trampolino"],"articleSection":["Intrattenimento attivo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/walltopia.com\/it\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/it\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\/","url":"https:\/\/walltopia.com\/it\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\/","name":"Walltopia al pi\u00f9 grande raduno di proprietari di parchi trampolini | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/it\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/it\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145226\/Walltopia-Trampoline-Park-Owners-Gathering.jpg","datePublished":"2018-05-14T09:28:04+00:00","dateModified":"2026-01-15T14:53:13+00:00","description":"Incontra Walltopia al Beurs van Berlage, per esplorare nuovi modi di migliorare i parchi di trampolini con esperienze di movimento innovative per i tuoi clienti.","breadcrumb":{"@id":"https:\/\/walltopia.com\/it\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/it\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145226\/Walltopia-Trampoline-Park-Owners-Gathering.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145226\/Walltopia-Trampoline-Park-Owners-Gathering.jpg","width":900,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/it\/walltopia-al-piu-grande-raduno-di-proprietari-di-parchi-trampolini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/it\/casa-it\/"},{"@type":"ListItem","position":2,"name":"Walltopia al pi\u00f9 grande raduno di proprietari di parchi trampolini"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/it\/#website","url":"https:\/\/walltopia.com\/it\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/it\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/194868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/comments?post=194868"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/194868\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media\/95654"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media?parent=194868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/categories?post=194868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/tags?post=194868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}