{"id":195505,"date":"2021-02-23T11:11:41","date_gmt":"2021-02-23T08:11:41","guid":{"rendered":"https:\/\/walltopia.com\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\/"},"modified":"2026-01-15T17:54:44","modified_gmt":"2026-01-15T14:54:44","slug":"walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2","status":"publish","type":"post","link":"https:\/\/walltopia.com\/it\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\/","title":{"rendered":"Walltopia annuncia un nuovo programma di finanziamento delle attrezzature in leasing"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column css_animation=&#8221;none&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<h5>Stiamo introducendo il programma di finanziamento per il leasing di attrezzature Walltopia, progettato per supportare i proprietari di aziende che vogliono continuare la loro crescita nel 2021 con condizioni di pagamento speciali.<\/h5>\n[\/vc_column_text][vc_separator css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1616078237302{padding-bottom: 4% !important;}&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">La crisi del COVID-19 ha rappresentato un&#8217;enorme sfida per tutte le attivit\u00e0 di <a href=\"https:\/\/staging-3.walltopia.com\/\" target=\"_blank\" rel=\"noopener\">intrattenimento attive<\/a> e in salita. La maggior parte di esse \u00e8 stata chiusa o ha operato a capacit\u00e0 limitata fino al 2020. Con la riapertura di un numero maggiore di strutture, l&#8217;aria \u00e8 piena di entusiasmo sia per i visitatori che per i proprietari. Il nuovo <a href=\"https:\/\/leasing.walltopia.com\/\" target=\"_blank\" rel=\"noopener\">programma di finanziamento<\/a> lanciato da Walltopia offre condizioni di pagamento speciali ai clienti che sottoscrivono un contratto nel 2021. \u00c8 aperto a nuovi accordi sia per l&#8217;arrampicata che per i prodotti di intrattenimento attivo.    <\/p>\n[\/vc_column_text][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Dal 1\u00b0 luglio 2021 il programma pu\u00f2 sostenere i progetti idonei dilazionando fino al 50% del valore del contratto con Walltopia per un massimo di 5 anni con un tasso d&#8217;interesse del 3%*.  <\/strong><\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Non sono previste commissioni di accensione o di pagamento anticipato.<\/strong><\/p>\n[\/vc_column_text][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 12px;\">* I termini e le condizioni possono variare in base al paese del richiedente, alle dimensioni del progetto, alla sua credibilit\u00e0, al rischio e al profilo finanziario. I requisiti di garanzia per i termini di pagamento speciali possono richiedere uno o pi\u00f9 dei seguenti elementi: riserva di propriet\u00e0, interessi di sicurezza registrati, depositi ucc, oneri fissi e fluttuanti, garanzie personali e altro. La presentazione di una domanda non garantisce l&#8217;approvazione.  <\/p>\n[\/vc_column_text][vc_column_text css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1616078267894{padding-bottom: 3% !important;}&#8221;]\n<h3>Il processo di candidatura richiede i seguenti requisiti:<\/h3>\n[\/vc_column_text][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Tutte le informazioni fornite saranno utilizzate esclusivamente per ottenere condizioni di pagamento speciali da parte del programma di finanziamento Walltopia Equipment Lease. Tutte le domande presentate saranno trattate con la massima riservatezza. <\/p>\n<p>Per saperne di pi\u00f9 sul programma e valutare l&#8217;opportunit\u00e0 per la tua azienda, Walltopia ti invita a visitare la pagina ufficiale del programma o a contattarla all&#8217;indirizzo <a href=\"mailto:leasing@walltopia.com\">leasing@walltopia.com.<\/a><\/p>\n[\/vc_column_text][vc_column_text css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1616078283470{padding-bottom: 3% !important;}&#8221;]\n<h3>Informativa sulla privacy<\/h3>\n[\/vc_column_text][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Alcune delle informazioni che ci fornisci possono costituire dati personali, come i dati identificativi e alcuni dati finanziari. In questo modo, acconsenti attivamente al trattamento di tali dati. Puoi revocare tale consenso in qualsiasi momento inviando un&#8217;e-mail al nostro team; ci\u00f2 limiter\u00e0 tuttavia il tuo coinvolgimento nell&#8217;iniziativa, in quanto le informazioni sono necessarie per identificare il richiedente e per effettuare la valutazione del rischio della domanda. Per quanto riguarda il trattamento dei dati personali nell&#8217;ambito dell&#8217;Iniziativa, si applica integralmente la Politica sulla privacy di Walltopia. In caso di trattamento dei dati personali, l&#8217;Amministratore &#8211; Walltopia AD, lo far\u00e0 nel pieno rispetto della legislazione bulgara ed europea applicabile. Il trattamento sar\u00e0 effettuato ai fini dell&#8217;iniziativa e sar\u00e0 limitato al suo periodo di attivit\u00e0. Ti invitiamo a consultare l&#8217;Informativa sulla Privacy di Walltopia per maggiori dettagli sui termini del Trattamento e sui tuoi diritti in qualit\u00e0 di soggetto interessato.      <\/p>\n[\/vc_column_text]<a class=\"wt-link \" href=\"https:\/\/leasing.walltopia.com\/\">Learn more<\/a>[\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column css_animation=&#8221;none&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221;] Stiamo introducendo il programma di finanziamento per il leasing di attrezzature Walltopia, progettato per supportare i proprietari&#8230;","protected":false},"author":5,"featured_media":95991,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[914,908],"tags":[2422,4467,4468],"class_list":["post-195505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intrattenimento-attivo","category-sala-stampa","tag-locazione-di-attrezzature","tag-noleggio-attrezzature-walltopia","tag-programma-di-finanziamento-per-il-leasing-di-attrezzature"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Walltopia annuncia un nuovo programma di finanziamento delle attrezzature in leasing | Walltopia<\/title>\n<meta name=\"description\" content=\"Stiamo introducendo il programma di finanziamento con leasing di attrezzature Walltopia, pensato per supportare gli imprenditori. Se vuoi saperne di pi\u00f9, leggi l&#039;articolo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/it\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Walltopia annuncia un nuovo programma di finanziamento delle attrezzature in leasing\" \/>\n<meta property=\"og:description\" content=\"Stiamo introducendo il programma di finanziamento con leasing di attrezzature Walltopia, pensato per supportare gli imprenditori. Se vuoi saperne di pi\u00f9, leggi l&#039;articolo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/it\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-23T08:11:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:54:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144526\/Walltopia-Equipment-Lease-Financing-Program-2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"256\" \/>\n\t<meta property=\"og:image:height\" content=\"171\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Walltopia annuncia un nuovo programma di finanziamento delle attrezzature in leasing\",\"datePublished\":\"2021-02-23T08:11:41+00:00\",\"dateModified\":\"2026-01-15T14:54:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\\\/\"},\"wordCount\":645,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027144526\\\/Walltopia-Equipment-Lease-Financing-Program-2-1.jpg\",\"keywords\":[\"Locazione di attrezzature\",\"Noleggio attrezzature Walltopia\",\"Programma di finanziamento per il leasing di attrezzature\"],\"articleSection\":[\"Intrattenimento attivo\",\"Sala stampa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\\\/\",\"name\":\"Walltopia annuncia un nuovo programma di finanziamento delle attrezzature in leasing | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027144526\\\/Walltopia-Equipment-Lease-Financing-Program-2-1.jpg\",\"datePublished\":\"2021-02-23T08:11:41+00:00\",\"dateModified\":\"2026-01-15T14:54:44+00:00\",\"description\":\"Stiamo introducendo il programma di finanziamento con leasing di attrezzature Walltopia, pensato per supportare gli imprenditori. Se vuoi saperne di pi\u00f9, leggi l'articolo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027144526\\\/Walltopia-Equipment-Lease-Financing-Program-2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027144526\\\/Walltopia-Equipment-Lease-Financing-Program-2-1.jpg\",\"width\":256,\"height\":171},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/casa-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Walltopia annuncia un nuovo programma di finanziamento delle attrezzature in leasing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Walltopia annuncia un nuovo programma di finanziamento delle attrezzature in leasing | Walltopia","description":"Stiamo introducendo il programma di finanziamento con leasing di attrezzature Walltopia, pensato per supportare gli imprenditori. Se vuoi saperne di pi\u00f9, leggi l'articolo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/it\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\/","og_locale":"it_IT","og_type":"article","og_title":"Walltopia annuncia un nuovo programma di finanziamento delle attrezzature in leasing","og_description":"Stiamo introducendo il programma di finanziamento con leasing di attrezzature Walltopia, pensato per supportare gli imprenditori. Se vuoi saperne di pi\u00f9, leggi l'articolo.","og_url":"https:\/\/walltopia.com\/it\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2021-02-23T08:11:41+00:00","article_modified_time":"2026-01-15T14:54:44+00:00","og_image":[{"width":256,"height":171,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144526\/Walltopia-Equipment-Lease-Financing-Program-2-1.jpg","type":"image\/jpeg"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/it\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Walltopia annuncia un nuovo programma di finanziamento delle attrezzature in leasing","datePublished":"2021-02-23T08:11:41+00:00","dateModified":"2026-01-15T14:54:44+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/it\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\/"},"wordCount":645,"commentCount":0,"publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/it\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144526\/Walltopia-Equipment-Lease-Financing-Program-2-1.jpg","keywords":["Locazione di attrezzature","Noleggio attrezzature Walltopia","Programma di finanziamento per il leasing di attrezzature"],"articleSection":["Intrattenimento attivo","Sala stampa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/walltopia.com\/it\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/it\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\/","url":"https:\/\/walltopia.com\/it\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\/","name":"Walltopia annuncia un nuovo programma di finanziamento delle attrezzature in leasing | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/it\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/it\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144526\/Walltopia-Equipment-Lease-Financing-Program-2-1.jpg","datePublished":"2021-02-23T08:11:41+00:00","dateModified":"2026-01-15T14:54:44+00:00","description":"Stiamo introducendo il programma di finanziamento con leasing di attrezzature Walltopia, pensato per supportare gli imprenditori. Se vuoi saperne di pi\u00f9, leggi l'articolo.","breadcrumb":{"@id":"https:\/\/walltopia.com\/it\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/it\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144526\/Walltopia-Equipment-Lease-Financing-Program-2-1.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144526\/Walltopia-Equipment-Lease-Financing-Program-2-1.jpg","width":256,"height":171},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/it\/walltopia-annuncia-un-nuovo-programma-di-finanziamento-delle-attrezzature-in-leasing-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/it\/casa-it\/"},{"@type":"ListItem","position":2,"name":"Walltopia annuncia un nuovo programma di finanziamento delle attrezzature in leasing"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/it\/#website","url":"https:\/\/walltopia.com\/it\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/it\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/195505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/comments?post=195505"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/195505\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media\/95991"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media?parent=195505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/categories?post=195505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/tags?post=195505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}