{"id":195621,"date":"2021-02-23T09:22:35","date_gmt":"2021-02-23T06:22:35","guid":{"rendered":"https:\/\/walltopia.com\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\/"},"modified":"2026-01-15T17:55:04","modified_gmt":"2026-01-15T14:55:04","slug":"prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone","status":"publish","type":"post","link":"https:\/\/walltopia.com\/it\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\/","title":{"rendered":"Prosegue la proficua collaborazione tra Walltopia e Tosho Associate Corporation in Giappone"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1616079143920{padding-bottom: 3% !important;}&#8221;]\n<h5>Walltopia ha annunciato che la sua partnership con Tosho Associate Corporation in Giappone \u00e8 stata rafforzata con la firma di un accordo di distribuzione continua la scorsa settimana.<\/h5>\n[\/vc_column_text][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><a href=\"https:\/\/www.climbing-tosho.com\/en\/\" target=\"_blank\" rel=\"noopener\">Tosho Associate Corporation<\/a> rappresenta Walltopia sul mercato giapponese dal 2015. Essendo l&#8217;intrattenimento attivo sempre pi\u00f9 popolare in Giappone, non sorprende che il numero di <a href=\"https:\/\/staging-3.walltopia.com\/industries\/family-entertainment-centers\/\" target=\"_blank\" rel=\"noopener\">centri di intrattenimento per famiglie<\/a> orientati allo sport prodotti da Walltopia per i clienti giapponesi sia cresciuto costantemente in questi anni. <\/p>\n[\/vc_column_text]<blockquote class=\"custom relative full-width-container margin-bottom-25\" style=\"color: #ffffff; font-size: 24px; line-height: 1.5; background-color: #333144;\"><div class=\"content block width-100 float-left\"><strong>\u201cWalltopia Active Entertainment products are very attractive and in high demand. We have already installed them in facilities across Japan in 10 different locations,\u201d commented Kensuke Namekawa, Director of Tosho Associate Corporation.<\/strong><\/div><span class=\"dashicons dashicons-format-quote\" style=\"color: #ffffff;\"><\/span><\/blockquote>[vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><em>&#8220;Siamo lieti di annunciare che Walltopia <a href=\"https:\/\/staging-3.walltopia.com\/products\/fun-walls\/\" target=\"_blank\" rel=\"noopener\">Fun Walls<\/a> pu\u00f2 essere vissuta da bambini e adulti in 8 localit\u00e0 nelle prefetture di Hokkaido, Chiba, Niigata, Hiroshima e Fukuoka. Due grandi <a href=\"https:\/\/staging-3.walltopia.com\/products\/ropes-course\/\" target=\"_blank\" rel=\"noopener\">percorsi a corde<\/a> possono essere esplorati anche nelle prefetture di Chiba e Fukuoka, mentre l&#8217;esclusiva zipline <a href=\"https:\/\/staging-3.walltopia.com\/products\/rollglider\/\" target=\"_blank\" rel=\"noopener\">Rollglider\u00ae<\/a>permette di provare la sensazione del volo libero nelle prefetture di Yamanashi e Fukuoka&#8221;, ha continuato Namekawa. <\/em><\/p>\n[\/vc_column_text][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><em><strong>&#8220;Siamo molto felici di continuare a sostenere Tosho Associate Corporation nei suoi sforzi per crescere ulteriormente nel mercato e fornire attrazioni di alta qualit\u00e0 al suo territorio. La nostra partnership \u00e8 un esempio di simbiosi perfetta tra due aziende che eccellono nel loro settore&#8221;,<\/strong> ha dichiarato Zlatimira Bancheva, responsabile delle vendite della divisione Active Entertainment di Walltopia.<\/em><\/p>\n[\/vc_column_text][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">I partner si impegnano a continuare a fornire in modo proattivo prodotti e servizi interessanti ed esperienze che combinano lo sport con il divertimento e una sana dose di adrenalina alle famiglie e alle persone di tutte le et\u00e0 in Giappone.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_column_text css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1616079143920{padding-bottom: 3% !important;}&#8221;] Walltopia ha annunciato che la sua partnership con Tosho Associate Corporation in Giappone \u00e8 stata&#8230;","protected":false},"author":5,"featured_media":95982,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[914,908],"tags":[4505,4507,4506],"class_list":["post-195621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intrattenimento-attivo","category-sala-stampa","tag-partnership","tag-tosho-associate-corporation","tag-walltopia-giappone"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Prosegue la proficua collaborazione tra Walltopia e Tosho Associate Corporation in Giappone | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/it\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prosegue la proficua collaborazione tra Walltopia e Tosho Associate Corporation in Giappone\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1616079143920{padding-bottom: 3% !important;}&#8221;] Walltopia ha annunciato che la sua partnership con Tosho Associate Corporation in Giappone \u00e8 stata...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/it\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-23T06:22:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:55:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144539\/nobolt-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Prosegue la proficua collaborazione tra Walltopia e Tosho Associate Corporation in Giappone\",\"datePublished\":\"2021-02-23T06:22:35+00:00\",\"dateModified\":\"2026-01-15T14:55:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\\\/\"},\"wordCount\":353,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027144539\\\/nobolt-01.jpg\",\"keywords\":[\"Partnership\",\"Tosho Associate Corporation\",\"Walltopia Giappone\"],\"articleSection\":[\"Intrattenimento attivo\",\"Sala stampa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\\\/\",\"name\":\"Prosegue la proficua collaborazione tra Walltopia e Tosho Associate Corporation in Giappone | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027144539\\\/nobolt-01.jpg\",\"datePublished\":\"2021-02-23T06:22:35+00:00\",\"dateModified\":\"2026-01-15T14:55:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027144539\\\/nobolt-01.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027144539\\\/nobolt-01.jpg\",\"width\":960,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/casa-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prosegue la proficua collaborazione tra Walltopia e Tosho Associate Corporation in Giappone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Prosegue la proficua collaborazione tra Walltopia e Tosho Associate Corporation in Giappone | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/it\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\/","og_locale":"it_IT","og_type":"article","og_title":"Prosegue la proficua collaborazione tra Walltopia e Tosho Associate Corporation in Giappone","og_description":"[vc_row][vc_column][vc_column_text css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1616079143920{padding-bottom: 3% !important;}&#8221;] Walltopia ha annunciato che la sua partnership con Tosho Associate Corporation in Giappone \u00e8 stata...","og_url":"https:\/\/walltopia.com\/it\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2021-02-23T06:22:35+00:00","article_modified_time":"2026-01-15T14:55:04+00:00","og_image":[{"width":960,"height":720,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144539\/nobolt-01.jpg","type":"image\/jpeg"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/it\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Prosegue la proficua collaborazione tra Walltopia e Tosho Associate Corporation in Giappone","datePublished":"2021-02-23T06:22:35+00:00","dateModified":"2026-01-15T14:55:04+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/it\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\/"},"wordCount":353,"commentCount":0,"publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/it\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144539\/nobolt-01.jpg","keywords":["Partnership","Tosho Associate Corporation","Walltopia Giappone"],"articleSection":["Intrattenimento attivo","Sala stampa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/walltopia.com\/it\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/it\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\/","url":"https:\/\/walltopia.com\/it\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\/","name":"Prosegue la proficua collaborazione tra Walltopia e Tosho Associate Corporation in Giappone | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/it\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/it\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144539\/nobolt-01.jpg","datePublished":"2021-02-23T06:22:35+00:00","dateModified":"2026-01-15T14:55:04+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/it\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/it\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144539\/nobolt-01.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144539\/nobolt-01.jpg","width":960,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/it\/prosegue-la-proficua-collaborazione-tra-walltopia-e-tosho-associate-corporation-in-giappone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/it\/casa-it\/"},{"@type":"ListItem","position":2,"name":"Prosegue la proficua collaborazione tra Walltopia e Tosho Associate Corporation in Giappone"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/it\/#website","url":"https:\/\/walltopia.com\/it\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/it\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/195621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/comments?post=195621"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/195621\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media\/95982"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media?parent=195621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/categories?post=195621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/tags?post=195621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}