{"id":196399,"date":"2020-07-09T13:32:24","date_gmt":"2020-07-09T10:32:24","guid":{"rendered":"https:\/\/walltopia.com\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\/"},"modified":"2026-01-15T17:56:57","modified_gmt":"2026-01-15T14:56:57","slug":"rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2","status":"publish","type":"post","link":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\/","title":{"rendered":"Rivestimento Walltopia Duplex: La nostra soluzione contro la corrosione"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_custom_heading text=&#8221;Rivestimento duplex: acciaio zincato a caldo con vernice polimerica sulla parte superiore del nostro percorso di corde a Playtopia Pachuca, in Messico.&#8221; font_container=&#8221;tag:p|font_size:12px|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221; css=&#8221;&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Magari non arriva sempre con un botto immediato, come fanno i terremoti, i tornado e gli uragani, ma questo silenzioso e lento distruttore costa all&#8217;economia statunitense pi\u00f9 di tutti gli altri disastri naturali messi insieme, arrivando a 437 miliardi di dollari all&#8217;anno o al 3% del PIL degli Stati Uniti*.<\/strong><\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Hai gi\u00e0 indovinato? No? Ok, ecco un altro indizio: questa minaccia dilagante trasforma una tonnellata di acciaio in ruggine ogni 90 secondi, in tutto il mondo. S\u00ec, esattamente! \u00c8 la corrosione!    <\/p>\n<h4>Che cos&#8217;\u00e8 la corrosione?<\/h4>\n<p style=\"font-size: 18px; line-height: 1.8em;\">La corrosione influisce sulla durata dei nostri beni, aumenta i costi di riparazione e manutenzione, fa crollare edifici e chiudere impianti industriali, provoca esplosioni, perdite tossiche e incendi. La protezione dalla corrosione \u00e8 legata a molte industrie e settori come i trasporti, le apparecchiature energetiche, l&#8217;approvvigionamento idrico e l&#8217;ingegneria delle infrastrutture. Non c&#8217;\u00e8 quasi nessuna azienda Fortune 500, oltre a quelle del settore finanziario, assicurativo o bancario, che non abbia a che fare direttamente con la corrosione, mentre i costi sostenuti da produttori e fornitori di beni e servizi vengono trasferiti ai clienti.  <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">La corrosione pu\u00f2 essere definita in senso lato come qualsiasi interazione chimica o elettrochimica tra un materiale e il suo ambiente, che causa il deterioramento del materiale e delle sue propriet\u00e0. Proprio come l&#8217;acqua scorre verso il livello pi\u00f9 basso, i processi naturali hanno la tendenza ad andare alla deriva verso gli stati energetici pi\u00f9 bassi possibili. Per la maggior parte dei metalli, ad eccezione di quelli nobili, lo stato energetico pi\u00f9 basso \u00e8 la forma di ossidi, proprio come il minerale metallico da cui sono stati lavorati. I metalli sono destinati a tornare lentamente a questo stato se non si prendono le dovute precauzioni.   <\/p>\n<h4>Fattori che influenzano i tassi di corrosione<\/h4>\n<p style=\"font-size: 18px; line-height: 1.8em;\">La velocit\u00e0 di attacco corrosivo di un determinato elemento metallico dipende dalle propriet\u00e0 chimiche intrinseche del metallo stesso e dalla corrosivit\u00e0 dell&#8217;ambiente in cui si trova. Ambienti umidi, inquinati dall&#8217;industria e saturi di acqua salata sono particolarmente aggressivi per le strutture metalliche. <\/p>\n<h4>Metodi per rallentare la corrosione<\/h4>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Tuttavia, esistono diversi metodi per rallentare la corrosione. Uno di questi \u00e8 l&#8217;applicazione di un rivestimento metallico sacrificale, che isola il metallo sottostante dagli agenti corrosivi. Questo pu\u00f2 essere ottenuto con la zincatura, ovvero immergendo elementi di acciaio accuratamente preparati nello zinco fuso. Il risultato \u00e8 uno strato protettivo di zinco, legato metallurgicamente al substrato di acciaio tramite una lega di ferro e zinco. Questo tipo di protezione dalla corrosione prolunga la vita utile delle strutture in acciaio di almeno 20-40 anni in ambienti industriali e fino a 100 anni in aree poco inquinate. I rivestimenti polimerici, o semplicemente vernici, hanno lo stesso scopo dei rivestimenti metallici, ma sono in grado di prolungarne la durata fino a 10 anni.     <\/p>\n<h4>L&#8217;approccio di Walltopia: Il rivestimento Duplex<\/h4>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Le opere in acciaio sono una parte essenziale dell&#8217;ingegneria strutturale di Walltopia. Per questo ci sentiamo obbligati a non generare costi evitabili legati alla corrosione. Il nostro modo per farlo \u00e8 offrire a tutte le nostre strutture in acciaio per esterni un &#8220;rivestimento duplex&#8221;. Si tratta di uno strato di vernice polimerica che si aggiunge allo strato di zinco. Grazie all&#8217;effetto sinergico, i sistemi duplex hanno una durata da 1,2 a 1,5 volte superiore ai periodi di protezione combinati della zincatura a caldo e della verniciatura.    <\/p>\n<h4>Garantire sicurezza e longevit\u00e0 con il rivestimento Duplex<\/h4>\n<p>Il nostro contributo a un mondo meno arrugginito forse non risolve i problemi di corrosione globale, ma protegge gli investimenti dei nostri clienti. Garantiamo la sicurezza dei loro clienti prolungando la durata delle costruzioni in acciaio per esterni delle attrazioni e delle strutture che realizziamo. <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">* &#8220;Rust: La guerra pi\u00f9 lunga&#8221; di Jonathan Waldman<\/p>\n[\/vc_column_text][vc_separator css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1616156063064{padding-bottom: 1% !important;}&#8221;][vc_custom_heading text=&#8221;FONTI&#8221; font_container=&#8221;tag:h4|font_size:14px|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 14px; line-height: 1.8em;\">&#8220;Protezione dalla corrosione&#8221; di ArcelorMittal Europe<br \/>\n&#8220;Corrosione: Capire le basi&#8221; di ASM International<br \/>\n&#8220;La ruggine: La guerra pi\u00f9 lunga&#8221; di Jonathan Waldman<br \/>\n&#8220;Il costo della corrosione in Cina&#8221; di Baorong Hou, Istituto di Oceanologia, Accademia Cinese delle Scienze, Qingdao, Shandong, Cina<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_custom_heading text=&#8221;Rivestimento duplex: acciaio zincato a caldo con vernice polimerica sulla parte superiore del nostro percorso di corde a Playtopia&#8230;","protected":false},"author":5,"featured_media":95922,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[909,914],"tags":[4665,4666,2602,4667],"class_list":["post-196399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arrampicata","category-intrattenimento-attivo","tag-corrosione","tag-ingegneria-strutturale","tag-rivestimento-duplex","tag-strutture-in-acciaio"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Rivestimento Walltopia Duplex: La nostra soluzione contro la corrosione | Walltopia<\/title>\n<meta name=\"description\" content=\"Forse non arriva sempre con un botto, ma questo silenzioso e lento distruttore costa all&#039;economia statunitense pi\u00f9 di tutti gli altri disastri naturali.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rivestimento Walltopia Duplex: La nostra soluzione contro la corrosione\" \/>\n<meta property=\"og:description\" content=\"Forse non arriva sempre con un botto, ma questo silenzioso e lento distruttore costa all&#039;economia statunitense pi\u00f9 di tutti gli altri disastri naturali.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-09T10:32:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:56:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144732\/WhatsApp-Image-2020-02-12-at-23.07.211-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Rivestimento Walltopia Duplex: La nostra soluzione contro la corrosione\",\"datePublished\":\"2020-07-09T10:32:24+00:00\",\"dateModified\":\"2026-01-15T14:56:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\\\/\"},\"wordCount\":758,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027144732\\\/WhatsApp-Image-2020-02-12-at-23.07.211-1.jpeg\",\"keywords\":[\"Corrosione\",\"Ingegneria strutturale\",\"Rivestimento Duplex\",\"Strutture in acciaio\"],\"articleSection\":[\"Arrampicata\",\"Intrattenimento attivo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\\\/\",\"name\":\"Rivestimento Walltopia Duplex: La nostra soluzione contro la corrosione | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027144732\\\/WhatsApp-Image-2020-02-12-at-23.07.211-1.jpeg\",\"datePublished\":\"2020-07-09T10:32:24+00:00\",\"dateModified\":\"2026-01-15T14:56:57+00:00\",\"description\":\"Forse non arriva sempre con un botto, ma questo silenzioso e lento distruttore costa all'economia statunitense pi\u00f9 di tutti gli altri disastri naturali.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027144732\\\/WhatsApp-Image-2020-02-12-at-23.07.211-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027144732\\\/WhatsApp-Image-2020-02-12-at-23.07.211-1.jpeg\",\"width\":1200,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/casa-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rivestimento Walltopia Duplex: La nostra soluzione contro la corrosione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rivestimento Walltopia Duplex: La nostra soluzione contro la corrosione | Walltopia","description":"Forse non arriva sempre con un botto, ma questo silenzioso e lento distruttore costa all'economia statunitense pi\u00f9 di tutti gli altri disastri naturali.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\/","og_locale":"it_IT","og_type":"article","og_title":"Rivestimento Walltopia Duplex: La nostra soluzione contro la corrosione","og_description":"Forse non arriva sempre con un botto, ma questo silenzioso e lento distruttore costa all'economia statunitense pi\u00f9 di tutti gli altri disastri naturali.","og_url":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2020-07-09T10:32:24+00:00","article_modified_time":"2026-01-15T14:56:57+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144732\/WhatsApp-Image-2020-02-12-at-23.07.211-1.jpeg","type":"image\/jpeg"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Rivestimento Walltopia Duplex: La nostra soluzione contro la corrosione","datePublished":"2020-07-09T10:32:24+00:00","dateModified":"2026-01-15T14:56:57+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\/"},"wordCount":758,"commentCount":0,"publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144732\/WhatsApp-Image-2020-02-12-at-23.07.211-1.jpeg","keywords":["Corrosione","Ingegneria strutturale","Rivestimento Duplex","Strutture in acciaio"],"articleSection":["Arrampicata","Intrattenimento attivo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\/","url":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\/","name":"Rivestimento Walltopia Duplex: La nostra soluzione contro la corrosione | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144732\/WhatsApp-Image-2020-02-12-at-23.07.211-1.jpeg","datePublished":"2020-07-09T10:32:24+00:00","dateModified":"2026-01-15T14:56:57+00:00","description":"Forse non arriva sempre con un botto, ma questo silenzioso e lento distruttore costa all'economia statunitense pi\u00f9 di tutti gli altri disastri naturali.","breadcrumb":{"@id":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144732\/WhatsApp-Image-2020-02-12-at-23.07.211-1.jpeg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144732\/WhatsApp-Image-2020-02-12-at-23.07.211-1.jpeg","width":1200,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/it\/rivestimento-walltopia-duplex-la-nostra-soluzione-contro-la-corrosione-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/it\/casa-it\/"},{"@type":"ListItem","position":2,"name":"Rivestimento Walltopia Duplex: La nostra soluzione contro la corrosione"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/it\/#website","url":"https:\/\/walltopia.com\/it\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/it\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/196399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/comments?post=196399"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/196399\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media\/95922"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media?parent=196399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/categories?post=196399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/tags?post=196399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}