{"id":196898,"date":"2020-07-15T08:59:49","date_gmt":"2020-07-15T05:59:49","guid":{"rendered":"https:\/\/walltopia.com\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\/"},"modified":"2026-01-15T17:58:38","modified_gmt":"2026-01-15T14:58:38","slug":"walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale","status":"publish","type":"post","link":"https:\/\/walltopia.com\/it\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\/","title":{"rendered":"Walltopia lavorer\u00e0 con Zipline Korea, Inc. come distributore ufficiale"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Walltopia ha annunciato una nuova partnership sul mercato coreano e la buona notizia \u00e8 che il paese potr\u00e0 ora beneficiare dell&#8217;esperienza dell&#8217;azienda nello sviluppo di complessi <a href=\"https:\/\/staging-3.walltopia.com\/projects\/\" target=\"_blank\" rel=\"noopener\">progetti di intrattenimento attivo<\/a> che portano le attrazioni a un livello completamente nuovo.<\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\"><a href=\"http:\/\/ziplinekorea.net\/eng.index.php\" target=\"_blank\" rel=\"noopener noreferrer\">Zipline Korea<\/a> ha sede a Seoul, in Corea del Sud, ed \u00e8 il pi\u00f9 grande fornitore di attrazioni zip line del paese con oltre 10 anni di esperienza nel settore. Membro da tempo dell&#8217;Association for Challenge Course Technology <a href=\"https:\/\/www.acctinfo.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">(ACCT)<\/a>, Zipline Korea \u00e8 destinata a diventare un rappresentante di successo di Walltopia sul territorio. <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Tutto questo avviene dopo un processo approfondito durante il quale Zipline Korea, Inc. e il suo team hanno seguito un programma di formazione approfondito con Walltopia, assicurandosi cos\u00ec di essere in grado di fornire ai clienti coreani tutto ci\u00f2 che Walltopia ha da offrire.<\/p>\n[\/vc_column_text]<blockquote class=\"custom relative full-width-container margin-bottom-25\" style=\"color: #ffffff; font-size: 24px; line-height: 1.5; background-color: #333144;\"><div class=\"content block width-100 float-left\">\u201cWe see great potential in our collaboration and we are very excited to see our first projects being designed.\u201d said Zlatimira Bancheva, Sales Director of Walltopia. \u201cBefore entering the partnership Zipline Korea visited Bulgaria and took part in a series of presentations of all of our products. They visited our production plants, participated in workshops and were able to experience first hand our latest developments and technologies\u201d continued Zlatimira.<\/div><span class=\"dashicons dashicons-format-quote\" style=\"color: #ffffff;\"><\/span><\/blockquote>[vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">I servizi che verranno offerti al mercato coreano comprendono architettura e design, ingegneria, gestione del progetto, produzione, assemblaggio, manutenzione e ispezione. La gamma di prodotti comprende attrazioni per l&#8217;intrattenimento attivo per tutti i livelli di abilit\u00e0, tra cui <a href=\"https:\/\/staging-3.walltopia.com\/products\/ropes-course\/\" target=\"_blank\" rel=\"noopener\">corsi di corde<\/a>, <a href=\"https:\/\/staging-3.walltopia.com\/products\/fun-walls\/\" target=\"_blank\" rel=\"noopener\">Fun Walls<\/a>, <a href=\"https:\/\/staging-3.walltopia.com\/products\/walltopia-caves\/\" target=\"_blank\" rel=\"noopener\">grotte artificiali<\/a>, <a href=\"http:\/\/walltopia.com\/en\/climbing-walls\/rope-and-bouldering-walls\" target=\"_blank\" rel=\"noopener\">pareti di arrampicata Boulder<\/a> e <a href=\"https:\/\/staging-3.walltopia.com\/products\/ninja-course\/\" target=\"_blank\" rel=\"noopener\">corsi Ninja<\/a> che rendono l&#8217;allenamento fisico divertente e vario. Walltopia \u00e8 stata anche la prima a presentare al settore il <a href=\"https:\/\/staging-3.walltopia.com\/products\/rollglider\/\" target=\"_blank\" rel=\"noopener\">Rollglider<\/a> di Safety Engineering, una zipline con montagne russe che offre un&#8217;esperienza di volo libero in un ambiente completamente sicuro.  <\/p>\n[\/vc_column_text]<blockquote class=\"custom relative full-width-container \" style=\"color: #ffffff; font-size: 24px; line-height: 1.5; background-color: #333144;\"><div class=\"content block width-100 float-left\">\u201cOur ambition is to bring to Korea projects that incorporate a number of active entertainment products in one. This is Walltopia\u2019s specialty. The company has a proven track record of delivering hubs for adventures that combine sport, adrenaline and fun and engage people in the experience of multiple different activities in one visit\u201d said Mr Jeffrey Wonkyu Jung, CEO of Zipline Korea Inc. \u201cWhat makes Walltopia different is that no matter how complex a project is, their team delivers expected results \u2013 starting with the design, moving on to the installation and finally \u2013 the certification. We have seen the great examples of their work and the expertise of their team and now know that we can confidently offer their products in Korea.\u201d<\/div><span class=\"dashicons dashicons-format-quote\" style=\"color: #ffffff;\"><\/span><\/blockquote>[\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_column_text css_animation=&#8221;fadeInUp&#8221;] Walltopia ha annunciato una nuova partnership sul mercato coreano e la buona notizia \u00e8 che il paese potr\u00e0&#8230;","protected":false},"author":5,"featured_media":95877,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[914],"tags":[911,4505,4819],"class_list":["post-196898","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intrattenimento-attivo","tag-intrattenimento-attivo","tag-partnership","tag-zipline-corea"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Walltopia lavorer\u00e0 con Zipline Korea, Inc. come distributore ufficiale | Walltopia<\/title>\n<meta name=\"description\" content=\"Walltopia ha annunciato una nuova partnership sul mercato coreano per lo sviluppo di complessi progetti di intrattenimento attivo. Leggi l&#039;articolo per saperne di pi\u00f9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/it\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Walltopia lavorer\u00e0 con Zipline Korea, Inc. come distributore ufficiale\" \/>\n<meta property=\"og:description\" content=\"Walltopia ha annunciato una nuova partnership sul mercato coreano per lo sviluppo di complessi progetti di intrattenimento attivo. Leggi l&#039;articolo per saperne di pi\u00f9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/it\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-15T05:59:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:58:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144848\/zipline_wallltopia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"761\" \/>\n\t<meta property=\"og:image:height\" content=\"449\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Walltopia lavorer\u00e0 con Zipline Korea, Inc. come distributore ufficiale\",\"datePublished\":\"2020-07-15T05:59:49+00:00\",\"dateModified\":\"2026-01-15T14:58:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\\\/\"},\"wordCount\":507,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027144848\\\/zipline_wallltopia.jpg\",\"keywords\":[\"intrattenimento attivo\",\"Partnership\",\"Zipline Corea\"],\"articleSection\":[\"Intrattenimento attivo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\\\/\",\"name\":\"Walltopia lavorer\u00e0 con Zipline Korea, Inc. come distributore ufficiale | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027144848\\\/zipline_wallltopia.jpg\",\"datePublished\":\"2020-07-15T05:59:49+00:00\",\"dateModified\":\"2026-01-15T14:58:38+00:00\",\"description\":\"Walltopia ha annunciato una nuova partnership sul mercato coreano per lo sviluppo di complessi progetti di intrattenimento attivo. Leggi l'articolo per saperne di pi\u00f9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027144848\\\/zipline_wallltopia.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027144848\\\/zipline_wallltopia.jpg\",\"width\":761,\"height\":449},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/casa-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Walltopia lavorer\u00e0 con Zipline Korea, Inc. come distributore ufficiale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Walltopia lavorer\u00e0 con Zipline Korea, Inc. come distributore ufficiale | Walltopia","description":"Walltopia ha annunciato una nuova partnership sul mercato coreano per lo sviluppo di complessi progetti di intrattenimento attivo. Leggi l'articolo per saperne di pi\u00f9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/it\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\/","og_locale":"it_IT","og_type":"article","og_title":"Walltopia lavorer\u00e0 con Zipline Korea, Inc. come distributore ufficiale","og_description":"Walltopia ha annunciato una nuova partnership sul mercato coreano per lo sviluppo di complessi progetti di intrattenimento attivo. Leggi l'articolo per saperne di pi\u00f9.","og_url":"https:\/\/walltopia.com\/it\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2020-07-15T05:59:49+00:00","article_modified_time":"2026-01-15T14:58:38+00:00","og_image":[{"width":761,"height":449,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144848\/zipline_wallltopia.jpg","type":"image\/jpeg"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/it\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Walltopia lavorer\u00e0 con Zipline Korea, Inc. come distributore ufficiale","datePublished":"2020-07-15T05:59:49+00:00","dateModified":"2026-01-15T14:58:38+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/it\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\/"},"wordCount":507,"commentCount":0,"publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/it\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144848\/zipline_wallltopia.jpg","keywords":["intrattenimento attivo","Partnership","Zipline Corea"],"articleSection":["Intrattenimento attivo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/walltopia.com\/it\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/it\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\/","url":"https:\/\/walltopia.com\/it\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\/","name":"Walltopia lavorer\u00e0 con Zipline Korea, Inc. come distributore ufficiale | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/it\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/it\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144848\/zipline_wallltopia.jpg","datePublished":"2020-07-15T05:59:49+00:00","dateModified":"2026-01-15T14:58:38+00:00","description":"Walltopia ha annunciato una nuova partnership sul mercato coreano per lo sviluppo di complessi progetti di intrattenimento attivo. Leggi l'articolo per saperne di pi\u00f9.","breadcrumb":{"@id":"https:\/\/walltopia.com\/it\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/it\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144848\/zipline_wallltopia.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144848\/zipline_wallltopia.jpg","width":761,"height":449},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/it\/walltopia-lavorera-con-zipline-korea-inc-come-distributore-ufficiale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/it\/casa-it\/"},{"@type":"ListItem","position":2,"name":"Walltopia lavorer\u00e0 con Zipline Korea, Inc. come distributore ufficiale"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/it\/#website","url":"https:\/\/walltopia.com\/it\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/it\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/it\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/196898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/comments?post=196898"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/posts\/196898\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media\/95877"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media?parent=196898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/categories?post=196898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/tags?post=196898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}