{"id":211790,"date":"2025-02-18T16:01:44","date_gmt":"2025-02-18T13:01:44","guid":{"rendered":"https:\/\/walltopia.com\/products\/senza-categoria\/tetris\/"},"modified":"2026-01-15T22:48:11","modified_gmt":"2026-01-15T19:48:11","slug":"tetris","status":"publish","type":"product","link":"https:\/\/walltopia.com\/it\/product\/muri-del-divertimento-a-cartoni-animati\/tetris\/","title":{"rendered":"Tetris"},"content":{"rendered":"<p>*Il percorso \u00e8 predeterminato e presenta un secondo livello di difficolt\u00e0.<\/p>\n<p><strong>Specifiche tecniche:<\/strong><\/p>\n<h4>Tipo di struttura<\/h4>\n<p>Tetris \u00e8 dotato di una struttura in acciaio standard che deve essere ancorata al pavimento e alla parte superiore del telaio. La struttura per esterni viene zincata a caldo per garantirne la durata e la resistenza agli agenti atmosferici in tutto il mondo. <\/p>\n<h4>Ancoraggio<\/h4>\n<p>\u00c8 necessario ancorare due piastre di base in acciaio, ciascuna con quattro ancoraggi nella parte inferiore, e fissare due punti di fissaggio nella parte superiore. I punti di fissaggio superiori possono variare a seconda dello spazio di installazione per sostenere correttamente il Tetris. La struttura deve essere ancorata a una solida lastra di cemento con uno spessore minimo di 15 cm. Per assicurarti che il tuo pavimento sia in grado di sostenere il Tetris Funwall <strong>, allega i calcoli statici dei carichi<\/strong> <em>Walltopia Standard Loads File<\/em> <strong>nella sezione scaricabile e consulta sempre il tuo ingegnere o un professionista qualificato.<\/strong>   <\/p>\n<h4>Posizionamento<\/h4>\n<p>Il Tetris deve essere posizionato lontano da oggetti duri come colonne di edifici, ringhiere, mobili o altro. Le dimensioni della zona di sicurezza sono definite nelle immagini del prodotto. Questa \u00e8 la zona che \u00e8 obbligatorio mantenere libera da qualsiasi ostacolo.  <\/p>\n<h4>Pannelli laterali<\/h4>\n<p>I pannelli laterali <strong>NON sono inclusi<\/strong> nel prezzo del prodotto. Se desideri acquistare dei pannelli laterali per le tue Fun Walls, visita la nostra pagina di prodotti <em><span style=\"text-decoration: underline;\">pagina del prodotto Pannelli laterali<\/span><\/em> e consulta uno dei nostri tecnici. <\/p>\n<h4>Pavimenti<\/h4>\n<p>Ti consigliamo vivamente di installare una pavimentazione di sicurezza nella zona di sicurezza intorno a ogni parete da arrampicata. Puoi acquistare Rope Wall Mat di 15 cm di spessore con finitura in moquette grigia o One More Life Safety Flooring da Walltopia o installare un altro tipo di pavimentazione che assorba gli urti. <\/p>\n<h4>Prodotti aggiuntivi<\/h4>\n<p>Questo prodotto non pu\u00f2 essere utilizzato senza un sistema di autobloccanti!<\/p>\n<p>Le nostre strutture Fun Walls sono compatibili con Tru Blue Auto Belay di Headrush e Perfect Descend Auto Belay Device.<\/p>\n<p>Non dimenticare di dare un&#8217;occhiata ai nostri accessori di sicurezza. I cancelli di sicurezza facilitano il funzionamento e riducono il rischio di arrampicata non sicura. La fettuccia di assicurazione automatica viene fissata quando nessuno si arrampica. La fettuccia di sicurezza automatica viene fissata quando nessuno si arrampica.   <\/p>\n<p>Scegli di installare il nostro Smart Gate e riduci al minimo il rischio di incidenti. Ti consigliamo anche il nostro sistema Self Belay che non solo contribuisce alla sicurezza dell&#8217;arrampicata, ma aiuta anche le operazioni riducendo il numero di membri del personale necessari: i partecipanti di et\u00e0 compresa tra i 5 anni possono utilizzare il dispositivo da soli, senza alcuna supervisione! <\/p>\n<h4>Opzioni di spedizione<\/h4>\n<p>Questo prodotto viene spedito in parti e deve essere assemblato alla consegna. Tutti i componenti, compresa la struttura in acciaio, sono progettati per essere assemblati facilmente. Vengono fornite istruzioni dettagliate per garantire che il prodotto finale sia sicuro da utilizzare e abbia un aspetto e una finitura eccellenti.  <\/p>\n<h4>Macchinari necessari per l&#8217;assemblaggio<\/h4>\n<p>Elenco degli strumenti: Avvitatore a percussione, Trapano, Smerigliatrice angolare, Pistola a percussione &#8211; prese 17\/ 19, Seghetto alternativo, Chiavi manuali &#8211; 13 \/ 17 \/ 19 \/ 24, Pilastri, Nastri di misura<\/p>\n<p>Macchinari: Sollevatore a forbice in grado di sollevare 260 kg fino a 8 metri, carrello elevatore 2T &#8211; per lo scarico, martinetto per pallet<\/p>\n","protected":false},"excerpt":{"rendered":"*Il percorso \u00e8 predeterminato e presenta un secondo livello di difficolt\u00e0. Specifiche tecniche: Tipo di struttura Tetris \u00e8 dotato di&#8230;","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"product_brand":[],"product_cat":[7244],"product_tag":[],"class_list":["post-211790","product","type-product","status-publish","product_cat-muri-del-divertimento-a-cartoni-animati","first","onbackorder","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tetris | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/it\/product\/muri-del-divertimento-a-cartoni-animati\/tetris\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tetris\" \/>\n<meta property=\"og:description\" content=\"*Il percorso \u00e8 predeterminato e presenta un secondo livello di difficolt\u00e0. Specifiche tecniche: Tipo di struttura Tetris \u00e8 dotato di...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/it\/product\/muri-del-divertimento-a-cartoni-animati\/tetris\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T19:48:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027181057\/Walltopia_Fun_Walls_Tetris-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"841\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/product\\\/muri-del-divertimento-a-cartoni-animati\\\/tetris\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/product\\\/muri-del-divertimento-a-cartoni-animati\\\/tetris\\\/\",\"name\":\"Tetris | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\"},\"datePublished\":\"2025-02-18T13:01:44+00:00\",\"dateModified\":\"2026-01-15T19:48:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/product\\\/muri-del-divertimento-a-cartoni-animati\\\/tetris\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/product\\\/muri-del-divertimento-a-cartoni-animati\\\/tetris\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/product\\\/muri-del-divertimento-a-cartoni-animati\\\/tetris\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/casa-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tetris\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tetris | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/it\/product\/muri-del-divertimento-a-cartoni-animati\/tetris\/","og_locale":"it_IT","og_type":"article","og_title":"Tetris","og_description":"*Il percorso \u00e8 predeterminato e presenta un secondo livello di difficolt\u00e0. Specifiche tecniche: Tipo di struttura Tetris \u00e8 dotato di...","og_url":"https:\/\/walltopia.com\/it\/product\/muri-del-divertimento-a-cartoni-animati\/tetris\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2026-01-15T19:48:11+00:00","og_image":[{"width":841,"height":1920,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027181057\/Walltopia_Fun_Walls_Tetris-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/it\/product\/muri-del-divertimento-a-cartoni-animati\/tetris\/","url":"https:\/\/walltopia.com\/it\/product\/muri-del-divertimento-a-cartoni-animati\/tetris\/","name":"Tetris | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/#website"},"datePublished":"2025-02-18T13:01:44+00:00","dateModified":"2026-01-15T19:48:11+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/it\/product\/muri-del-divertimento-a-cartoni-animati\/tetris\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/it\/product\/muri-del-divertimento-a-cartoni-animati\/tetris\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/it\/product\/muri-del-divertimento-a-cartoni-animati\/tetris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/it\/casa-it\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/walltopia.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Tetris"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/it\/#website","url":"https:\/\/walltopia.com\/it\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/it\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/product\/211790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/product\/211790\/revisions"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media?parent=211790"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/product_brand?post=211790"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/product_cat?post=211790"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/product_tag?post=211790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}