{"id":218180,"date":"2025-07-10T10:07:47","date_gmt":"2025-07-10T07:07:47","guid":{"rendered":"https:\/\/walltopia.com\/products\/senza-categoria\/corda-per-ponte-celeste\/"},"modified":"2026-01-15T23:11:47","modified_gmt":"2026-01-15T20:11:47","slug":"corda-per-ponte-celeste","status":"publish","type":"product","link":"https:\/\/walltopia.com\/it\/product\/ostacoli-del-percorso-ninja\/ostacoli-ninja-sospesi\/corda-per-ponte-celeste\/","title":{"rendered":"Corda per ponte celeste"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"product_brand":[],"product_cat":[7876,7877],"product_tag":[],"class_list":["post-218180","product","type-product","status-publish","product_cat-ostacoli-del-percorso-ninja","product_cat-ostacoli-ninja-sospesi","first","onbackorder","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Corda per ponte celeste | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/it\/product\/ostacoli-del-percorso-ninja\/ostacoli-ninja-sospesi\/corda-per-ponte-celeste\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corda per ponte celeste\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/it\/product\/ostacoli-del-percorso-ninja\/ostacoli-ninja-sospesi\/corda-per-ponte-celeste\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T20:11:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250710101213\/walltopia-ninja-course-obstacles-sky-bridge-rope-scaled-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1281\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/product\\\/ostacoli-del-percorso-ninja\\\/ostacoli-ninja-sospesi\\\/corda-per-ponte-celeste\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/product\\\/ostacoli-del-percorso-ninja\\\/ostacoli-ninja-sospesi\\\/corda-per-ponte-celeste\\\/\",\"name\":\"Corda per ponte celeste | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\"},\"datePublished\":\"2025-07-10T07:07:47+00:00\",\"dateModified\":\"2026-01-15T20:11:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/product\\\/ostacoli-del-percorso-ninja\\\/ostacoli-ninja-sospesi\\\/corda-per-ponte-celeste\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/product\\\/ostacoli-del-percorso-ninja\\\/ostacoli-ninja-sospesi\\\/corda-per-ponte-celeste\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/product\\\/ostacoli-del-percorso-ninja\\\/ostacoli-ninja-sospesi\\\/corda-per-ponte-celeste\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/casa-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Corda per ponte celeste\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Corda per ponte celeste | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/it\/product\/ostacoli-del-percorso-ninja\/ostacoli-ninja-sospesi\/corda-per-ponte-celeste\/","og_locale":"it_IT","og_type":"article","og_title":"Corda per ponte celeste","og_url":"https:\/\/walltopia.com\/it\/product\/ostacoli-del-percorso-ninja\/ostacoli-ninja-sospesi\/corda-per-ponte-celeste\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2026-01-15T20:11:47+00:00","og_image":[{"width":1920,"height":1281,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250710101213\/walltopia-ninja-course-obstacles-sky-bridge-rope-scaled-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/it\/product\/ostacoli-del-percorso-ninja\/ostacoli-ninja-sospesi\/corda-per-ponte-celeste\/","url":"https:\/\/walltopia.com\/it\/product\/ostacoli-del-percorso-ninja\/ostacoli-ninja-sospesi\/corda-per-ponte-celeste\/","name":"Corda per ponte celeste | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/#website"},"datePublished":"2025-07-10T07:07:47+00:00","dateModified":"2026-01-15T20:11:47+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/it\/product\/ostacoli-del-percorso-ninja\/ostacoli-ninja-sospesi\/corda-per-ponte-celeste\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/it\/product\/ostacoli-del-percorso-ninja\/ostacoli-ninja-sospesi\/corda-per-ponte-celeste\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/it\/product\/ostacoli-del-percorso-ninja\/ostacoli-ninja-sospesi\/corda-per-ponte-celeste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/it\/casa-it\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/walltopia.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Corda per ponte celeste"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/it\/#website","url":"https:\/\/walltopia.com\/it\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/it\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/product\/218180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/product\/218180\/revisions"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media?parent=218180"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/product_brand?post=218180"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/product_cat?post=218180"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/product_tag?post=218180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}