{"id":220514,"date":"2025-10-07T08:48:33","date_gmt":"2025-10-07T05:48:33","guid":{"rendered":"https:\/\/walltopia.com\/products\/senza-categoria\/fungo-cloud-climb\/"},"modified":"2026-01-22T14:26:31","modified_gmt":"2026-01-22T11:26:31","slug":"fungo-cloud-climb","status":"publish","type":"product","link":"https:\/\/walltopia.com\/it\/product\/salita-delle-nuvole\/fungo-cloud-climb\/","title":{"rendered":"Fungo Cloud Climb"},"content":{"rendered":"<p>Questo prodotto \u00e8 disponibile nelle seguenti combinazioni di colori:<\/p>\n<h4>Tramonto<\/h4>\n<div class=\"pantone-grid\">\n<div class=\"pantone-card p-283-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">283 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-1665-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">1665 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-1495-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">1495 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-1235-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">1235 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-283-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">283 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-308-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">308 C<\/div><\/div><\/div>\n<\/div>\n<h4>Lavanda<\/h4>\n<div class=\"pantone-grid\">\n<div class=\"pantone-card p-270-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">270 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-2050-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">2050 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-7443-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">7443 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-250-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">250 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-270-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">270 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-7451-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">7451 C<\/div><\/div><\/div>\n<\/div>\n<h4>Foresta<\/h4>\n<div class=\"pantone-grid\">\n<div class=\"pantone-card p-635-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">635 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-196-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">196 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-635-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">635 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-372-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">372 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-7465-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">7465 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-7473-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">7473 C<\/div><\/div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"Con la sua forma sorprendente e la sua presenza audace, Mushroom \u00e8 un centro visivo che attira immediatamente l&#8217;attenzione. Progettato per assomigliare a un fungo gigante, questo modello invita i bambini a un&#8217;emozionante scalata verticale che termina con un&#8217;esilarante discesa sullo scivolo in acciaio inox incorporato. Accattivante e divertente, Mushroom trasforma qualsiasi luogo in una destinazione.  \n\n<strong>*Il prezzo del modello Mushroom include lo scivolo.<\/strong>","protected":false},"featured_media":171772,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"product_brand":[],"product_cat":[7924],"product_tag":[],"class_list":["post-220514","product","type-product","status-publish","has-post-thumbnail","product_cat-salita-delle-nuvole","first","instock","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fungo Cloud Climb | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/it\/product\/salita-delle-nuvole\/fungo-cloud-climb\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fungo Cloud Climb\" \/>\n<meta property=\"og:description\" content=\"Con la sua forma sorprendente e la sua presenza audace, Mushroom \u00e8 un centro visivo che attira immediatamente l&#039;attenzione. Progettato per assomigliare a un fungo gigante, questo modello invita i bambini a un&#039;emozionante scalata verticale che termina con un&#039;esilarante discesa sullo scivolo in acciaio inox incorporato. Accattivante e divertente, Mushroom trasforma qualsiasi luogo in una destinazione.  *Il prezzo del modello Mushroom include lo scivolo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/it\/product\/salita-delle-nuvole\/fungo-cloud-climb\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-22T11:26:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250930094848\/cloud-climb-mushroom-forest-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/product\\\/salita-delle-nuvole\\\/fungo-cloud-climb\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/product\\\/salita-delle-nuvole\\\/fungo-cloud-climb\\\/\",\"name\":\"Fungo Cloud Climb | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/product\\\/salita-delle-nuvole\\\/fungo-cloud-climb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/product\\\/salita-delle-nuvole\\\/fungo-cloud-climb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20250930094848\\\/cloud-climb-mushroom-forest-01.jpg\",\"datePublished\":\"2025-10-07T05:48:33+00:00\",\"dateModified\":\"2026-01-22T11:26:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/product\\\/salita-delle-nuvole\\\/fungo-cloud-climb\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/product\\\/salita-delle-nuvole\\\/fungo-cloud-climb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/product\\\/salita-delle-nuvole\\\/fungo-cloud-climb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20250930094848\\\/cloud-climb-mushroom-forest-01.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20250930094848\\\/cloud-climb-mushroom-forest-01.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"Walltopia Cloud Climb Mushroom\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/product\\\/salita-delle-nuvole\\\/fungo-cloud-climb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/casa-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fungo Cloud Climb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fungo Cloud Climb | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/it\/product\/salita-delle-nuvole\/fungo-cloud-climb\/","og_locale":"it_IT","og_type":"article","og_title":"Fungo Cloud Climb","og_description":"Con la sua forma sorprendente e la sua presenza audace, Mushroom \u00e8 un centro visivo che attira immediatamente l'attenzione. Progettato per assomigliare a un fungo gigante, questo modello invita i bambini a un'emozionante scalata verticale che termina con un'esilarante discesa sullo scivolo in acciaio inox incorporato. Accattivante e divertente, Mushroom trasforma qualsiasi luogo in una destinazione.  *Il prezzo del modello Mushroom include lo scivolo.","og_url":"https:\/\/walltopia.com\/it\/product\/salita-delle-nuvole\/fungo-cloud-climb\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2026-01-22T11:26:31+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250930094848\/cloud-climb-mushroom-forest-01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/it\/product\/salita-delle-nuvole\/fungo-cloud-climb\/","url":"https:\/\/walltopia.com\/it\/product\/salita-delle-nuvole\/fungo-cloud-climb\/","name":"Fungo Cloud Climb | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/it\/product\/salita-delle-nuvole\/fungo-cloud-climb\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/it\/product\/salita-delle-nuvole\/fungo-cloud-climb\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250930094848\/cloud-climb-mushroom-forest-01.jpg","datePublished":"2025-10-07T05:48:33+00:00","dateModified":"2026-01-22T11:26:31+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/it\/product\/salita-delle-nuvole\/fungo-cloud-climb\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/it\/product\/salita-delle-nuvole\/fungo-cloud-climb\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/product\/salita-delle-nuvole\/fungo-cloud-climb\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250930094848\/cloud-climb-mushroom-forest-01.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250930094848\/cloud-climb-mushroom-forest-01.jpg","width":1920,"height":1280,"caption":"Walltopia Cloud Climb Mushroom"},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/it\/product\/salita-delle-nuvole\/fungo-cloud-climb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/it\/casa-it\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/walltopia.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Fungo Cloud Climb"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/it\/#website","url":"https:\/\/walltopia.com\/it\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/it\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/product\/220514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/product\/220514\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media\/171772"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media?parent=220514"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/product_brand?post=220514"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/product_cat?post=220514"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/product_tag?post=220514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}