{"id":7267,"count":9,"description":"Le sfide di oscillazione diversificano l'esperienza di arrampicata. Queste Fun Wall sono montate su una serie di corde che si estendono dal pavimento al soffitto. Si muovono leggermente in avanti e indietro, rendendo le salite emozionanti. Le sfide ottimizzano l'uso dello spazio e si adattano bene alle altre attrazioni.   ","link":"https:\/\/walltopia.com\/it\/categoria-prodotto\/pareti-di-divertimento-oscillanti\/","name":"Pareti di divertimento oscillanti","slug":"pareti-di-divertimento-oscillanti","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pareti di divertimento oscillanti | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/it\/categoria-prodotto\/pareti-di-divertimento-oscillanti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pareti di divertimento oscillanti Archives\" \/>\n<meta property=\"og:description\" content=\"Le sfide di oscillazione diversificano l&#8217;esperienza di arrampicata. Queste Fun Wall sono montate su una serie di corde che si estendono dal pavimento al soffitto. Si muovono leggermente in avanti e indietro, rendendo le salite emozionanti. Le sfide ottimizzano l&#8217;uso dello spazio e si adattano bene alle altre attrazioni.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/it\/categoria-prodotto\/pareti-di-divertimento-oscillanti\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/categoria-prodotto\\\/pareti-di-divertimento-oscillanti\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/categoria-prodotto\\\/pareti-di-divertimento-oscillanti\\\/\",\"name\":\"Pareti di divertimento oscillanti | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/categoria-prodotto\\\/pareti-di-divertimento-oscillanti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/categoria-prodotto\\\/pareti-di-divertimento-oscillanti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/casa-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pareti di divertimento oscillanti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pareti di divertimento oscillanti | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/it\/categoria-prodotto\/pareti-di-divertimento-oscillanti\/","og_locale":"it_IT","og_type":"article","og_title":"Pareti di divertimento oscillanti Archives","og_description":"Le sfide di oscillazione diversificano l&#8217;esperienza di arrampicata. Queste Fun Wall sono montate su una serie di corde che si estendono dal pavimento al soffitto. Si muovono leggermente in avanti e indietro, rendendo le salite emozionanti. Le sfide ottimizzano l&#8217;uso dello spazio e si adattano bene alle altre attrazioni.","og_url":"https:\/\/walltopia.com\/it\/categoria-prodotto\/pareti-di-divertimento-oscillanti\/","og_site_name":"Walltopia","twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/walltopia.com\/it\/categoria-prodotto\/pareti-di-divertimento-oscillanti\/","url":"https:\/\/walltopia.com\/it\/categoria-prodotto\/pareti-di-divertimento-oscillanti\/","name":"Pareti di divertimento oscillanti | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/walltopia.com\/it\/categoria-prodotto\/pareti-di-divertimento-oscillanti\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/it\/categoria-prodotto\/pareti-di-divertimento-oscillanti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/it\/casa-it\/"},{"@type":"ListItem","position":2,"name":"Pareti di divertimento oscillanti"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/it\/#website","url":"https:\/\/walltopia.com\/it\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/it\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/product_cat\/7267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/product?product_cat=7267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}