{"id":115651,"date":"2020-10-24T00:00:33","date_gmt":"2020-10-23T21:00:33","guid":{"rendered":"http:\/\/walltopia.com\/industries\/parchi-di-trampolino\/"},"modified":"2024-04-12T13:43:15","modified_gmt":"2024-04-12T10:43:15","slug":"parchi-di-trampolino","status":"publish","type":"wt_industry","link":"https:\/\/walltopia.com\/it\/industries\/parchi-di-trampolino\/","title":{"rendered":"Parchi di trampolino"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"Scoprite le attrazioni per i parchi di trampolini: Corsi Ninja, Corsi di corda, Pareti di arrampicata per aumentare le visite ripetute e il coinvolgimento.","protected":false},"featured_media":94392,"template":"","class_list":["post-115651","wt_industry","type-wt_industry","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Parchi Trampolino Attrazioni Produttore | Walltopia<\/title>\n<meta name=\"description\" content=\"Scoprite le attrazioni per i parchi di trampolini: Corsi Ninja, Corsi di corda, Pareti di arrampicata per aumentare le visite ripetute e il coinvolgimento.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/it\/industries\/parchi-di-trampolino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parchi Trampolino Attrazioni Produttore | Walltopia Active Entertainment\" \/>\n<meta property=\"og:description\" content=\"Costruiamo attrazioni per parchi di trampolini che aumentano le visite ripetute e il coinvolgimento. Scoprite i nostri percorsi ninja, i percorsi a corda, le pareti di arrampicata per bambini e altri prodotti per interni ed esterni.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/it\/industries\/parchi-di-trampolino\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-12T10:43:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027150955\/SAM_6884-34-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Parchi Trampolino Attrazioni Produttore | Walltopia Active Entertainment\" \/>\n<meta name=\"twitter:description\" content=\"Costruiamo attrazioni per parchi di trampolini che aumentano le visite ripetute e il coinvolgimento. Scoprite i nostri percorsi ninja, i percorsi a corda, le pareti di arrampicata per bambini e altri prodotti per interni ed esterni.\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/industries\\\/parchi-di-trampolino\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/industries\\\/parchi-di-trampolino\\\/\",\"name\":\"Parchi Trampolino Attrazioni Produttore | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/industries\\\/parchi-di-trampolino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/industries\\\/parchi-di-trampolino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027150955\\\/SAM_6884-34-1.jpg\",\"datePublished\":\"2020-10-23T21:00:33+00:00\",\"dateModified\":\"2024-04-12T10:43:15+00:00\",\"description\":\"Scoprite le attrazioni per i parchi di trampolini: Corsi Ninja, Corsi di corda, Pareti di arrampicata per aumentare le visite ripetute e il coinvolgimento.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/industries\\\/parchi-di-trampolino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/industries\\\/parchi-di-trampolino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/industries\\\/parchi-di-trampolino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027150955\\\/SAM_6884-34-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027150955\\\/SAM_6884-34-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/industries\\\/parchi-di-trampolino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/casa-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Industries\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/industries\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Parchi di trampolino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Parchi Trampolino Attrazioni Produttore | Walltopia","description":"Scoprite le attrazioni per i parchi di trampolini: Corsi Ninja, Corsi di corda, Pareti di arrampicata per aumentare le visite ripetute e il coinvolgimento.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/it\/industries\/parchi-di-trampolino\/","og_locale":"it_IT","og_type":"article","og_title":"Parchi Trampolino Attrazioni Produttore | Walltopia Active Entertainment","og_description":"Costruiamo attrazioni per parchi di trampolini che aumentano le visite ripetute e il coinvolgimento. Scoprite i nostri percorsi ninja, i percorsi a corda, le pareti di arrampicata per bambini e altri prodotti per interni ed esterni.","og_url":"https:\/\/walltopia.com\/it\/industries\/parchi-di-trampolino\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2024-04-12T10:43:15+00:00","og_image":[{"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027150955\/SAM_6884-34-1.jpg","width":1,"height":1,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Parchi Trampolino Attrazioni Produttore | Walltopia Active Entertainment","twitter_description":"Costruiamo attrazioni per parchi di trampolini che aumentano le visite ripetute e il coinvolgimento. Scoprite i nostri percorsi ninja, i percorsi a corda, le pareti di arrampicata per bambini e altri prodotti per interni ed esterni.","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/it\/industries\/parchi-di-trampolino\/","url":"https:\/\/walltopia.com\/it\/industries\/parchi-di-trampolino\/","name":"Parchi Trampolino Attrazioni Produttore | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/it\/industries\/parchi-di-trampolino\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/it\/industries\/parchi-di-trampolino\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027150955\/SAM_6884-34-1.jpg","datePublished":"2020-10-23T21:00:33+00:00","dateModified":"2024-04-12T10:43:15+00:00","description":"Scoprite le attrazioni per i parchi di trampolini: Corsi Ninja, Corsi di corda, Pareti di arrampicata per aumentare le visite ripetute e il coinvolgimento.","breadcrumb":{"@id":"https:\/\/walltopia.com\/it\/industries\/parchi-di-trampolino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/it\/industries\/parchi-di-trampolino\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/industries\/parchi-di-trampolino\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027150955\/SAM_6884-34-1.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027150955\/SAM_6884-34-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/it\/industries\/parchi-di-trampolino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/it\/casa-it\/"},{"@type":"ListItem","position":2,"name":"Industries","item":"https:\/\/walltopia.com\/it\/industries\/"},{"@type":"ListItem","position":3,"name":"Parchi di trampolino"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/it\/#website","url":"https:\/\/walltopia.com\/it\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/it\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/wt_industry\/115651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/wt_industry"}],"about":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/types\/wt_industry"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media\/94392"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media?parent=115651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}