{"id":113756,"date":"2024-02-12T18:56:10","date_gmt":"2024-02-12T15:56:10","guid":{"rendered":"http:\/\/walltopia.com\/?post_type=wt_project&#038;p=113756"},"modified":"2024-04-05T19:57:38","modified_gmt":"2024-04-05T16:57:38","slug":"are-klatterhall","status":"publish","type":"wt_project","link":"https:\/\/walltopia.com\/it\/projects\/are-klatterhall\/","title":{"rendered":"\u00c5re Kl\u00e4tterhall"},"content":{"rendered":"<p>\u00c5re Kl\u00e4tterhall is a full-service climbing gym in Duved, Sweden featuring 475 sqm climbing surface. Walltopia has designed, engineered, produced and built climbing walls for bouldering, top rope and lead climbing and training boards for the facility as well as boulder mats and rope wall safety flooring. A large portion of the holds and macros was delivered in one shipping from Holdtopia.<\/p>\n","protected":false},"featured_media":113757,"template":"","wt_project_category":[881],"class_list":["post-113756","wt_project","type-wt_project","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00c5re Kl\u00e4tterhall | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/it\/projects\/are-klatterhall\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c5re Kl\u00e4tterhall\" \/>\n<meta property=\"og:description\" content=\"\u00c5re Kl\u00e4tterhall is a full-service climbing gym in Duved, Sweden featuring 475 sqm climbing surface. Walltopia has designed, engineered, produced...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/it\/projects\/are-klatterhall\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-05T16:57:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240212185342\/Are-Klatterhall-Sweden-Walltopia-climbing-walls-7-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/are-klatterhall\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/are-klatterhall\\\/\",\"name\":\"\u00c5re Kl\u00e4tterhall | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/are-klatterhall\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/are-klatterhall\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20240212185342\\\/Are-Klatterhall-Sweden-Walltopia-climbing-walls-7-scaled.jpg\",\"datePublished\":\"2024-02-12T15:56:10+00:00\",\"dateModified\":\"2024-04-05T16:57:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/are-klatterhall\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/are-klatterhall\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/are-klatterhall\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20240212185342\\\/Are-Klatterhall-Sweden-Walltopia-climbing-walls-7-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20240212185342\\\/Are-Klatterhall-Sweden-Walltopia-climbing-walls-7-scaled.jpg\",\"width\":900,\"height\":1200,\"caption\":\"Walltopia boulder and rope climbing walls featuring natural wood panels at Are Klatterhall in Duved, Sweden\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/are-klatterhall\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/casa-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c5re Kl\u00e4tterhall\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00c5re Kl\u00e4tterhall | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/it\/projects\/are-klatterhall\/","og_locale":"it_IT","og_type":"article","og_title":"\u00c5re Kl\u00e4tterhall","og_description":"\u00c5re Kl\u00e4tterhall is a full-service climbing gym in Duved, Sweden featuring 475 sqm climbing surface. Walltopia has designed, engineered, produced...","og_url":"https:\/\/walltopia.com\/it\/projects\/are-klatterhall\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2024-04-05T16:57:38+00:00","og_image":[{"width":900,"height":1200,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240212185342\/Are-Klatterhall-Sweden-Walltopia-climbing-walls-7-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/it\/projects\/are-klatterhall\/","url":"https:\/\/walltopia.com\/it\/projects\/are-klatterhall\/","name":"\u00c5re Kl\u00e4tterhall | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/it\/projects\/are-klatterhall\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/it\/projects\/are-klatterhall\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240212185342\/Are-Klatterhall-Sweden-Walltopia-climbing-walls-7-scaled.jpg","datePublished":"2024-02-12T15:56:10+00:00","dateModified":"2024-04-05T16:57:38+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/it\/projects\/are-klatterhall\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/it\/projects\/are-klatterhall\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/projects\/are-klatterhall\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240212185342\/Are-Klatterhall-Sweden-Walltopia-climbing-walls-7-scaled.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240212185342\/Are-Klatterhall-Sweden-Walltopia-climbing-walls-7-scaled.jpg","width":900,"height":1200,"caption":"Walltopia boulder and rope climbing walls featuring natural wood panels at Are Klatterhall in Duved, Sweden"},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/it\/projects\/are-klatterhall\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/it\/casa-it\/"},{"@type":"ListItem","position":2,"name":"Progetti","item":"https:\/\/walltopia.com\/it\/projects\/"},{"@type":"ListItem","position":3,"name":"\u00c5re Kl\u00e4tterhall"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/it\/#website","url":"https:\/\/walltopia.com\/it\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/it\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/wt_project\/113756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/wt_project"}],"about":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/types\/wt_project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media\/113757"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media?parent=113756"}],"wp:term":[{"taxonomy":"wt_project_category","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/wt_project_category?post=113756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}