{"id":143688,"date":"2024-09-19T17:23:32","date_gmt":"2024-09-19T14:23:32","guid":{"rendered":"http:\/\/walltopia.com\/?post_type=wt_project&#038;p=143688"},"modified":"2024-09-25T13:30:51","modified_gmt":"2024-09-25T10:30:51","slug":"hype-arena-romexpo","status":"publish","type":"wt_project","link":"https:\/\/walltopia.com\/it\/projects\/hype-arena-romexpo\/","title":{"rendered":"Hype Arena Romexpo"},"content":{"rendered":"<p>Hype Romexpo is the ultimate playground for all ages in Bucharest, featuring Fun Walls, Ninja Course and a Ropes Course by Walltopia.<\/p>\n","protected":false},"featured_media":143773,"template":"","wt_project_category":[8790],"class_list":["post-143688","wt_project","type-wt_project","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hype Arena Romexpo | Walltopia<\/title>\n<meta name=\"description\" content=\"Hype Romexpo is the ultimate playground for all ages in Bucharest, featuring Fun Walls, Ninja Course and a Ropes Course by Walltopia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/it\/projects\/hype-arena-romexpo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hype Arena Romexpo\" \/>\n<meta property=\"og:description\" content=\"Hype Romexpo is the ultimate playground for all ages in Bucharest, featuring Fun Walls, Ninja Course and a Ropes Course by Walltopia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/it\/projects\/hype-arena-romexpo\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-25T10:30:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240919171816\/Hype-By-Kiddo-c-Valentin-Razvan-27.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/hype-arena-romexpo\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/hype-arena-romexpo\\\/\",\"name\":\"Hype Arena Romexpo | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/hype-arena-romexpo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/hype-arena-romexpo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20240919171816\\\/Hype-By-Kiddo-c-Valentin-Razvan-27.jpg\",\"datePublished\":\"2024-09-19T14:23:32+00:00\",\"dateModified\":\"2024-09-25T10:30:51+00:00\",\"description\":\"Hype Romexpo is the ultimate playground for all ages in Bucharest, featuring Fun Walls, Ninja Course and a Ropes Course by Walltopia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/hype-arena-romexpo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/hype-arena-romexpo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/hype-arena-romexpo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20240919171816\\\/Hype-By-Kiddo-c-Valentin-Razvan-27.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20240919171816\\\/Hype-By-Kiddo-c-Valentin-Razvan-27.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/hype-arena-romexpo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/casa-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hype Arena Romexpo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hype Arena Romexpo | Walltopia","description":"Hype Romexpo is the ultimate playground for all ages in Bucharest, featuring Fun Walls, Ninja Course and a Ropes Course by Walltopia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/it\/projects\/hype-arena-romexpo\/","og_locale":"it_IT","og_type":"article","og_title":"Hype Arena Romexpo","og_description":"Hype Romexpo is the ultimate playground for all ages in Bucharest, featuring Fun Walls, Ninja Course and a Ropes Course by Walltopia.","og_url":"https:\/\/walltopia.com\/it\/projects\/hype-arena-romexpo\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2024-09-25T10:30:51+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240919171816\/Hype-By-Kiddo-c-Valentin-Razvan-27.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/it\/projects\/hype-arena-romexpo\/","url":"https:\/\/walltopia.com\/it\/projects\/hype-arena-romexpo\/","name":"Hype Arena Romexpo | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/it\/projects\/hype-arena-romexpo\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/it\/projects\/hype-arena-romexpo\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240919171816\/Hype-By-Kiddo-c-Valentin-Razvan-27.jpg","datePublished":"2024-09-19T14:23:32+00:00","dateModified":"2024-09-25T10:30:51+00:00","description":"Hype Romexpo is the ultimate playground for all ages in Bucharest, featuring Fun Walls, Ninja Course and a Ropes Course by Walltopia.","breadcrumb":{"@id":"https:\/\/walltopia.com\/it\/projects\/hype-arena-romexpo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/it\/projects\/hype-arena-romexpo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/projects\/hype-arena-romexpo\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240919171816\/Hype-By-Kiddo-c-Valentin-Razvan-27.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240919171816\/Hype-By-Kiddo-c-Valentin-Razvan-27.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/it\/projects\/hype-arena-romexpo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/it\/casa-it\/"},{"@type":"ListItem","position":2,"name":"Progetti","item":"https:\/\/walltopia.com\/it\/projects\/"},{"@type":"ListItem","position":3,"name":"Hype Arena Romexpo"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/it\/#website","url":"https:\/\/walltopia.com\/it\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/it\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/wt_project\/143688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/wt_project"}],"about":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/types\/wt_project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media\/143773"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media?parent=143688"}],"wp:term":[{"taxonomy":"wt_project_category","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/wt_project_category?post=143688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}