{"id":154309,"date":"2025-01-30T00:37:59","date_gmt":"2025-01-29T21:37:59","guid":{"rendered":"http:\/\/walltopia.com\/?post_type=wt_project&#038;p=154309"},"modified":"2025-01-30T13:07:37","modified_gmt":"2025-01-30T10:07:37","slug":"vertical-park","status":"publish","type":"wt_project","link":"https:\/\/walltopia.com\/it\/projects\/vertical-park\/","title":{"rendered":"Vertical Park"},"content":{"rendered":"<p><a href=\"https:\/\/www.verticalpark.fr\/\">Vertical Park<\/a> &#8211; Salle d&#8217;escalade \u00e0 Avignon is a massive full-service climbing gym in Le Pontet, France. Over 2000m\u00b2 climbing surface are distributed between <a href=\"http:\/\/walltopia.com\/products\/boulder-walls\/\">bouldering<\/a>, indoor <a href=\"http:\/\/walltopia.com\/products\/rope-walls\/\">rope climbing<\/a>, <a href=\"http:\/\/walltopia.com\/products\/fun-walls\/\">Fun Walls<\/a> and <a href=\"http:\/\/walltopia.com\/products\/outdoor-climbing-walls\/\">an outdoor climbing wall<\/a>. <\/p>\n<p>The climbing gym caters to everyone from absolute beginner to expert level and also has access for people with reduced mobility. <\/p>\n<p><a href=\"http:\/\/walltopia.com\/products\/climbmat-safety-mats\/\">Climbmat safety mats<\/a> take care for the comfortable jumps and landings on both the bouldering and rope climbing zones. The bouldering mat of the client&#8217;s choice is BM 400 S, with carpet top and hard edge, while the rope wall mats are the modular RM600.<\/p>\n<p>A large selection of <a href=\"http:\/\/walltopia.com\/products\/climbing-holds-and-volumes\/\">holds, macros and volumes<\/a> from <a href=\"https:\/\/holdtopia.com\/\">holdtopia.com<\/a> got the climbing facility all set for their visitors.<\/p>\n<p>Fun Walls complement the kids climbing area offering an entertaining challenge to the young audience.<\/p>\n<p>If you&#8217;re in the Avignon region, don&#8217;t miss out the chance to visit Vertical Park!<\/p>\n","protected":false},"featured_media":154409,"template":"","wt_project_category":[8780],"class_list":["post-154309","wt_project","type-wt_project","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Vertical Park | Walltopia<\/title>\n<meta name=\"description\" content=\"Vertical Park Avignon is a full-service climbing gym in Le Pontet, France with bouldering, rope climbing, Fun Walls and an outdoor climbing wall\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/it\/projects\/vertical-park\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vertical Park\" \/>\n<meta property=\"og:description\" content=\"Vertical Park Avignon is a full-service climbing gym in Le Pontet, France with bouldering, rope climbing, Fun Walls and an outdoor climbing wall\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/it\/projects\/vertical-park\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-30T10:07:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250130002243\/Vertical-Park-Avignon-France-Walltopia-climbing-walls-12-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"675\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/vertical-park\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/vertical-park\\\/\",\"name\":\"Vertical Park | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/vertical-park\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/vertical-park\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20250130002243\\\/Vertical-Park-Avignon-France-Walltopia-climbing-walls-12-scaled.jpeg\",\"datePublished\":\"2025-01-29T21:37:59+00:00\",\"dateModified\":\"2025-01-30T10:07:37+00:00\",\"description\":\"Vertical Park Avignon is a full-service climbing gym in Le Pontet, France with bouldering, rope climbing, Fun Walls and an outdoor climbing wall\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/vertical-park\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/vertical-park\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/vertical-park\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20250130002243\\\/Vertical-Park-Avignon-France-Walltopia-climbing-walls-12-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20250130002243\\\/Vertical-Park-Avignon-France-Walltopia-climbing-walls-12-scaled.jpeg\",\"width\":675,\"height\":1200,\"caption\":\"Walltopia rope climbing walls and Fun Walls and Climbmat safety mats at Vertical Park Avignon\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/vertical-park\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/casa-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vertical Park\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Vertical Park | Walltopia","description":"Vertical Park Avignon is a full-service climbing gym in Le Pontet, France with bouldering, rope climbing, Fun Walls and an outdoor climbing wall","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/it\/projects\/vertical-park\/","og_locale":"it_IT","og_type":"article","og_title":"Vertical Park","og_description":"Vertical Park Avignon is a full-service climbing gym in Le Pontet, France with bouldering, rope climbing, Fun Walls and an outdoor climbing wall","og_url":"https:\/\/walltopia.com\/it\/projects\/vertical-park\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2025-01-30T10:07:37+00:00","og_image":[{"width":675,"height":1200,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250130002243\/Vertical-Park-Avignon-France-Walltopia-climbing-walls-12-scaled.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/it\/projects\/vertical-park\/","url":"https:\/\/walltopia.com\/it\/projects\/vertical-park\/","name":"Vertical Park | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/it\/projects\/vertical-park\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/it\/projects\/vertical-park\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250130002243\/Vertical-Park-Avignon-France-Walltopia-climbing-walls-12-scaled.jpeg","datePublished":"2025-01-29T21:37:59+00:00","dateModified":"2025-01-30T10:07:37+00:00","description":"Vertical Park Avignon is a full-service climbing gym in Le Pontet, France with bouldering, rope climbing, Fun Walls and an outdoor climbing wall","breadcrumb":{"@id":"https:\/\/walltopia.com\/it\/projects\/vertical-park\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/it\/projects\/vertical-park\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/projects\/vertical-park\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250130002243\/Vertical-Park-Avignon-France-Walltopia-climbing-walls-12-scaled.jpeg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250130002243\/Vertical-Park-Avignon-France-Walltopia-climbing-walls-12-scaled.jpeg","width":675,"height":1200,"caption":"Walltopia rope climbing walls and Fun Walls and Climbmat safety mats at Vertical Park Avignon"},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/it\/projects\/vertical-park\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/it\/casa-it\/"},{"@type":"ListItem","position":2,"name":"Progetti","item":"https:\/\/walltopia.com\/it\/projects\/"},{"@type":"ListItem","position":3,"name":"Vertical Park"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/it\/#website","url":"https:\/\/walltopia.com\/it\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/it\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/wt_project\/154309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/wt_project"}],"about":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/types\/wt_project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media\/154409"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media?parent=154309"}],"wp:term":[{"taxonomy":"wt_project_category","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/wt_project_category?post=154309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}