{"id":69011,"date":"2023-01-08T11:32:22","date_gmt":"2023-01-08T08:32:22","guid":{"rendered":"http:\/\/walltopia.com\/projects\/hoover-metropolitan-complex\/"},"modified":"2024-04-08T11:03:20","modified_gmt":"2024-04-08T08:03:20","slug":"hoover-metropolitan-complex","status":"publish","type":"wt_project","link":"https:\/\/walltopia.com\/it\/projects\/hoover-metropolitan-complex\/","title":{"rendered":"Hoover Metropolitan Complex"},"content":{"rendered":"","protected":false},"featured_media":69012,"template":"","wt_project_category":[760],"class_list":["post-69011","wt_project","type-wt_project","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hoover Metropolitan Complex | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/it\/projects\/hoover-metropolitan-complex\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hoover Metropolitan Complex\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/it\/projects\/hoover-metropolitan-complex\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-08T08:03:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027204805\/Fun-Walls-USA-Alabama-Hoover-City-4.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/hoover-metropolitan-complex\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/hoover-metropolitan-complex\\\/\",\"name\":\"Hoover Metropolitan Complex | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/hoover-metropolitan-complex\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/hoover-metropolitan-complex\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027204805\\\/Fun-Walls-USA-Alabama-Hoover-City-4.jpeg\",\"datePublished\":\"2023-01-08T08:32:22+00:00\",\"dateModified\":\"2024-04-08T08:03:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/hoover-metropolitan-complex\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/hoover-metropolitan-complex\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/hoover-metropolitan-complex\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027204805\\\/Fun-Walls-USA-Alabama-Hoover-City-4.jpeg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027204805\\\/Fun-Walls-USA-Alabama-Hoover-City-4.jpeg\",\"width\":1440,\"height\":1920,\"caption\":\"Hoover Metropolitan Complex\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/hoover-metropolitan-complex\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/casa-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hoover Metropolitan Complex\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hoover Metropolitan Complex | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/it\/projects\/hoover-metropolitan-complex\/","og_locale":"it_IT","og_type":"article","og_title":"Hoover Metropolitan Complex","og_url":"https:\/\/walltopia.com\/it\/projects\/hoover-metropolitan-complex\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2024-04-08T08:03:20+00:00","og_image":[{"width":1440,"height":1920,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027204805\/Fun-Walls-USA-Alabama-Hoover-City-4.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/it\/projects\/hoover-metropolitan-complex\/","url":"https:\/\/walltopia.com\/it\/projects\/hoover-metropolitan-complex\/","name":"Hoover Metropolitan Complex | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/it\/projects\/hoover-metropolitan-complex\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/it\/projects\/hoover-metropolitan-complex\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027204805\/Fun-Walls-USA-Alabama-Hoover-City-4.jpeg","datePublished":"2023-01-08T08:32:22+00:00","dateModified":"2024-04-08T08:03:20+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/it\/projects\/hoover-metropolitan-complex\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/it\/projects\/hoover-metropolitan-complex\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/projects\/hoover-metropolitan-complex\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027204805\/Fun-Walls-USA-Alabama-Hoover-City-4.jpeg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027204805\/Fun-Walls-USA-Alabama-Hoover-City-4.jpeg","width":1440,"height":1920,"caption":"Hoover Metropolitan Complex"},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/it\/projects\/hoover-metropolitan-complex\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/it\/casa-it\/"},{"@type":"ListItem","position":2,"name":"Progetti","item":"https:\/\/walltopia.com\/it\/projects\/"},{"@type":"ListItem","position":3,"name":"Hoover Metropolitan Complex"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/it\/#website","url":"https:\/\/walltopia.com\/it\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/it\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/wt_project\/69011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/wt_project"}],"about":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/types\/wt_project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media\/69012"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media?parent=69011"}],"wp:term":[{"taxonomy":"wt_project_category","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/wt_project_category?post=69011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}