{"id":118183,"date":"2024-04-04T15:01:52","date_gmt":"2024-04-04T12:01:52","guid":{"rendered":"http:\/\/walltopia.com\/testimonials\/lintero-team-e-stato-molto-professionale-e-davvero-impegnato\/"},"modified":"2024-04-24T15:33:23","modified_gmt":"2024-04-24T12:33:23","slug":"lintero-team-e-stato-molto-professionale-e-davvero-impegnato","status":"publish","type":"wt_testimonial","link":"https:\/\/walltopia.com\/it\/testimonials\/lintero-team-e-stato-molto-professionale-e-davvero-impegnato\/","title":{"rendered":"L&#8217;intero team \u00e8 stato molto professionale e davvero impegnato"},"featured_media":0,"template":"","testimonial_category":[828],"class_list":["post-118183","wt_testimonial","type-wt_testimonial","status-publish","hentry","testimonial_category-climbing"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L&#039;intero team \u00e8 stato molto professionale e davvero impegnato | Walltopia<\/title>\n<meta name=\"description\" content=\"Era chiaro che tutti volevano realizzare il progetto nel miglior modo possibile.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/it\/testimonials\/lintero-team-e-stato-molto-professionale-e-davvero-impegnato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;intero team \u00e8 stato molto professionale e davvero impegnato\" \/>\n<meta property=\"og:description\" content=\"Era chiaro che tutti volevano realizzare il progetto nel miglior modo possibile.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/it\/testimonials\/lintero-team-e-stato-molto-professionale-e-davvero-impegnato\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-24T12:33:23+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/testimonials\\\/lintero-team-e-stato-molto-professionale-e-davvero-impegnato\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/testimonials\\\/lintero-team-e-stato-molto-professionale-e-davvero-impegnato\\\/\",\"name\":\"L'intero team \u00e8 stato molto professionale e davvero impegnato | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\"},\"datePublished\":\"2024-04-04T12:01:52+00:00\",\"dateModified\":\"2024-04-24T12:33:23+00:00\",\"description\":\"Era chiaro che tutti volevano realizzare il progetto nel miglior modo possibile.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/testimonials\\\/lintero-team-e-stato-molto-professionale-e-davvero-impegnato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/it\\\/testimonials\\\/lintero-team-e-stato-molto-professionale-e-davvero-impegnato\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/testimonials\\\/lintero-team-e-stato-molto-professionale-e-davvero-impegnato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/casa-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Testimonials\",\"item\":\"https:\\\/\\\/walltopia.com\\\/it\\\/testimonials\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L&#8217;intero team \u00e8 stato molto professionale e davvero impegnato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L'intero team \u00e8 stato molto professionale e davvero impegnato | Walltopia","description":"Era chiaro che tutti volevano realizzare il progetto nel miglior modo possibile.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/it\/testimonials\/lintero-team-e-stato-molto-professionale-e-davvero-impegnato\/","og_locale":"it_IT","og_type":"article","og_title":"L'intero team \u00e8 stato molto professionale e davvero impegnato","og_description":"Era chiaro che tutti volevano realizzare il progetto nel miglior modo possibile.","og_url":"https:\/\/walltopia.com\/it\/testimonials\/lintero-team-e-stato-molto-professionale-e-davvero-impegnato\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2024-04-24T12:33:23+00:00","twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/it\/testimonials\/lintero-team-e-stato-molto-professionale-e-davvero-impegnato\/","url":"https:\/\/walltopia.com\/it\/testimonials\/lintero-team-e-stato-molto-professionale-e-davvero-impegnato\/","name":"L'intero team \u00e8 stato molto professionale e davvero impegnato | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/it\/#website"},"datePublished":"2024-04-04T12:01:52+00:00","dateModified":"2024-04-24T12:33:23+00:00","description":"Era chiaro che tutti volevano realizzare il progetto nel miglior modo possibile.","breadcrumb":{"@id":"https:\/\/walltopia.com\/it\/testimonials\/lintero-team-e-stato-molto-professionale-e-davvero-impegnato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/it\/testimonials\/lintero-team-e-stato-molto-professionale-e-davvero-impegnato\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/it\/testimonials\/lintero-team-e-stato-molto-professionale-e-davvero-impegnato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/it\/casa-it\/"},{"@type":"ListItem","position":2,"name":"Testimonials","item":"https:\/\/walltopia.com\/it\/testimonials\/"},{"@type":"ListItem","position":3,"name":"L&#8217;intero team \u00e8 stato molto professionale e davvero impegnato"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/it\/#website","url":"https:\/\/walltopia.com\/it\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/it\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/wt_testimonial\/118183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/wt_testimonial"}],"about":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/types\/wt_testimonial"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/media?parent=118183"}],"wp:term":[{"taxonomy":"testimonial_category","embeddable":true,"href":"https:\/\/walltopia.com\/it\/wp-json\/wp\/v2\/testimonial_category?post=118183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}