{"id":181519,"date":"2021-06-17T16:24:04","date_gmt":"2021-06-17T13:24:04","guid":{"rendered":"https:\/\/walltopia.com\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\/"},"modified":"2026-01-15T16:54:50","modified_gmt":"2026-01-15T13:54:50","slug":"poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015","status":"publish","type":"post","link":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\/","title":{"rendered":"Poznaj Walltopia Adventure na targach IAAPA Attractions Expo 2015"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><a href=\"https:\/\/adventure.walltopia.com\/\">Walltopia Adventure<\/a> zaprezentuje swoje marki <a href=\"https:\/\/adventure.walltopia.com\/products\/fun-walls\/\">Fun Walls<\/a>, <a href=\"https:\/\/adventure.walltopia.com\/products\/walltopia-caves\/\">Walltopia Caves<\/a>, <a href=\"https:\/\/adventure.walltopia.com\/products\/ropes-course\/\">Ropes Course<\/a> i <a href=\"https:\/\/adventure.walltopia.com\/products\/rollglider\/\">Rollglider<\/a> na targach IAAPA Attractions Expo w Orlando na Florydzie. Dowiedz si\u0119, co ka\u017cdy produkt mo\u017ce zrobi\u0107 dla firm z bran\u017cy rozrywkowej od <strong>17 do 20 listopada<\/strong> na stoisku <strong>4054<\/strong>. <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Konferencja prasowa oficjalnie og\u0142aszaj\u0105ca uruchomienie Rollglidera odb\u0119dzie si\u0119 <strong>18 listopada o godzinie 11:45<\/strong> na stoisku.<\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\"><em>Skontaktuj si\u0119 z nami pod adresem<\/em> <a href=\"mailto:sales@walltopia.com\">sales@walltopia.com<\/a><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Walltopia Adventure zaprezentuje swoje marki Fun Walls, Walltopia Caves, Ropes Course i Rollglider na IAAPA Attractions Expo w Orlando,&#8230;","protected":false},"author":10,"featured_media":181521,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1108],"tags":[1749,1109,1753,1123,1122,1751],"class_list":["post-181519","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsroom-pl","tag-fun-walls","tag-iaapa-pl","tag-jaskinie-walltopia","tag-park-linowy","tag-rollglider-pl","tag-walltopia-adventure"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Poznaj Walltopia Adventure na targach IAAPA Attractions Expo 2015 | Walltopia<\/title>\n<meta name=\"description\" content=\"Spotkaj si\u0119 z nami na IAAPA Attractions Expo w Orlando na Florydzie i dowiedz si\u0119, co ka\u017cdy produkt mo\u017ce zrobi\u0107 dla firm z bran\u017cy rozrywkowej.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Poznaj Walltopia Adventure na targach IAAPA Attractions Expo 2015\" \/>\n<meta property=\"og:description\" content=\"Spotkaj si\u0119 z nami na IAAPA Attractions Expo w Orlando na Florydzie i dowiedz si\u0119, co ka\u017cdy produkt mo\u017ce zrobi\u0107 dla firm z bran\u017cy rozrywkowej.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-17T13:24:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T13:54:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090648\/IAAPA-Attractions-Expo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"479\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"the_id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\\\/\"},\"author\":{\"name\":\"the_id\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\"},\"headline\":\"Poznaj Walltopia Adventure na targach IAAPA Attractions Expo 2015\",\"datePublished\":\"2021-06-17T13:24:04+00:00\",\"dateModified\":\"2026-01-15T13:54:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\\\/\"},\"wordCount\":92,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090648\\\/IAAPA-Attractions-Expo.jpg\",\"keywords\":[\"Fun Walls\",\"IAAPA\",\"jaskinie walltopia\",\"park linowy\",\"Rollglider\",\"Walltopia Adventure\"],\"articleSection\":[\"Newsroom\"],\"inLanguage\":\"pl-PL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\\\/\",\"name\":\"Poznaj Walltopia Adventure na targach IAAPA Attractions Expo 2015 | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090648\\\/IAAPA-Attractions-Expo.jpg\",\"datePublished\":\"2021-06-17T13:24:04+00:00\",\"dateModified\":\"2026-01-15T13:54:50+00:00\",\"description\":\"Spotkaj si\u0119 z nami na IAAPA Attractions Expo w Orlando na Florydzie i dowiedz si\u0119, co ka\u017cdy produkt mo\u017ce zrobi\u0107 dla firm z bran\u017cy rozrywkowej.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pl\\\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090648\\\/IAAPA-Attractions-Expo.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090648\\\/IAAPA-Attractions-Expo.jpg\",\"width\":900,\"height\":479},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/strona-glowna-pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Poznaj Walltopia Adventure na targach IAAPA Attractions Expo 2015\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\",\"name\":\"the_id\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Poznaj Walltopia Adventure na targach IAAPA Attractions Expo 2015 | Walltopia","description":"Spotkaj si\u0119 z nami na IAAPA Attractions Expo w Orlando na Florydzie i dowiedz si\u0119, co ka\u017cdy produkt mo\u017ce zrobi\u0107 dla firm z bran\u017cy rozrywkowej.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\/","og_locale":"pl_PL","og_type":"article","og_title":"Poznaj Walltopia Adventure na targach IAAPA Attractions Expo 2015","og_description":"Spotkaj si\u0119 z nami na IAAPA Attractions Expo w Orlando na Florydzie i dowiedz si\u0119, co ka\u017cdy produkt mo\u017ce zrobi\u0107 dla firm z bran\u017cy rozrywkowej.","og_url":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2021-06-17T13:24:04+00:00","article_modified_time":"2026-01-15T13:54:50+00:00","og_image":[{"width":900,"height":479,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090648\/IAAPA-Attractions-Expo.jpg","type":"image\/jpeg"}],"author":"the_id","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\/"},"author":{"name":"the_id","@id":"https:\/\/walltopia.com\/pl\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff"},"headline":"Poznaj Walltopia Adventure na targach IAAPA Attractions Expo 2015","datePublished":"2021-06-17T13:24:04+00:00","dateModified":"2026-01-15T13:54:50+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\/"},"wordCount":92,"publisher":{"@id":"https:\/\/walltopia.com\/pl\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090648\/IAAPA-Attractions-Expo.jpg","keywords":["Fun Walls","IAAPA","jaskinie walltopia","park linowy","Rollglider","Walltopia Adventure"],"articleSection":["Newsroom"],"inLanguage":"pl-PL"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\/","url":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\/","name":"Poznaj Walltopia Adventure na targach IAAPA Attractions Expo 2015 | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090648\/IAAPA-Attractions-Expo.jpg","datePublished":"2021-06-17T13:24:04+00:00","dateModified":"2026-01-15T13:54:50+00:00","description":"Spotkaj si\u0119 z nami na IAAPA Attractions Expo w Orlando na Florydzie i dowiedz si\u0119, co ka\u017cdy produkt mo\u017ce zrobi\u0107 dla firm z bran\u017cy rozrywkowej.","breadcrumb":{"@id":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090648\/IAAPA-Attractions-Expo.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090648\/IAAPA-Attractions-Expo.jpg","width":900,"height":479},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/pl\/strona-glowna-pl\/"},{"@type":"ListItem","position":2,"name":"Poznaj Walltopia Adventure na targach IAAPA Attractions Expo 2015"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/pl\/#website","url":"https:\/\/walltopia.com\/pl\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/pl\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/walltopia.com\/pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/pl\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff","name":"the_id"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/posts\/181519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/comments?post=181519"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/posts\/181519\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/media\/181521"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/media?parent=181519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/categories?post=181519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/tags?post=181519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}