{"id":182006,"date":"2021-06-17T14:43:20","date_gmt":"2021-06-17T11:43:20","guid":{"rendered":"https:\/\/walltopia.com\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\/"},"modified":"2026-01-15T16:56:16","modified_gmt":"2026-01-15T13:56:16","slug":"walltopia-sponsor-tytularny-australian-lead-climbing-championship","status":"publish","type":"post","link":"https:\/\/walltopia.com\/pl\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\/","title":{"rendered":"Walltopia &#8211; sponsor tytularny Australian Lead Climbing Championship"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_custom_heading text=&#8221;Mieli\u015bmy przyjemno\u015b\u0107 by\u0107 sponsorem tytularnym Australian Lead Championship, kt\u00f3re zosta\u0142y zorganizowane przez naszych przyjaci\u00f3\u0142 i partner\u00f3w z Urban Climb w Brisbane.&#8221; font_container=&#8221;tag:h2|font_size:18|text_align:left|color:%23000000|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221; link=&#8221;url:https%3A%2F%2Fsetinstonemedia.com.au%2Fshop%2Fevent-galleries%2F2015-australian-lead-nationals%2F|title:%20Australian%20Lead%20Championship|target:_blank|&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Transmisja na \u017cywo, zupe\u0142nie nowe chwyty, niesamowite trasy i imponuj\u0105ce umiej\u0119tno\u015bci zawodnik\u00f3w by\u0142y sk\u0142adnikami, kt\u00f3re przenios\u0142y wspinaczk\u0119 konkursow\u0105 w Australii na wy\u017cszy poziom. Dwudniowe wydarzenie go\u015bci\u0142o wspinaczy od m\u0142odzie\u017cy po junior\u00f3w, paraklimator\u00f3w, dywizje Open i Masters &#8211; spore wyzwanie dla routesetter\u00f3w. <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Opr\u00f3cz pami\u0119tnego weekendu, og\u0142oszono r\u00f3wnie\u017c kilka wa\u017cnych wiadomo\u015bci! Nowa si\u0142ownia Urban Climb ma zosta\u0107 otwarta tej jesieni.<br \/>\nZgadnij, kto buduje \u015bciany? My na pewno!    <strong>B\u0105d\u017a na bie\u017c\u0105co!<\/strong><\/p>\n[\/vc_column_text][vc_images_carousel images=&#8221;13995,13996,13997,13998&#8243; img_size=&#8221;full&#8221; autoplay=&#8221;yes&#8221; wrap=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1623929913290{padding-top: 5% !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;]<div class=\"link-button-container block width-100  text-align-center\"><a class=\"wt-link \" href=\"https:\/\/www.facebook.com\/urbanclimb\" target=\"_blank\">URBAN CLIMB FACEBOOK<\/a><\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243;]<div class=\"link-button-container block width-100  text-align-center\"><a class=\"wt-link \" href=\"https:\/\/www.urbanclimb.com.au\/\" target=\"_blank\">URBAN CLIMB WEBSITE<\/a><\/div>[\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Mieli\u015bmy przyjemno\u015b\u0107 by\u0107 sponsorem tytularnym Australian Lead Championship, kt\u00f3re zosta\u0142y zorganizowane przez naszych przyjaci\u00f3\u0142 i partner\u00f3w z Urban Climb w Brisbane.","protected":false},"author":10,"featured_media":182008,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1108],"tags":[2046,1949],"class_list":["post-182006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsroom-pl","tag-miejska-wspinaczka","tag-wspinaczka-na-walltopia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Walltopia - sponsor tytularny Australian Lead Climbing Championship | Walltopia<\/title>\n<meta name=\"description\" content=\"Zupe\u0142nie nowe chwyty i niesamowite trasy by\u0142y jednymi z element\u00f3w, kt\u00f3re przenios\u0142y wspinaczk\u0119 zawodnicz\u0105 w Australii na wy\u017cszy poziom.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/pl\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Walltopia - sponsor tytularny Australian Lead Climbing Championship\" \/>\n<meta property=\"og:description\" content=\"Zupe\u0142nie nowe chwyty i niesamowite trasy by\u0142y jednymi z element\u00f3w, kt\u00f3re przenios\u0142y wspinaczk\u0119 zawodnicz\u0105 w Australii na wy\u017cszy poziom.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/pl\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-17T11:43:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T13:56:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090722\/11393362_705504699575153_2899450455245342486_o.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"the_id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\\\/\"},\"author\":{\"name\":\"the_id\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\"},\"headline\":\"Walltopia &#8211; sponsor tytularny Australian Lead Climbing Championship\",\"datePublished\":\"2021-06-17T11:43:20+00:00\",\"dateModified\":\"2026-01-15T13:56:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\\\/\"},\"wordCount\":271,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090722\\\/11393362_705504699575153_2899450455245342486_o.jpg\",\"keywords\":[\"miejska wspinaczka\",\"Wspinaczka na Walltopia\"],\"articleSection\":[\"Newsroom\"],\"inLanguage\":\"pl-PL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\\\/\",\"name\":\"Walltopia - sponsor tytularny Australian Lead Climbing Championship | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090722\\\/11393362_705504699575153_2899450455245342486_o.jpg\",\"datePublished\":\"2021-06-17T11:43:20+00:00\",\"dateModified\":\"2026-01-15T13:56:16+00:00\",\"description\":\"Zupe\u0142nie nowe chwyty i niesamowite trasy by\u0142y jednymi z element\u00f3w, kt\u00f3re przenios\u0142y wspinaczk\u0119 zawodnicz\u0105 w Australii na wy\u017cszy poziom.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090722\\\/11393362_705504699575153_2899450455245342486_o.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090722\\\/11393362_705504699575153_2899450455245342486_o.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/strona-glowna-pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Walltopia &#8211; sponsor tytularny Australian Lead Climbing Championship\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\",\"name\":\"the_id\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Walltopia - sponsor tytularny Australian Lead Climbing Championship | Walltopia","description":"Zupe\u0142nie nowe chwyty i niesamowite trasy by\u0142y jednymi z element\u00f3w, kt\u00f3re przenios\u0142y wspinaczk\u0119 zawodnicz\u0105 w Australii na wy\u017cszy poziom.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/pl\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\/","og_locale":"pl_PL","og_type":"article","og_title":"Walltopia - sponsor tytularny Australian Lead Climbing Championship","og_description":"Zupe\u0142nie nowe chwyty i niesamowite trasy by\u0142y jednymi z element\u00f3w, kt\u00f3re przenios\u0142y wspinaczk\u0119 zawodnicz\u0105 w Australii na wy\u017cszy poziom.","og_url":"https:\/\/walltopia.com\/pl\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2021-06-17T11:43:20+00:00","article_modified_time":"2026-01-15T13:56:16+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090722\/11393362_705504699575153_2899450455245342486_o.jpg","type":"image\/jpeg"}],"author":"the_id","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/pl\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/pl\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\/"},"author":{"name":"the_id","@id":"https:\/\/walltopia.com\/pl\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff"},"headline":"Walltopia &#8211; sponsor tytularny Australian Lead Climbing Championship","datePublished":"2021-06-17T11:43:20+00:00","dateModified":"2026-01-15T13:56:16+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/pl\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\/"},"wordCount":271,"publisher":{"@id":"https:\/\/walltopia.com\/pl\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/pl\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090722\/11393362_705504699575153_2899450455245342486_o.jpg","keywords":["miejska wspinaczka","Wspinaczka na Walltopia"],"articleSection":["Newsroom"],"inLanguage":"pl-PL"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/pl\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\/","url":"https:\/\/walltopia.com\/pl\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\/","name":"Walltopia - sponsor tytularny Australian Lead Climbing Championship | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/pl\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/pl\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090722\/11393362_705504699575153_2899450455245342486_o.jpg","datePublished":"2021-06-17T11:43:20+00:00","dateModified":"2026-01-15T13:56:16+00:00","description":"Zupe\u0142nie nowe chwyty i niesamowite trasy by\u0142y jednymi z element\u00f3w, kt\u00f3re przenios\u0142y wspinaczk\u0119 zawodnicz\u0105 w Australii na wy\u017cszy poziom.","breadcrumb":{"@id":"https:\/\/walltopia.com\/pl\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/pl\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/walltopia.com\/pl\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090722\/11393362_705504699575153_2899450455245342486_o.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090722\/11393362_705504699575153_2899450455245342486_o.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/pl\/walltopia-sponsor-tytularny-australian-lead-climbing-championship\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/pl\/strona-glowna-pl\/"},{"@type":"ListItem","position":2,"name":"Walltopia &#8211; sponsor tytularny Australian Lead Climbing Championship"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/pl\/#website","url":"https:\/\/walltopia.com\/pl\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/pl\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/walltopia.com\/pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/pl\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff","name":"the_id"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/posts\/182006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/comments?post=182006"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/posts\/182006\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/media\/182008"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/media?parent=182006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/categories?post=182006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/tags?post=182006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}