{"id":182392,"date":"2021-06-17T12:45:13","date_gmt":"2021-06-17T09:45:13","guid":{"rendered":"https:\/\/walltopia.com\/walltopia-na-recon-2015\/"},"modified":"2026-01-15T16:57:01","modified_gmt":"2026-01-15T13:57:01","slug":"walltopia-na-recon-2015","status":"publish","type":"post","link":"https:\/\/walltopia.com\/pl\/walltopia-na-recon-2015\/","title":{"rendered":"Walltopia na RECon 2015"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_custom_heading text=&#8221;Przysz\u0142o\u015b\u0107 centr\u00f3w handlowych jest teraz i jest to przygoda.&#8221; font_container=&#8221;tag:h2|font_size:18|text_align:left|color:%23000000|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Poniewa\u017c ludzie nigdy nie przestan\u0105 chodzi\u0107 do centr\u00f3w handlowych, ale ich d\u0105\u017cenie szybko zmienia si\u0119 w kierunku rzeczy, kt\u00f3rych nie mo\u017cna po prostu kupi\u0107 online, ale kt\u00f3rych trzeba do\u015bwiadczy\u0107.<\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Spotkaj si\u0119 z nami na <strong>RECON 2015<\/strong> i dowiedz si\u0119, w jaki spos\u00f3b Walltopia i Adventure Facility Concepts &amp; Management rozwijaj\u0105 obiekty przygodowe, kt\u00f3re \u0142\u0105cz\u0105 zdrow\u0105 dawk\u0119 sportu i zaj\u0119\u0107 edukacyjnych, a tak\u017ce uzupe\u0142niaj\u0105 je zabaw\u0105 i adrenalin\u0105.<\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Data:<\/strong> 18-20 maja<br \/>\n<strong>Lokalizacja:<\/strong> Las Vegas Convention Center, Las Vegas, Nevada<br \/>\n<strong>Stoisko:<\/strong> #N1147<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Przysz\u0142o\u015b\u0107 centr\u00f3w handlowych jest teraz i jest przygod\u0105. Poniewa\u017c ludzie nigdy nie przestan\u0105 chodzi\u0107 do centr\u00f3w&#8230; ","protected":false},"author":10,"featured_media":182394,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1108],"tags":[1751],"class_list":["post-182392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsroom-pl","tag-walltopia-adventure"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Walltopia na RECon 2015 | Walltopia<\/title>\n<meta name=\"description\" content=\"Dowiedz si\u0119, w jaki spos\u00f3b \u0142\u0105czymy zdrow\u0105 dawk\u0119 sportu i nauki, uzupe\u0142niaj\u0105c je zabaw\u0105 i adrenalin\u0105.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/pl\/walltopia-na-recon-2015\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Walltopia na RECon 2015\" \/>\n<meta property=\"og:description\" content=\"Dowiedz si\u0119, w jaki spos\u00f3b \u0142\u0105czymy zdrow\u0105 dawk\u0119 sportu i nauki, uzupe\u0142niaj\u0105c je zabaw\u0105 i adrenalin\u0105.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/pl\/walltopia-na-recon-2015\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-17T09:45:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T13:57:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090748\/recon2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"479\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"the_id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-recon-2015\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-recon-2015\\\/\"},\"author\":{\"name\":\"the_id\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\"},\"headline\":\"Walltopia na RECon 2015\",\"datePublished\":\"2021-06-17T09:45:13+00:00\",\"dateModified\":\"2026-01-15T13:57:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-recon-2015\\\/\"},\"wordCount\":143,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-recon-2015\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090748\\\/recon2.jpg\",\"keywords\":[\"Walltopia Adventure\"],\"articleSection\":[\"Newsroom\"],\"inLanguage\":\"pl-PL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-recon-2015\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-recon-2015\\\/\",\"name\":\"Walltopia na RECon 2015 | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-recon-2015\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-recon-2015\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090748\\\/recon2.jpg\",\"datePublished\":\"2021-06-17T09:45:13+00:00\",\"dateModified\":\"2026-01-15T13:57:01+00:00\",\"description\":\"Dowiedz si\u0119, w jaki spos\u00f3b \u0142\u0105czymy zdrow\u0105 dawk\u0119 sportu i nauki, uzupe\u0142niaj\u0105c je zabaw\u0105 i adrenalin\u0105.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-recon-2015\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-recon-2015\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-recon-2015\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090748\\\/recon2.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090748\\\/recon2.jpg\",\"width\":900,\"height\":479},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-recon-2015\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/strona-glowna-pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Walltopia na RECon 2015\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\",\"name\":\"the_id\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Walltopia na RECon 2015 | Walltopia","description":"Dowiedz si\u0119, w jaki spos\u00f3b \u0142\u0105czymy zdrow\u0105 dawk\u0119 sportu i nauki, uzupe\u0142niaj\u0105c je zabaw\u0105 i adrenalin\u0105.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/pl\/walltopia-na-recon-2015\/","og_locale":"pl_PL","og_type":"article","og_title":"Walltopia na RECon 2015","og_description":"Dowiedz si\u0119, w jaki spos\u00f3b \u0142\u0105czymy zdrow\u0105 dawk\u0119 sportu i nauki, uzupe\u0142niaj\u0105c je zabaw\u0105 i adrenalin\u0105.","og_url":"https:\/\/walltopia.com\/pl\/walltopia-na-recon-2015\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2021-06-17T09:45:13+00:00","article_modified_time":"2026-01-15T13:57:01+00:00","og_image":[{"width":900,"height":479,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090748\/recon2.jpg","type":"image\/jpeg"}],"author":"the_id","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/pl\/walltopia-na-recon-2015\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/pl\/walltopia-na-recon-2015\/"},"author":{"name":"the_id","@id":"https:\/\/walltopia.com\/pl\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff"},"headline":"Walltopia na RECon 2015","datePublished":"2021-06-17T09:45:13+00:00","dateModified":"2026-01-15T13:57:01+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/pl\/walltopia-na-recon-2015\/"},"wordCount":143,"publisher":{"@id":"https:\/\/walltopia.com\/pl\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/pl\/walltopia-na-recon-2015\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090748\/recon2.jpg","keywords":["Walltopia Adventure"],"articleSection":["Newsroom"],"inLanguage":"pl-PL"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/pl\/walltopia-na-recon-2015\/","url":"https:\/\/walltopia.com\/pl\/walltopia-na-recon-2015\/","name":"Walltopia na RECon 2015 | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/pl\/walltopia-na-recon-2015\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/pl\/walltopia-na-recon-2015\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090748\/recon2.jpg","datePublished":"2021-06-17T09:45:13+00:00","dateModified":"2026-01-15T13:57:01+00:00","description":"Dowiedz si\u0119, w jaki spos\u00f3b \u0142\u0105czymy zdrow\u0105 dawk\u0119 sportu i nauki, uzupe\u0142niaj\u0105c je zabaw\u0105 i adrenalin\u0105.","breadcrumb":{"@id":"https:\/\/walltopia.com\/pl\/walltopia-na-recon-2015\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/pl\/walltopia-na-recon-2015\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/walltopia.com\/pl\/walltopia-na-recon-2015\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090748\/recon2.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090748\/recon2.jpg","width":900,"height":479},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/pl\/walltopia-na-recon-2015\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/pl\/strona-glowna-pl\/"},{"@type":"ListItem","position":2,"name":"Walltopia na RECon 2015"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/pl\/#website","url":"https:\/\/walltopia.com\/pl\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/pl\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/walltopia.com\/pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/pl\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff","name":"the_id"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/posts\/182392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/comments?post=182392"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/posts\/182392\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/media\/182394"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/media?parent=182392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/categories?post=182392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/tags?post=182392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}