{"id":188652,"date":"2015-10-30T08:08:22","date_gmt":"2015-10-30T05:08:22","guid":{"rendered":"https:\/\/walltopia.com\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\/"},"modified":"2026-01-15T17:38:29","modified_gmt":"2026-01-15T14:38:29","slug":"poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2","status":"publish","type":"post","link":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\/","title":{"rendered":"Poznaj Walltopia Adventure na targach IAAPA Attractions Expo 2015"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column css_animation=&#8221;fadeInUp&#8221;][vc_column_text]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Walltopia Adventure zaprezentuje swoje marki <a href=\"https:\/\/staging-3.walltopia.com\/products\/fun-walls\/\">Fun Walls<\/a>, <a href=\"https:\/\/staging-3.walltopia.com\/products\/walltopia-caves\/\">Walltopia Caves<\/a>, <a href=\"https:\/\/staging-3.walltopia.com\/products\/ropes-course\/\">Ropes Course<\/a> i <a href=\"https:\/\/staging-3.walltopia.com\/products\/rollglider\/\">Rollglider<\/a> na targach <a href=\"https:\/\/www.iaapa.org\/\">IAAPA Attractions Expo<\/a> w Orlando na Florydzie. Dowiedz si\u0119, co ka\u017cdy produkt mo\u017ce zrobi\u0107 dla firm z <a href=\"https:\/\/staging-3.walltopia.com\/industries\/amusement-parks\/\">bran\u017cy rozrywkowej<\/a> od 17 do 20 listopada na stoisku 4054. <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Konferencja prasowa oficjalnie og\u0142aszaj\u0105ca uruchomienie Rollglidera odb\u0119dzie si\u0119 18 listopada o godzinie 11:45 na stoisku.<\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Chcesz um\u00f3wi\u0107 si\u0119 na spotkanie? Skontaktuj si\u0119 z nami pod adresem <a href=\"mailto:sales@walltopia.com\">sales@walltopia.com.<\/a> <\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Walltopia Adventure zaprezentuje swoje marki Fun Walls, Rocktopia, Ropetopia i Rollglider na targach IAAPA Attractions Expo.","protected":false},"author":5,"featured_media":188654,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1113],"tags":[1109,3071,3072],"class_list":["post-188652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktywna-rozrywka","tag-iaapa-pl","tag-iaapa-attractions-expo","tag-iaapa-attractions-expo-2015"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Poznaj Walltopia Adventure na targach IAAPA Attractions Expo 2015 | Walltopia<\/title>\n<meta name=\"description\" content=\"Walltopia Adventure zaprezentuje swoje marki. Dowiedz si\u0119, co ka\u017cdy produkt mo\u017ce zrobi\u0107 dla firm z bran\u017cy rozrywkowej.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Poznaj Walltopia Adventure na targach IAAPA Attractions Expo 2015\" \/>\n<meta property=\"og:description\" content=\"Walltopia Adventure zaprezentuje swoje marki. Dowiedz si\u0119, co ka\u017cdy produkt mo\u017ce zrobi\u0107 dla firm z bran\u017cy rozrywkowej.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-30T05:08:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:38:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027150059\/Walltopia-IAAPA-Attractions-Expo-2015.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"479\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Poznaj Walltopia Adventure na targach IAAPA Attractions Expo 2015\",\"datePublished\":\"2015-10-30T05:08:22+00:00\",\"dateModified\":\"2026-01-15T14:38:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\\\/\"},\"wordCount\":98,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027150059\\\/Walltopia-IAAPA-Attractions-Expo-2015.jpg\",\"keywords\":[\"IAAPA\",\"IAAPA Attractions Expo\",\"IAAPA Attractions Expo 2015\"],\"articleSection\":[\"Aktywna rozrywka\"],\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pl\\\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\\\/\",\"name\":\"Poznaj Walltopia Adventure na targach IAAPA Attractions Expo 2015 | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027150059\\\/Walltopia-IAAPA-Attractions-Expo-2015.jpg\",\"datePublished\":\"2015-10-30T05:08:22+00:00\",\"dateModified\":\"2026-01-15T14:38:29+00:00\",\"description\":\"Walltopia Adventure zaprezentuje swoje marki. Dowiedz si\u0119, co ka\u017cdy produkt mo\u017ce zrobi\u0107 dla firm z bran\u017cy rozrywkowej.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pl\\\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027150059\\\/Walltopia-IAAPA-Attractions-Expo-2015.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027150059\\\/Walltopia-IAAPA-Attractions-Expo-2015.jpg\",\"width\":900,\"height\":479},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/strona-glowna-pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Poznaj Walltopia Adventure na targach IAAPA Attractions Expo 2015\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Poznaj Walltopia Adventure na targach IAAPA Attractions Expo 2015 | Walltopia","description":"Walltopia Adventure zaprezentuje swoje marki. Dowiedz si\u0119, co ka\u017cdy produkt mo\u017ce zrobi\u0107 dla firm z bran\u017cy rozrywkowej.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\/","og_locale":"pl_PL","og_type":"article","og_title":"Poznaj Walltopia Adventure na targach IAAPA Attractions Expo 2015","og_description":"Walltopia Adventure zaprezentuje swoje marki. Dowiedz si\u0119, co ka\u017cdy produkt mo\u017ce zrobi\u0107 dla firm z bran\u017cy rozrywkowej.","og_url":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2015-10-30T05:08:22+00:00","article_modified_time":"2026-01-15T14:38:29+00:00","og_image":[{"width":900,"height":479,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027150059\/Walltopia-IAAPA-Attractions-Expo-2015.jpg","type":"image\/jpeg"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/pl\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Poznaj Walltopia Adventure na targach IAAPA Attractions Expo 2015","datePublished":"2015-10-30T05:08:22+00:00","dateModified":"2026-01-15T14:38:29+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\/"},"wordCount":98,"commentCount":0,"publisher":{"@id":"https:\/\/walltopia.com\/pl\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027150059\/Walltopia-IAAPA-Attractions-Expo-2015.jpg","keywords":["IAAPA","IAAPA Attractions Expo","IAAPA Attractions Expo 2015"],"articleSection":["Aktywna rozrywka"],"inLanguage":"pl-PL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\/","url":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\/","name":"Poznaj Walltopia Adventure na targach IAAPA Attractions Expo 2015 | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027150059\/Walltopia-IAAPA-Attractions-Expo-2015.jpg","datePublished":"2015-10-30T05:08:22+00:00","dateModified":"2026-01-15T14:38:29+00:00","description":"Walltopia Adventure zaprezentuje swoje marki. Dowiedz si\u0119, co ka\u017cdy produkt mo\u017ce zrobi\u0107 dla firm z bran\u017cy rozrywkowej.","breadcrumb":{"@id":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027150059\/Walltopia-IAAPA-Attractions-Expo-2015.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027150059\/Walltopia-IAAPA-Attractions-Expo-2015.jpg","width":900,"height":479},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/pl\/poznaj-walltopia-adventure-na-targach-iaapa-attractions-expo-2015-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/pl\/strona-glowna-pl\/"},{"@type":"ListItem","position":2,"name":"Poznaj Walltopia Adventure na targach IAAPA Attractions Expo 2015"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/pl\/#website","url":"https:\/\/walltopia.com\/pl\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/pl\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/walltopia.com\/pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/pl\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/posts\/188652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/comments?post=188652"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/posts\/188652\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/media\/188654"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/media?parent=188652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/categories?post=188652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/tags?post=188652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}