{"id":191370,"date":"2016-07-13T08:19:34","date_gmt":"2016-07-13T05:19:34","guid":{"rendered":"https:\/\/walltopia.com\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\/"},"modified":"2026-01-15T17:44:44","modified_gmt":"2026-01-15T14:44:44","slug":"walltopia-na-targach-outdoor-show-we-friedrichshafen-3","status":"publish","type":"post","link":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\/","title":{"rendered":"Walltopia na targach Outdoor Show we Friedrichshafen"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column css_animation=&#8221;fadeInUp&#8221;][vc_column_text]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Walltopia wystawia si\u0119 na targach <a href=\"https:\/\/www.outdoor-show.com\/\">Outdoor Show<\/a> we Friedrichshafen od 13 do 16 lipca. Sprawd\u017a nasze najnowsze produkty i innowacje na <strong> stoisku 505 (hala B2).<\/strong> Zapoznamy Ci\u0119 z kolejn\u0105 wielk\u0105 rzecz\u0105 w aktywnej rozrywce &#8211; <a href=\"https:\/\/staging-3.walltopia.com\/products\/ninja-course\/\">Ninja Course.<\/a> <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Jeste\u015bmy r\u00f3wnie\u017c bardzo podekscytowani mo\u017cliwo\u015bci\u0105 pokazania niekt\u00f3rych z naszych projekt\u00f3w w 3D! Zapytaj o nasze gogle wirtualnej rzeczywisto\u015bci i zobacz, jak nasze produkty o\u017cywaj\u0105. <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Do zobaczenia wkr\u00f3tce!<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Walltopia wystawia si\u0119 na targach Outdoor Show we Friedrichshafen od 13 do 16 lipca.","protected":false},"author":5,"featured_media":191371,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1113],"tags":[2225],"class_list":["post-191370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktywna-rozrywka","tag-outdoor-show-we-friedrichshafen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Walltopia na targach Outdoor Show we Friedrichshafen | Walltopia<\/title>\n<meta name=\"description\" content=\"Wystawiamy si\u0119 na Outdoor Show, sprawd\u017a nasze najnowsze produkty i innowacje. Przeczytaj artyku\u0142, aby zobaczy\u0107, co jeszcze poka\u017cemy.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/pl\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Walltopia na targach Outdoor Show we Friedrichshafen\" \/>\n<meta property=\"og:description\" content=\"Wystawiamy si\u0119 na Outdoor Show, sprawd\u017a nasze najnowsze produkty i innowacje. Przeczytaj artyku\u0142, aby zobaczy\u0107, co jeszcze poka\u017cemy.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/pl\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-13T05:19:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:44:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145813\/Walltopia-Outdoor-Show-Friedrichshafen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Walltopia na targach Outdoor Show we Friedrichshafen\",\"datePublished\":\"2016-07-13T05:19:34+00:00\",\"dateModified\":\"2026-01-15T14:44:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\\\/\"},\"wordCount\":94,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145813\\\/Walltopia-Outdoor-Show-Friedrichshafen.jpg\",\"keywords\":[\"Outdoor Show we Friedrichshafen\"],\"articleSection\":[\"Aktywna rozrywka\"],\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\\\/\",\"name\":\"Walltopia na targach Outdoor Show we Friedrichshafen | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145813\\\/Walltopia-Outdoor-Show-Friedrichshafen.jpg\",\"datePublished\":\"2016-07-13T05:19:34+00:00\",\"dateModified\":\"2026-01-15T14:44:44+00:00\",\"description\":\"Wystawiamy si\u0119 na Outdoor Show, sprawd\u017a nasze najnowsze produkty i innowacje. Przeczytaj artyku\u0142, aby zobaczy\u0107, co jeszcze poka\u017cemy.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145813\\\/Walltopia-Outdoor-Show-Friedrichshafen.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145813\\\/Walltopia-Outdoor-Show-Friedrichshafen.jpg\",\"width\":900,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/strona-glowna-pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Walltopia na targach Outdoor Show we Friedrichshafen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Walltopia na targach Outdoor Show we Friedrichshafen | Walltopia","description":"Wystawiamy si\u0119 na Outdoor Show, sprawd\u017a nasze najnowsze produkty i innowacje. Przeczytaj artyku\u0142, aby zobaczy\u0107, co jeszcze poka\u017cemy.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\/","og_locale":"pl_PL","og_type":"article","og_title":"Walltopia na targach Outdoor Show we Friedrichshafen","og_description":"Wystawiamy si\u0119 na Outdoor Show, sprawd\u017a nasze najnowsze produkty i innowacje. Przeczytaj artyku\u0142, aby zobaczy\u0107, co jeszcze poka\u017cemy.","og_url":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2016-07-13T05:19:34+00:00","article_modified_time":"2026-01-15T14:44:44+00:00","og_image":[{"width":900,"height":478,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145813\/Walltopia-Outdoor-Show-Friedrichshafen.jpg","type":"image\/jpeg"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/pl\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Walltopia na targach Outdoor Show we Friedrichshafen","datePublished":"2016-07-13T05:19:34+00:00","dateModified":"2026-01-15T14:44:44+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\/"},"wordCount":94,"commentCount":0,"publisher":{"@id":"https:\/\/walltopia.com\/pl\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145813\/Walltopia-Outdoor-Show-Friedrichshafen.jpg","keywords":["Outdoor Show we Friedrichshafen"],"articleSection":["Aktywna rozrywka"],"inLanguage":"pl-PL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/walltopia.com\/pl\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\/","url":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\/","name":"Walltopia na targach Outdoor Show we Friedrichshafen | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145813\/Walltopia-Outdoor-Show-Friedrichshafen.jpg","datePublished":"2016-07-13T05:19:34+00:00","dateModified":"2026-01-15T14:44:44+00:00","description":"Wystawiamy si\u0119 na Outdoor Show, sprawd\u017a nasze najnowsze produkty i innowacje. Przeczytaj artyku\u0142, aby zobaczy\u0107, co jeszcze poka\u017cemy.","breadcrumb":{"@id":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/pl\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145813\/Walltopia-Outdoor-Show-Friedrichshafen.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145813\/Walltopia-Outdoor-Show-Friedrichshafen.jpg","width":900,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-outdoor-show-we-friedrichshafen-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/pl\/strona-glowna-pl\/"},{"@type":"ListItem","position":2,"name":"Walltopia na targach Outdoor Show we Friedrichshafen"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/pl\/#website","url":"https:\/\/walltopia.com\/pl\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/pl\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/walltopia.com\/pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/pl\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/posts\/191370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/comments?post=191370"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/posts\/191370\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/media\/191371"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/media?parent=191370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/categories?post=191370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/tags?post=191370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}