{"id":192695,"date":"2017-09-27T08:29:58","date_gmt":"2017-09-27T05:29:58","guid":{"rendered":"https:\/\/walltopia.com\/walltopia-na-targach-family-attractions-expo-w-birmingham\/"},"modified":"2026-01-15T17:47:33","modified_gmt":"2026-01-15T14:47:33","slug":"walltopia-na-targach-family-attractions-expo-w-birmingham","status":"publish","type":"post","link":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-family-attractions-expo-w-birmingham\/","title":{"rendered":"Walltopia na targach Family Attractions Expo w Birmingham"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column css_animation=&#8221;fadeInUp&#8221;][vc_column_text]\n<p style=\"font-size:18px; line-height: 1.8em;\">Wkr\u00f3tce odwiedzimy <b>Birmingham<\/b> i chcemy si\u0119 z Tob\u0105 spotka\u0107, aby porozmawia\u0107 o Twoich przysz\u0142ych planach rozbudowy lub renowacji Twojego obiektu. Odkryj, w jaki spos\u00f3b nasze aktywne rozwi\u0105zania rozrywkowe tworz\u0105 wyj\u0105tkowe do\u015bwiadczenia dla odwiedzaj\u0105cych FEC i ostatecznie przyci\u0105gaj\u0105 wi\u0119cej klient\u00f3w. <\/p>\n<p style=\"font-size:18px; line-height: 1.8em;\">Odwied\u017a <b> stoisko 1130 <\/b> w <b> NEC <\/b> w dniach <b> 8 i 9 listopada<\/b>. Zalecamy wcze\u015bniejsze um\u00f3wienie spotkania z jednym z cz\u0142onk\u00f3w naszego zespo\u0142u. Skontaktuj si\u0119 z nami pod adresem <a href=\"mailto:adventure@walltopia.com\">adventure@walltopia.com.<\/a>  <\/p>\n<p style=\"font-size:18px; line-height: 1.8em;\">Nie zapomnij sprawdzi\u0107 naszej powietrznej przeja\u017cd\u017cki <a href=\"https:\/\/staging-3.walltopia.com\/products\/rollglider\/\" target=\"_blank\" rel=\"noopener\">(Rollglider)<\/a>, <a href=\"https:\/\/staging-3.walltopia.com\/products\/ropes-course\/\" target=\"_blank\" rel=\"noopener\">tor\u00f3w linowych<\/a>, <a href=\"https:\/\/staging-3.walltopia.com\/products\/fun-walls\/\" target=\"_blank\" rel=\"noopener\">interaktywnych \u015bcianek wspinaczkowych<\/a> dla dzieci i doros\u0142ych (Fun Walls) oraz tor\u00f3w przeszk\u00f3d <a href=\"https:\/\/staging-3.walltopia.com\/products\/ninja-course\/\" target=\"_blank\" rel=\"noopener\">(Ninja Course)<\/a>.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Wkr\u00f3tce odwiedzimy Birmingham i chcemy si\u0119 z Tob\u0105 spotka\u0107, aby porozmawia\u0107 o Twoich przysz\u0142ych planach rozbudowy lub renowacji Twojego obiektu.","protected":false},"author":5,"featured_media":192697,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1113],"tags":[3882,3880],"class_list":["post-192695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktywna-rozrywka","tag-atrakcje-rodzinne","tag-family-attractions-expo-w-birmingham"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Walltopia na targach Family Attractions Expo w Birmingham | Walltopia<\/title>\n<meta name=\"description\" content=\"Odkryj, w jaki spos\u00f3b nasze aktywne rozwi\u0105zania rozrywkowe tworz\u0105 wyj\u0105tkowe do\u015bwiadczenia dla odwiedzaj\u0105cych FEC i ostatecznie przyci\u0105gaj\u0105 wi\u0119cej klient\u00f3w.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/pl\/walltopia-na-targach-family-attractions-expo-w-birmingham\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Walltopia na targach Family Attractions Expo w Birmingham\" \/>\n<meta property=\"og:description\" content=\"Odkryj, w jaki spos\u00f3b nasze aktywne rozwi\u0105zania rozrywkowe tworz\u0105 wyj\u0105tkowe do\u015bwiadczenia dla odwiedzaj\u0105cych FEC i ostatecznie przyci\u0105gaj\u0105 wi\u0119cej klient\u00f3w.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/pl\/walltopia-na-targach-family-attractions-expo-w-birmingham\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-27T05:29:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:47:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145410\/Walltopia-Family-Attractions-Expo-Birmingham-2017.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-family-attractions-expo-w-birmingham\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-family-attractions-expo-w-birmingham\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Walltopia na targach Family Attractions Expo w Birmingham\",\"datePublished\":\"2017-09-27T05:29:58+00:00\",\"dateModified\":\"2026-01-15T14:47:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-family-attractions-expo-w-birmingham\\\/\"},\"wordCount\":135,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-family-attractions-expo-w-birmingham\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145410\\\/Walltopia-Family-Attractions-Expo-Birmingham-2017.jpg\",\"keywords\":[\"Atrakcje rodzinne\",\"Family Attractions Expo w Birmingham\"],\"articleSection\":[\"Aktywna rozrywka\"],\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-family-attractions-expo-w-birmingham\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-family-attractions-expo-w-birmingham\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-family-attractions-expo-w-birmingham\\\/\",\"name\":\"Walltopia na targach Family Attractions Expo w Birmingham | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-family-attractions-expo-w-birmingham\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-family-attractions-expo-w-birmingham\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145410\\\/Walltopia-Family-Attractions-Expo-Birmingham-2017.jpg\",\"datePublished\":\"2017-09-27T05:29:58+00:00\",\"dateModified\":\"2026-01-15T14:47:33+00:00\",\"description\":\"Odkryj, w jaki spos\u00f3b nasze aktywne rozwi\u0105zania rozrywkowe tworz\u0105 wyj\u0105tkowe do\u015bwiadczenia dla odwiedzaj\u0105cych FEC i ostatecznie przyci\u0105gaj\u0105 wi\u0119cej klient\u00f3w.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-family-attractions-expo-w-birmingham\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-family-attractions-expo-w-birmingham\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-family-attractions-expo-w-birmingham\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145410\\\/Walltopia-Family-Attractions-Expo-Birmingham-2017.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145410\\\/Walltopia-Family-Attractions-Expo-Birmingham-2017.jpg\",\"width\":900,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/walltopia-na-targach-family-attractions-expo-w-birmingham\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/strona-glowna-pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Walltopia na targach Family Attractions Expo w Birmingham\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Walltopia na targach Family Attractions Expo w Birmingham | Walltopia","description":"Odkryj, w jaki spos\u00f3b nasze aktywne rozwi\u0105zania rozrywkowe tworz\u0105 wyj\u0105tkowe do\u015bwiadczenia dla odwiedzaj\u0105cych FEC i ostatecznie przyci\u0105gaj\u0105 wi\u0119cej klient\u00f3w.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-family-attractions-expo-w-birmingham\/","og_locale":"pl_PL","og_type":"article","og_title":"Walltopia na targach Family Attractions Expo w Birmingham","og_description":"Odkryj, w jaki spos\u00f3b nasze aktywne rozwi\u0105zania rozrywkowe tworz\u0105 wyj\u0105tkowe do\u015bwiadczenia dla odwiedzaj\u0105cych FEC i ostatecznie przyci\u0105gaj\u0105 wi\u0119cej klient\u00f3w.","og_url":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-family-attractions-expo-w-birmingham\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2017-09-27T05:29:58+00:00","article_modified_time":"2026-01-15T14:47:33+00:00","og_image":[{"width":900,"height":478,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145410\/Walltopia-Family-Attractions-Expo-Birmingham-2017.jpg","type":"image\/jpeg"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-family-attractions-expo-w-birmingham\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-family-attractions-expo-w-birmingham\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/pl\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Walltopia na targach Family Attractions Expo w Birmingham","datePublished":"2017-09-27T05:29:58+00:00","dateModified":"2026-01-15T14:47:33+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-family-attractions-expo-w-birmingham\/"},"wordCount":135,"commentCount":0,"publisher":{"@id":"https:\/\/walltopia.com\/pl\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-family-attractions-expo-w-birmingham\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145410\/Walltopia-Family-Attractions-Expo-Birmingham-2017.jpg","keywords":["Atrakcje rodzinne","Family Attractions Expo w Birmingham"],"articleSection":["Aktywna rozrywka"],"inLanguage":"pl-PL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/walltopia.com\/pl\/walltopia-na-targach-family-attractions-expo-w-birmingham\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-family-attractions-expo-w-birmingham\/","url":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-family-attractions-expo-w-birmingham\/","name":"Walltopia na targach Family Attractions Expo w Birmingham | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-family-attractions-expo-w-birmingham\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-family-attractions-expo-w-birmingham\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145410\/Walltopia-Family-Attractions-Expo-Birmingham-2017.jpg","datePublished":"2017-09-27T05:29:58+00:00","dateModified":"2026-01-15T14:47:33+00:00","description":"Odkryj, w jaki spos\u00f3b nasze aktywne rozwi\u0105zania rozrywkowe tworz\u0105 wyj\u0105tkowe do\u015bwiadczenia dla odwiedzaj\u0105cych FEC i ostatecznie przyci\u0105gaj\u0105 wi\u0119cej klient\u00f3w.","breadcrumb":{"@id":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-family-attractions-expo-w-birmingham\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/pl\/walltopia-na-targach-family-attractions-expo-w-birmingham\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-family-attractions-expo-w-birmingham\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145410\/Walltopia-Family-Attractions-Expo-Birmingham-2017.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145410\/Walltopia-Family-Attractions-Expo-Birmingham-2017.jpg","width":900,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/pl\/walltopia-na-targach-family-attractions-expo-w-birmingham\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/pl\/strona-glowna-pl\/"},{"@type":"ListItem","position":2,"name":"Walltopia na targach Family Attractions Expo w Birmingham"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/pl\/#website","url":"https:\/\/walltopia.com\/pl\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/pl\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/walltopia.com\/pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/pl\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/posts\/192695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/comments?post=192695"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/posts\/192695\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/media\/192697"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/media?parent=192695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/categories?post=192695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/tags?post=192695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}