{"id":136856,"date":"2024-07-11T20:19:05","date_gmt":"2024-07-11T17:19:05","guid":{"rendered":"http:\/\/walltopia.com\/?post_type=wt_project&#038;p=136856"},"modified":"2024-07-11T20:19:05","modified_gmt":"2024-07-11T17:19:05","slug":"hidden-valley-outdoor-fun-walls","status":"publish","type":"wt_project","link":"https:\/\/walltopia.com\/pl\/projects\/hidden-valley-outdoor-fun-walls\/","title":{"rendered":"Hidden Valley"},"content":{"rendered":"<p>Outdoor <a href=\"http:\/\/walltopia.com\/products\/fun-walls\/\">Fun Walls<\/a> located in the <a href=\"https:\/\/www.hiddenvalley.ie\/\">Hidden Valley<\/a> resort in Ireland. The kids climbing area is a new addition to the active entertainment offerings of the adventure park. A selection of Walltopia fun climbs attracts kids and adults alike! <\/p>\n","protected":false},"featured_media":136857,"template":"","wt_project_category":[760],"class_list":["post-136856","wt_project","type-wt_project","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hidden Valley | Walltopia<\/title>\n<meta name=\"description\" content=\"Outdoor Fun Walls in Hidden Valley resort, Ireland are a new addition to the active entertainment offerings of the adventure park.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/pl\/projects\/hidden-valley-outdoor-fun-walls\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hidden Valley\" \/>\n<meta property=\"og:description\" content=\"Outdoor Fun Walls in Hidden Valley resort, Ireland are a new addition to the active entertainment offerings of the adventure park.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/pl\/projects\/hidden-valley-outdoor-fun-walls\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240711201355\/hidden-valley-ireland-outdoor-funwalls-web-5-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/hidden-valley-outdoor-fun-walls\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/hidden-valley-outdoor-fun-walls\\\/\",\"name\":\"Hidden Valley | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/hidden-valley-outdoor-fun-walls\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/hidden-valley-outdoor-fun-walls\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20240711201355\\\/hidden-valley-ireland-outdoor-funwalls-web-5-scaled.jpg\",\"datePublished\":\"2024-07-11T17:19:05+00:00\",\"description\":\"Outdoor Fun Walls in Hidden Valley resort, Ireland are a new addition to the active entertainment offerings of the adventure park.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/hidden-valley-outdoor-fun-walls\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/hidden-valley-outdoor-fun-walls\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/hidden-valley-outdoor-fun-walls\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20240711201355\\\/hidden-valley-ireland-outdoor-funwalls-web-5-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20240711201355\\\/hidden-valley-ireland-outdoor-funwalls-web-5-scaled.jpg\",\"width\":1200,\"height\":900,\"caption\":\"Outdoor FunWalls in Hidden Valley adventure park and resort, Ireland\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/hidden-valley-outdoor-fun-walls\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/strona-glowna-pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hidden Valley\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hidden Valley | Walltopia","description":"Outdoor Fun Walls in Hidden Valley resort, Ireland are a new addition to the active entertainment offerings of the adventure park.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/pl\/projects\/hidden-valley-outdoor-fun-walls\/","og_locale":"pl_PL","og_type":"article","og_title":"Hidden Valley","og_description":"Outdoor Fun Walls in Hidden Valley resort, Ireland are a new addition to the active entertainment offerings of the adventure park.","og_url":"https:\/\/walltopia.com\/pl\/projects\/hidden-valley-outdoor-fun-walls\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","og_image":[{"width":1200,"height":900,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240711201355\/hidden-valley-ireland-outdoor-funwalls-web-5-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/pl\/projects\/hidden-valley-outdoor-fun-walls\/","url":"https:\/\/walltopia.com\/pl\/projects\/hidden-valley-outdoor-fun-walls\/","name":"Hidden Valley | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/pl\/projects\/hidden-valley-outdoor-fun-walls\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/pl\/projects\/hidden-valley-outdoor-fun-walls\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240711201355\/hidden-valley-ireland-outdoor-funwalls-web-5-scaled.jpg","datePublished":"2024-07-11T17:19:05+00:00","description":"Outdoor Fun Walls in Hidden Valley resort, Ireland are a new addition to the active entertainment offerings of the adventure park.","breadcrumb":{"@id":"https:\/\/walltopia.com\/pl\/projects\/hidden-valley-outdoor-fun-walls\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/pl\/projects\/hidden-valley-outdoor-fun-walls\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/walltopia.com\/pl\/projects\/hidden-valley-outdoor-fun-walls\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240711201355\/hidden-valley-ireland-outdoor-funwalls-web-5-scaled.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240711201355\/hidden-valley-ireland-outdoor-funwalls-web-5-scaled.jpg","width":1200,"height":900,"caption":"Outdoor FunWalls in Hidden Valley adventure park and resort, Ireland"},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/pl\/projects\/hidden-valley-outdoor-fun-walls\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/pl\/strona-glowna-pl\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/walltopia.com\/pl\/projects\/"},{"@type":"ListItem","position":3,"name":"Hidden Valley"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/pl\/#website","url":"https:\/\/walltopia.com\/pl\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/pl\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/walltopia.com\/pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/wt_project\/136856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/wt_project"}],"about":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/types\/wt_project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/media\/136857"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/media?parent=136856"}],"wp:term":[{"taxonomy":"wt_project_category","embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/wt_project_category?post=136856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}