{"id":163375,"date":"2025-04-16T17:36:26","date_gmt":"2025-04-16T14:36:26","guid":{"rendered":"http:\/\/walltopia.com\/?post_type=wt_project&#038;p=163375"},"modified":"2026-07-14T10:38:37","modified_gmt":"2026-07-14T07:38:37","slug":"high-point-climbing-and-fitness-orlando","status":"publish","type":"wt_project","link":"https:\/\/walltopia.com\/pl\/projects\/high-point-climbing-and-fitness-orlando\/","title":{"rendered":"High Point Climbing and Fitness Orlando"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"High Point Climbing &amp; Fitness Orlando\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/EwXHcBmoou8?feature=oembed&#038;enablejsapi=1&#038;origin=https:\/\/walltopia.com\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><a href=\"https:\/\/www.highpointclimbing.com\/orlando\">High Point Climbing &amp; Fitness<\/a> is a climbing gym chain in the USA. Operating 6 climbing gyms in Alabama and Tennessee, this one is their seventh facility and first location in Florida. The full-service gym include a 52-foot-tall rope climbing area with the only competition <a href=\"http:\/\/walltopia.com\/products\/speed-walls\/\">speed wall <\/a>in Florida, along with a large <a href=\"http:\/\/walltopia.com\/products\/boulder-walls\/\">bouldering <\/a> and training area. High Point Orlando will also include a 4,000 square foot <a href=\"http:\/\/walltopia.com\/products\/kids-climbing-walls\/\">Kid Zone<\/a> with <a href=\"http:\/\/walltopia.com\/products\/fun-walls\/\">Fun Walls<\/a> designed to introduce children to the fun of climbing. Beyond climbing, the facility will have a fitness area with weights, strength and aerobic machines, a yoga studio, locker rooms with showers and a pro shop to compliment the experience.<\/p>\n","protected":false},"featured_media":163561,"template":"","wt_project_category":[761],"class_list":["post-163375","wt_project","type-wt_project","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>High Point Climbing and Fitness Orlando | Walltopia<\/title>\n<meta name=\"description\" content=\"High Point is a full-service climbing gym in Orlando, USA featuring the only speed wall in Florida along with bouldering, rope climbing and a kids zone.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/pl\/projects\/high-point-climbing-and-fitness-orlando\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"High Point Climbing and Fitness Orlando\" \/>\n<meta property=\"og:description\" content=\"High Point is a full-service climbing gym in Orlando, USA featuring the only speed wall in Florida along with bouldering, rope climbing and a kids zone.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/pl\/projects\/high-point-climbing-and-fitness-orlando\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T07:38:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250417014153\/High-Point-Orlando-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/high-point-climbing-and-fitness-orlando\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/high-point-climbing-and-fitness-orlando\\\/\",\"name\":\"High Point Climbing and Fitness Orlando | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/high-point-climbing-and-fitness-orlando\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/high-point-climbing-and-fitness-orlando\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20250417014153\\\/High-Point-Orlando-1-scaled.jpg\",\"datePublished\":\"2025-04-16T14:36:26+00:00\",\"dateModified\":\"2026-07-14T07:38:37+00:00\",\"description\":\"High Point is a full-service climbing gym in Orlando, USA featuring the only speed wall in Florida along with bouldering, rope climbing and a kids zone.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/high-point-climbing-and-fitness-orlando\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/high-point-climbing-and-fitness-orlando\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/high-point-climbing-and-fitness-orlando\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20250417014153\\\/High-Point-Orlando-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20250417014153\\\/High-Point-Orlando-1-scaled.jpg\",\"width\":1200,\"height\":675,\"caption\":\"Walltopia climbing walls in High Point Climbing and Fitness - Orlando, FL, USA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/high-point-climbing-and-fitness-orlando\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/strona-glowna-pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"High Point Climbing and Fitness Orlando\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"High Point Climbing and Fitness Orlando | Walltopia","description":"High Point is a full-service climbing gym in Orlando, USA featuring the only speed wall in Florida along with bouldering, rope climbing and a kids zone.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/pl\/projects\/high-point-climbing-and-fitness-orlando\/","og_locale":"pl_PL","og_type":"article","og_title":"High Point Climbing and Fitness Orlando","og_description":"High Point is a full-service climbing gym in Orlando, USA featuring the only speed wall in Florida along with bouldering, rope climbing and a kids zone.","og_url":"https:\/\/walltopia.com\/pl\/projects\/high-point-climbing-and-fitness-orlando\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2026-07-14T07:38:37+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250417014153\/High-Point-Orlando-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/pl\/projects\/high-point-climbing-and-fitness-orlando\/","url":"https:\/\/walltopia.com\/pl\/projects\/high-point-climbing-and-fitness-orlando\/","name":"High Point Climbing and Fitness Orlando | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/pl\/projects\/high-point-climbing-and-fitness-orlando\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/pl\/projects\/high-point-climbing-and-fitness-orlando\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250417014153\/High-Point-Orlando-1-scaled.jpg","datePublished":"2025-04-16T14:36:26+00:00","dateModified":"2026-07-14T07:38:37+00:00","description":"High Point is a full-service climbing gym in Orlando, USA featuring the only speed wall in Florida along with bouldering, rope climbing and a kids zone.","breadcrumb":{"@id":"https:\/\/walltopia.com\/pl\/projects\/high-point-climbing-and-fitness-orlando\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/pl\/projects\/high-point-climbing-and-fitness-orlando\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/walltopia.com\/pl\/projects\/high-point-climbing-and-fitness-orlando\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250417014153\/High-Point-Orlando-1-scaled.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250417014153\/High-Point-Orlando-1-scaled.jpg","width":1200,"height":675,"caption":"Walltopia climbing walls in High Point Climbing and Fitness - Orlando, FL, USA"},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/pl\/projects\/high-point-climbing-and-fitness-orlando\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/pl\/strona-glowna-pl\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/walltopia.com\/pl\/projects\/"},{"@type":"ListItem","position":3,"name":"High Point Climbing and Fitness Orlando"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/pl\/#website","url":"https:\/\/walltopia.com\/pl\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/pl\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/walltopia.com\/pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/wt_project\/163375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/wt_project"}],"about":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/types\/wt_project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/media\/163561"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/media?parent=163375"}],"wp:term":[{"taxonomy":"wt_project_category","embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/wt_project_category?post=163375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}