{"id":17131,"date":"2021-07-12T11:17:04","date_gmt":"2021-07-12T08:17:04","guid":{"rendered":"https:\/\/dev-three.agmastudio.com\/?post_type=wt_project&#038;p=17131"},"modified":"2023-05-22T14:21:01","modified_gmt":"2023-05-22T11:21:01","slug":"blockle-boulderhalle-ravensburg","status":"publish","type":"wt_project","link":"https:\/\/walltopia.com\/pl\/projects\/blockle-boulderhalle-ravensburg\/","title":{"rendered":"Bl\u00f6ckle Boulderhalle Ravensburg"},"content":{"rendered":"","protected":false},"featured_media":19744,"template":"","wt_project_category":[8771],"class_list":["post-17131","wt_project","type-wt_project","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bl\u00f6ckle Boulderhalle Ravensburg - Projects | Walltopia Climbin Walls<\/title>\n<meta name=\"description\" content=\"Bl\u00f6ckle Boulderhalle Ravensburg is a Boulder Gym with Boulder Walls in Ravensburg, Germany. Find out more about the project here.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/pl\/projects\/blockle-boulderhalle-ravensburg\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bl\u00f6ckle Boulderhalle Ravensburg\" \/>\n<meta property=\"og:description\" content=\"Bl\u00f6ckle Boulderhalle Ravensburg is a Boulder Gym with Boulder Walls in Ravensburg, Germany. Find out more about the project here.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/pl\/projects\/blockle-boulderhalle-ravensburg\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-22T11:21:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027215236\/Walltopia_Blockle_Boulderhalle_Ravensburg_6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/blockle-boulderhalle-ravensburg\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/blockle-boulderhalle-ravensburg\\\/\",\"name\":\"Bl\u00f6ckle Boulderhalle Ravensburg - Projects | Walltopia Climbin Walls\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/blockle-boulderhalle-ravensburg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/blockle-boulderhalle-ravensburg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027215236\\\/Walltopia_Blockle_Boulderhalle_Ravensburg_6.jpg\",\"datePublished\":\"2021-07-12T08:17:04+00:00\",\"dateModified\":\"2023-05-22T11:21:01+00:00\",\"description\":\"Bl\u00f6ckle Boulderhalle Ravensburg is a Boulder Gym with Boulder Walls in Ravensburg, Germany. Find out more about the project here.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/blockle-boulderhalle-ravensburg\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/blockle-boulderhalle-ravensburg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/blockle-boulderhalle-ravensburg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027215236\\\/Walltopia_Blockle_Boulderhalle_Ravensburg_6.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027215236\\\/Walltopia_Blockle_Boulderhalle_Ravensburg_6.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/blockle-boulderhalle-ravensburg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/strona-glowna-pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bl\u00f6ckle Boulderhalle Ravensburg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bl\u00f6ckle Boulderhalle Ravensburg - Projects | Walltopia Climbin Walls","description":"Bl\u00f6ckle Boulderhalle Ravensburg is a Boulder Gym with Boulder Walls in Ravensburg, Germany. Find out more about the project here.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/pl\/projects\/blockle-boulderhalle-ravensburg\/","og_locale":"pl_PL","og_type":"article","og_title":"Bl\u00f6ckle Boulderhalle Ravensburg","og_description":"Bl\u00f6ckle Boulderhalle Ravensburg is a Boulder Gym with Boulder Walls in Ravensburg, Germany. Find out more about the project here.","og_url":"https:\/\/walltopia.com\/pl\/projects\/blockle-boulderhalle-ravensburg\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2023-05-22T11:21:01+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027215236\/Walltopia_Blockle_Boulderhalle_Ravensburg_6.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/pl\/projects\/blockle-boulderhalle-ravensburg\/","url":"https:\/\/walltopia.com\/pl\/projects\/blockle-boulderhalle-ravensburg\/","name":"Bl\u00f6ckle Boulderhalle Ravensburg - Projects | Walltopia Climbin Walls","isPartOf":{"@id":"https:\/\/walltopia.com\/pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/pl\/projects\/blockle-boulderhalle-ravensburg\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/pl\/projects\/blockle-boulderhalle-ravensburg\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027215236\/Walltopia_Blockle_Boulderhalle_Ravensburg_6.jpg","datePublished":"2021-07-12T08:17:04+00:00","dateModified":"2023-05-22T11:21:01+00:00","description":"Bl\u00f6ckle Boulderhalle Ravensburg is a Boulder Gym with Boulder Walls in Ravensburg, Germany. Find out more about the project here.","breadcrumb":{"@id":"https:\/\/walltopia.com\/pl\/projects\/blockle-boulderhalle-ravensburg\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/pl\/projects\/blockle-boulderhalle-ravensburg\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/walltopia.com\/pl\/projects\/blockle-boulderhalle-ravensburg\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027215236\/Walltopia_Blockle_Boulderhalle_Ravensburg_6.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027215236\/Walltopia_Blockle_Boulderhalle_Ravensburg_6.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/pl\/projects\/blockle-boulderhalle-ravensburg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/pl\/strona-glowna-pl\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/walltopia.com\/pl\/projects\/"},{"@type":"ListItem","position":3,"name":"Bl\u00f6ckle Boulderhalle Ravensburg"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/pl\/#website","url":"https:\/\/walltopia.com\/pl\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/pl\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/walltopia.com\/pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/wt_project\/17131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/wt_project"}],"about":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/types\/wt_project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/media\/19744"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/media?parent=17131"}],"wp:term":[{"taxonomy":"wt_project_category","embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/wt_project_category?post=17131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}