{"id":393869,"date":"2026-08-20T11:52:51","date_gmt":"2026-08-20T08:52:51","guid":{"rendered":"https:\/\/walltopia.com\/?post_type=wt_project&#038;p=393869"},"modified":"2026-08-20T11:52:51","modified_gmt":"2026-08-20T08:52:51","slug":"blocs-walls-adjustable-tension-board","status":"publish","type":"wt_project","link":"https:\/\/walltopia.com\/pl\/projects\/blocs-walls-adjustable-tension-board\/","title":{"rendered":"Blocs &#038; Walls &#8211; Adjustable Tension Board"},"content":{"rendered":"<p>We delivered the <a href=\"https:\/\/walltopia.com\/products\/training-boards\/\">adjustable-angle Tension board<\/a> for <a href=\"https:\/\/www.dbkk.dk\/\">Blocs &#038; Walls<\/a> in Denmark. Exntending their training zone offerings, our adjustable-angle frame is easy to use, electrical with a simple navigation and professionally engineered to meet the european standards.<\/p>\n<p>Our training boards come equipped with Climbmat Safety mats for safe landings and efficient training.<\/p>\n","protected":false},"featured_media":393870,"template":"","wt_project_category":[761],"class_list":["post-393869","wt_project","type-wt_project","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Blocs &amp; Walls - Adjustable Tension Board | Walltopia<\/title>\n<meta name=\"description\" content=\"Walltopia adjustable-angle board frame for Tension board and Climbmat safety mats in Blocs &amp; Walls, Denmark.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/pl\/projects\/blocs-walls-adjustable-tension-board\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blocs &amp; Walls - Adjustable Tension Board\" \/>\n<meta property=\"og:description\" content=\"Walltopia adjustable-angle board frame for Tension board and Climbmat safety mats in Blocs &amp; Walls, Denmark.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/pl\/projects\/blocs-walls-adjustable-tension-board\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20260820114941\/Blocs-and-walls-Adjustable-angle-board-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/blocs-walls-adjustable-tension-board\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/blocs-walls-adjustable-tension-board\\\/\",\"name\":\"Blocs & Walls - Adjustable Tension Board | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/blocs-walls-adjustable-tension-board\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/blocs-walls-adjustable-tension-board\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20260820114941\\\/Blocs-and-walls-Adjustable-angle-board-2.jpg\",\"datePublished\":\"2026-08-20T08:52:51+00:00\",\"description\":\"Walltopia adjustable-angle board frame for Tension board and Climbmat safety mats in Blocs & Walls, Denmark.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/blocs-walls-adjustable-tension-board\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/blocs-walls-adjustable-tension-board\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/blocs-walls-adjustable-tension-board\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20260820114941\\\/Blocs-and-walls-Adjustable-angle-board-2.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20260820114941\\\/Blocs-and-walls-Adjustable-angle-board-2.jpg\",\"width\":1500,\"height\":2000,\"caption\":\"Walltopia adjustable-angle board in Blocs & Walls, Denmark\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/blocs-walls-adjustable-tension-board\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/strona-glowna-pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Blocs &#038; Walls &#8211; Adjustable Tension Board\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Blocs & Walls - Adjustable Tension Board | Walltopia","description":"Walltopia adjustable-angle board frame for Tension board and Climbmat safety mats in Blocs & Walls, Denmark.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/pl\/projects\/blocs-walls-adjustable-tension-board\/","og_locale":"pl_PL","og_type":"article","og_title":"Blocs & Walls - Adjustable Tension Board","og_description":"Walltopia adjustable-angle board frame for Tension board and Climbmat safety mats in Blocs & Walls, Denmark.","og_url":"https:\/\/walltopia.com\/pl\/projects\/blocs-walls-adjustable-tension-board\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","og_image":[{"width":1500,"height":2000,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20260820114941\/Blocs-and-walls-Adjustable-angle-board-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/pl\/projects\/blocs-walls-adjustable-tension-board\/","url":"https:\/\/walltopia.com\/pl\/projects\/blocs-walls-adjustable-tension-board\/","name":"Blocs & Walls - Adjustable Tension Board | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/pl\/projects\/blocs-walls-adjustable-tension-board\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/pl\/projects\/blocs-walls-adjustable-tension-board\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20260820114941\/Blocs-and-walls-Adjustable-angle-board-2.jpg","datePublished":"2026-08-20T08:52:51+00:00","description":"Walltopia adjustable-angle board frame for Tension board and Climbmat safety mats in Blocs & Walls, Denmark.","breadcrumb":{"@id":"https:\/\/walltopia.com\/pl\/projects\/blocs-walls-adjustable-tension-board\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/pl\/projects\/blocs-walls-adjustable-tension-board\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/walltopia.com\/pl\/projects\/blocs-walls-adjustable-tension-board\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20260820114941\/Blocs-and-walls-Adjustable-angle-board-2.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20260820114941\/Blocs-and-walls-Adjustable-angle-board-2.jpg","width":1500,"height":2000,"caption":"Walltopia adjustable-angle board in Blocs & Walls, Denmark"},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/pl\/projects\/blocs-walls-adjustable-tension-board\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/pl\/strona-glowna-pl\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/walltopia.com\/pl\/projects\/"},{"@type":"ListItem","position":3,"name":"Blocs &#038; Walls &#8211; Adjustable Tension Board"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/pl\/#website","url":"https:\/\/walltopia.com\/pl\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/pl\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/walltopia.com\/pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/wt_project\/393869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/wt_project"}],"about":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/types\/wt_project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/media\/393870"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/media?parent=393869"}],"wp:term":[{"taxonomy":"wt_project_category","embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/wt_project_category?post=393869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}