{"id":68837,"date":"2023-01-08T12:04:08","date_gmt":"2023-01-08T09:04:08","guid":{"rendered":"http:\/\/walltopia.com\/projects\/the-adventure-islands\/"},"modified":"2023-05-22T13:28:12","modified_gmt":"2023-05-22T10:28:12","slug":"the-adventure-island","status":"publish","type":"wt_project","link":"https:\/\/walltopia.com\/pl\/projects\/the-adventure-island\/","title":{"rendered":"The Adventure Island"},"content":{"rendered":"","protected":false},"featured_media":68838,"template":"","wt_project_category":[8791],"class_list":["post-68837","wt_project","type-wt_project","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>The Adventure Island | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/pl\/projects\/the-adventure-island\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Adventure Island\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/pl\/projects\/the-adventure-island\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-22T10:28:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027203248\/1074776_485575051527906_140627378_o.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1363\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/the-adventure-island\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/the-adventure-island\\\/\",\"name\":\"The Adventure Island | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/the-adventure-island\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/the-adventure-island\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027203248\\\/1074776_485575051527906_140627378_o.jpg\",\"datePublished\":\"2023-01-08T09:04:08+00:00\",\"dateModified\":\"2023-05-22T10:28:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/the-adventure-island\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/the-adventure-island\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/the-adventure-island\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027203248\\\/1074776_485575051527906_140627378_o.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027203248\\\/1074776_485575051527906_140627378_o.jpg\",\"width\":2048,\"height\":1363},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/the-adventure-island\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/strona-glowna-pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"The Adventure Island\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"The Adventure Island | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/pl\/projects\/the-adventure-island\/","og_locale":"pl_PL","og_type":"article","og_title":"The Adventure Island","og_url":"https:\/\/walltopia.com\/pl\/projects\/the-adventure-island\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2023-05-22T10:28:12+00:00","og_image":[{"width":2048,"height":1363,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027203248\/1074776_485575051527906_140627378_o.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/pl\/projects\/the-adventure-island\/","url":"https:\/\/walltopia.com\/pl\/projects\/the-adventure-island\/","name":"The Adventure Island | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/pl\/projects\/the-adventure-island\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/pl\/projects\/the-adventure-island\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027203248\/1074776_485575051527906_140627378_o.jpg","datePublished":"2023-01-08T09:04:08+00:00","dateModified":"2023-05-22T10:28:12+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/pl\/projects\/the-adventure-island\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/pl\/projects\/the-adventure-island\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/walltopia.com\/pl\/projects\/the-adventure-island\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027203248\/1074776_485575051527906_140627378_o.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027203248\/1074776_485575051527906_140627378_o.jpg","width":2048,"height":1363},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/pl\/projects\/the-adventure-island\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/pl\/strona-glowna-pl\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/walltopia.com\/pl\/projects\/"},{"@type":"ListItem","position":3,"name":"The Adventure Island"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/pl\/#website","url":"https:\/\/walltopia.com\/pl\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/pl\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/walltopia.com\/pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/wt_project\/68837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/wt_project"}],"about":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/types\/wt_project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/media\/68838"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/media?parent=68837"}],"wp:term":[{"taxonomy":"wt_project_category","embeddable":true,"href":"https:\/\/walltopia.com\/pl\/wp-json\/wp\/v2\/wt_project_category?post=68837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}