{"id":125340,"date":"2021-07-09T10:05:10","date_gmt":"2021-07-09T07:05:10","guid":{"rendered":"http:\/\/walltopia.com\/termos-e-condicoes\/"},"modified":"2024-06-10T09:21:19","modified_gmt":"2024-06-10T06:21:19","slug":"termos-e-condicoes","status":"publish","type":"page","link":"https:\/\/walltopia.com\/pt-br\/termos-e-condicoes\/","title":{"rendered":"Termos e condi\u00e7\u00f5es"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row css=&#8221;.vc_custom_1610043030118{padding-top: 100px !important;padding-bottom: 75px !important;}&#8221;][vc_column][vc_custom_heading text=&#8221;Termos e condi\u00e7\u00f5es gerais&#8221; font_container=&#8221;tag:h3|text_align:left|line_height:1&#8243; use_theme_fonts=&#8221;yes&#8221; el_class=&#8221;uppercase letter-spacing-1px&#8221; css=&#8221;.vc_custom_1610042433452{margin-top: 0px !important;margin-bottom: 25px !important;}&#8221;][vc_column_text]\n<ol>\n<li><strong>APLICABILIDADE DOS TERMOS E CONDI\u00c7\u00d5ES GERAIS.<\/strong> Os seguintes termos e condi\u00e7\u00f5es (os &#8220;Termos e Condi\u00e7\u00f5es&#8221;) regem a venda de quaisquer suportes de escalada (<strong>&#8220;Produtos&#8221;)<\/strong> fornecidos pela Walltopia AD (<strong>&#8220;Walltopia&#8221;)<\/strong> a um cliente (<strong>&#8220;Cliente&#8221;<\/strong>)) e a presta\u00e7\u00e3o pela Walltopia de quaisquer servi\u00e7os relacionados (como servi\u00e7os de instala\u00e7\u00e3o) ao Cliente, conforme aplic\u00e1vel, excluindo quaisquer outros termos e condi\u00e7\u00f5es que o Cliente possa tentar impor \u00e0 Walltopia sob qualquer ordem de compra ou de outra forma, a menos que esses outros termos e condi\u00e7\u00f5es sejam expressamente acordados por escrito pela Walltopia.<\/li>\n<li><strong>PEDIDOS DE COMPRA.<\/strong> O recebimento pela Walltopia de um pedido de compra em qualquer forma, t\u00edtulo ou nome<strong>(um &#8220;pedido de compra&#8221;)<\/strong> do Cliente ser\u00e1 considerado como o reconhecimento e a aceita\u00e7\u00e3o do Cliente destes Termos e Condi\u00e7\u00f5es. Qualquer pedido de compra enviado por meio do formul\u00e1rio de pedido padr\u00e3o neste site constitui uma oferta \u00e0 Walltopia para a compra de Produtos. Refer\u00eancias a &#8220;ordem de compra&#8221; neste documento significam qualquer documento que n\u00e3o seja os Termos e Condi\u00e7\u00f5es negociados ou executados pela Walltopia e pelo Cliente para a compra e venda de Produtos e\/ou servi\u00e7os.<\/li>\n<li><strong>ACEITA\u00c7\u00c3O DE PEDIDOS.<\/strong>  Todos os pedidos de compra do Cliente est\u00e3o sujeitos \u00e0 aceita\u00e7\u00e3o pela Walltopia, cuja aceita\u00e7\u00e3o ficar\u00e1 a crit\u00e9rio exclusivo da Walltopia. Nenhum pedido de compra ser\u00e1 vinculativo para a Walltopia, a menos e at\u00e9 que tenha sido aceito por escrito pela Walltopia.<\/li>\n<li><strong>PRE\u00c7OS.<\/strong>  Dependendo da localiza\u00e7\u00e3o do cliente, os pre\u00e7os s\u00e3o cotados em d\u00f3lares americanos ou euros e est\u00e3o sujeitos a altera\u00e7\u00f5es sem aviso pr\u00e9vio. Todos os impostos (incluindo IVA), custos de transporte, taxas e outros encargos, se houver, s\u00e3o adicionais ao pre\u00e7o cotado.<\/li>\n<li><strong>PAGAMENTO.<\/strong>  A menos que a Walltopia e o Cliente acordem de outra forma por escrito, o pagamento de todos os Produtos e servi\u00e7os dever\u00e1 ser feito por meio das facilidades de pagamento no site ou por transfer\u00eancia banc\u00e1ria antes da entrega, livre de todos os encargos banc\u00e1rios. A Walltopia se reserva o direito de alterar os m\u00e9todos de pagamento a qualquer momento.<\/li>\n<li><strong>ENTREGA.<\/strong>  A menos que a Walltopia e o Cliente acordem de outra forma por escrito, a entrega de todos os Produtos ser\u00e1 EXW nas instala\u00e7\u00f5es da Walltopia. Os prazos de entrega s\u00e3o apenas estimativas. A Walltopia n\u00e3o ser\u00e1 respons\u00e1vel por quaisquer danos decorrentes de qualquer atraso na entrega, por qualquer motivo. A entrega no local do Cliente constitui entrega ao Cliente, independentemente de o Cliente ou seu agente estar no local no momento da entrega ou assinar um recibo de entrega. Quaisquer reclama\u00e7\u00f5es por falta ou entrega inadequada devem ser feitas por escrito dentro de cinco (5) dias da entrega, caso contr\u00e1rio, tais reclama\u00e7\u00f5es ser\u00e3o consideradas renunciadas pelo Cliente.<\/li>\n<li><strong>INSTALA\u00c7\u00c3O.<\/strong>  A menos que a Walltopia e o Cliente acordem de outra forma por escrito, a Walltopia n\u00e3o ter\u00e1 qualquer responsabilidade pela instala\u00e7\u00e3o de quaisquer Produtos.<\/li>\n<li><strong>PROPRIEDADE E RISCO DE PERDA.<\/strong>  A propriedade dos Produtos ser\u00e1 transferida ao Cliente quando a Walltopia receber o pagamento integral de todos os valores devidos em rela\u00e7\u00e3o aos Produtos, incluindo impostos e taxas de entrega. O risco ser\u00e1 transferido para o Cliente no momento da entrega.<\/li>\n<li><strong>GARANTIAS.<\/strong>  A Walltopia garante apenas o t\u00edtulo dos Produtos. Todas as outras garantias s\u00e3o do fabricante. A Walltopia se isenta de todas as garantias expressas e impl\u00edcitas de comercializa\u00e7\u00e3o ou adequa\u00e7\u00e3o a uma finalidade espec\u00edfica. A Walltopia ceder\u00e1 ao Cliente qualquer garantia fornecida por seu fornecedor e pelo fabricante. O Comprador renuncia a qualquer direito de a\u00e7\u00e3o legal contra a Walltopia em rela\u00e7\u00e3o a danos causados pelos Produtos.<\/li>\n<li><strong>LIMITA\u00c7\u00c3O DE RESPONSABILIDADE.<\/strong>  EM NENHUMA CIRCUNST\u00c2NCIA, A WALLTOPIA SER\u00c1 RESPONS\u00c1VEL POR DANOS INDIRETOS, LIQUIDADOS, INCIDENTAIS, PUNITIVOS, ESPECIAIS OU CONSEQUENCIAIS DE QUALQUER TIPO. A RESPONSABILIDADE DA WALLTOPIA, SE HOUVER, SER\u00c1 LIMITADA AO PRE\u00c7O L\u00cdQUIDO DE VENDA RECEBIDO PELA WALLTOPIA.<\/li>\n<li><strong>LEI APLIC\u00c1VEL.<\/strong>  Estes Termos e Condi\u00e7\u00f5es e qualquer contrato para a venda de Produtos ou para a presta\u00e7\u00e3o de servi\u00e7os relacionados dever\u00e3o ser interpretados de acordo com as leis da Rep\u00fablica da Bulg\u00e1ria.<\/li>\n<li><strong>JURISDI\u00c7\u00c3O EXCLUSIVA.<\/strong>  Toda e qualquer disputa decorrente de ou relacionada a qualquer pedido de compra dever\u00e1 ser resolvida exclusivamente pelos tribunais b\u00falgaros.<\/li>\n<li><strong>POL\u00cdTICA DE CUSTO DE DEVOLU\u00c7\u00c3O.<\/strong>  O comprador \u00e9 respons\u00e1vel pelo pagamento do custo do frete de devolu\u00e7\u00e3o. O custo estimado do frete de devolu\u00e7\u00e3o \u00e9 igual ao custo do frete no pedido da Walltopia.<\/li>\n<\/ol>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row css=&#8221;.vc_custom_1610043030118{padding-top: 100px !important;padding-bottom: 75px !important;}&#8221;][vc_column][vc_custom_heading text=&#8221;Termos e condi\u00e7\u00f5es gerais&#8221; font_container=&#8221;tag:h3|text_align:left|line_height:1&#8243; use_theme_fonts=&#8221;yes&#8221; el_class=&#8221;uppercase letter-spacing-1px&#8221; css=&#8221;.vc_custom_1610042433452{margin-top: 0px !important;margin-bottom: 25px !important;}&#8221;][vc_column_text] APLICABILIDADE&#8230;","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-small-header.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-125340","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Termos e condi\u00e7\u00f5es | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/pt-br\/termos-e-condicoes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Termos e condi\u00e7\u00f5es\" \/>\n<meta property=\"og:description\" content=\"[vc_row css=&#8221;.vc_custom_1610043030118{padding-top: 100px !important;padding-bottom: 75px !important;}&#8221;][vc_column][vc_custom_heading text=&#8221;Termos e condi\u00e7\u00f5es gerais&#8221; font_container=&#8221;tag:h3|text_align:left|line_height:1&#8243; use_theme_fonts=&#8221;yes&#8221; el_class=&#8221;uppercase letter-spacing-1px&#8221; css=&#8221;.vc_custom_1610042433452{margin-top: 0px !important;margin-bottom: 25px !important;}&#8221;][vc_column_text] APLICABILIDADE...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/pt-br\/termos-e-condicoes\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-10T06:21:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/termos-e-condicoes\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/termos-e-condicoes\\\/\",\"name\":\"Termos e condi\u00e7\u00f5es | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\"},\"datePublished\":\"2021-07-09T07:05:10+00:00\",\"dateModified\":\"2024-06-10T06:21:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/termos-e-condicoes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/termos-e-condicoes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/termos-e-condicoes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/inicio-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Termos e condi\u00e7\u00f5es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Termos e condi\u00e7\u00f5es | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/pt-br\/termos-e-condicoes\/","og_locale":"pt_BR","og_type":"article","og_title":"Termos e condi\u00e7\u00f5es","og_description":"[vc_row css=&#8221;.vc_custom_1610043030118{padding-top: 100px !important;padding-bottom: 75px !important;}&#8221;][vc_column][vc_custom_heading text=&#8221;Termos e condi\u00e7\u00f5es gerais&#8221; font_container=&#8221;tag:h3|text_align:left|line_height:1&#8243; use_theme_fonts=&#8221;yes&#8221; el_class=&#8221;uppercase letter-spacing-1px&#8221; css=&#8221;.vc_custom_1610042433452{margin-top: 0px !important;margin-bottom: 25px !important;}&#8221;][vc_column_text] APLICABILIDADE...","og_url":"https:\/\/walltopia.com\/pt-br\/termos-e-condicoes\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2024-06-10T06:21:19+00:00","twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/pt-br\/termos-e-condicoes\/","url":"https:\/\/walltopia.com\/pt-br\/termos-e-condicoes\/","name":"Termos e condi\u00e7\u00f5es | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/pt-br\/#website"},"datePublished":"2021-07-09T07:05:10+00:00","dateModified":"2024-06-10T06:21:19+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/pt-br\/termos-e-condicoes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/pt-br\/termos-e-condicoes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/pt-br\/termos-e-condicoes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/pt-br\/inicio-pt\/"},{"@type":"ListItem","position":2,"name":"Termos e condi\u00e7\u00f5es"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/pt-br\/#website","url":"https:\/\/walltopia.com\/pt-br\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/pt-br\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/pages\/125340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/comments?post=125340"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/pages\/125340\/revisions"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/media?parent=125340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}