{"id":181330,"date":"2021-06-17T16:54:36","date_gmt":"2021-06-17T13:54:36","guid":{"rendered":"https:\/\/walltopia.com\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\/"},"modified":"2026-01-15T16:54:21","modified_gmt":"2026-01-15T13:54:21","slug":"a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento","status":"publish","type":"post","link":"https:\/\/walltopia.com\/pt-br\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\/","title":{"rendered":"A Walltopia continua a apoiar o crescimento do setor de escalada com um novo investimento"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_custom_heading text=&#8221;Atualmente, nossa empresa est\u00e1 concluindo seu quinto investimento em uma academia de escalada, desta vez financiando a Momentum, sediada em Salt Lake City, Utah. Ap\u00f3s investimentos bem-sucedidos no setor de divers\u00f5es e atra\u00e7\u00f5es, a Walltopia voltou seu foco para o setor de escalada. &#8221; font_container=&#8221;tag:h2|font_size:18|text_align:left|color:%23000000|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Fundada em 1998, a Walltopia se tornou uma das principais fabricantes de paredes de escalada do mundo. Aumentamos nossa participa\u00e7\u00e3o no mercado dos EUA combinando o design, a fabrica\u00e7\u00e3o e a instala\u00e7\u00e3o de paredes de escalada de primeira classe com investimentos inteligentes em v\u00e1rias empresas lideradas por empreendedores que pensam da mesma forma. Nossas oportunidades e nosso crescimento se aceleraram depois de 2007, quando a Momentum se tornou a primeira empresa sediada nos EUA a confiar seu projeto a n\u00f3s, uma empresa em ascens\u00e3o do leste europeu. A Walltopia ganhou ainda mais destaque em 2012, quando Chris Sharma concordou com um acordo de patroc\u00ednio. Isso tamb\u00e9m fez com que a empresa assumisse uma participa\u00e7\u00e3o na rede Sender One, na Calif\u00f3rnia. Essas parcerias nos deram uma base melhor no mercado dos EUA e ajudaram a estabelecer nossos pr\u00f3prios limites e expectativas para investimentos futuros. O atual acordo da Walltopia com a Momentum \u00e9 um pr\u00f3ximo passo l\u00f3gico para n\u00f3s no apoio cont\u00ednuo ao esporte e ao setor, juntamente com nossos investimentos anteriores nos EUA, Canad\u00e1, Israel, R\u00fassia e Bulg\u00e1ria.      <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">A Walltopia n\u00e3o \u00e9 o \u00fanico fabricante de paredes a investir em academias de escalada. A maioria dos grandes produtores foi ainda mais longe, possuindo e operando diretamente redes de academias. No entanto, a Walltopia n\u00e3o est\u00e1 relacionada a esse modelo, pois n\u00e3o estamos interessados em nos tornarmos operadores de academias. Continuamos apaixonados por projetar, desenvolver, fabricar e fornecer produtos de alta qualidade para operadores do setor de escalada e de divers\u00f5es. A Walltopia continuar\u00e1 a apoiar o crescimento do nosso esporte por meio de investimentos, parcerias e patroc\u00ednios &#8211; apreciamos muito o setor de escalada e vemos um enorme potencial de crescimento e lucro. No entanto, nosso foco principal sempre permanecer\u00e1 naquilo em que somos excelentes: desenvolvimento e fabrica\u00e7\u00e3o de produtos.     <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Entendemos que os clientes far\u00e3o perguntas e expressar\u00e3o preocupa\u00e7\u00f5es sobre as estrat\u00e9gias de investimento em andamento da empresa. Com isso em mente, reiteramos nossa estrita ades\u00e3o \u00e0s pr\u00e1ticas comerciais padr\u00e3o com rela\u00e7\u00e3o ao tratamento dos clientes e \u00e0 prote\u00e7\u00e3o dos planos de neg\u00f3cios dos clientes. Uma pol\u00edtica de n\u00e3o divulga\u00e7\u00e3o tem sido, desde o in\u00edcio, a pedra angular de todos os contratos da Walltopia. Em um futuro pr\u00f3ximo, ser\u00e1 criada uma entidade completamente separada para cuidar e administrar todos os investimentos, a fim de garantir que n\u00e3o haja incentivos financeiros que justifiquem tratamento preferencial no projeto, na fabrica\u00e7\u00e3o ou na disponibilidade de produtos dentro da empresa.   <\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221; css=&#8221;.vc_custom_1623937787528{padding-top: 2% !important;}&#8221;][vc_column][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Entendemos que os clientes far\u00e3o perguntas e expressar\u00e3o preocupa\u00e7\u00f5es sobre as estrat\u00e9gias de investimento em andamento da empresa. Com isso em mente, reiteramos nossa estrita ades\u00e3o \u00e0s pr\u00e1ticas comerciais padr\u00e3o com rela\u00e7\u00e3o ao tratamento dos clientes e \u00e0 prote\u00e7\u00e3o dos planos de neg\u00f3cios dos clientes. Uma pol\u00edtica de n\u00e3o divulga\u00e7\u00e3o tem sido, desde o in\u00edcio, a pedra angular de todos os contratos da Walltopia. Em um futuro pr\u00f3ximo, ser\u00e1 criada uma entidade completamente separada para cuidar e administrar todos os investimentos, a fim de garantir que n\u00e3o haja incentivos financeiros que justifiquem tratamento preferencial no projeto, na fabrica\u00e7\u00e3o ou na disponibilidade de produtos dentro da empresa.   <\/p>\n[\/vc_column_text]<blockquote class=\"custom relative full-width-container margin-bottom-22\" style=\"color: #000000; font-size: 19px; line-height: 1.5; background-color: #f3f5f6;\"><div class=\"content block width-100 float-left\">\u201cWe are a high-integrity company that respects its clients,\u201d says our CEO, Ivaylo Penchev.<\/div><span class=\"dashicons dashicons-format-quote\" style=\"color: #a3e7f0;\"><\/span><\/blockquote>[\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1623937800381{padding-top: 2% !important;}&#8221;][vc_column][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Al\u00e9m de gerenciar a Walltopia, Penchev \u00e9 um dos principais acionistas da f\u00e1brica de suportes Composite-X, que produz suportes para mais de 40 marcas de escalada diferentes, incluindo a HRT, marca de propriedade da Walltopia. Penchev ressalta que o que pode parecer um poss\u00edvel conflito de interesses nunca resultou em tratamento preferencial para a HRT em rela\u00e7\u00e3o aos outros clientes da Composite-X. &#8220;Cada cliente \u00e9 importante para o sucesso da Composite-X, e a HRT \u00e9 apenas um deles&#8221;, explica ele.  <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">A Walltopia conquistou a confian\u00e7a das empresas durante 18 anos por meio de dilig\u00eancia, persist\u00eancia, criatividade, lealdade e responsabilidade, tornando-se assim o fornecedor preferencial de paredes para muitas academias de escalada em todo o mundo. Hoje, mantemos rela\u00e7\u00f5es de confian\u00e7a e confidencialidade com todos os nossos clientes, algo que n\u00e3o mudar\u00e1 independentemente de onde investimos. <\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_custom_heading text=&#8221;Atualmente, nossa empresa est\u00e1 concluindo seu quinto investimento em uma academia de escalada, desta vez financiando a Momentum, sediada&#8230;","protected":false},"author":10,"featured_media":181333,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1151],"tags":[1158,1870,1871],"class_list":["post-181330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sala-de-imprensa","tag-escalada","tag-eua","tag-mercado-dos-eua"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>A Walltopia continua a apoiar o crescimento do setor de escalada com um novo investimento | Walltopia<\/title>\n<meta name=\"description\" content=\"Atualmente, nossa empresa est\u00e1 concluindo seu quinto investimento em uma academia de escalada com a Momentum, o que \u00e9 um pr\u00f3ximo passo l\u00f3gico no apoio cont\u00ednuo ao esporte.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/pt-br\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Walltopia continua a apoiar o crescimento do setor de escalada com um novo investimento\" \/>\n<meta property=\"og:description\" content=\"Atualmente, nossa empresa est\u00e1 concluindo seu quinto investimento em uma academia de escalada com a Momentum, o que \u00e9 um pr\u00f3ximo passo l\u00f3gico no apoio cont\u00ednuo ao esporte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/pt-br\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-17T13:54:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T13:54:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090617\/walltopia-and-momentum.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"479\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"the_id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\\\/\"},\"author\":{\"name\":\"the_id\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\"},\"headline\":\"A Walltopia continua a apoiar o crescimento do setor de escalada com um novo investimento\",\"datePublished\":\"2021-06-17T13:54:36+00:00\",\"dateModified\":\"2026-01-15T13:54:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\\\/\"},\"wordCount\":879,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090617\\\/walltopia-and-momentum.jpg\",\"keywords\":[\"escalada\",\"EUA\",\"Mercado dos EUA\"],\"articleSection\":[\"Sala de imprensa\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\\\/\",\"name\":\"A Walltopia continua a apoiar o crescimento do setor de escalada com um novo investimento | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090617\\\/walltopia-and-momentum.jpg\",\"datePublished\":\"2021-06-17T13:54:36+00:00\",\"dateModified\":\"2026-01-15T13:54:21+00:00\",\"description\":\"Atualmente, nossa empresa est\u00e1 concluindo seu quinto investimento em uma academia de escalada com a Momentum, o que \u00e9 um pr\u00f3ximo passo l\u00f3gico no apoio cont\u00ednuo ao esporte.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090617\\\/walltopia-and-momentum.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090617\\\/walltopia-and-momentum.jpg\",\"width\":900,\"height\":479},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/inicio-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Walltopia continua a apoiar o crescimento do setor de escalada com um novo investimento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\",\"name\":\"the_id\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"A Walltopia continua a apoiar o crescimento do setor de escalada com um novo investimento | Walltopia","description":"Atualmente, nossa empresa est\u00e1 concluindo seu quinto investimento em uma academia de escalada com a Momentum, o que \u00e9 um pr\u00f3ximo passo l\u00f3gico no apoio cont\u00ednuo ao esporte.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/pt-br\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\/","og_locale":"pt_BR","og_type":"article","og_title":"A Walltopia continua a apoiar o crescimento do setor de escalada com um novo investimento","og_description":"Atualmente, nossa empresa est\u00e1 concluindo seu quinto investimento em uma academia de escalada com a Momentum, o que \u00e9 um pr\u00f3ximo passo l\u00f3gico no apoio cont\u00ednuo ao esporte.","og_url":"https:\/\/walltopia.com\/pt-br\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2021-06-17T13:54:36+00:00","article_modified_time":"2026-01-15T13:54:21+00:00","og_image":[{"width":900,"height":479,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090617\/walltopia-and-momentum.jpg","type":"image\/jpeg"}],"author":"the_id","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/pt-br\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/pt-br\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\/"},"author":{"name":"the_id","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff"},"headline":"A Walltopia continua a apoiar o crescimento do setor de escalada com um novo investimento","datePublished":"2021-06-17T13:54:36+00:00","dateModified":"2026-01-15T13:54:21+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/pt-br\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\/"},"wordCount":879,"publisher":{"@id":"https:\/\/walltopia.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090617\/walltopia-and-momentum.jpg","keywords":["escalada","EUA","Mercado dos EUA"],"articleSection":["Sala de imprensa"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/pt-br\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\/","url":"https:\/\/walltopia.com\/pt-br\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\/","name":"A Walltopia continua a apoiar o crescimento do setor de escalada com um novo investimento | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/pt-br\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090617\/walltopia-and-momentum.jpg","datePublished":"2021-06-17T13:54:36+00:00","dateModified":"2026-01-15T13:54:21+00:00","description":"Atualmente, nossa empresa est\u00e1 concluindo seu quinto investimento em uma academia de escalada com a Momentum, o que \u00e9 um pr\u00f3ximo passo l\u00f3gico no apoio cont\u00ednuo ao esporte.","breadcrumb":{"@id":"https:\/\/walltopia.com\/pt-br\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/pt-br\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/walltopia.com\/pt-br\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090617\/walltopia-and-momentum.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090617\/walltopia-and-momentum.jpg","width":900,"height":479},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/pt-br\/a-walltopia-continua-a-apoiar-o-crescimento-do-setor-de-escalada-com-um-novo-investimento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/pt-br\/inicio-pt\/"},{"@type":"ListItem","position":2,"name":"A Walltopia continua a apoiar o crescimento do setor de escalada com um novo investimento"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/pt-br\/#website","url":"https:\/\/walltopia.com\/pt-br\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/pt-br\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff","name":"the_id"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/posts\/181330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/comments?post=181330"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/posts\/181330\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/media\/181333"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/media?parent=181330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/categories?post=181330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/tags?post=181330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}