{"id":183454,"date":"2021-06-18T17:41:21","date_gmt":"2021-06-18T14:41:21","guid":{"rendered":"https:\/\/walltopia.com\/grip-boulderhal-do-sonho-a-realidade\/"},"modified":"2026-01-15T17:00:29","modified_gmt":"2026-01-15T14:00:29","slug":"grip-boulderhal-do-sonho-a-realidade","status":"publish","type":"post","link":"https:\/\/walltopia.com\/pt-br\/grip-boulderhal-do-sonho-a-realidade\/","title":{"rendered":"Grip Boulderhal &#8211; do sonho \u00e0 realidade"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_custom_heading text=&#8221;Uma ideia. Uma ideia que se transforma em um sonho. E um sonho que se transforma em um projeto. Um projeto com muitas perguntas, vari\u00e1veis e noites sem dormir.   &#8221; font_container=&#8221;tag:h2|font_size:18|text_align:left|color:%23000000|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221; css=&#8221;&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Esse \u00e9 o ponto de partida para muitas das academias de escalada que conhecemos. \u00c0s vezes n\u00e3o h\u00e1 uma boa academia de escalada na \u00e1rea, \u00e0s vezes h\u00e1 uma, mas ela n\u00e3o \u00e9 suficiente para atender \u00e0 comunidade, \u00e0s vezes voc\u00ea simplesmente acha que pode melhor\u00e1-la. Ou, voc\u00ea sabe, voc\u00ea simplesmente acredita que o trabalho das 9h \u00e0s 17h o serviu bem at\u00e9 agora. E agora \u00e9 hora de voc\u00ea come\u00e7ar a cultivar essa sua ideia, transform\u00e1-la em um sonho e depois em um projeto.   <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Inspirados na hist\u00f3ria por tr\u00e1s de cada academia de escalada e nas li\u00e7\u00f5es aprendidas ao longo do caminho, iniciaremos uma s\u00e9rie de entrevistas curtas com propriet\u00e1rios de academias para explorar a for\u00e7a motriz por tr\u00e1s da decis\u00e3o de criar e administrar uma academia de escalada.<\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Come\u00e7aremos com um velho amigo &#8211; conhecemos Noel h\u00e1 cerca de 10 anos ou mais. Trabalhamos juntos na Holanda e na B\u00e9lgica, concluindo muitos projetos e desenvolvendo o cen\u00e1rio da escalada l\u00e1. Com base em sua longa experi\u00eancia no setor de escalada, ele decidiu que era hora de dar um passo adiante e ver as coisas de outra perspectiva. A perspectiva da pessoa com o sonho e a lista intermin\u00e1vel de tarefas. O propriet\u00e1rio. Sua academia, a GRIP Boulderhal, que abriu as portas em 2016, est\u00e1 entre nossos melhores trabalhos.       <strong>Veja abaixo o que ele tem a dizer.<\/strong><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_custom_heading text=&#8221;WT: Voc\u00ea se lembra de como surgiu a ideia de ter uma academia de escalada? O que levou voc\u00ea at\u00e9 l\u00e1? &#8221; font_container=&#8221;tag:h2|font_size:17|text_align:left|color:%23ed2020|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Noel:<\/strong> <em>Deve ter sido h\u00e1 15 anos. Enquanto trabalhava na academia de escalada local como gerente geral, logo descobri que uma academia de escalada, na minha opini\u00e3o, n\u00e3o deveria ser um lugar onde voc\u00ea apenas treina para escalar em outro lugar (como ao ar livre em rochas), mas um lugar onde voc\u00ea realmente escala. Escalar em uma academia pode ser incr\u00edvel! Eu achava que isso estava faltando na academia em que eu trabalhava, e ainda mais em outras academias do pa\u00eds naquela \u00e9poca. Ao criar as paredes do GRIP Boulderhal em 2015, eu ainda estava profundamente convencido de que esse era exatamente o caminho que dever\u00edamos seguir. Foi quando tivemos a ideia dessas paredes brutais que temos: a Wave e a Alien Head, em particular. As pessoas adoram escalar essas paredes e eu n\u00e3o mudaria nada.      <\/em><\/p>\n[\/vc_column_text][vc_custom_heading text=&#8221;WT: Qual foi o desafio mais dif\u00edcil ao longo do caminho do sonho \u00e0 realidade?&#8221; font_container=&#8221;tag:h2|font_size:17|text_align:left|color:%23ed2020|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Noel:<\/strong> <em>Encontrar todas as pe\u00e7as do quebra-cabe\u00e7a: finan\u00e7as, localiza\u00e7\u00e3o, licen\u00e7as e depois juntar tudo na ordem certa. Que, ali\u00e1s, n\u00e3o existe. Em alguns momentos, voc\u00ea realmente se sentiu na corda bamba: o banco precisava de garantias com rela\u00e7\u00e3o \u00e0 localiza\u00e7\u00e3o e \u00e0s licen\u00e7as, o locador precisava de garantias banc\u00e1rias e, para as licen\u00e7as, n\u00f3s dever\u00edamos fornecer garantias com rela\u00e7\u00e3o \u00e0 localiza\u00e7\u00e3o e ao financiamento. Era como se voc\u00ea tivesse que morder seu pr\u00f3prio rabo. Havia alguns prazos s\u00e9rios tamb\u00e9m. No final, de alguma forma, conseguimos fazer tudo no tempo determinado, mas foi preciso muita energia para manter o controle, convencer as pessoas e fazer um planejamento preciso. Para n\u00f3s, foi uma grande vantagem o fato de que tudo em rela\u00e7\u00e3o \u00e0 Walltopia foi super tranquilo. Essas pessoas s\u00e3o profissionais.       <\/em><\/p>\n[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;14098&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1624026076899{padding-top: 2% !important;}&#8221;][vc_single_image image=&#8221;14097&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1624027085962{padding-top: 4% !important;}&#8221;][vc_single_image image=&#8221;14099&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1624027090159{padding-top: 4% !important;}&#8221;][vc_single_image image=&#8221;14100&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1624027098375{padding-top: 4% !important;}&#8221;][vc_single_image image=&#8221;14101&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1624027106062{padding-top: 4% !important;}&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;14102&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1624026935218{padding-top: 2% !important;}&#8221;][vc_single_image image=&#8221;14103&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1624026942434{padding-top: 4% !important;}&#8221;][vc_single_image image=&#8221;14106&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1624026959946{padding-top: 4% !important;}&#8221;][vc_single_image image=&#8221;14104&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1624026954589{padding-top: 4% !important;}&#8221;][vc_single_image image=&#8221;14105&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1624026948442{padding-top: 4% !important;}&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_custom_heading text=&#8221;WT: Como foi a noite anterior \u00e0 abertura oficial? E depois, como voc\u00ea se sentiu no grande dia seguinte? &#8221; font_container=&#8221;tag:h2|font_size:17|text_align:left|color:%23ed2020|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Noel:<\/strong> <em>Louco. Totalmente exausto de uma forma e totalmente empolgado de outra. Faltavam tantas coisas para fazer, mas n\u00f3s as fizemos! O dia seguinte foi muito gratificante por causa da incr\u00edvel quantidade de positividade de nossos clientes e amigos que compareceram \u00e0 grande inaugura\u00e7\u00e3o do GRIP Boulderhal. De fato, foi muito gratificante!    <\/em><\/p>\n[\/vc_column_text][vc_custom_heading text=&#8221;WT: Olhando para tr\u00e1s, voc\u00ea mudaria alguma coisa?&#8221; font_container=&#8221;tag:h2|font_size:17|text_align:left|color:%23ed2020|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1624026862274{padding-top: -2% !important;}&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Noel:<\/strong> <em>Eu teria usado mais margem tanto no tempo de constru\u00e7\u00e3o quanto no dinheiro inicial.<\/em><\/p>\n[\/vc_column_text][vc_custom_heading text=&#8221;WT: Algum conselho para as pessoas que est\u00e3o pensando em seguir o seu caminho?&#8221; font_container=&#8221;tag:h2|font_size:17|text_align:left|color:%23ed2020|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1627564029545{padding-top: -2% !important;}&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Noel:<\/strong><em>  N\u00e3o fa\u00e7a tudo o que voc\u00ea quiser. Pe\u00e7a a profissionais que fa\u00e7am as coisas importantes. Tivemos um empreiteiro para fazer a maior parte dos ajustes na constru\u00e7\u00e3o, como fazer camarins, mudar o layout etc., e tivemos especialistas para eletricidade, som e luz. O mais importante \u00e9 que tivemos dois \u00f3timos consultores que nos mostraram o caminho atrav\u00e9s do p\u00e2ntano da burocracia: o primeiro foi uma empresa especializada em normas de seguran\u00e7a contra inc\u00eandio e o segundo foi um arquiteto com muita experi\u00eancia em licenciamento. Por \u00faltimo, mas n\u00e3o menos importante: tivemos a Walltopia com todo o seu conhecimento sobre constru\u00e7\u00e3o de paredes, planejamento de paredes e como encontrar o ponto ideal para a maneira como meus clientes vivenciam o local.    <\/em><\/p>\n[\/vc_column_text][vc_custom_heading text=&#8221;WT: Em tr\u00eas palavras, o que significa para voc\u00ea ser propriet\u00e1rio e administrar uma academia de escalada?&#8221; font_container=&#8221;tag:h2|font_size:17|text_align:left|color:%23ed2020|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1624026887601{padding-bottom: -2% !important;}&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1624026844203{padding-top: -2% !important;}&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Noel:<\/strong> <em>Fazer os escaladores felizes.<\/em><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">No\u00ebl Poels, propriet\u00e1rio da Grip Boulderhal em Nijmegen, Holanda<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_custom_heading text=&#8221;Uma ideia. Uma ideia que se transforma em um sonho. E um sonho que se transforma em um projeto&#8230;.","protected":false},"author":10,"featured_media":183457,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1151],"tags":[2237,2268],"class_list":["post-183454","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sala-de-imprensa","tag-ginasio-de-escalada","tag-parede-de-escalada"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Grip Boulderhal - do sonho \u00e0 realidade | Walltopia<\/title>\n<meta name=\"description\" content=\"Conhe\u00e7a nosso velho amigo, Noel, que abriu sua primeira academia em 2016 - GRIP Boulderhal, que est\u00e1 entre nossos melhores trabalhos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/pt-br\/grip-boulderhal-do-sonho-a-realidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grip Boulderhal - do sonho \u00e0 realidade\" \/>\n<meta property=\"og:description\" content=\"Conhe\u00e7a nosso velho amigo, Noel, que abriu sua primeira academia em 2016 - GRIP Boulderhal, que est\u00e1 entre nossos melhores trabalhos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/pt-br\/grip-boulderhal-do-sonho-a-realidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-18T14:41:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:00:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085817\/Grip-Boulderhal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"477\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"the_id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/grip-boulderhal-do-sonho-a-realidade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/grip-boulderhal-do-sonho-a-realidade\\\/\"},\"author\":{\"name\":\"the_id\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\"},\"headline\":\"Grip Boulderhal &#8211; do sonho \u00e0 realidade\",\"datePublished\":\"2021-06-18T14:41:21+00:00\",\"dateModified\":\"2026-01-15T14:00:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/grip-boulderhal-do-sonho-a-realidade\\\/\"},\"wordCount\":1368,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/grip-boulderhal-do-sonho-a-realidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085817\\\/Grip-Boulderhal.jpg\",\"keywords\":[\"gin\u00e1sio de escalada\",\"parede de escalada\"],\"articleSection\":[\"Sala de imprensa\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/grip-boulderhal-do-sonho-a-realidade\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/grip-boulderhal-do-sonho-a-realidade\\\/\",\"name\":\"Grip Boulderhal - do sonho \u00e0 realidade | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/grip-boulderhal-do-sonho-a-realidade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/grip-boulderhal-do-sonho-a-realidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085817\\\/Grip-Boulderhal.jpg\",\"datePublished\":\"2021-06-18T14:41:21+00:00\",\"dateModified\":\"2026-01-15T14:00:29+00:00\",\"description\":\"Conhe\u00e7a nosso velho amigo, Noel, que abriu sua primeira academia em 2016 - GRIP Boulderhal, que est\u00e1 entre nossos melhores trabalhos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/grip-boulderhal-do-sonho-a-realidade\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/grip-boulderhal-do-sonho-a-realidade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/grip-boulderhal-do-sonho-a-realidade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085817\\\/Grip-Boulderhal.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085817\\\/Grip-Boulderhal.jpg\",\"width\":900,\"height\":477},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/grip-boulderhal-do-sonho-a-realidade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/inicio-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grip Boulderhal &#8211; do sonho \u00e0 realidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\",\"name\":\"the_id\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Grip Boulderhal - do sonho \u00e0 realidade | Walltopia","description":"Conhe\u00e7a nosso velho amigo, Noel, que abriu sua primeira academia em 2016 - GRIP Boulderhal, que est\u00e1 entre nossos melhores trabalhos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/pt-br\/grip-boulderhal-do-sonho-a-realidade\/","og_locale":"pt_BR","og_type":"article","og_title":"Grip Boulderhal - do sonho \u00e0 realidade","og_description":"Conhe\u00e7a nosso velho amigo, Noel, que abriu sua primeira academia em 2016 - GRIP Boulderhal, que est\u00e1 entre nossos melhores trabalhos.","og_url":"https:\/\/walltopia.com\/pt-br\/grip-boulderhal-do-sonho-a-realidade\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2021-06-18T14:41:21+00:00","article_modified_time":"2026-01-15T14:00:29+00:00","og_image":[{"width":900,"height":477,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085817\/Grip-Boulderhal.jpg","type":"image\/jpeg"}],"author":"the_id","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/pt-br\/grip-boulderhal-do-sonho-a-realidade\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/pt-br\/grip-boulderhal-do-sonho-a-realidade\/"},"author":{"name":"the_id","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff"},"headline":"Grip Boulderhal &#8211; do sonho \u00e0 realidade","datePublished":"2021-06-18T14:41:21+00:00","dateModified":"2026-01-15T14:00:29+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/pt-br\/grip-boulderhal-do-sonho-a-realidade\/"},"wordCount":1368,"publisher":{"@id":"https:\/\/walltopia.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/grip-boulderhal-do-sonho-a-realidade\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085817\/Grip-Boulderhal.jpg","keywords":["gin\u00e1sio de escalada","parede de escalada"],"articleSection":["Sala de imprensa"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/pt-br\/grip-boulderhal-do-sonho-a-realidade\/","url":"https:\/\/walltopia.com\/pt-br\/grip-boulderhal-do-sonho-a-realidade\/","name":"Grip Boulderhal - do sonho \u00e0 realidade | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/pt-br\/grip-boulderhal-do-sonho-a-realidade\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/grip-boulderhal-do-sonho-a-realidade\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085817\/Grip-Boulderhal.jpg","datePublished":"2021-06-18T14:41:21+00:00","dateModified":"2026-01-15T14:00:29+00:00","description":"Conhe\u00e7a nosso velho amigo, Noel, que abriu sua primeira academia em 2016 - GRIP Boulderhal, que est\u00e1 entre nossos melhores trabalhos.","breadcrumb":{"@id":"https:\/\/walltopia.com\/pt-br\/grip-boulderhal-do-sonho-a-realidade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/pt-br\/grip-boulderhal-do-sonho-a-realidade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/walltopia.com\/pt-br\/grip-boulderhal-do-sonho-a-realidade\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085817\/Grip-Boulderhal.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085817\/Grip-Boulderhal.jpg","width":900,"height":477},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/pt-br\/grip-boulderhal-do-sonho-a-realidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/pt-br\/inicio-pt\/"},{"@type":"ListItem","position":2,"name":"Grip Boulderhal &#8211; do sonho \u00e0 realidade"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/pt-br\/#website","url":"https:\/\/walltopia.com\/pt-br\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/pt-br\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff","name":"the_id"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/posts\/183454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/comments?post=183454"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/posts\/183454\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/media\/183457"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/media?parent=183454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/categories?post=183454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/tags?post=183454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}