{"id":183856,"date":"2021-06-18T15:21:40","date_gmt":"2021-06-18T12:21:40","guid":{"rendered":"https:\/\/walltopia.com\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\/"},"modified":"2026-01-15T17:01:33","modified_gmt":"2026-01-15T14:01:33","slug":"conferencia-da-associacao-britanica-de-paredes-de-escalada-2016","status":"publish","type":"post","link":"https:\/\/walltopia.com\/pt-br\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\/","title":{"rendered":"Confer\u00eancia da Associa\u00e7\u00e3o Brit\u00e2nica de Paredes de Escalada 2016"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_custom_heading text=&#8221;A Association of British Climbing Walls realizar\u00e1 sua Reuni\u00e3o Geral Anual e Confer\u00eancia nos dias 29 e 30 de setembro, e a Walltopia ser\u00e1 uma das principais parceiras do evento pelo segundo ano.&#8221; font_container=&#8221;tag:h2|font_size:18|text_align:left|color:%23000000|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221; link=&#8221;url:https%3A%2F%2Fwww.abcwalls.co.uk%2F|title:ABC%20Walls|target:_blank|&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">A ABC promete que o evento ser\u00e1 maior do que nunca, com muitos novos workshops e discuss\u00f5es. Estamos entusiasmados por sermos um dos principais impulsores de inova\u00e7\u00e3o no setor de paredes de escalada em todo o mundo e mal podemos esperar para mostrar ao Reino Unido nossos produtos e projetos mais recentes. Junte-se a n\u00f3s para conferir nossos novos conjuntos de volumes e descobrir como conseguimos construir as paredes de escalada de 700 m2 para o Campeonato Mundial de Escalada em Paris em apenas 3 dias!  <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Agende uma reuni\u00e3o com anteced\u00eancia em <a href=\"mailto:sales@walltopia.com\">sales@walltopia.com<\/a> ou venha conversar com nossa equipe de vendas do Reino Unido no <strong>National Mountain Centre em Plas y Brenin<\/strong>, em Snowdonia, nos dias 29 e 30 de setembro.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_custom_heading text=&#8221;A Association of British Climbing Walls realizar\u00e1 sua Reuni\u00e3o Geral Anual e Confer\u00eancia nos dias 29 e 30 de&#8230;","protected":false},"author":10,"featured_media":183858,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1151],"tags":[2334],"class_list":["post-183856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sala-de-imprensa","tag-abc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Confer\u00eancia da Associa\u00e7\u00e3o Brit\u00e2nica de Paredes de Escalada 2016 | Walltopia<\/title>\n<meta name=\"description\" content=\"A ABC Walls est\u00e1 realizando sua confer\u00eancia anual e a Walltopia ser\u00e1 um dos principais parceiros do evento.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/pt-br\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Confer\u00eancia da Associa\u00e7\u00e3o Brit\u00e2nica de Paredes de Escalada 2016\" \/>\n<meta property=\"og:description\" content=\"A ABC Walls est\u00e1 realizando sua confer\u00eancia anual e a Walltopia ser\u00e1 um dos principais parceiros do evento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/pt-br\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-18T12:21:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:01:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085933\/ABC-2016.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"477\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"the_id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\\\/\"},\"author\":{\"name\":\"the_id\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\"},\"headline\":\"Confer\u00eancia da Associa\u00e7\u00e3o Brit\u00e2nica de Paredes de Escalada 2016\",\"datePublished\":\"2021-06-18T12:21:40+00:00\",\"dateModified\":\"2026-01-15T14:01:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\\\/\"},\"wordCount\":223,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085933\\\/ABC-2016.jpg\",\"keywords\":[\"ABC\"],\"articleSection\":[\"Sala de imprensa\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\\\/\",\"name\":\"Confer\u00eancia da Associa\u00e7\u00e3o Brit\u00e2nica de Paredes de Escalada 2016 | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085933\\\/ABC-2016.jpg\",\"datePublished\":\"2021-06-18T12:21:40+00:00\",\"dateModified\":\"2026-01-15T14:01:33+00:00\",\"description\":\"A ABC Walls est\u00e1 realizando sua confer\u00eancia anual e a Walltopia ser\u00e1 um dos principais parceiros do evento.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085933\\\/ABC-2016.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085933\\\/ABC-2016.jpg\",\"width\":900,\"height\":477},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/inicio-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Confer\u00eancia da Associa\u00e7\u00e3o Brit\u00e2nica de Paredes de Escalada 2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\",\"name\":\"the_id\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Confer\u00eancia da Associa\u00e7\u00e3o Brit\u00e2nica de Paredes de Escalada 2016 | Walltopia","description":"A ABC Walls est\u00e1 realizando sua confer\u00eancia anual e a Walltopia ser\u00e1 um dos principais parceiros do evento.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/pt-br\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\/","og_locale":"pt_BR","og_type":"article","og_title":"Confer\u00eancia da Associa\u00e7\u00e3o Brit\u00e2nica de Paredes de Escalada 2016","og_description":"A ABC Walls est\u00e1 realizando sua confer\u00eancia anual e a Walltopia ser\u00e1 um dos principais parceiros do evento.","og_url":"https:\/\/walltopia.com\/pt-br\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2021-06-18T12:21:40+00:00","article_modified_time":"2026-01-15T14:01:33+00:00","og_image":[{"width":900,"height":477,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085933\/ABC-2016.jpg","type":"image\/jpeg"}],"author":"the_id","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/pt-br\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/pt-br\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\/"},"author":{"name":"the_id","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff"},"headline":"Confer\u00eancia da Associa\u00e7\u00e3o Brit\u00e2nica de Paredes de Escalada 2016","datePublished":"2021-06-18T12:21:40+00:00","dateModified":"2026-01-15T14:01:33+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/pt-br\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\/"},"wordCount":223,"publisher":{"@id":"https:\/\/walltopia.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085933\/ABC-2016.jpg","keywords":["ABC"],"articleSection":["Sala de imprensa"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/pt-br\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\/","url":"https:\/\/walltopia.com\/pt-br\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\/","name":"Confer\u00eancia da Associa\u00e7\u00e3o Brit\u00e2nica de Paredes de Escalada 2016 | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/pt-br\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085933\/ABC-2016.jpg","datePublished":"2021-06-18T12:21:40+00:00","dateModified":"2026-01-15T14:01:33+00:00","description":"A ABC Walls est\u00e1 realizando sua confer\u00eancia anual e a Walltopia ser\u00e1 um dos principais parceiros do evento.","breadcrumb":{"@id":"https:\/\/walltopia.com\/pt-br\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/pt-br\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/walltopia.com\/pt-br\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085933\/ABC-2016.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085933\/ABC-2016.jpg","width":900,"height":477},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/pt-br\/conferencia-da-associacao-britanica-de-paredes-de-escalada-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/pt-br\/inicio-pt\/"},{"@type":"ListItem","position":2,"name":"Confer\u00eancia da Associa\u00e7\u00e3o Brit\u00e2nica de Paredes de Escalada 2016"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/pt-br\/#website","url":"https:\/\/walltopia.com\/pt-br\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/pt-br\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff","name":"the_id"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/posts\/183856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/comments?post=183856"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/posts\/183856\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/media\/183858"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/media?parent=183856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/categories?post=183856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/tags?post=183856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}