{"id":185691,"date":"2021-06-23T09:19:21","date_gmt":"2021-06-23T06:19:21","guid":{"rendered":"https:\/\/walltopia.com\/nosso-padrao-e-a-perfeicao\/"},"modified":"2026-01-15T17:30:08","modified_gmt":"2026-01-15T14:30:08","slug":"nosso-padrao-e-a-perfeicao","status":"publish","type":"post","link":"https:\/\/walltopia.com\/pt-br\/nosso-padrao-e-a-perfeicao\/","title":{"rendered":"Nosso padr\u00e3o \u00e9 a perfei\u00e7\u00e3o"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_custom_heading text=&#8221;Um ponto de venda importante para a maioria das empresas do setor de escalada \u00e9 que suas paredes s\u00e3o constru\u00eddas de acordo com as normas de seguran\u00e7a e, mais especificamente, com a EN 12572, partes 1 e 2, e suas equivalentes em todo o mundo. Como resultado, a maioria dos clientes acredita que essa \u00e9 uma garantia suficiente de qualidade. &#8221; font_container=&#8221;tag:h2|font_size:18|text_align:left|color:%23000000|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221; css=&#8221;&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">No entanto, isso n\u00e3o pode estar mais longe da verdade. O setor evolui muito rapidamente. E com os requisitos que os usu\u00e1rios e operadores de paredes de escalada estabelecem, \u00e9 uma quest\u00e3o de apenas alguns meses para que a \u00faltima atualiza\u00e7\u00e3o da EN12572 fique desatualizada. Al\u00e9m disso, a norma garante apenas que as paredes de escalada sejam seguras. Entretanto, ela n\u00e3o estabelece nenhum requisito para sua funcionalidade ou durabilidade.    <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Neste artigo, informaremos voc\u00ea sobre os detalhes importantes que selecionamos ao longo de nossos muitos anos de experi\u00eancia no setor. Dessa forma, voc\u00ea saber\u00e1 o que procurar ao escolher uma parede de escalada. Assim, voc\u00ea ajudar\u00e1 seu neg\u00f3cio a prosperar e far\u00e1 com que seu investimento valha a pena. Ou exatamente o contr\u00e1rio, se voc\u00ea n\u00e3o escolher com sabedoria.   <\/p>\n[\/vc_column_text][vc_tta_accordion active_section=&#8221;1&#8243; collapsible_all=&#8221;true&#8221;][vc_tta_section title=&#8221;Pontos de prote\u00e7\u00e3o individual&#8221; tab_id=&#8221;1624370060554-70e2024d-e92f&#8221; el_class=&#8221;vc_active&#8221;][vc_column_text css_animation=&#8221;none&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Vamos come\u00e7ar com um dos elementos vitais do equipamento para escalada com chumbo &#8211; os pontos de prote\u00e7\u00e3o individual nas paredes de escalada. Os padr\u00f5es de seguran\u00e7a n\u00e3o definem o tipo e a forma dos pontos de prote\u00e7\u00e3o, mas apenas a carga que eles devem ser capazes de suportar. Eles tamb\u00e9m estabelecem alguns requisitos para o formato e os arredondamentos da abertura na qual passa o elo r\u00e1pido do cabo (fig. 1), mas qual \u00e9 a relev\u00e2ncia deles?  <\/p>\n[\/vc_column_text][vc_single_image image=&#8221;14252&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;none&#8221;][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1708421681550{padding-top: 2% !important;}&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Os arredondamentos descritos na norma s\u00e3o emprestados da EN 959 e da EN 795, que descrevem os requisitos para os ganchos normalmente usados em vias de escalada em rocha. Entretanto, quando os elos r\u00e1pidos usados para escalada comercial s\u00e3o colocados no referido suporte, eles precisam suportar muito mais ciclos de carga e, como resultado, se desgastam muito mais rapidamente. Dessa forma, eles representam um risco maior para a seguran\u00e7a do escalador e aumentam os custos de manuten\u00e7\u00e3o do operador.  <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Al\u00e9m disso, n\u00e3o \u00e9 aconselh\u00e1vel usar esse tipo de cabide ao instalar em grandes sali\u00eancias ou telhados. A dire\u00e7\u00e3o diferente da carga reduz muito a resist\u00eancia do cabide &#8211; a maioria dos fabricantes menciona isso em seus manuais. <\/p>\n[\/vc_column_text][vc_single_image image=&#8221;14253&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;none&#8221;][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1728633291777{padding-top: 2% !important;}&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">A norma tamb\u00e9m exige que a porca usada para fixar o ponto de prote\u00e7\u00e3o seja protegida contra poss\u00edveis afrouxamentos (contraporca). As paredes de escalada sofrem vibra\u00e7\u00f5es constantes e, \u00e0s vezes, at\u00e9 mesmo a contraporca \u00e9 desparafusada, o que resulta em uma grave amea\u00e7a ao bem-estar do escalador. <\/p>\n<h4>O parafuso em U<\/h4>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Em resposta a todos os perigos mencionados acima, inventamos o parafuso em U, que agora faz parte do nosso equipamento padr\u00e3o. Ele evita que o engate r\u00e1pido se desgaste, \u00e9 igualmente forte tanto em paredes verticais quanto em telhados, pois seu valor de ruptura \u00e9 de 35 kN, e \u00e9 fixado \u00e0 constru\u00e7\u00e3o met\u00e1lica n\u00e3o apenas com uma, mas com 4 porcas, 3 das quais podem se soltar e o ponto de prote\u00e7\u00e3o permanecer\u00e1 seguro. <\/p>\n[\/vc_column_text][vc_single_image image=&#8221;14254&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;none&#8221;][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1708421749046{padding-top: 2% !important;}&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Tudo o que mencionamos sobre os pontos de prote\u00e7\u00e3o individuais at\u00e9 agora tamb\u00e9m \u00e9 relevante para os pontos de prote\u00e7\u00e3o da corda superior.<\/p>\n[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;Estrutura de suporte&#8221; tab_id=&#8221;1624370060565-80f9bea2-7c77&#8243; el_class=&#8221;vc_active&#8221;][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Como sabemos, os pontos de prote\u00e7\u00e3o individuais s\u00e3o conectados \u00e0 estrutura de suporte principal da parede de escalada. A norma estabelece instru\u00e7\u00f5es claras para o c\u00e1lculo de sua integridade estrutural, mas, mais uma vez, deixa espa\u00e7o para concess\u00f5es quando se trata do projeto da parede. <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Por exemplo, a norma define claramente todas as cargas que precisam ser consideradas nos c\u00e1lculos e afirma que elas devem ser aplicadas no ponto de prote\u00e7\u00e3o mais desfavor\u00e1vel. Entretanto, ela n\u00e3o fornece nenhuma instru\u00e7\u00e3o sobre como definir o ponto em quest\u00e3o. <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">A verdade \u00e9 que isso n\u00e3o \u00e9 poss\u00edvel, pois a carga de projeto de cada ponto de prote\u00e7\u00e3o afeta cada um dos elementos do suporte estrutural de forma diferente. Como consequ\u00eancia, o ponto de prote\u00e7\u00e3o mais desfavor\u00e1vel pode variar para cada um dos elementos. <\/p>\n<h4>Modelos de c\u00e1lculo 3D<\/h4>\n<p style=\"font-size: 18px; line-height: 1.8em;\">\u00c9 por isso que nossa equipe na Walltopia acredita que a \u00fanica maneira de calcular a integridade estrutural da estrutura \u00e9 criando primeiro um modelo de c\u00e1lculo 3D completo que inclua todos os elementos da parede de escalada. Em seguida, aplicamos as cargas normativas em cada um dos pontos de prote\u00e7\u00e3o sucessivamente e, no processo, encontramos o ponto de prote\u00e7\u00e3o mais desfavor\u00e1vel para cada elemento e cada conex\u00e3o entre os elementos. Infelizmente, poucas empresas do setor se esfor\u00e7am tanto para garantir que realmente levem em considera\u00e7\u00e3o a combina\u00e7\u00e3o mais desfavor\u00e1vel de cargas para a estrutura.  <\/p>\n[\/vc_column_text][vc_single_image image=&#8221;14255&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;none&#8221;][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1708421829518{padding-top: 2% !important;}&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Outro sinal de alerta no padr\u00e3o de escalada \u00e9 que ele permite que a subestrutura que conecta os pontos de prote\u00e7\u00e3o e a estrutura de suporte seja comprovada por um teste de carga pr\u00e1tico. Isso seria aceit\u00e1vel h\u00e1 10-15 anos, quando todas as paredes de escalada eram planas e as conex\u00f5es entre os pontos de prote\u00e7\u00e3o e a estrutura de suporte eram todas iguais. Atualmente, no entanto, as paredes evolu\u00edram para uma estrutura geom\u00e9trica 3D complexa e os pontos de prote\u00e7\u00e3o s\u00e3o fixados \u00e0 constru\u00e7\u00e3o met\u00e1lica com elementos de diferentes comprimentos e \u00e2ngulos.  <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Al\u00e9m disso, os elementos da estrutura de suporte aos quais os pontos de prote\u00e7\u00e3o s\u00e3o fixados tamb\u00e9m variam de acordo com o tamanho e a espessura do perfil, bem como com a orienta\u00e7\u00e3o espacial. Tudo isso demonstra que o teste pr\u00e1tico de uma \u00fanica amostra \u00e9 completamente irrelevante. <\/p>\n[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;Porcas em T&#8221; tab_id=&#8221;1624370483013-8830032c-c24c&#8221; el_class=&#8221;vc_active&#8221;][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">As porcas em T s\u00e3o uma parte essencial da parede de escalada que desempenha um papel fundamental na funcionalidade e durabilidade da instala\u00e7\u00e3o. Dito isso, o \u00fanico requisito que os padr\u00f5es incluem com rela\u00e7\u00e3o \u00e0s porcas em T \u00e9 o seu ponto de ruptura (de acordo com o Anexo E). <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Isso, no entanto, est\u00e1 longe de ser suficiente. Queremos que a porca em T n\u00e3o apenas segure com firmeza, mas que tamb\u00e9m seja fixada com for\u00e7a no painel de parede de compensado. \u00c9 por isso que a fixamos com dois parafusos s\u00f3lidos e muito grossos &#8211; isso evita que ela se solte do painel, mesmo que a instala\u00e7\u00e3o do suporte falhe devido a um parafuso de fixa\u00e7\u00e3o danificado ou enferrujado.  <\/p>\n<h4>Distribui\u00e7\u00e3o das porcas t<\/h4>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Outro detalhe fino ao qual prestamos aten\u00e7\u00e3o \u00e9 a distribui\u00e7\u00e3o das porcas em T na superf\u00edcie do painel, de modo que sempre haja um n\u00famero suficiente delas nos cantos. A maioria dos produtores de paredes de escalada precisa colocar pe\u00e7as de madeira para conectar os pain\u00e9is uns aos outros, e o fato de voc\u00ea ter porcas em T nos cantos geralmente atrapalha essa conex\u00e3o &#8211; um detalhe importante que \u00e0s vezes \u00e9 esquecido. <\/p>\n[\/vc_column_text][vc_single_image image=&#8221;14256&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;none&#8221;][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1708421879029{padding-top: 2% !important;}&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Al\u00e9m disso, tamb\u00e9m definimos um requisito para a dist\u00e2ncia m\u00e1xima entre a superf\u00edcie do painel e o in\u00edcio da rosca da porca em T. Isso facilita muito o trabalho dos definidores de rotas e reduz o risco de rosca cruzada dos parafusos de reten\u00e7\u00e3o. Isso facilita muito o trabalho dos tra\u00e7adores de rotas e reduz o risco de os parafusos de fixa\u00e7\u00e3o serem rosqueados transversalmente. <\/p>\n[\/vc_column_text][vc_single_image image=&#8221;137439&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;none&#8221;][\/vc_tta_section][vc_tta_section title=&#8221;Pain\u00e9is&#8221; tab_id=&#8221;1624371364804-efd528ae-5225&#8243; el_class=&#8221;vc_active&#8221;][vc_column_text css_animation=&#8221;none&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Quando se trata de pain\u00e9is, o padr\u00e3o se concentra apenas na resist\u00eancia do material de que s\u00e3o feitos. Obviamente, os requisitos s\u00e3o muito mais abrangentes e o motivo \u00e9 que eles definem a funcionalidade da instala\u00e7\u00e3o, bem como a apar\u00eancia e o custo de opera\u00e7\u00e3o. A Walltopia definiu os seguintes requisitos para os pain\u00e9is que produzimos:  <\/p>\n[\/vc_column_text][vc_custom_heading text=&#8221;1. Textura:&#8221; font_container=&#8221;tag:h2|font_size:18|text_align:left|color:%23ed2020|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;none&#8221;][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;&#8221;]\n<h6 style=\"font-size: 18px; line-height: 1.8em;\"><strong>1.1. Fric\u00e7\u00e3o<\/strong><\/h6>\n<p style=\"font-size: 18px; line-height: 1.8em;\">  O n\u00edvel de atrito \u00e9 quase sempre um ponto de disputa. Se voc\u00ea pedir a dez escaladores diferentes que avaliem a mesma textura, pode ter certeza de que n\u00e3o obter\u00e1 a mesma resposta duas vezes. Alguns deles considerar\u00e3o que ficou bom, outros dir\u00e3o que ficou escorregadio e outros achar\u00e3o que ficou muito \u00e1spero. Apesar disso, ainda acreditamos que conseguimos criar a superf\u00edcie que far\u00e1 com que voc\u00ea obtenha o maior \u00edndice de aprova\u00e7\u00e3o dos clientes. <\/p>\n<h6 style=\"font-size: 18px; line-height: 1.8em;\"><strong>1.2. Resist\u00eancia ao desgaste<\/strong><\/h6>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Essa \u00e9 uma propriedade incrivelmente importante da textura, pois, sem surpresa, \u00e9 a parte com a maior taxa de deprecia\u00e7\u00e3o e basicamente define a expectativa de vida \u00fatil da instala\u00e7\u00e3o. Acreditamos que a textura n\u00e3o deve se desgastar e tamb\u00e9m deve manter suas cores vivas por pelo menos 20 anos. Para controlar esse processo, criamos um procedimento especial para o teste r\u00e1pido de fadiga de textura.<\/p>\n<h6 style=\"font-size: 18px; line-height: 1.8em;\"><strong>1.3. Capacidade anti-sujeira<\/strong><\/h6>\n<p style=\"font-size: 18px; line-height: 1.8em;\">  Os operadores raramente levam isso em considera\u00e7\u00e3o, mas as paredes de escalada se sujam com muita facilidade e, al\u00e9m disso, s\u00e3o muito dif\u00edceis de limpar. As paredes com superf\u00edcies padr\u00e3o rapidamente come\u00e7am a parecer mais velhas do que s\u00e3o, enquanto as superf\u00edcies resistentes a manchas mant\u00eam sua apar\u00eancia fresca por muito mais tempo. \u00c9 por isso que acreditamos que \u00e9 nosso dever fornecer a voc\u00ea as paredes com a melhor apar\u00eancia, independentemente do n\u00famero de pessoas que as escalam diariamente.  <\/p>\n<h6 style=\"font-size: 18px; line-height: 1.8em;\"><strong>1.4. Resist\u00eancia aos raios UV<\/strong><\/h6>\n<p style=\"font-size: 18px; line-height: 1.8em;\">As paredes de escalada ou parte delas s\u00e3o frequentemente expostas \u00e0 luz solar direta, por isso \u00e9 aconselh\u00e1vel usar um revestimento resistente a raios UV para a camada de acabamento dos pain\u00e9is, a fim de evitar que a colora\u00e7\u00e3o fique p\u00e1lida. A maioria dos fabricantes presume que as paredes de escalada ser\u00e3o instaladas em espa\u00e7os fechados, sem luz solar direta ao redor, e \u00e9 por isso que eles usam revestimentos ep\u00f3xi n\u00e3o resistentes a UV. Preferimos presumir o contr\u00e1rio &#8211; que todas as paredes que produzimos podem ser instaladas em um local com luz solar direta, e \u00e9 por isso que estabelecemos o padr\u00e3o de usar materiais resistentes a UV em nossos produtos.<\/p>\n[\/vc_column_text][vc_custom_heading text=&#8221;2. Pe\u00e7as de conex\u00e3o entre os pain\u00e9is.&#8221; font_container=&#8221;tag:h2|font_size:18|text_align:left|color:%23ed2020|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;none&#8221;][vc_column_text css_animation=&#8221;none&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">O setor oferece muitas solu\u00e7\u00f5es diferentes para conectar os pain\u00e9is de parede. Alguns usam parafusos (com cabe\u00e7as planas ou c\u00f4nicas) colocados na face e placas de a\u00e7o ou dobradi\u00e7as na parte de tr\u00e1s, enquanto outros usam perfis de madeira fixados com parafusos vis\u00edveis na parte frontal do painel. Nos \u00faltimos 5 anos, temos usado uma liga\u00e7\u00e3o oculta em que todos os parafusos s\u00e3o fixados atr\u00e1s do painel &#8211; dessa forma, eles n\u00e3o ficam vis\u00edveis na frente e a parede fica muito mais agrad\u00e1vel esteticamente.  <\/p>\n[\/vc_column_text][vc_single_image image=&#8221;14258&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;none&#8221;][vc_custom_heading text=&#8221;3. Linha de agarrar.&#8221; font_container=&#8221;tag:h2|font_size:18|text_align:left|color:%23ed2020|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1708421992286{padding-top: 2% !important;}&#8221;][vc_column_text css_animation=&#8221;none&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Esse elemento tamb\u00e9m n\u00e3o \u00e9 exigido pelos padr\u00f5es de escalada, mas n\u00f3s o consideramos obrigat\u00f3rio e ele faz parte do nosso pacote padr\u00e3o. Ele garante uma ader\u00eancia confort\u00e1vel no final da via e um grampeamento mais seguro e f\u00e1cil na esta\u00e7\u00e3o de corda superior. <\/p>\n[\/vc_column_text][vc_single_image image=&#8221;14259&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;none&#8221;][\/vc_tta_section][vc_tta_section title=&#8221;Prote\u00e7\u00e3o contra intemp\u00e9ries&#8221; tab_id=&#8221;1624370516429-5c131a89-9537&#8243; el_class=&#8221;vc_active&#8221;][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Quando se trata de paredes de escalada externas, devemos levar em considera\u00e7\u00e3o que elas ficam expostas \u00e0 chuva, neve e umidade. Isso estabelece novos requisitos para os materiais que usamos. Mesmo que o padr\u00e3o de escalada n\u00e3o mencione isso, sabemos que, para tornar uma estrutura externa adequada para uso e garantir sua longevidade, precisamos usar uma variedade de materiais diferente da usada para estruturas de escalada internas.  <\/p>\n[\/vc_column_text][vc_custom_heading text=&#8221;1. Estrutura de suporte.&#8221; font_container=&#8221;tag:h2|font_size:18|text_align:left|color:%23ed2020|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;none&#8221;][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">O procedimento padr\u00e3o em rela\u00e7\u00e3o \u00e0 constru\u00e7\u00e3o met\u00e1lica das paredes de escalada internas \u00e9 que ela seja preparada e pintada. O poliuretano ou a tinta alqu\u00eddica s\u00e3o usados com mais frequ\u00eancia para essa finalidade. No entanto, se a parede de escalada for instalada ao ar livre e, especialmente, em uma regi\u00e3o \u00famida, levar\u00e1 apenas cerca de um ano para que a constru\u00e7\u00e3o pintada comece a enferrujar.  <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Como consequ\u00eancia, o operador precisa come\u00e7ar a repint\u00e1-lo regularmente, gastando assim muito dinheiro em manuten\u00e7\u00e3o anual. \u00c9 por isso que galvanizamos por imers\u00e3o a quente todos os elementos de nossas constru\u00e7\u00f5es met\u00e1licas externas. Assim, evitamos que eles sofram corros\u00e3o. Todos os fixadores usados para montar esses elementos tamb\u00e9m s\u00e3o de a\u00e7o inoxid\u00e1vel ou galvanizados por imers\u00e3o a quente.   <\/p>\n[\/vc_column_text][vc_single_image image=&#8221;14262&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;none&#8221;][vc_custom_heading text=&#8221;2. Pain\u00e9is.&#8221; font_container=&#8221;tag:h2|font_size:18|text_align:left|color:%23ed2020|line_height:1.5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;none&#8221;][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">A instala\u00e7\u00e3o de pain\u00e9is de compensado em ambientes externos leva a uma s\u00e9ria redu\u00e7\u00e3o da vida \u00fatil da parede. Por isso, recomendamos que voc\u00ea use pain\u00e9is de madeira compensada somente se os seguintes requisitos forem atendidos: <\/p>\n<h6 style=\"font-size: 18px; line-height: 1.8em;\"><strong>2.1. Compensado externo<\/strong><\/h6>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Muitas pessoas acreditam que o uso de compensado externo garante a durabilidade do painel em espa\u00e7os externos. Isso n\u00e3o pode estar mais longe da verdade. A diferen\u00e7a entre o compensado interno e o externo \u00e9 apenas o tipo de cola usada para colar suas camadas. A cola usada para compensados externos n\u00e3o permite a delamina\u00e7\u00e3o das camadas se elas ficarem molhadas, mas isso n\u00e3o faz nada para proteger o folheado da umidade. \u00c9 por isso que recomendamos a voc\u00ea:    <\/p>\n<h6 style=\"font-size: 18px; line-height: 1.8em;\"><strong>2.2. Impregna\u00e7\u00e3o da parte traseira dos pain\u00e9is  <\/strong><\/h6>\n<p style=\"font-size: 18px; line-height: 1.8em;\">N\u00e3o \u00e9 pr\u00e1tica comum no setor impregnar a parte de tr\u00e1s dos pain\u00e9is de compensado, instalados em ambientes externos. Isso pode ser muito prejudicial, pois a umidade pode se espalhar dentro do painel e reduzir drasticamente sua vida \u00fatil. \u00c9 por isso que impregnamos a parte de tr\u00e1s dos pain\u00e9is para paredes de escalada externas da mesma forma que os protegemos melhor do contato com os elementos. No entanto, a madeira compensada n\u00e3o \u00e9 totalmente \u00e0 prova de intemp\u00e9ries e tem uma vida \u00fatil mais curta, em compara\u00e7\u00e3o com os <a href=\"http:\/\/walltopia.com\/products\/outdoor-climbing-walls\/#panels\">pain\u00e9is externos premium<\/a> de fibra de vidro e Walltopia.<\/p>\n[\/vc_column_text][vc_single_image image=&#8221;53481&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;none&#8221;][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1729673242627{padding-top: 2% !important;}&#8221;]\n<h6 style=\"font-size: 18px; line-height: 1.8em;\"><strong>2.3. Porcas em T e parafusos de a\u00e7o inoxid\u00e1vel<\/strong><\/h6>\n<p style=\"font-size: 18px; line-height: 1.8em;\">A maioria dos fabricantes costuma ignorar esses detalhes, mas, para garantir a m\u00e1xima resist\u00eancia \u00e0 \u00e1gua e durabilidade do produto, sabemos que nossas estruturas externas devem ser equipadas com porcas em T e parafusos de fixa\u00e7\u00e3o em a\u00e7o inoxid\u00e1vel.<\/p>\n<h6 style=\"font-size: 18px; line-height: 1.8em;\"><strong>2.4. Abrigo contra chuva<\/strong><\/h6>\n<p style=\"font-size: 18px; line-height: 1.8em;\">A Walltopia recomenda que voc\u00ea sempre cubra as paredes de escalada externas, feitas com pain\u00e9is PLW, com abrigos. A cobertura proteger\u00e1 os pain\u00e9is e a constru\u00e7\u00e3o met\u00e1lica do contato direto com a \u00e1gua e prolongar\u00e1 sua vida \u00fatil, al\u00e9m de oferecer aos clientes a oportunidade de escalar mesmo quando estiver chovendo. <\/p>\n[\/vc_column_text][vc_single_image image=&#8221;14264&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css_animation=&#8221;none&#8221;][\/vc_tta_section][\/vc_tta_accordion][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Essa lista \u00e9 apenas um resumo do esfor\u00e7o que fazemos para oferecer o produto de melhor qualidade do mercado. Ao escolher uma parede de escalada, h\u00e1 muitos fatores a serem considerados que podem afetar significativamente o sucesso de suas instala\u00e7\u00f5es. Com nossa ampla experi\u00eancia no setor, concentramo-nos nesses detalhes porque n\u00e3o se trata apenas de atender aos padr\u00f5es &#8211; trata-se de buscar a perfei\u00e7\u00e3o. Para n\u00f3s, a verdadeira perfei\u00e7\u00e3o vem da sinergia entre projeto, instala\u00e7\u00e3o e precis\u00e3o t\u00e9cnica.   <\/p>\n[\/vc_column_text][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 15px; line-height: 1.8em;\"><em>*As imagens s\u00e3o apenas para fins ilustrativos.<\/em><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"A Walltopia \u00e9 a fabricante l\u00edder mundial de paredes de escalada e oferecemos as melhores solu\u00e7\u00f5es do mercado. Descubra o que nos torna t\u00e3o especiais. ","protected":false},"author":10,"featured_media":185693,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1157,1151],"tags":[2556,2555,2557],"class_list":["post-185691","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escalada-pt-br","category-sala-de-imprensa","tag-inovacao","tag-inovacao-de-produtos","tag-padrao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nosso padr\u00e3o \u00e9 a perfei\u00e7\u00e3o | Walltopia<\/title>\n<meta name=\"description\" content=\"A Walltopia \u00e9 a fabricante l\u00edder mundial de paredes de escalada e oferecemos as melhores solu\u00e7\u00f5es do mercado. Descubra o que nos torna t\u00e3o especiais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/pt-br\/nosso-padrao-e-a-perfeicao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nosso padr\u00e3o \u00e9 a perfei\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"A Walltopia \u00e9 a fabricante l\u00edder mundial de paredes de escalada e oferecemos as melhores solu\u00e7\u00f5es do mercado. Descubra o que nos torna t\u00e3o especiais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/pt-br\/nosso-padrao-e-a-perfeicao\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-23T06:19:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:30:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026084154\/our-standard-is-perfection.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"267\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"the_id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/nosso-padrao-e-a-perfeicao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/nosso-padrao-e-a-perfeicao\\\/\"},\"author\":{\"name\":\"the_id\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\"},\"headline\":\"Nosso padr\u00e3o \u00e9 a perfei\u00e7\u00e3o\",\"datePublished\":\"2021-06-23T06:19:21+00:00\",\"dateModified\":\"2026-01-15T14:30:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/nosso-padrao-e-a-perfeicao\\\/\"},\"wordCount\":3142,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/nosso-padrao-e-a-perfeicao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026084154\\\/our-standard-is-perfection.jpg\",\"keywords\":[\"inova\u00e7\u00e3o\",\"Inova\u00e7\u00e3o de produtos\",\"padr\u00e3o\"],\"articleSection\":[\"Escalada\",\"Sala de imprensa\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/nosso-padrao-e-a-perfeicao\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/nosso-padrao-e-a-perfeicao\\\/\",\"name\":\"Nosso padr\u00e3o \u00e9 a perfei\u00e7\u00e3o | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/nosso-padrao-e-a-perfeicao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/nosso-padrao-e-a-perfeicao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026084154\\\/our-standard-is-perfection.jpg\",\"datePublished\":\"2021-06-23T06:19:21+00:00\",\"dateModified\":\"2026-01-15T14:30:08+00:00\",\"description\":\"A Walltopia \u00e9 a fabricante l\u00edder mundial de paredes de escalada e oferecemos as melhores solu\u00e7\u00f5es do mercado. Descubra o que nos torna t\u00e3o especiais.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/nosso-padrao-e-a-perfeicao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/nosso-padrao-e-a-perfeicao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/nosso-padrao-e-a-perfeicao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026084154\\\/our-standard-is-perfection.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026084154\\\/our-standard-is-perfection.jpg\",\"width\":400,\"height\":267},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/nosso-padrao-e-a-perfeicao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/inicio-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nosso padr\u00e3o \u00e9 a perfei\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\",\"name\":\"the_id\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nosso padr\u00e3o \u00e9 a perfei\u00e7\u00e3o | Walltopia","description":"A Walltopia \u00e9 a fabricante l\u00edder mundial de paredes de escalada e oferecemos as melhores solu\u00e7\u00f5es do mercado. Descubra o que nos torna t\u00e3o especiais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/pt-br\/nosso-padrao-e-a-perfeicao\/","og_locale":"pt_BR","og_type":"article","og_title":"Nosso padr\u00e3o \u00e9 a perfei\u00e7\u00e3o","og_description":"A Walltopia \u00e9 a fabricante l\u00edder mundial de paredes de escalada e oferecemos as melhores solu\u00e7\u00f5es do mercado. Descubra o que nos torna t\u00e3o especiais.","og_url":"https:\/\/walltopia.com\/pt-br\/nosso-padrao-e-a-perfeicao\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2021-06-23T06:19:21+00:00","article_modified_time":"2026-01-15T14:30:08+00:00","og_image":[{"width":400,"height":267,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026084154\/our-standard-is-perfection.jpg","type":"image\/jpeg"}],"author":"the_id","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/pt-br\/nosso-padrao-e-a-perfeicao\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/pt-br\/nosso-padrao-e-a-perfeicao\/"},"author":{"name":"the_id","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff"},"headline":"Nosso padr\u00e3o \u00e9 a perfei\u00e7\u00e3o","datePublished":"2021-06-23T06:19:21+00:00","dateModified":"2026-01-15T14:30:08+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/pt-br\/nosso-padrao-e-a-perfeicao\/"},"wordCount":3142,"publisher":{"@id":"https:\/\/walltopia.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/nosso-padrao-e-a-perfeicao\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026084154\/our-standard-is-perfection.jpg","keywords":["inova\u00e7\u00e3o","Inova\u00e7\u00e3o de produtos","padr\u00e3o"],"articleSection":["Escalada","Sala de imprensa"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/pt-br\/nosso-padrao-e-a-perfeicao\/","url":"https:\/\/walltopia.com\/pt-br\/nosso-padrao-e-a-perfeicao\/","name":"Nosso padr\u00e3o \u00e9 a perfei\u00e7\u00e3o | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/pt-br\/nosso-padrao-e-a-perfeicao\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/nosso-padrao-e-a-perfeicao\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026084154\/our-standard-is-perfection.jpg","datePublished":"2021-06-23T06:19:21+00:00","dateModified":"2026-01-15T14:30:08+00:00","description":"A Walltopia \u00e9 a fabricante l\u00edder mundial de paredes de escalada e oferecemos as melhores solu\u00e7\u00f5es do mercado. Descubra o que nos torna t\u00e3o especiais.","breadcrumb":{"@id":"https:\/\/walltopia.com\/pt-br\/nosso-padrao-e-a-perfeicao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/pt-br\/nosso-padrao-e-a-perfeicao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/walltopia.com\/pt-br\/nosso-padrao-e-a-perfeicao\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026084154\/our-standard-is-perfection.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026084154\/our-standard-is-perfection.jpg","width":400,"height":267},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/pt-br\/nosso-padrao-e-a-perfeicao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/pt-br\/inicio-pt\/"},{"@type":"ListItem","position":2,"name":"Nosso padr\u00e3o \u00e9 a perfei\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/pt-br\/#website","url":"https:\/\/walltopia.com\/pt-br\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/pt-br\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff","name":"the_id"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/posts\/185691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/comments?post=185691"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/posts\/185691\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/media\/185693"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/media?parent=185691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/categories?post=185691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/tags?post=185691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}