{"id":188636,"date":"2015-10-30T08:08:22","date_gmt":"2015-10-30T05:08:22","guid":{"rendered":"https:\/\/walltopia.com\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\/"},"modified":"2026-01-15T17:38:29","modified_gmt":"2026-01-15T14:38:29","slug":"conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2","status":"publish","type":"post","link":"https:\/\/walltopia.com\/pt-br\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\/","title":{"rendered":"Conhe\u00e7a a Walltopia Adventure na IAAPA Attractions Expo 2015"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column css_animation=&#8221;fadeInUp&#8221;][vc_column_text]\n<p style=\"font-size: 18px; line-height: 1.8em;\">A Walltopia Adventure apresentar\u00e1 suas marcas <a href=\"https:\/\/staging-3.walltopia.com\/products\/fun-walls\/\">Fun Walls<\/a>, <a href=\"https:\/\/staging-3.walltopia.com\/products\/walltopia-caves\/\">Walltopia Caves<\/a>, <a href=\"https:\/\/staging-3.walltopia.com\/products\/ropes-course\/\">Ropes Course<\/a> e <a href=\"https:\/\/staging-3.walltopia.com\/products\/rollglider\/\">Rollglider<\/a> na <a href=\"https:\/\/www.iaapa.org\/\">IAAPA Attractions Expo<\/a> em Orlando, Fl\u00f3rida. Saiba o que cada produto pode fazer pelas empresas do <a href=\"https:\/\/staging-3.walltopia.com\/industries\/amusement-parks\/\">setor de divers\u00f5es<\/a>, de 17 a 20 de novembro, no estande 4054. <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Uma coletiva de imprensa anunciando oficialmente o lan\u00e7amento do Rollglider ser\u00e1 realizada no dia 18 de novembro, \u00e0s 11h45, no estande da empresa.<\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Voc\u00ea tem interesse em marcar uma reuni\u00e3o? Entre em contato conosco pelo <a href=\"mailto:sales@walltopia.com\">e-mail sales@walltopia.com.<\/a> <\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"A Walltopia Adventure apresentar\u00e1 suas marcas Fun Walls, Rocktopia, Ropetopia e Rollglider na IAAPA Attractions Expo.","protected":false},"author":5,"featured_media":188640,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1156],"tags":[3067,1152,3068],"class_list":["post-188636","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento-ativo","tag-exposicao-de-atracoes-da-iaapa","tag-iaapa-pt-br","tag-iaapa-attractions-expo-2015"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Conhe\u00e7a a Walltopia Adventure na IAAPA Attractions Expo 2015 | Walltopia<\/title>\n<meta name=\"description\" content=\"A Walltopia Adventure apresentar\u00e1 suas marcas. Saiba o que cada produto pode fazer pelas empresas do setor de divers\u00f5es.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/pt-br\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conhe\u00e7a a Walltopia Adventure na IAAPA Attractions Expo 2015\" \/>\n<meta property=\"og:description\" content=\"A Walltopia Adventure apresentar\u00e1 suas marcas. Saiba o que cada produto pode fazer pelas empresas do setor de divers\u00f5es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/pt-br\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-30T05:08:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:38:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027150059\/Walltopia-IAAPA-Attractions-Expo-2015.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"479\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Conhe\u00e7a a Walltopia Adventure na IAAPA Attractions Expo 2015\",\"datePublished\":\"2015-10-30T05:08:22+00:00\",\"dateModified\":\"2026-01-15T14:38:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\\\/\"},\"wordCount\":108,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027150059\\\/Walltopia-IAAPA-Attractions-Expo-2015.jpg\",\"keywords\":[\"Exposi\u00e7\u00e3o de atra\u00e7\u00f5es da IAAPA\",\"IAAPA\",\"IAAPA Attractions Expo 2015\"],\"articleSection\":[\"Entretenimento ativo\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\\\/\",\"name\":\"Conhe\u00e7a a Walltopia Adventure na IAAPA Attractions Expo 2015 | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027150059\\\/Walltopia-IAAPA-Attractions-Expo-2015.jpg\",\"datePublished\":\"2015-10-30T05:08:22+00:00\",\"dateModified\":\"2026-01-15T14:38:29+00:00\",\"description\":\"A Walltopia Adventure apresentar\u00e1 suas marcas. Saiba o que cada produto pode fazer pelas empresas do setor de divers\u00f5es.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027150059\\\/Walltopia-IAAPA-Attractions-Expo-2015.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027150059\\\/Walltopia-IAAPA-Attractions-Expo-2015.jpg\",\"width\":900,\"height\":479},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/inicio-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conhe\u00e7a a Walltopia Adventure na IAAPA Attractions Expo 2015\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Conhe\u00e7a a Walltopia Adventure na IAAPA Attractions Expo 2015 | Walltopia","description":"A Walltopia Adventure apresentar\u00e1 suas marcas. Saiba o que cada produto pode fazer pelas empresas do setor de divers\u00f5es.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/pt-br\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Conhe\u00e7a a Walltopia Adventure na IAAPA Attractions Expo 2015","og_description":"A Walltopia Adventure apresentar\u00e1 suas marcas. Saiba o que cada produto pode fazer pelas empresas do setor de divers\u00f5es.","og_url":"https:\/\/walltopia.com\/pt-br\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2015-10-30T05:08:22+00:00","article_modified_time":"2026-01-15T14:38:29+00:00","og_image":[{"width":900,"height":479,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027150059\/Walltopia-IAAPA-Attractions-Expo-2015.jpg","type":"image\/jpeg"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/pt-br\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/pt-br\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Conhe\u00e7a a Walltopia Adventure na IAAPA Attractions Expo 2015","datePublished":"2015-10-30T05:08:22+00:00","dateModified":"2026-01-15T14:38:29+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/pt-br\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\/"},"wordCount":108,"commentCount":0,"publisher":{"@id":"https:\/\/walltopia.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027150059\/Walltopia-IAAPA-Attractions-Expo-2015.jpg","keywords":["Exposi\u00e7\u00e3o de atra\u00e7\u00f5es da IAAPA","IAAPA","IAAPA Attractions Expo 2015"],"articleSection":["Entretenimento ativo"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/walltopia.com\/pt-br\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/pt-br\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\/","url":"https:\/\/walltopia.com\/pt-br\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\/","name":"Conhe\u00e7a a Walltopia Adventure na IAAPA Attractions Expo 2015 | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/pt-br\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027150059\/Walltopia-IAAPA-Attractions-Expo-2015.jpg","datePublished":"2015-10-30T05:08:22+00:00","dateModified":"2026-01-15T14:38:29+00:00","description":"A Walltopia Adventure apresentar\u00e1 suas marcas. Saiba o que cada produto pode fazer pelas empresas do setor de divers\u00f5es.","breadcrumb":{"@id":"https:\/\/walltopia.com\/pt-br\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/pt-br\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/walltopia.com\/pt-br\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027150059\/Walltopia-IAAPA-Attractions-Expo-2015.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027150059\/Walltopia-IAAPA-Attractions-Expo-2015.jpg","width":900,"height":479},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/pt-br\/conheca-a-walltopia-adventure-na-iaapa-attractions-expo-2015-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/pt-br\/inicio-pt\/"},{"@type":"ListItem","position":2,"name":"Conhe\u00e7a a Walltopia Adventure na IAAPA Attractions Expo 2015"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/pt-br\/#website","url":"https:\/\/walltopia.com\/pt-br\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/pt-br\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/posts\/188636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/comments?post=188636"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/posts\/188636\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/media\/188640"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/media?parent=188636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/categories?post=188636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/tags?post=188636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}