{"id":189925,"date":"2017-02-17T11:39:33","date_gmt":"2017-02-17T08:39:33","guid":{"rendered":"https:\/\/walltopia.com\/afcm-sobre-o-sucesso-do-funtopia\/"},"modified":"2026-01-15T17:41:36","modified_gmt":"2026-01-15T14:41:36","slug":"afcm-sobre-o-sucesso-do-funtopia","status":"publish","type":"post","link":"https:\/\/walltopia.com\/pt-br\/afcm-sobre-o-sucesso-do-funtopia\/","title":{"rendered":"AFCM sobre o sucesso do Funtopia"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column css_animation=&#8221;fadeInUp&#8221;][vc_column_text]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Observando a velocidade com que nosso setor est\u00e1 crescendo e mudando, decidimos iniciar uma conversa com nossos clientes e parceiros sobre as li\u00e7\u00f5es aprendidas no caminho e o futuro pr\u00f3ximo.<\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">A primeira da lista \u00e9 a nossa empresa parceira, a <a href=\"https:\/\/adventurefacilities.com\/\" target=\"_blank\" rel=\"noopener\">Adventure Facility Concepts &amp; Management<\/a> (AFCM). Costumamos brincar que, se fosse para o Facebook decidir nosso relacionamento com a AFCM, parece que ele se encaixa melhor no status de &#8220;relacionamento aberto&#8221;. Por que aberto? A AFCM foi criada em 2013 como uma entidade separada da fam\u00edlia Walltopia com um objetivo bem distinto: ser excelente em opera\u00e7\u00f5es de centros de aventura. Eles se basearam em nosso produto de aventura mais reconhecido &#8211; o Fun Walls &#8211; e o transformaram em um modelo de franquia bem-sucedido.    <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Hoje, por\u00e9m, eles s\u00e3o mais do que isso. A AFCM agora trabalha com conceitos de instala\u00e7\u00f5es de aventura de A a Z, em que as paredes divertidas s\u00e3o apenas uma das atra\u00e7\u00f5es &#8211; em algum lugar entre trampolins, brinquedos macios, tirolesas, cursos de corda, cavernas artificiais etc. E, portanto, \u00e9 a\u00ed que surge o relacionamento &#8220;aberto&#8221;. A Walltopia \u00e9 apenas um dos muitos fornecedores com os quais a AFCM trabalha. Saiba como a AFCM v\u00ea sua fun\u00e7\u00e3o e o que eles t\u00eam a nos dizer sobre seu modelo de franquia de entretenimento ativo. Leia abaixo a entrevista com Tania Kishkin, Vice-CEO da AFCM, que est\u00e1 com eles desde a funda\u00e7\u00e3o e passou por todo o processo de transformar um conceito em um modelo de trabalho.     <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Walltopia: O que est\u00e1 por tr\u00e1s da franquia Funtopia?<\/strong><\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Tania (AFCM):<\/strong> A for\u00e7a e o entusiasmo de v\u00e1rios jovens que adoram desafios e os superam como se fosse sua segunda natureza. Aventureiros, perspicazes e criativos, eles est\u00e3o conquistando o mercado de entretenimento e espalhando centros Funtopia por todo o mundo. <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Walltopia: Muitas vezes somos procurados para fazer cita\u00e7\u00f5es de Funtopia e voc\u00ea \u00e9 procurado para fazer cita\u00e7\u00f5es de Fun Walls. Como voc\u00ea explicaria a diferen\u00e7a entre os dois? <\/strong><\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>T:<\/strong> A diferen\u00e7a \u00e9 simples &#8211; o <a href=\"https:\/\/staging-3.walltopia.com\/products\/fun-walls\/\" target=\"_blank\" rel=\"noopener\">Fun Walls<\/a> \u00e9 o Big Mac do card\u00e1pio e o Funtopia \u00e9 o restaurante do McDonald&#8217;s. Voc\u00ea pode encontrar muitas outras ofertas no card\u00e1pio. H\u00e1 muitas outras ofertas no card\u00e1pio. Com o Funtopia, voc\u00ea oferece aos seus visitantes um mix de atra\u00e7\u00f5es de aventura onde eles podem escalar, pular, escorregar, rastejar, voar, comemorar, se divertir com a fam\u00edlia, amigos, colegas etc. As Fun Walls s\u00e3o a atividade \u00e2ncora, mas a for\u00e7a do Funtopia est\u00e1 escondida nas opera\u00e7\u00f5es, no programa de marketing, nos pacotes de eventos, nos torneios, na forma\u00e7\u00e3o de equipes etc. O Funtopia tem tudo o que voc\u00ea precisa para triplicar a receita dos Fun Walls.    <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Walltopia: Qual foi o motivo que levou voc\u00ea a transformar a Funtopia em uma franquia? E quais s\u00e3o os benef\u00edcios que isso traria para os clientes? <\/strong><\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>T:<\/strong> O Funtopia \u00e9 um \u00f3timo conceito, n\u00f3s sabemos disso. Havia duas op\u00e7\u00f5es: desenvolver e administrar em c\u00e2mera lenta nossos pr\u00f3prios centros Funtopia ou vender o conceito para muitas outras pessoas entusiasmadas e cheias de energia que percebem os benef\u00edcios. N\u00f3s nos esfor\u00e7amos para desenvolver. A franquia \u00e9 a maneira mais r\u00e1pida de se tornar global e, \u00e9 claro, quanto mais desafiador, mais atraente \u00e9 para n\u00f3s.   <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Os benef\u00edcios &#8211; Os franqueados do Funtopia t\u00eam quatro vezes mais chances de sucesso em compara\u00e7\u00e3o com os n\u00e3o franqueados, que lutam com adivinha\u00e7\u00f5es durante os primeiros anos do in\u00edcio do neg\u00f3cio operacional. As tarefas a serem realizadas s\u00e3o in\u00fameras e, enquanto os n\u00e3o franqueados gastam tempo decidindo o que deve ser feito, quando, onde e como, as vendas caem. O Funtopia oferece uma estrutura clara e consecutiva em etapas para que as vendas comecem a crescer desde a inaugura\u00e7\u00e3o.  <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">A Funtopia possui o poder de compra de equipamentos e suprimentos e o conhecimento compartilhado do sistema de franquia, o que torna a marca mais forte e mais atraente para franqueados em potencial. Al\u00e9m disso, durante o per\u00edodo do contrato, voc\u00ea ter\u00e1 ao lado do franqueado um Gerente de Desenvolvimento de Neg\u00f3cios dedicado, jovem e entusiasmado, com vasta experi\u00eancia e um bom senso para opera\u00e7\u00f5es de aventura. Essa pessoa, juntamente com outros profissionais da equipe, apoia o franqueado com consultoria jur\u00eddica, planejamento de neg\u00f3cios, gerenciamento de projetos, treinamentos, revis\u00e3o da pol\u00edtica de pre\u00e7os, programas e pacotes, assist\u00eancia para abertura no local, coaching de desempenho, benchmarks e KPIs.  <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">A Funtopia desenvolveu um software de PDV personalizado que rastreia cada minuto de opera\u00e7\u00e3o, vendas e resultados por grupo de servi\u00e7os, promo\u00e7\u00f5es e reservas on-line. Ele tamb\u00e9m pode enviar mensagens pessoais para seus clientes. Essa \u00e9 uma pequena parte do que oferecemos aos franqueados &#8211; eles tamb\u00e9m recebem um site e perfis de m\u00eddia social, al\u00e9m de um programa de marketing totalmente desenvolvido com v\u00e1rias ferramentas e um rico conjunto de designs e recursos visuais. Obviamente, tudo isso \u00e9 acompanhado pelo Manual de Opera\u00e7\u00f5es do Funtopia, que inclui todos os instrumentos necess\u00e1rios para que voc\u00ea possa administrar as opera\u00e7\u00f5es desde o primeiro dia.   <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">[vc_single_image image=&#8221;11968&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_image&#8221; css=&#8221;.vc_custom_1612365510397{padding-bottom: 5% !important;}&#8221;][vc_column_text]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Walltopia: At\u00e9 o momento, voc\u00ea tem 9 centros em 4 continentes. Voc\u00ea j\u00e1 tem uma receita para o sucesso? <\/strong><\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>T:<\/strong> Velha, mas dourada &#8211; a receita para o sucesso \u00e9 amar o que voc\u00ea faz. Nossa equipe n\u00e3o \u00e9 apenas um grupo de funcion\u00e1rios &#8211; \u00e9 uma equipe que possui a energia, o poder, o know-how e o desejo de atrair o mundo para o franqueado. A Funtopia est\u00e1 em 4 continentes porque trabalhamos duro e nos dedicamos ao que fazemos. Todo neg\u00f3cio bem-sucedido exige uma abordagem s\u00e9ria, embora estejamos no ramo do entretenimento.   <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Walltopia: Qual \u00e9 o perfil t\u00edpico de um propriet\u00e1rio do Funtopia?<\/strong><\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>T:<\/strong> O propriet\u00e1rio \u00e9 uma pessoa com uma atitude positiva em rela\u00e7\u00e3o aos jovens. O Funtopia est\u00e1 no setor de servi\u00e7os e seus clientes s\u00e3o pais com crian\u00e7as e adolescentes. O propriet\u00e1rio deve ter essa intui\u00e7\u00e3o e o desejo de se tornar o local mais querido e preferido por esses grupos-alvo. N\u00e3o \u00e9 apenas o conceito, mas tamb\u00e9m a equipe, sua apar\u00eancia, cortesia e educa\u00e7\u00e3o que fazem do lugar o que ele \u00e9.   <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">O propriet\u00e1rio tamb\u00e9m precisa ser en\u00e9rgico, empreendedor, criativo e ficar de olho em cada cent\u00edmetro quadrado de seu centro Funtopia. N\u00e3o \u00e9 necess\u00e1rio ter experi\u00eancia anterior no setor de entretenimento &#8211; n\u00f3s o ensinaremos sobre isso, mas \u00e9 altamente recomend\u00e1vel que voc\u00ea tenha experi\u00eancia na administra\u00e7\u00e3o de uma empresa. <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Walltopia: Olhando para tr\u00e1s, qual foi o maior desafio que voc\u00ea teve at\u00e9 agora?<\/strong><\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>T:<\/strong> Ser franqueado em 4 continentes e em 6 pa\u00edses diferentes \u00e9 um trabalho bastante interessante. Alguns entender\u00e3o. Por tr\u00e1s disso h\u00e1 diferentes legisla\u00e7\u00f5es, culturas, abordagens, atividades, h\u00e1bitos etc. Os indicadores de desempenho s\u00e3o diferentes e dificilmente podem ser comparados entre os pa\u00edses. O sucesso de um \u00fanico local \u00e9 medido pelo prisma da cultura local. Os desafios come\u00e7am com as legisla\u00e7\u00f5es de franquia, os requisitos de design e arquitetura das autoridades locais e n\u00e3o terminam com a grande inaugura\u00e7\u00e3o. Temos que nos adaptar rapidamente, ser flex\u00edveis e ter a mente aberta se quisermos crescer.      <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Walltopia: Sua maior recompensa?<\/strong><\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>T:<\/strong> Em termos de neg\u00f3cios, ser apresentado em 4 continentes n\u00e3o \u00e9 uma recompensa pequena, voc\u00ea h\u00e1 de concordar. Mas o mais gratificante \u00e9 que nossos franqueados abrem uma segunda unidade menos de um ano ap\u00f3s a primeira. Isso fala por si s\u00f3 &#8211; a marca se torna mais forte, as pessoas adoram o Funtopia e precisam de mais, confiam em n\u00f3s. Isso deixa todos felizes.   <\/p>\n<p>Em termos de responsabilidade social, todos os dias ouvimos ou lemos coment\u00e1rios de pais que agradecem e apreciam as horas que seus filhos passam no Funtopia, porque essa experi\u00eancia substituiu parte de sua dose di\u00e1ria de entretenimento na tela. Queremos que as crian\u00e7as cres\u00e7am felizes, cheias de energia e perspicazes. No Funtopia, elas podem desfrutar de todas as atividades de aventura, participar de diferentes desafios f\u00edsicos, competir e compartilhar a alegria e a divers\u00e3o. Esta \u00e9 a aventura FUNbelievable que fizemos h\u00e1 pouco tempo&#8230;   <\/p>\n<p><strong>Walltopia: Funtopia em uma palavra: &#8230;.?<\/strong><\/p>\n<p><strong>T:<\/strong> Fant\u00e1stico!<\/p>\n<p><strong>Walltopia: O que devemos esperar de voc\u00ea no futuro?<\/strong><\/p>\n<p><strong>T:<\/strong> Nossas ambi\u00e7\u00f5es s\u00e3o grandes, mas somos corajosos e inteligentes e vamos alcan\u00e7\u00e1-las. A prova: voc\u00ea pode esperar a abertura de 7 novos centros Funtopia at\u00e9 o final de 2017.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Observando a velocidade com que nosso setor est\u00e1 crescendo e mudando, decidimos iniciar uma conversa com nossos clientes e parceiros.","protected":false},"author":5,"featured_media":189927,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1156],"tags":[3376,3377],"class_list":["post-189925","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento-ativo","tag-afcm","tag-conceitos-e-gerenciamento-de-instalacoes-de-aventura"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>AFCM sobre o sucesso do Funtopia | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/pt-br\/afcm-sobre-o-sucesso-do-funtopia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AFCM sobre o sucesso do Funtopia\" \/>\n<meta property=\"og:description\" content=\"Observando a velocidade com que nosso setor est\u00e1 crescendo e mudando, decidimos iniciar uma conversa com nossos clientes e parceiros.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/pt-br\/afcm-sobre-o-sucesso-do-funtopia\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-17T08:39:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:41:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145643\/Walltopia-AFCM-Interview.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"477\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/afcm-sobre-o-sucesso-do-funtopia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/afcm-sobre-o-sucesso-do-funtopia\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"AFCM sobre o sucesso do Funtopia\",\"datePublished\":\"2017-02-17T08:39:33+00:00\",\"dateModified\":\"2026-01-15T14:41:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/afcm-sobre-o-sucesso-do-funtopia\\\/\"},\"wordCount\":1495,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/afcm-sobre-o-sucesso-do-funtopia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145643\\\/Walltopia-AFCM-Interview.jpg\",\"keywords\":[\"AFCM\",\"Conceitos e gerenciamento de instala\u00e7\u00f5es de aventura\"],\"articleSection\":[\"Entretenimento ativo\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/afcm-sobre-o-sucesso-do-funtopia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/afcm-sobre-o-sucesso-do-funtopia\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/afcm-sobre-o-sucesso-do-funtopia\\\/\",\"name\":\"AFCM sobre o sucesso do Funtopia | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/afcm-sobre-o-sucesso-do-funtopia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/afcm-sobre-o-sucesso-do-funtopia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145643\\\/Walltopia-AFCM-Interview.jpg\",\"datePublished\":\"2017-02-17T08:39:33+00:00\",\"dateModified\":\"2026-01-15T14:41:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/afcm-sobre-o-sucesso-do-funtopia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/afcm-sobre-o-sucesso-do-funtopia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/afcm-sobre-o-sucesso-do-funtopia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145643\\\/Walltopia-AFCM-Interview.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145643\\\/Walltopia-AFCM-Interview.jpg\",\"width\":900,\"height\":477},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/afcm-sobre-o-sucesso-do-funtopia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/inicio-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AFCM sobre o sucesso do Funtopia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"AFCM sobre o sucesso do Funtopia | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/pt-br\/afcm-sobre-o-sucesso-do-funtopia\/","og_locale":"pt_BR","og_type":"article","og_title":"AFCM sobre o sucesso do Funtopia","og_description":"Observando a velocidade com que nosso setor est\u00e1 crescendo e mudando, decidimos iniciar uma conversa com nossos clientes e parceiros.","og_url":"https:\/\/walltopia.com\/pt-br\/afcm-sobre-o-sucesso-do-funtopia\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2017-02-17T08:39:33+00:00","article_modified_time":"2026-01-15T14:41:36+00:00","og_image":[{"width":900,"height":477,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145643\/Walltopia-AFCM-Interview.jpg","type":"image\/jpeg"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/pt-br\/afcm-sobre-o-sucesso-do-funtopia\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/pt-br\/afcm-sobre-o-sucesso-do-funtopia\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"AFCM sobre o sucesso do Funtopia","datePublished":"2017-02-17T08:39:33+00:00","dateModified":"2026-01-15T14:41:36+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/pt-br\/afcm-sobre-o-sucesso-do-funtopia\/"},"wordCount":1495,"commentCount":0,"publisher":{"@id":"https:\/\/walltopia.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/afcm-sobre-o-sucesso-do-funtopia\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145643\/Walltopia-AFCM-Interview.jpg","keywords":["AFCM","Conceitos e gerenciamento de instala\u00e7\u00f5es de aventura"],"articleSection":["Entretenimento ativo"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/walltopia.com\/pt-br\/afcm-sobre-o-sucesso-do-funtopia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/pt-br\/afcm-sobre-o-sucesso-do-funtopia\/","url":"https:\/\/walltopia.com\/pt-br\/afcm-sobre-o-sucesso-do-funtopia\/","name":"AFCM sobre o sucesso do Funtopia | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/pt-br\/afcm-sobre-o-sucesso-do-funtopia\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/afcm-sobre-o-sucesso-do-funtopia\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145643\/Walltopia-AFCM-Interview.jpg","datePublished":"2017-02-17T08:39:33+00:00","dateModified":"2026-01-15T14:41:36+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/pt-br\/afcm-sobre-o-sucesso-do-funtopia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/pt-br\/afcm-sobre-o-sucesso-do-funtopia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/walltopia.com\/pt-br\/afcm-sobre-o-sucesso-do-funtopia\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145643\/Walltopia-AFCM-Interview.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145643\/Walltopia-AFCM-Interview.jpg","width":900,"height":477},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/pt-br\/afcm-sobre-o-sucesso-do-funtopia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/pt-br\/inicio-pt\/"},{"@type":"ListItem","position":2,"name":"AFCM sobre o sucesso do Funtopia"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/pt-br\/#website","url":"https:\/\/walltopia.com\/pt-br\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/pt-br\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/posts\/189925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/comments?post=189925"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/posts\/189925\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/media\/189927"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/media?parent=189925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/categories?post=189925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/tags?post=189925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}