{"id":196145,"date":"2020-11-26T17:16:26","date_gmt":"2020-11-26T14:16:26","guid":{"rendered":"https:\/\/walltopia.com\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\/"},"modified":"2026-01-15T17:56:12","modified_gmt":"2026-01-15T14:56:12","slug":"walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo","status":"publish","type":"post","link":"https:\/\/walltopia.com\/pt-br\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\/","title":{"rendered":"Walltopia anuncia a nova e maior pista de cordas interna do mundo"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Este m\u00eas, adicionamos mais um recorde \u00e0 nossa cole\u00e7\u00e3o, desta vez superando nossa pr\u00f3pria conquista e criando a <a href=\"https:\/\/staging-3.walltopia.com\/projects\/play-cbus\/\" target=\"_blank\" rel=\"noopener\">maior pista de cordas coberta<\/a> do mundo pela segunda vez. O mais novo detentor do recorde \u00e9 o Play: CBUS, em Ohio, com incr\u00edveis 129 obst\u00e1culos diferentes. S\u00e3o 10 a mais do que o detentor do recorde anterior, o incr\u00edvel <a href=\"https:\/\/staging-3.walltopia.com\/projects\/summit-ropes\/\" target=\"_blank\" rel=\"noopener\">Summit Ropes<\/a>, que criamos no ano passado. No entanto, o tamanho n\u00e3o \u00e9 a \u00fanica caracter\u00edstica distintiva do Play: CBUS. Os propriet\u00e1rios do centro conseguiram criar um espa\u00e7o que \u00e9 inclusivo e oferece um pouco de divers\u00e3o para todos. Nas palavras de Brian, o COO do centro:     <\/p>\n[\/vc_column_text][vc_custom_heading text=&#8221;&quot;Criamos uma experi\u00eancia de primeira classe<br \/>\nque qualquer pessoa pode aproveitar, desde crian\u00e7as pequenas<br \/>\nat\u00e9 adultos e todos os demais.&quot;&#8221; font_container=&#8221;tag:h5|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1616079742954{padding-bottom: 3% !important;}&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Esse conceito de divers\u00e3o e experi\u00eancias familiares compartilhadas por meio do Active Entertainment n\u00e3o \u00e9 novo, mas est\u00e1 se tornando cada vez mais popular. Al\u00e9m disso, parece ser o elo perdido, mas vital, entre a divers\u00e3o familiar saud\u00e1vel e o exerc\u00edcio f\u00edsico. Isso faz com que os espa\u00e7os que conseguem reunir v\u00e1rias gera\u00e7\u00f5es sejam cada vez mais valiosos para o Play: CBUS, s\u00e3o cada vez mais valiosos tanto para seus clientes quanto para suas comunidades.  <\/p>\n[\/vc_column_text][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Na verdade, <a href=\"https:\/\/www.playadventureparks.com\/location\/columbus\/\" target=\"_blank\" rel=\"noopener\">o Play: CBUS<\/a> \u00e9 o segundo Centro de Entretenimento Ativo da Play Holdings, totalmente projetado, concebido e produzido pela Walltopia. Ele inclui n\u00e3o apenas a maior pista de cordas coberta, mas tamb\u00e9m dois tipos de pistas ninja para aqueles que querem se exercitar e se desafiar, uma parede de escalada para escaladores \u00e1vidos, Fun Walls e uma pista de cordas para crian\u00e7as para os visitantes mais jovens e uma tirolesa para os mais corajosos. <\/p>\n[\/vc_column_text]<blockquote class=\"custom relative full-width-container margin-bottom-25\" style=\"color: #ffffff; font-size: 24px; line-height: 1.5; background-color: #333144;\"><div class=\"content block width-100 float-left\">To be honest, the most challenging part of a big project like Play: CBUS is not the scale, but creating a mix of attractions that achieve the right balance between physical challenge and entertainment, for people of different ages and interests`` \u2013 explains Konstantin Karamfilov, Product Manager for the Active Entertainment in Walltopia.<\/div><span class=\"dashicons dashicons-format-quote\" style=\"color: #ffffff;\"><\/span><\/blockquote>[vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Alcan\u00e7ar esse equil\u00edbrio correto \u00e9 uma de nossas principais compet\u00eancias e um segredo bem guardado. No entanto, o que certamente ajuda a mant\u00ea-lo \u00e9 o <a href=\"https:\/\/staging-3.walltopia.com\/products\/\" target=\"_blank\" rel=\"noopener\">portf\u00f3lio de produtos<\/a> da empresa, que est\u00e1 em constante expans\u00e3o, e a vasta experi\u00eancia de sua equipe de mais de 40 designers e engenheiros que criam cada projeto desde o in\u00edcio. <\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Experi\u00eancia de primeira classe que todos podem desfrutar. Divers\u00e3o e experi\u00eancias compartilhadas em fam\u00edlia por meio do Active Entertainment. Leia mais no artigo.  ","protected":false},"author":5,"featured_media":196147,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1156,1151],"tags":[4609,1169,4607],"class_list":["post-196145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento-ativo","category-sala-de-imprensa","tag-a-maior-pista-de-cordas-coberta-do-mundo","tag-curso-de-cordas","tag-curso-de-obstaculos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Walltopia anuncia a nova e maior pista de cordas interna do mundo | Walltopia<\/title>\n<meta name=\"description\" content=\"Experi\u00eancia de primeira classe que todos podem desfrutar. Divers\u00e3o e experi\u00eancias compartilhadas em fam\u00edlia por meio do Active Entertainment. Leia mais no artigo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/pt-br\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Walltopia anuncia a nova e maior pista de cordas interna do mundo\" \/>\n<meta property=\"og:description\" content=\"Experi\u00eancia de primeira classe que todos podem desfrutar. Divers\u00e3o e experi\u00eancias compartilhadas em fam\u00edlia por meio do Active Entertainment. Leia mais no artigo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/pt-br\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-26T14:16:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:56:12+00:00\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144611\/walltopia-ropes-course-play-cbus-1-1.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Walltopia anuncia a nova e maior pista de cordas interna do mundo\",\"datePublished\":\"2020-11-26T14:16:26+00:00\",\"dateModified\":\"2026-01-15T14:56:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\\\/\"},\"wordCount\":511,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027144611\\\/walltopia-ropes-course-play-cbus-1-1.jpg\",\"keywords\":[\"A maior pista de cordas coberta do mundo\",\"Curso de cordas\",\"Curso de obst\u00e1culos\"],\"articleSection\":[\"Entretenimento ativo\",\"Sala de imprensa\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\\\/\",\"name\":\"Walltopia anuncia a nova e maior pista de cordas interna do mundo | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027144611\\\/walltopia-ropes-course-play-cbus-1-1.jpg\",\"datePublished\":\"2020-11-26T14:16:26+00:00\",\"dateModified\":\"2026-01-15T14:56:12+00:00\",\"description\":\"Experi\u00eancia de primeira classe que todos podem desfrutar. Divers\u00e3o e experi\u00eancias compartilhadas em fam\u00edlia por meio do Active Entertainment. Leia mais no artigo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027144611\\\/walltopia-ropes-course-play-cbus-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027144611\\\/walltopia-ropes-course-play-cbus-1-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/inicio-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Walltopia anuncia a nova e maior pista de cordas interna do mundo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Walltopia anuncia a nova e maior pista de cordas interna do mundo | Walltopia","description":"Experi\u00eancia de primeira classe que todos podem desfrutar. Divers\u00e3o e experi\u00eancias compartilhadas em fam\u00edlia por meio do Active Entertainment. Leia mais no artigo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/pt-br\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\/","og_locale":"pt_BR","og_type":"article","og_title":"Walltopia anuncia a nova e maior pista de cordas interna do mundo","og_description":"Experi\u00eancia de primeira classe que todos podem desfrutar. Divers\u00e3o e experi\u00eancias compartilhadas em fam\u00edlia por meio do Active Entertainment. Leia mais no artigo.","og_url":"https:\/\/walltopia.com\/pt-br\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2020-11-26T14:16:26+00:00","article_modified_time":"2026-01-15T14:56:12+00:00","author":"walltopia","twitter_card":"summary_large_image","twitter_image":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144611\/walltopia-ropes-course-play-cbus-1-1.jpg","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/pt-br\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/pt-br\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Walltopia anuncia a nova e maior pista de cordas interna do mundo","datePublished":"2020-11-26T14:16:26+00:00","dateModified":"2026-01-15T14:56:12+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/pt-br\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\/"},"wordCount":511,"commentCount":0,"publisher":{"@id":"https:\/\/walltopia.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144611\/walltopia-ropes-course-play-cbus-1-1.jpg","keywords":["A maior pista de cordas coberta do mundo","Curso de cordas","Curso de obst\u00e1culos"],"articleSection":["Entretenimento ativo","Sala de imprensa"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/walltopia.com\/pt-br\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/pt-br\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\/","url":"https:\/\/walltopia.com\/pt-br\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\/","name":"Walltopia anuncia a nova e maior pista de cordas interna do mundo | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/pt-br\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144611\/walltopia-ropes-course-play-cbus-1-1.jpg","datePublished":"2020-11-26T14:16:26+00:00","dateModified":"2026-01-15T14:56:12+00:00","description":"Experi\u00eancia de primeira classe que todos podem desfrutar. Divers\u00e3o e experi\u00eancias compartilhadas em fam\u00edlia por meio do Active Entertainment. Leia mais no artigo.","breadcrumb":{"@id":"https:\/\/walltopia.com\/pt-br\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/pt-br\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/walltopia.com\/pt-br\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144611\/walltopia-ropes-course-play-cbus-1-1.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144611\/walltopia-ropes-course-play-cbus-1-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/pt-br\/walltopia-anuncia-a-nova-e-maior-pista-de-cordas-interna-do-mundo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/pt-br\/inicio-pt\/"},{"@type":"ListItem","position":2,"name":"Walltopia anuncia a nova e maior pista de cordas interna do mundo"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/pt-br\/#website","url":"https:\/\/walltopia.com\/pt-br\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/pt-br\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/posts\/196145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/comments?post=196145"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/posts\/196145\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/media\/196147"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/media?parent=196145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/categories?post=196145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/tags?post=196145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}