{"id":206979,"date":"2025-02-17T12:13:53","date_gmt":"2025-02-17T09:13:53","guid":{"rendered":"https:\/\/walltopia.com\/products\/sem categoria\/pe-de-feijao\/"},"modified":"2025-02-17T12:13:53","modified_gmt":"2025-02-17T09:13:53","slug":"pe-de-feijao","status":"publish","type":"product","link":"https:\/\/walltopia.com\/pt-br\/product\/paredes-3d-divertidas\/pe-de-feijao\/","title":{"rendered":"P\u00e9 de feij\u00e3o"},"content":{"rendered":"<p>*As rotas s\u00e3o predeterminadas e t\u00eam um terceiro n\u00edvel de dificuldade<\/p>\n<p><strong>Especifica\u00e7\u00e3o t\u00e9cnica:<\/strong><\/p>\n<h4>Tipo de estrutura<\/h4>\n<p>O Beanstalk \u00e9 fornecido com nossa estrutura de a\u00e7o aut\u00f4noma padr\u00e3o que precisa ser ancorada no piso. A estrutura para locais externos \u00e9 galvanizada por imers\u00e3o a quente, o que garante sua durabilidade e resist\u00eancia \u00e0s condi\u00e7\u00f5es clim\u00e1ticas em todo o mundo <\/p>\n<h4>Ancoragem<\/h4>\n<p>Voc\u00ea precisa ancorar tr\u00eas placas de a\u00e7o de base, cada uma com quatro \u00e2ncoras na parte inferior. A estrutura deve ser ancorada em uma laje de concreto s\u00f3lida com espessura m\u00ednima de 15 cm. Para ter certeza de que seu piso pode suportar o Beanstalk <strong>, veja em anexo os c\u00e1lculos est\u00e1ticos das cargas<\/strong> <em>Walltopia Standard Loads File<\/em> <strong>na se\u00e7\u00e3o para download e sempre consulte seu engenheiro ou um profissional qualificado.<\/strong>  <\/p>\n<h4>Coloca\u00e7\u00e3o<\/h4>\n<p>O Beanstalk deve ser colocado longe de objetos r\u00edgidos, como colunas de edif\u00edcios, grades, m\u00f3veis ou outros. As dimens\u00f5es da zona de seguran\u00e7a est\u00e3o definidas nas imagens do produto. Essa \u00e9 a zona que voc\u00ea deve obrigatoriamente manter livre de quaisquer obstru\u00e7\u00f5es  <\/p>\n<h4>Pisos<\/h4>\n<p>Recomendamos enfaticamente que voc\u00ea instale um piso de seguran\u00e7a na zona de seguran\u00e7a ao redor de cada parede de escalada. Voc\u00ea pode comprar o Rope Wall Mat de 15 cm de espessura com acabamento em carpete cinza ou o One More Life Safety Flooring da Walltopia ou instalar outro tipo de piso absorvente de choque. <\/p>\n<h4>Produtos adicionais<\/h4>\n<p>Este produto n\u00e3o pode ser usado sem um sistema de retardo autom\u00e1tico!<\/p>\n<p>Nossa estrutura Fun Walls \u00e9 compat\u00edvel com o Tru Blue Auto Belay da Headrush e o Perfect Descend Auto Belay Device<\/p>\n<p>N\u00e3o se esque\u00e7a de conferir nossos acess\u00f3rios de seguran\u00e7a aqui. As portas de seguran\u00e7a facilitam a opera\u00e7\u00e3o e reduzem o risco de escalada sem seguran\u00e7a. As correias do Auto Belay s\u00e3o presas a elas quando ningu\u00e9m est\u00e1 escalando. As correias do Auto Belay s\u00e3o presas a elas quando ningu\u00e9m est\u00e1 escalando.   <\/p>\n<p>Opte por instalar nosso Smart Gate e reduza ao m\u00ednimo o risco de incidentes. Tamb\u00e9m recomendamos nosso sistema Self Belay, que n\u00e3o s\u00f3 contribui para a seguran\u00e7a da escalada, mas tamb\u00e9m ajuda nas opera\u00e7\u00f5es, reduzindo o n\u00famero de membros da equipe necess\u00e1rios &#8211; participantes a partir de 5 anos de idade podem usar o dispositivo por conta pr\u00f3pria, sem supervis\u00e3o! <\/p>\n<h4>Op\u00e7\u00f5es de envio<\/h4>\n<p>Este produto ser\u00e1 enviado em pe\u00e7as pr\u00e9-montadas maiores que exigir\u00e3o montagem no momento da entrega. Todos os componentes foram projetados para facilitar a montagem. Instru\u00e7\u00f5es detalhadas s\u00e3o fornecidas para garantir que o produto final seja seguro para a opera\u00e7\u00e3o e tenha excelente apar\u00eancia e acabamento.  <\/p>\n<h4>M\u00e1quinas necess\u00e1rias para a montagem<\/h4>\n<p>Lista de ferramentas: Chave de impacto, Furadeira, Rebarbadora, Pistola de impacto &#8211; soquetes 17\/19, Serra de vaiv\u00e9m, Chaves manuais &#8211; 13 \/ 17 \/ 19 \/ 24, Pilares, Fitas m\u00e9tricas<\/p>\n<p>Maquin\u00e1rio: Elevador tipo tesoura com capacidade para elevar 260 kg at\u00e9 8 metros, empilhadeira 2T &#8211; para descarregamento, paleteira<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"flex flex-col items-start\">\n<div class=\"flex items-center text-xs rounded p-3 text-gray-900 bg-gray-100\">\n<div>\n<div class=\"flex items-center gap-3\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"657a2499-85b3-44fc-80ac-df77e319da55\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n\nO Beanstalk 3D Fun Wall \u00e9 uma experi\u00eancia de escalada encantadora projetada para cativar a imagina\u00e7\u00e3o de jovens aventureiros de 5 a 12 anos. Com seu design vibrante e envolvente, ele estimula o desenvolvimento f\u00edsico e cognitivo das crian\u00e7as. Seja para playgrounds internos, centros recreativos ou institui\u00e7\u00f5es educacionais, o Beanstalk oferece a combina\u00e7\u00e3o perfeita de esporte e divers\u00e3o. Voc\u00ea pode adicionar elementos interativos para obter gamifica\u00e7\u00e3o e uma dose extra de emo\u00e7\u00e3o.   \n\n<\/div>\n<\/div>","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"product_brand":[],"product_cat":[6846],"product_tag":[],"class_list":["post-206979","product","type-product","status-publish","product_cat-paredes-3d-divertidas","first","onbackorder","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>P\u00e9 de feij\u00e3o | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/pt-br\/product\/paredes-3d-divertidas\/pe-de-feijao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"P\u00e9 de feij\u00e3o\" \/>\n<meta property=\"og:description\" content=\"O Beanstalk 3D Fun Wall \u00e9 uma experi\u00eancia de escalada encantadora projetada para cativar a imagina\u00e7\u00e3o de jovens aventureiros de 5 a 12 anos. Com seu design vibrante e envolvente, ele estimula o desenvolvimento f\u00edsico e cognitivo das crian\u00e7as. Seja para playgrounds internos, centros recreativos ou institui\u00e7\u00f5es educacionais, o Beanstalk oferece a combina\u00e7\u00e3o perfeita de esporte e divers\u00e3o. Voc\u00ea pode adicionar elementos interativos para obter gamifica\u00e7\u00e3o e uma dose extra de emo\u00e7\u00e3o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/pt-br\/product\/paredes-3d-divertidas\/pe-de-feijao\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250219162530\/walltopia-fun-walls-beanstalk-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"526\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/product\\\/paredes-3d-divertidas\\\/pe-de-feijao\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/product\\\/paredes-3d-divertidas\\\/pe-de-feijao\\\/\",\"name\":\"P\u00e9 de feij\u00e3o | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\"},\"datePublished\":\"2025-02-17T09:13:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/product\\\/paredes-3d-divertidas\\\/pe-de-feijao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/product\\\/paredes-3d-divertidas\\\/pe-de-feijao\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/product\\\/paredes-3d-divertidas\\\/pe-de-feijao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/inicio-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/loja\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"P\u00e9 de feij\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"P\u00e9 de feij\u00e3o | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/pt-br\/product\/paredes-3d-divertidas\/pe-de-feijao\/","og_locale":"pt_BR","og_type":"article","og_title":"P\u00e9 de feij\u00e3o","og_description":"O Beanstalk 3D Fun Wall \u00e9 uma experi\u00eancia de escalada encantadora projetada para cativar a imagina\u00e7\u00e3o de jovens aventureiros de 5 a 12 anos. Com seu design vibrante e envolvente, ele estimula o desenvolvimento f\u00edsico e cognitivo das crian\u00e7as. Seja para playgrounds internos, centros recreativos ou institui\u00e7\u00f5es educacionais, o Beanstalk oferece a combina\u00e7\u00e3o perfeita de esporte e divers\u00e3o. Voc\u00ea pode adicionar elementos interativos para obter gamifica\u00e7\u00e3o e uma dose extra de emo\u00e7\u00e3o.","og_url":"https:\/\/walltopia.com\/pt-br\/product\/paredes-3d-divertidas\/pe-de-feijao\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","og_image":[{"width":526,"height":1200,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250219162530\/walltopia-fun-walls-beanstalk-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/pt-br\/product\/paredes-3d-divertidas\/pe-de-feijao\/","url":"https:\/\/walltopia.com\/pt-br\/product\/paredes-3d-divertidas\/pe-de-feijao\/","name":"P\u00e9 de feij\u00e3o | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/pt-br\/#website"},"datePublished":"2025-02-17T09:13:53+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/pt-br\/product\/paredes-3d-divertidas\/pe-de-feijao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/pt-br\/product\/paredes-3d-divertidas\/pe-de-feijao\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/pt-br\/product\/paredes-3d-divertidas\/pe-de-feijao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/pt-br\/inicio-pt\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/walltopia.com\/pt-br\/loja\/"},{"@type":"ListItem","position":3,"name":"P\u00e9 de feij\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/pt-br\/#website","url":"https:\/\/walltopia.com\/pt-br\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/pt-br\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/product\/206979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/product\/206979\/revisions"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/media?parent=206979"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/product_brand?post=206979"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/product_cat?post=206979"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/product_tag?post=206979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}